{"id":536801,"date":"2024-12-01T23:01:13","date_gmt":"2024-12-01T22:01:13","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=536801&#038;preview=true&#038;preview_id=536801"},"modified":"2024-12-01T23:20:32","modified_gmt":"2024-12-01T22:20:32","slug":"top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/","title":{"rendered":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TOP 14 2024\/2025 &#8211; L&rsquo;Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13). Une victoire pr\u00e9cieuse pour Bayonne, qui rentre dans le Top 6. Le Stade Fran\u00e7ais aurait peut-\u00eatre m\u00e9rit\u00e9 mieux, mais repart les mains vides. Et reste 12e, avec 19 points.<\/em><\/h4>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-top-14-2024-2025\/\">Le classement du Top 14 2024\/2025<\/a><\/strong><\/li>\n<\/ul>\n<h2>Les deux \u00e9quipes dos \u00e0 dos \u00e0 la pause<\/h2>\n<p style=\"text-align: justify;\">Ce premier acte \u00e9tait pourtant bien parti. Et il n&rsquo;est pas si mauvais que cela. Beaucoup de temps de jeu (22 minutes de temps de jeu effectif) mais beaucoup de maladresses de chaque c\u00f4t\u00e9. Cinq ballons perdus pour Bayonne, sept pour le Stade Fran\u00e7ais. Et un score nul \u00e0 la pause (10-10)<\/p>\n<p style=\"text-align: justify;\">Et pourtant, quand les choses se sont enclench\u00e9es, on a vraiment vu de belles choses. Et deux beaux essais. Le premier pour les Basques. \u00c0 l&rsquo;initiative d&rsquo;une belle perc\u00e9e de <strong>Sireli Maqala<\/strong>, d&rsquo;un relais avec une passe entre les jambes spectaculaire de <strong>Giovanni Habel-Kuffner.<\/strong> Avant que <strong>Facundo Bosch<\/strong> \u00e9carte \u00e0 gauche vers <strong>Mateo Carreras<\/strong> (7-3, 12e). Mais que dire de la r\u00e9action parisienne, avec un coup de pied par-dessus de <strong>Louis Carbonel<\/strong>, r\u00e9cup\u00e9r\u00e9 acrobatiquement par <strong>Joe Marchant<\/strong>, qui file vers l&rsquo;en-but. Et remet les siens imm\u00e9diatement devant (7-10, 14e). \u00c0 vrai dire, on a cru \u00e0 un match fou. La suite sera un peu moins bonne. Mais si Bayonne a gal\u00e9r\u00e9, c&rsquo;est aussi que Paris a \u00e9t\u00e9 courageux dans le premier acte. Malgr\u00e9 14 plaquages manqu\u00e9s en 78 tent\u00e9s. Avec quelques ballons gratt\u00e9s dans les rucks.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">CARBONEL \ud83e\udd1c\ud83e\udd1b MARCHANT<\/p>\n<p>La coup de pied par dessus g\u00e9nial de Carbonel qui permet \u00e0 Marchant d&rsquo;inscrire le premier essai du <a href=\"https:\/\/twitter.com\/SFParisRugby?ref_src=twsrc%5Etfw\">@SFParisRugby<\/a> \ud83c\udf38<a href=\"https:\/\/twitter.com\/hashtag\/ABSFP?src=hash&amp;ref_src=twsrc%5Etfw\">#ABSFP<\/a> <a href=\"https:\/\/t.co\/JHN9r5wTAg\">pic.twitter.com\/JHN9r5wTAg<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/twitter.com\/CanalplusRugby\/status\/1863319849729974739?ref_src=twsrc%5Etfw\">December 1, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Un \u00e9clair de Bayonne et puis c&rsquo;est tout<\/h2>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/video-resume-bayonne-stade-francais-11eme-journee-de-top-14\/\">Le r\u00e9sum\u00e9 vid\u00e9o de Bayonne &#8211; Stade Fran\u00e7ais<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Baptiste Chouzenoux<\/strong> trouve un intervalle et sert <strong>Mateo Carreras<\/strong>. Si l&rsquo;ailier est repris et priv\u00e9 du doubl\u00e9, le ballon continue \u00e0 vivre. En force, <strong>Esteban Capilla<\/strong> parvient \u00e0 enfoncer la ligne parisienne, pour le deuxi\u00e8me essai des siens (15-10, 47e). Si le Stade Fran\u00e7ais a pu \u00e9coper m\u00eame en \u00e9tant largement domin\u00e9 dans les statistiques offensives, on sent que les Parisiens souffrent physiquement apr\u00e8s avoir beaucoup donn\u00e9. Les duels et les impacts sont de plus en plus en faveur de l&rsquo;Aviron Bayonnais. Une \u00e9quipe incroyablement disciplin\u00e9e sur ses s\u00e9quences d\u00e9fensives (deux plaquages rat\u00e9s en 70 tent\u00e9s, \u00e0 l&rsquo;heure de jeu). Mais toujours ce manque de liant offensif pour encore plus enfoncer des Parisiens encore en vie \u00e0 l&rsquo;heure de jeu (18-13, 57e).<\/p>\n<p style=\"text-align: justify;\">Et sur ses rares sorties, le Stade Fran\u00e7ais aura pu \u00eatre mena\u00e7ant. Que ce soit <strong>Lester Etien<\/strong> (49e) ou <strong>Samuel Ezeala<\/strong> (63e), qui sont rentr\u00e9s dans les 22 m\u00e8tres bayonnais. La menace s&rsquo;est m\u00eame encore plus pr\u00e9cis\u00e9e, quand l&rsquo;essai de <strong>L\u00e9o Barr\u00e9<\/strong> a \u00e9t\u00e9 refus\u00e9 pour un passage en touche de l&rsquo;international, qui venait d&rsquo;entrer en jeu (69e). C&rsquo;est le tournant d\u00e9finitif de cette rencontre. Longtemps dans le coup pour ramener quelque chose, le Stade Fran\u00e7ais va se casser les dents aux portes du bonus d\u00e9fensif. Avec une fin de match marqu\u00e9e par l&rsquo;indiscipline. \u00c0 l&rsquo;image d&rsquo;une rencontre qui a failli d\u00e9coller \u00e0 plusieurs reprises, mais qui est rest\u00e9e relativement moyenne. Surtout le second acte.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2024\/2025 &#8211; L&rsquo;Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13). Une victoire pr\u00e9cieuse pour Bayonne, qui rentre dans le Top 6. Le Stade Fran\u00e7ais aurait peut-\u00eatre m\u00e9rit\u00e9 mieux, mais repart les mains vides. Et reste 12e, avec 19 points.<\/p>\n","protected":false},"author":83,"featured_media":536811,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[8158,16878,24,3076,111],"class_list":["post-536801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-aviron-bayonnais","tag-breve","tag-sport","tag-stade-francais","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais<\/title>\n<meta name=\"description\" content=\"TOP 14 2024\/2025 - L&#039;Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2024\/2025 - L&#039;Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-01T22:01:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-01T22:20:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\",\"datePublished\":\"2024-12-01T22:01:13+00:00\",\"dateModified\":\"2024-12-01T22:20:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png\",\"keywords\":[\"Aviron Bayonnais\",\"br\u00e8ve\",\"sport\",\"Stade Fran\u00e7ais\",\"Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\",\"name\":\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png\",\"datePublished\":\"2024-12-01T22:01:13+00:00\",\"dateModified\":\"2024-12-01T22:20:32+00:00\",\"description\":\"TOP 14 2024\/2025 - L'Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png\",\"width\":1200,\"height\":674,\"caption\":\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais","description":"TOP 14 2024\/2025 - L'Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais","og_description":"TOP 14 2024\/2025 - L'Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-12-01T22:01:13+00:00","article_modified_time":"2024-12-01T22:20:32+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais","datePublished":"2024-12-01T22:01:13+00:00","dateModified":"2024-12-01T22:20:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png","keywords":["Aviron Bayonnais","br\u00e8ve","sport","Stade Fran\u00e7ais","Top 14"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/","name":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png","datePublished":"2024-12-01T22:01:13+00:00","dateModified":"2024-12-01T22:20:32+00:00","description":"TOP 14 2024\/2025 - L'Aviron Bayonnais a domin\u00e9 le Stade Fran\u00e7ais lors du dernier match de la onzi\u00e8me journ\u00e9e (21-13).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Top-14-J11-Bayonne-toujours-imperial-a-domicile-contre-le-Stade-Francais.png","width":1200,"height":674,"caption":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j11-bayonne-toujours-imperial-a-domicile-contre-le-stade-francais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 (J11) : Bayonne toujours imp\u00e9rial \u00e0 domicile contre le Stade Fran\u00e7ais"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/536801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=536801"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/536801\/revisions"}],"predecessor-version":[{"id":536821,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/536801\/revisions\/536821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/536811"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=536801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=536801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=536801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}