{"id":537270,"date":"2024-12-04T13:38:39","date_gmt":"2024-12-04T12:38:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=537270&#038;preview=true&#038;preview_id=537270"},"modified":"2024-12-04T13:42:53","modified_gmt":"2024-12-04T12:42:53","slug":"tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/","title":{"rendered":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 &#8211; Il n\u2019y a pas eu photo entre l\u2019\u00e9quipe de France et la Roumanie aujourd\u2019hui. Pour leur premier match dans ce top 8, pris de vitesse, les Bleus s\u2019inclinent lourdement contre la Roumanie (3-8).<\/em><\/h4>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir \u00e9vacu\u00e9 la pression du premier match de la comp\u00e9tition, les Bleus du ping avaient peu \u00e0 peu repris de l\u2019assurance. <a href=\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-sinvite-au-tour-principal-de-la-coupe-du-monde-par-equipes-mixtes\/\">Le dernier succ\u00e8s en date contre le Canada<\/a> les avait plac\u00e9s en haut de leur groupe pour acc\u00e9der au top 8. Mais contre la Roumanie aujourd\u2019hui, l\u2019\u00e9quipe de France n\u2019a que peu exist\u00e9 et prend une bien mauvaise option sur les demi-finales.<\/p>\n<h2 style=\"text-align: justify;\">Une mauvaise op\u00e9ration pour l&rsquo;\u00e9quipe de France<\/h2>\n<p style=\"text-align: justify;\">On pensait <strong>Esteban Dorr<\/strong> et <strong>Camille Lutz<\/strong> partis sur les m\u00eames bases que la veille, pliant la premi\u00e8re manche 11-4 face \u00e0 la paire Ionescu\/Szocs. Mais piqu\u00e9s, les Roumains se sont rebell\u00e9s dans le deuxi\u00e8me set 11-7 avant de renverser le bin\u00f4me tricolore sur le m\u00eame score dans le troisi\u00e8me. Une bonne opportunit\u00e9 de perdue de faire course en t\u00eate, surtout que pour l\u2019\u00e9quipe de France, les affaires se sont davantage cors\u00e9es. Totalement prise de vitesse face \u00e0 <strong>Adina Diaconu<\/strong>, <strong>Audrey Zarif<\/strong> a tr\u00e8s mal entam\u00e9 les deux premi\u00e8res manches de sa rencontre. Et malgr\u00e9 quelques sursauts d\u2019orgueil, elle a laiss\u00e9 filer les trois points du duel, frustr\u00e9e (<strong>8-11, 2-11, 6-11<\/strong>).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u00c7a va vite le tennis de table\u2026difficile mentalement pour Thibault Poret <a href=\"https:\/\/t.co\/6YH0sB9fCE\">pic.twitter.com\/6YH0sB9fCE<\/a><\/p>\n<p>\u2014 Cho Allez !\ud83c\udfd3 (@ChoAllez) <a href=\"https:\/\/twitter.com\/ChoAllez\/status\/1864280285208088979?ref_src=twsrc%5Etfw\">December 4, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">5-1 Roumanie, il ne fallait pas flancher pour <strong>Thibault Poret<\/strong> face \u00e0 <strong>Eduard Ionescu<\/strong>. Malheureusement le Fran\u00e7ais n\u2019a pas su convertir les points cl\u00e9s, l\u00e2chant notamment 5 balles de set cons\u00e9cutives dans le premier, perdu finalement 10-12. Ce qui a \u00e9videmment donn\u00e9 des ailes \u00e0 son adversaire. Port\u00e9 par sa remontada, Ionescu a encha\u00een\u00e9 avec le gain de deuxi\u00e8me acte, Poret n\u2019a pu que forcer un 4<sup>\u00e8 <\/sup>match dont Zarif et Lutz ne se sortiront pas indemnes (1-1). Une lourde d\u00e9faite 3-8 pour les Bleus qui les place en mauvaise posture quant \u00e0 une qualification en demies. Surtout avant d\u2019affronter le Japon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 &#8211; La France s\u2019incline lourdement contre la Roumanie (3-8).<\/p>\n","protected":false},"author":18,"featured_media":537273,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9663],"tags":[16878,43115,27448,1197],"class_list":["post-537270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis-de-table","tag-breve","tag-coupe-monde-par-equipes-mixtes","tag-ping-francais","tag-tennis-de-table"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T12:38:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T12:42:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\",\"datePublished\":\"2024-12-04T12:38:39+00:00\",\"dateModified\":\"2024-12-04T12:42:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png\",\"keywords\":[\"br\u00e8ve\",\"coupe monde par \u00e9quipes mixtes\",\"ping fran\u00e7ais\",\"tennis de table\"],\"articleSection\":[\"Tennis de table\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\",\"name\":\"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png\",\"datePublished\":\"2024-12-04T12:38:39+00:00\",\"dateModified\":\"2024-12-04T12:42:53+00:00\",\"description\":\"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png\",\"width\":1200,\"height\":674,\"caption\":\"Tennis de table La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes","description":"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/","og_locale":"fr_FR","og_type":"article","og_title":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes","og_description":"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).","og_url":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2024-12-04T12:38:39+00:00","article_modified_time":"2024-12-04T12:42:53+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes","datePublished":"2024-12-04T12:38:39+00:00","dateModified":"2024-12-04T12:42:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png","keywords":["br\u00e8ve","coupe monde par \u00e9quipes mixtes","ping fran\u00e7ais","tennis de table"],"articleSection":["Tennis de table"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/","url":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/","name":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png","datePublished":"2024-12-04T12:38:39+00:00","dateModified":"2024-12-04T12:42:53+00:00","description":"COUPE DU MONDE PAR \u00c9QUIPES MIXTES DE TENNIS DE TABLE 2024 - La France s\u2019incline lourdement contre la Roumanie (3-8).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Tennis-de-table-La-France-battue-par-la-Roumanie-lors-de-la-Coupe-du-monde-par-equipes-mixtes.png","width":1200,"height":674,"caption":"Tennis de table La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-france-battue-par-la-roumanie-lors-de-la-coupe-du-monde-par-equipes-mixtes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tennis de table : La France battue par la Roumanie lors de la Coupe du monde par \u00e9quipes mixtes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=537270"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537270\/revisions"}],"predecessor-version":[{"id":537275,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537270\/revisions\/537275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/537273"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=537270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=537270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=537270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}