{"id":537548,"date":"2024-12-05T19:30:50","date_gmt":"2024-12-05T18:30:50","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=537548&#038;preview=true&#038;preview_id=537548"},"modified":"2024-12-05T19:30:50","modified_gmt":"2024-12-05T18:30:50","slug":"transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/","title":{"rendered":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Garry Ringrose (Leinster, Irlande) sur les tablettes d&rsquo;un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">Leinster : Garry Ringrose pist\u00e9 par l&rsquo;USAP<\/h2>\n<p style=\"text-align: justify;\"><strong>Ross Byrne<\/strong> (29 ans, Leinster) et <strong>Bundee Aki<\/strong> (34 ans, Connacht) il y a quelques semaines, <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-john-cooney-irlande-piste-par-un-cador-de-top-14\/\"><strong>John Cooney<\/strong><\/a> (34 ans, Ulster) et <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-jacob-stockdale-irlande-pourrait-signer-en-top-14\/\"><strong>Jacob Stockdale<\/strong><\/a> (28 ans, Ulster) ces derniers jours, les Irlandais ont d\u00e9finitivement la cote en France. Selon <a href=\"https:\/\/actu.fr\/occitanie\/perpignan_66136\/transferts-perpignan-s-active-au-moins-un-joker-en-approche-renseignements-pris-sur-garry-ringrose_61959298.html\"><em>Actu Rugby<\/em><\/a>, un autre international avec le <em>XV du Tr\u00e8fle<\/em> est, \u00e0 son tir, courtis\u00e9 en Top 14. Il s&rsquo;agit du trois-quarts <strong>Garry Ringrose<\/strong> (29 ans, Leinster).<\/p>\n<p style=\"text-align: justify;\">En effet, l&rsquo;<strong>USAP<\/strong> est venue aux renseignements concernant le joueur aux 64 s\u00e9lections avec l&rsquo;Irlande. Ce dernier arrive en fin de contrat au <strong>Leinster<\/strong> en juin prochain et n&rsquo;a pas encore prolong\u00e9 avec les <em>Dubliners<\/em>. N\u00e9anmoins, les pr\u00e9tentions salariales du centre irlandais compliquent les discussions. Ce qui pourrait bien mettre fin rapidement \u00e0 la piste <strong>Ringrose<\/strong>. Affaire \u00e0 suivre.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> R\u00e9ussir \u00e0 convaincre Garry Ringrose serait un sacr\u00e9 coup de la part de l&rsquo;USAP. Mais la t\u00e2che s&rsquo;annonce ardue, financi\u00e8rement et sportivement, les Catalans restant, quoi qu&rsquo;on en dise, dans la course au maintien.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-garry-ringrose-irlande-a-une-touche-en-top-14\/\">Transferts : Garry Ringrose (Irlande) a une touche en Top 14<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Brive : Pas de d\u00e9part anticip\u00e9 pour Mathis Fert\u00e9<\/h2>\n<p style=\"text-align: justify;\"><strong>Mathis Fert\u00e9<\/strong> (20 ans) ne bougera pas de <strong>Brive<\/strong> l&rsquo;\u00e9t\u00e9 prochain. Selon le <em>Midi Olympique<\/em>, le trois-quarts polyvalent, international U20, n&rsquo;aura pas de bon de sortie \u00e0 l&rsquo;issue de cette saison. Sous contrat avec le <strong>CAB<\/strong> jusqu&rsquo;en 2028, le club corr\u00e9zien a indiqu\u00e9 que <strong>Fert\u00e9<\/strong> ne disposait pas de clause de sortie. Du moins, pas pour le moment.<\/p>\n<p style=\"text-align: justify;\">Pour rappel, le <strong>RC Toulon<\/strong>, et surtout le <strong>Stade Toulousain<\/strong>, faisaient les yeux doux \u00e0 l&rsquo;arri\u00e8re\/ailier\/demi de m\u00eal\u00e9e. <strong>Mathis Fert\u00e9<\/strong> a m\u00eame visit\u00e9 les installations stadistes, il y a quelques semaines. Depuis, les Haut-Garonnais ont boucl\u00e9 l&rsquo;arriv\u00e9e de <strong>Teddy Thomas<\/strong> (31 ans, La Rochelle). Mais, nul doute que de nombreuses \u00e9curies de Top 14 reviendront \u00e0 la charge ces prochains mois.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Une, mais pas deux. Brive refuse de voir sa deuxi\u00e8me p\u00e9pite partir \u00e0 l&rsquo;issue de la saison en cours. Logique, le CAB est un club ambitieux et a des chances de revenir en Top 14 la saison prochaine. Dans le cas contraire, le board corr\u00e9zien reverra peut-\u00eatre sa position, si un club de Top 14 offre un joli ch\u00e8que en \u00e9change.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-brive-a-tranche-pour-lavenir-de-mathis-ferte\/\">Transferts : Brive a tranch\u00e9 pour l\u2019avenir de Mathis Fert\u00e9<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">LOU : Karim Ghezal arrive<\/h2>\n<p style=\"text-align: justify;\"><strong>Karim Ghezal<\/strong> va reprendre du service. D\u00e9barqu\u00e9 du <strong>Stade Fran\u00e7ais<\/strong> fin septembre, l&rsquo;ancien entra\u00eeneur de la touche du<strong> XV de France<\/strong> (2019-2023) est sur le point de retrouver un poste, et pas n&rsquo;importe o\u00f9. Selon le <a href=\"https:\/\/www.rugbyrama.fr\/2024\/12\/05\/transferts-top-14-exclusivite-midol-lyon-karim-ghezal-en-pole-pour-remplacer-gibbes-12370729.php\"><em>Midi Olympique<\/em><\/a>, <strong>Ghezal<\/strong> va devenir entra\u00eeneur en chef au <strong>LOU<\/strong> et succ\u00e9der \u00e0 <strong>Jono Gibbes<\/strong>, remerci\u00e9 en d\u00e9but de semaine par la direction lyonnaise.<\/p>\n<p style=\"text-align: justify;\">Pour rappel, <strong>Karim Ghezal<\/strong> conna\u00eet bien la maison rhodanienne. Il y a termin\u00e9 sa carri\u00e8re de joueur, entre 2014 et 2016. Avant d&rsquo;enfiler le costume d&rsquo;entra\u00eeneur en charge des avants, entre 2016 et 2019. Reste \u00e0 savoir comment l&rsquo;ancien deuxi\u00e8me ligne va s&rsquo;entendre avec le directeur du rugby du LOU, <strong>Fabien Gengenbacher<\/strong>. Affaire \u00e0 suivre.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> Ghezal de retour au LOU, tout sauf une surprise. Le technicien de 43 ans est tr\u00e8s attach\u00e9 au club rhodanien et a encore des attaches dans la r\u00e9gion. Si sa courte aventure au Stade Fran\u00e7ais s&rsquo;est mal termin\u00e9e, il va apporter sa touche \u00e0 un groupe qui a besoin de r\u00e9gularit\u00e9.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-karim-ghezal-va-deja-reprendre-du-service-en-top-14\/\">Transferts : Karim Ghezal va d\u00e9j\u00e0 reprendre du service en Top 14<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre<\/p>\n","protected":false},"author":4,"featured_media":537555,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-537548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d&#039;un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d&#039;un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T18:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\",\"datePublished\":\"2024-12-05T18:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\",\"name\":\"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png\",\"datePublished\":\"2024-12-05T18:30:50+00:00\",\"description\":\"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d'un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre","description":"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d'un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre","og_description":"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d'un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-12-05T18:30:50+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre","datePublished":"2024-12-05T18:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/","name":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png","datePublished":"2024-12-05T18:30:50+00:00","description":"TRANSFERTS RUGBY - Garry Ringrose (Leinster, Irlande) sur les tablettes d'un club de Top 14, avenir scell\u00e9 pour Mathis Fert\u00e9 (Brive), Karim Ghezal va reprendre du service : les infos transferts de ce jeudi 5 d\u00e9cembre 2024.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Rugby-Garry-Ringrose-Mathis-Ferte-Karim-Ghezal-les-infos-du-jeudi-5-decembre.png","width":1200,"height":674,"caption":"Transferts Rugby Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garry-ringrose-mathis-ferte-karim-ghezal-les-infos-du-jeudi-5-decembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Garry Ringrose, Mathis Fert\u00e9, Karim Ghezal, les infos du jeudi 5 d\u00e9cembre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=537548"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537548\/revisions"}],"predecessor-version":[{"id":537561,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537548\/revisions\/537561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/537555"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=537548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=537548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=537548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}