{"id":537710,"date":"2024-12-06T16:39:27","date_gmt":"2024-12-06T15:39:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=537710&#038;preview=true&#038;preview_id=537710"},"modified":"2024-12-06T16:39:27","modified_gmt":"2024-12-06T15:39:27","slug":"betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/","title":{"rendered":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>BETCLIC \u00c9LITE 2024-2025 &#8211; Malik Fitts out pendant 3 mois, Strasbourg se devait de r\u00e9agir. La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">De retour, 5 ans apr\u00e8s. <strong>Malcolm Cazalon<\/strong> (23 ans) revient en <strong>Betclic \u00c9lite<\/strong> \u00e0 la faveur de la blessure de <strong>Malik Fitts<\/strong>\u00a0et d&rsquo;une infirmerie d\u00e9j\u00e0 bien remplie du c\u00f4t\u00e9 de la <a href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-la-sig-met-le-grappin-sur-edon-maxhuni\/\"><strong>SIG Strasbourg<\/strong><\/a>. Fils de l\u2019ancien joueur <strong>Laurent Cazalon<\/strong>, le Roannais de naissance fait partie de la g\u00e9n\u00e9ration 2001 (Hayes, Maledon). Apr\u00e8s \u00eatre pass\u00e9 par la <em>G-League<\/em> de <a href=\"https:\/\/dicodusport.fr\/blog\/draft-nba-2022-malcolm-cazalon-tente-sa-chance\/\">l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;Atlantique<\/a>, l&rsquo;athl\u00e9tique ailier devrait avoir du temps de jeu en Alsace.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udea8 \ud835\udc70\ud835\udc75\ud835\udc6d\ud835\udc76 \ud835\udc6c\ud835\udc6d\ud835\udc6d\ud835\udc6c\ud835\udc6a\ud835\udc7b\ud835\udc70\ud835\udc6d \ud83c\udfe5<\/p>\n<p>En cons\u00e9quence de l\u2019absence de Malik Fitts, le club a r\u00e9agit tr\u00e8s vite en signant Malcolm Cazalon comme pigiste m\u00e9dical.<\/p>\n<p>Ce dernier est d\u2019ores et d\u00e9j\u00e0 qualifi\u00e9 pour le match de ce samedi face \u00e0 Cholet \ud83d\udd25<\/p>\n<p>\ud83d\udc49 Communiqu\u00e9 : <a href=\"https:\/\/t.co\/bJFx5YT7wj\">https:\/\/t.co\/bJFx5YT7wj<\/a> <a href=\"https:\/\/t.co\/5rUunvrbIl\">pic.twitter.com\/5rUunvrbIl<\/a><\/p>\n<p>\u2014 SIG Strasbourg (@sigstrasbourg) <a href=\"https:\/\/twitter.com\/sigstrasbourg\/status\/1865031116618416466?ref_src=twsrc%5Etfw\">December 6, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Malcolm correspond totalement au type de joueur souhait\u00e9 pour remplacer Malik : tr\u00e8s offensif, polyvalent, capable de driver, de shooter et de jouer le pick and roll. Il conna\u00eet le jeu europ\u00e9en, puisqu\u2019apr\u00e8s l\u2019ASVEL et Bourg, il a jou\u00e9 avec Mega Leks en Serbie avant de partir en G-League. De plus il a port\u00e9 le maillot de l\u2019\u00e9quipe de France en jeune. Pour lui c\u2019est un retour en France avec l\u2019ambition de retrouver la comp\u00e9tition et de montrer \u00e0 tout le monde le joueur qu\u2019il est devenu et nous sommes tr\u00e8s heureux qu\u2019il ait choisi notre projet. On compte sur lui pour nous amener les qualit\u00e9s et la dimension que Malik nous apportait\u00a0\u00bb<\/em>, a d\u00e9clar\u00e9 \u00e0 son propos le coach <strong>Laurent Vila<\/strong> sur le <a href=\"https:\/\/sigstrasbourg.fr\/2024\/12\/malik-out-3-mois-malcolm-cazalon-arrive-en-aide\">communiqu\u00e9 du club<\/a>.<\/p>\n<p>Il est d\u2019ores et d\u00e9j\u00e0 qualifi\u00e9 pour la r\u00e9ception de Cholet ce samedi 7 d\u00e9cembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BETCLIC \u00c9LITE 2024-2025 &#8211; Malik Fitts out pendant 3 mois, Strasbourg se devait de r\u00e9agir. La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0<\/p>\n","protected":false},"author":88,"featured_media":537714,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46998],"tags":[16878,22894,23095],"class_list":["post-537710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betclic-elite","tag-breve","tag-malcolm-cazalon","tag-sig-strasbourg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg<\/title>\n<meta name=\"description\" content=\"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\" \/>\n<meta property=\"og:description\" content=\"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-06T15:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paul Lalevee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/\"},\"author\":{\"name\":\"Paul Lalevee\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/1eaa63dfac40b5e5c47f03a71920c1cd\"},\"headline\":\"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\",\"datePublished\":\"2024-12-06T15:39:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/\"},\"wordCount\":343,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png\",\"keywords\":[\"br\u00e8ve\",\"Malcolm Cazalon\",\"SIG Strasbourg\"],\"articleSection\":[\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/\",\"name\":\"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png\",\"datePublished\":\"2024-12-06T15:39:27+00:00\",\"description\":\"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png\",\"width\":1200,\"height\":674,\"caption\":\"Betclic \u00c9lite Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/1eaa63dfac40b5e5c47f03a71920c1cd\",\"name\":\"Paul Lalevee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"caption\":\"Paul Lalevee\"},\"description\":\"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/paul-lalevee\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg","description":"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg","og_description":"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-12-06T15:39:27+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png","type":"image\/png"}],"author":"Paul Lalevee","twitter_card":"summary_large_image","twitter_title":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/"},"author":{"name":"Paul Lalevee","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd"},"headline":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg","datePublished":"2024-12-06T15:39:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/"},"wordCount":343,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png","keywords":["br\u00e8ve","Malcolm Cazalon","SIG Strasbourg"],"articleSection":["Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/","url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/","name":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png","datePublished":"2024-12-06T15:39:27+00:00","description":"BETCLIC ELITE - La SIG annonce ce vendredi 6 d\u00e9cembre la signature en tant que joker m\u00e9dical de Malcolm Cazalon, libre de tout contrat.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Betclic-Elite-Malcolm-Cazalon-arrive-en-pigiste-medical-a-Strasbourg.png","width":1200,"height":674,"caption":"Betclic \u00c9lite Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-malcolm-cazalon-arrive-en-pigiste-medical-a-strasbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Betclic \u00c9lite : Malcolm Cazalon arrive en pigiste m\u00e9dical \u00e0 Strasbourg"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd","name":"Paul Lalevee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","caption":"Paul Lalevee"},"description":"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.","url":"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=537710"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537710\/revisions"}],"predecessor-version":[{"id":537715,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/537710\/revisions\/537715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/537714"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=537710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=537710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=537710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}