{"id":538961,"date":"2024-12-11T11:50:32","date_gmt":"2024-12-11T10:50:32","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=538961&#038;preview=true&#038;preview_id=538961"},"modified":"2024-12-11T11:50:32","modified_gmt":"2024-12-11T10:50:32","slug":"mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/","title":{"rendered":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 &#8211; Sans trembler, les Bleues ont accompli leur mission contre le Canada pour s&rsquo;offrir un quart de finale de prestige.<\/em><\/h4>\n<p style=\"text-align: justify;\">Pas vernie au tirage, l&rsquo;\u00e9quipe de France femmes de squash a \u00e9t\u00e9 plac\u00e9e dans le quart de tableau de l&rsquo;\u00c9gypte, ternissant indubitablement les chances de m\u00e9daille. Mais avant de s&rsquo;offrir un match de prestige contre la meilleure \u00e9quipe du monde, il fallait d\u00e9j\u00e0 passer le cap des 8e de finale. Face au Canada, les Bleues \u00e9taient favorites, mais n&rsquo;avaient pas n\u00e9cessairement une \u00e9norme marge.<\/p>\n<h2 style=\"text-align: justify;\">Les Bleues assurent<\/h2>\n<p style=\"text-align: justify;\">Et ce parce que <strong>Hollie Naughton<\/strong>, 26e mondiale, repr\u00e9sentait une adversaire de choix pour <strong>M\u00e9lissa Alves<\/strong>. Et la Fran\u00e7aise a \u00e9t\u00e9 totalement d\u00e9bord\u00e9e en d\u00e9but de rencontre par le squash agressif de sa rivale, avant de retrouver ses esprits pour prendre le contr\u00f4le du match. On n&rsquo;en attendait pas moins d&rsquo;une joueuse en tr\u00e8s grande forme r\u00e9cemment, qui a fait son retour dans le Top 20 mondial. Parfois ballott\u00e9e, elle a fait parler sa ma\u00eetrise sur les points importants pour une victoire en trois jeux.<\/p>\n<p style=\"text-align: justify;\">Premi\u00e8re balle de match donc pour <strong>Lauren Baltayan<\/strong> contre <strong>Nikki Todd<\/strong>. Sur le papier, une affiche facile au vu des plus de 100 places d&rsquo;\u00e9cart entre les deux. Pour sa premi\u00e8re campagne aux Mondiaux, la Fran\u00e7aise a quelque peu trembl\u00e9, notamment dans un deuxi\u00e8me jeu absolument hom\u00e9rique qu&rsquo;elle aurait pu (d\u00fb ?) perdre, avant de conclure en beaut\u00e9. <strong>2-0<\/strong>, l&rsquo;affaire est faite, l&rsquo;\u00e9quipe de France a rempli son contrat, et m\u00eame si son parcours se termine en quarts, on pourra qualifier ces Mondiaux de r\u00e9ussis pour les Bleues.<\/p>\n<h2 style=\"text-align: justify;\">Les r\u00e9sultats<\/h2>\n<h4 style=\"text-align: justify;\">Femmes<\/h4>\n<p style=\"text-align: justify;\">France <b>2-0\u00a0<\/b>Canada<\/p>\n<p style=\"text-align: justify;\">M\u00e9lissa Alves 11-8, 11-5, 11-8 Hollie Naughton<\/p>\n<p style=\"text-align: justify;\">Lauren Baltayan 11-8, 14-12, 11-3 Nikki Todd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 &#8211; Sans trembler, les Bleues ont accompli leur mission contre le Canada pour s&rsquo;offrir un quart de finale de prestige.<\/p>\n","protected":false},"author":59,"featured_media":538974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9608],"tags":[16878,28405,24081],"class_list":["post-538961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-squash","tag-breve","tag-championnats-du-monde-par-equipes-de-squash","tag-squash-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s&#039;offrir un quart de finale de prestige.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s&#039;offrir un quart de finale de prestige.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T10:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts\",\"datePublished\":\"2024-12-11T10:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png\",\"keywords\":[\"br\u00e8ve\",\"Championnats du monde par \u00e9quipes de squash\",\"Squash fran\u00e7ais\"],\"articleSection\":[\"Squash\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\",\"name\":\"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png\",\"datePublished\":\"2024-12-11T10:50:32+00:00\",\"description\":\"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s'offrir un quart de finale de prestige.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png\",\"width\":1200,\"height\":674,\"caption\":\"Mondiaux par \u00e9quipes squash 2024 Les Bleues passent elles aussi en quarts\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts","description":"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s'offrir un quart de finale de prestige.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/","og_locale":"fr_FR","og_type":"article","og_title":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts","og_description":"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s'offrir un quart de finale de prestige.","og_url":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2024-12-11T10:50:32+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts","datePublished":"2024-12-11T10:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/"},"wordCount":330,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png","keywords":["br\u00e8ve","Championnats du monde par \u00e9quipes de squash","Squash fran\u00e7ais"],"articleSection":["Squash"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/","url":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/","name":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png","datePublished":"2024-12-11T10:50:32+00:00","description":"CHAMPIONNATS DU MONDE PAR \u00c9QUIPES DE SQUASH 2024 - les Bleues ont accompli leur mission contre le Canada pour s'offrir un quart de finale de prestige.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-par-equipes-squash-2024-Les-Bleues-passent-elles-aussi-en-quarts.png","width":1200,"height":674,"caption":"Mondiaux par \u00e9quipes squash 2024 Les Bleues passent elles aussi en quarts"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-par-equipes-squash-2024-les-bleues-passent-elles-aussi-en-quarts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mondiaux par \u00e9quipes squash 2024 : Les Bleues passent elles aussi en quarts"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/538961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=538961"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/538961\/revisions"}],"predecessor-version":[{"id":538977,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/538961\/revisions\/538977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/538974"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=538961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=538961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=538961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}