{"id":543258,"date":"2025-01-01T16:54:11","date_gmt":"2025-01-01T15:54:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=543258&#038;preview=true&#038;preview_id=543258"},"modified":"2025-01-01T20:15:57","modified_gmt":"2025-01-01T19:15:57","slug":"transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/","title":{"rendered":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TRANSFERTS RUGBY &#8211; Selon <a href=\"https:\/\/www.letelegramme.fr\/sports\/rugby\/rc-vannes\/un-deuxieme-ligne-neo-zelandais-en-renfort-au-rc-vannes-6733587.php?utm_content=link&amp;utm_term=TelegrammeSport&amp;utm_campaign=twitter&amp;utm_source=nonli&amp;utm_medium=Social\" target=\"_blank\" rel=\"noopener\">Le T\u00e9l\u00e9gramme<\/a>, le N\u00e9o-Z\u00e9landais Jesse Parete (31 ans) va s&rsquo;engager avec le RC Vannes dans les jours \u00e0 venir.<br \/>\n<\/em><\/h4>\n<p style=\"text-align: justify;\">Apr\u00e8s l&rsquo;engouement li\u00e9 \u00e0 la premi\u00e8re mont\u00e9e en <strong>Top<\/strong> <strong>14<\/strong> de l&rsquo;histoire du club, le <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-2025-arrivees-departs-et-prolongations\/\"><strong>RC<\/strong> <strong>Vannes<\/strong><\/a> fait face \u00e0 la dure r\u00e9alit\u00e9 de cette comp\u00e9tition. Les <strong>Bretons<\/strong> comptent seulement 15 points \u00e0 la mi-championnat, et pointent au dernier rang au classement de Top 14. Ils ont m\u00eame un retard important sur <strong>Lyon<\/strong>, treizi\u00e8me, avec d\u00e9j\u00e0 sept points de d\u00e9bours.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-stade-toulousain-annonce-10-prolongations\/\" target=\"_blank\" rel=\"noopener\">Transferts : Le Stade Toulousain annonce 10 prolongations<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Jesse Parete au RC Vannes<\/h2>\n<p style=\"text-align: justify;\">Conscients de l&rsquo;urgence dans laquelle se trouve le club, les dirigeants bretons vont renforcer l&rsquo;effectif dans les jours \u00e0 venir. <strong>Jesse Parete<\/strong>, deuxi\u00e8me ligne de 31 ans, va s&rsquo;engager jusqu&rsquo;\u00e0 la fin de la saison. Ces derniers temps, il a altern\u00e9 entre le championnat NPC avec les <strong>Taranaki<\/strong> <strong>Bulls<\/strong> et la <strong>Major<\/strong> <strong>Rugby<\/strong> <strong>League<\/strong> avec <strong>New<\/strong> <strong>England<\/strong>.<\/p>\n<p style=\"text-align: justify;\">S&rsquo;il a d\u00e9j\u00e0 \u00e9volu\u00e9 en Super Rugby avec les <strong>Highlanders<\/strong>, notamment lors de la saison 2019\/2020, <strong>Jesse<\/strong> <strong>Parete<\/strong> n&rsquo;y a pas rejou\u00e9 depuis. Deuxi\u00e8me ligne de formation, il peut aussi d\u00e9panner au poste de troisi\u00e8me ligne. R\u00e9put\u00e9 pour sa puissance, il va apporter de la densit\u00e9 \u00e0 l&rsquo;effectif du <strong>RC<\/strong> <strong>Vannes<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 ce sujet<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-pio-muarua-devrait-signer-en-top-14\/\" class=\"vlp-link\" title=\"Transferts : Pio Muarua (Grenoble) devrait signer en Top 14\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Pio-Muarua-devrait-signer-en-Top-14.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Pio-Muarua-devrait-signer-en-Top-14.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Pio-Muarua-devrait-signer-en-Top-14-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Pio-Muarua-devrait-signer-en-Top-14-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Pio-Muarua-devrait-signer-en-Top-14-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts : Pio Muarua (Grenoble) devrait signer en Top 14<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS RUGBY - Selon le Midi Olympique, Pio Muarua serait sur le point de s'engager avec l'ASM cLermont pour la saison prochaine.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s&rsquo;engager avec le RC Vannes dans les jours \u00e0 venir.<\/p>\n","protected":false},"author":1,"featured_media":543259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,10224,29105],"class_list":["post-543258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-rc-vannes","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s&#039;engager avec le RC Vannes dans les jours \u00e0 venir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s&#039;engager avec le RC Vannes dans les jours \u00e0 venir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-01T15:54:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-01T19:15:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14\",\"datePublished\":\"2025-01-01T15:54:11+00:00\",\"dateModified\":\"2025-01-01T19:15:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"RC Vannes\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\",\"name\":\"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png\",\"datePublished\":\"2025-01-01T15:54:11+00:00\",\"dateModified\":\"2025-01-01T19:15:57+00:00\",\"description\":\"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s'engager avec le RC Vannes dans les jours \u00e0 venir.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14","description":"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s'engager avec le RC Vannes dans les jours \u00e0 venir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14","og_description":"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s'engager avec le RC Vannes dans les jours \u00e0 venir.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-01-01T15:54:11+00:00","article_modified_time":"2025-01-01T19:15:57+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14","datePublished":"2025-01-01T15:54:11+00:00","dateModified":"2025-01-01T19:15:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png","keywords":["actu","br\u00e8ve","RC Vannes","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/","name":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png","datePublished":"2025-01-01T15:54:11+00:00","dateModified":"2025-01-01T19:15:57+00:00","description":"TRANSFERTS RUGBY - Selon Le T\u00e9l\u00e9gramme, le N\u00e9o-Z\u00e9landais Jesse Parete va s'engager avec le RC Vannes dans les jours \u00e0 venir.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Le-Neo-Zelandais-Jesse-Parete-va-signer-en-Top-14.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jesse-parete-va-signer-en-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Le N\u00e9o-Z\u00e9landais Jesse Parete va signer en Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/543258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=543258"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/543258\/revisions"}],"predecessor-version":[{"id":543271,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/543258\/revisions\/543271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/543259"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=543258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=543258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=543258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}