{"id":544556,"date":"2025-01-08T13:03:05","date_gmt":"2025-01-08T12:03:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=544556&#038;preview=true&#038;preview_id=544556"},"modified":"2025-01-08T13:37:41","modified_gmt":"2025-01-08T12:37:41","slug":"dakar-2025-classement-4eme-etape-categorie-motos","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/","title":{"rendered":"Dakar 2025 &#8211; Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><i>DAKAR 2025 &#8211; D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s&rsquo;est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.<\/i><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/parcours-dakar-2025-le-programme-des-etapes\/\">Parcours Dakar 2025 : Le programme des \u00e9tapes<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2025-motos-classement-general\/\">Dakar 2025 Motos &#8211; Classement g\u00e9n\u00e9ral<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Au lendemain d&rsquo;une <a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2025-motos-classement-3eme-etape\/\">3\u00e8me \u00e9tape<\/a> anim\u00e9e, les motos du <strong>Dakar 2025<\/strong> rallient <strong>Al Henakiyah<\/strong> \u00e0 <strong>AlUla<\/strong> ce mercredi 8 janvier, pour le compte de la 4\u00e8me \u00e9tape. 415 km de sp\u00e9ciale sont au programme. <strong>Ricky Brabec<\/strong> et <strong>Ross Branch<\/strong> sont les favoris du jour.<\/p>\n<h2 style=\"text-align: justify;\">Classement de la 4\u00e8me \u00e9tape motos &#8211; Dakar 2025<\/h2>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f3c6.svg\" alt=\"\" \/><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>PILOTES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa Daniel SANDERS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL KTM FACTORY TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">5h10m33s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 Tosha SCHAREINA<br \/>\n<\/strong><span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 15s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddf1 Jose Ignacio CORNEJO FLORIMO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">HERO MOTOSPORTS TEAM RALLY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 7m49s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 Adrien VAN BEVEREN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 8m08s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf5\ud83c\uddf9 Rui GON\u00c7ALVES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SHERCO RALLY FACTORY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 8m55s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 TOBIAS EBSTER<\/strong><br \/>\n<span style=\"font-size: 11.52px\">BAS WORLD KTM RACING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 10m14s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddff\ud83c\udde6 BRADLEY COX<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BAS WORLD KTM RACING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 10m55s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 Lorenzo SANTOLINO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SHERCO RALLY FACTORY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 12m27s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddf1 Pablo QUINTANILLA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 12m38s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf8\ud83c\uddf0 Stefan SVITKO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SLOVNAFT RALLY TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 15m42s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2>\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.dakar.live.worldrallyraidchampionship.com\/fr\/moto\/4\/classements\"><strong>Dakar 2025 &#8211; Motos : le classement complet de la 4\u00e8me \u00e9tape<\/strong><\/a><strong><br \/>\n<\/strong><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2025-nasser-al-attiyah-sebastien-loeb-ricky-brabec-les-favoris-de-cette-edition\/\" class=\"vlp-link\" title=\"Dakar 2025 : Nasser Al-Attiyah, S\u00e9bastien Loeb, Ricky Brabec, les favoris de cette \u00e9dition\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Nasser-Al-Attiyah-Sebastien-Loeb-Ricky-Brabec-les-favoris-de-cette-edition.png\" class=\"attachment-800x445 size-800x445\" alt=\"Dakar 2025 Nasser Al-Attiyah, S\u00e9bastien Loeb, Ricky Brabec, les favoris de cette \u00e9dition\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Nasser-Al-Attiyah-Sebastien-Loeb-Ricky-Brabec-les-favoris-de-cette-edition.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Nasser-Al-Attiyah-Sebastien-Loeb-Ricky-Brabec-les-favoris-de-cette-edition-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Nasser-Al-Attiyah-Sebastien-Loeb-Ricky-Brabec-les-favoris-de-cette-edition-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Nasser-Al-Attiyah-Sebastien-Loeb-Ricky-Brabec-les-favoris-de-cette-edition-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Dakar 2025 : Nasser Al-Attiyah, S\u00e9bastien Loeb, Ricky Brabec, les favoris de cette \u00e9dition<\/div><div class=\"vlp-block-1 vlp-link-summary\">RALLYE DAKAR 2025 \u2013 La 47\u00e8me \u00e9dition du Dakar s\u2019\u00e9lancera demain avec le prologue. L\u2019occasion d\u2019\u00e9voquer les favoris au titre. Qui succ\u00e9dera \u00e0 Carlos Sainz en cat\u00e9gorie auto et \u00e0 Ricky Brabec en cat\u00e9gorie moto ?<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DAKAR 2025 &#8211; D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s&rsquo;est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.<\/p>\n","protected":false},"author":4,"featured_media":544559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9493],"tags":[16878,2736],"class_list":["post-544556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dakar","tag-breve","tag-dakar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos<\/title>\n<meta name=\"description\" content=\"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s&#039;est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos\" \/>\n<meta property=\"og:description\" content=\"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s&#039;est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-08T12:03:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T12:37:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Dakar 2025 &#8211; Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos\",\"datePublished\":\"2025-01-08T12:03:05+00:00\",\"dateModified\":\"2025-01-08T12:37:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\"},\"wordCount\":296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png\",\"keywords\":[\"br\u00e8ve\",\"dakar\"],\"articleSection\":[\"Dakar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\",\"name\":\"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png\",\"datePublished\":\"2025-01-08T12:03:05+00:00\",\"dateModified\":\"2025-01-08T12:37:41+00:00\",\"description\":\"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png\",\"width\":1200,\"height\":674,\"caption\":\"Dakar 2025 - Classement 10\u00e8me \u00e9tape cat\u00e9gorie motos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2025 &#8211; Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos","description":"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/","og_locale":"fr_FR","og_type":"article","og_title":"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos","og_description":"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-01-08T12:03:05+00:00","article_modified_time":"2025-01-08T12:37:41+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Dakar 2025 &#8211; Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos","datePublished":"2025-01-08T12:03:05+00:00","dateModified":"2025-01-08T12:37:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/"},"wordCount":296,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png","keywords":["br\u00e8ve","dakar"],"articleSection":["Dakar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/","url":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/","name":"Dakar 2025 - Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png","datePublished":"2025-01-08T12:03:05+00:00","dateModified":"2025-01-08T12:37:41+00:00","description":"DAKAR 2025 - D\u00e9couvrez le classement de la 4\u00e8me \u00e9tape du Dakar 2025 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9e ce mercredi 8 janvier 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Dakar-2025-Classement-4eme-etape-categorie-motos.png","width":1200,"height":674,"caption":"Dakar 2025 - Classement 10\u00e8me \u00e9tape cat\u00e9gorie motos"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2025-classement-4eme-etape-categorie-motos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2025 &#8211; Classement 4\u00e8me \u00e9tape cat\u00e9gorie motos"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=544556"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544556\/revisions"}],"predecessor-version":[{"id":544628,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544556\/revisions\/544628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/544559"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=544556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=544556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=544556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}