{"id":544692,"date":"2025-01-08T20:22:38","date_gmt":"2025-01-08T19:22:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=544692&#038;preview=true&#038;preview_id=544692"},"modified":"2025-01-08T22:21:11","modified_gmt":"2025-01-08T21:21:11","slug":"volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/","title":{"rendered":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 &#8211; Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d&rsquo;\u00e9limination.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Pour <strong>Levallois Paris Saint-Cloud<\/strong> et <strong>Nantes<\/strong>, cette avant-derni\u00e8re journ\u00e9e de la phase de poule de la Ligue des Champions avait une importance capitale. Les deux \u00e9quipes occupaient la derni\u00e8re place de leur poule, et pour poursuivre leur saison europ\u00e9enne, il fallait gagner ce soir contre l&rsquo;\u00e9quipe qui occupait la troisi\u00e8me position, respectivement <strong>Palmberg Schwerin<\/strong> et <strong>Vasas<\/strong>. En effet, sachant qu&rsquo;en cas d&rsquo;\u00e9galit\u00e9, les \u00e9quipes se d\u00e9partagent au nombre de victoires, une d\u00e9faite ici \u00e9tait \u00e9liminatoire.<\/p>\n<h2 style=\"text-align: justify;\">Les regrets de Levallois Paris Saint-Cloud<\/h2>\n<p style=\"text-align: justify;\"><strong>Levallois Paris Saint-Cloud<\/strong> avait disput\u00e9 le premier match de son histoire en Ligue des Champions lors de l&rsquo;aller, mais avait subi l&rsquo;\u00e9v\u00e8nement et encaiss\u00e9 une lourde d\u00e9faite. Les Mariannes voulaient leur vengeance, et l&rsquo;ont d\u00e9montr\u00e9 en remportant de haute lutte le premier set, toujours port\u00e9es par un duo <strong>Natalia Murek &#8211; Bianca Cugno<\/strong> redoutable en attaque. Mais le prix pay\u00e9 \u00e9tait un deuxi\u00e8me set outrageusement domin\u00e9 par les locales.<\/p>\n<p style=\"text-align: justify;\">Et comme on pouvait le craindre, la dynamique du match s&rsquo;est alors invers\u00e9e. Les Allemandes dominaient les d\u00e9bats, prenaient la troisi\u00e8me manche, mais c&rsquo;\u00e9tait sans compter sur la vaillance des Mariannes, qui allaient chercher un set d\u00e9cisif \u00e0 la force du poignet. Men\u00e9es ensuite de quatre points, elles semblaient promises \u00e0 la d\u00e9faite mais renversaient la situation gr\u00e2ce \u00e0 une fantastique s\u00e9rie au service de <strong>Jazmine White<\/strong>&#8230; avant de craquer et de s&rsquo;incliner <strong>23-25, 25-12, 25-21, 21-25, 15-12<\/strong>. Un bon r\u00e9sum\u00e9 de leur campagne : de belles choses, mais la victoire n&rsquo;est pas au bout. Et la saison europ\u00e9enne est d&rsquo;ores et d\u00e9j\u00e0 termin\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\">Nantes trop juste<\/h2>\n<p style=\"text-align: justify;\"><strong>Nantes<\/strong> avait \u00e9galement d\u00e9but\u00e9 par une d\u00e9faite \u00e0 domicile contre <strong>Vasas,<\/strong> mais au tie-break. Une des deux d\u00e9faites conc\u00e9d\u00e9es au set d\u00e9cisif par les Neptunes dans cette campagne, ce qui leur permettaient d&rsquo;\u00eatre \u00e0 \u00e9galit\u00e9 avec les Hongroises avant ce match. Mais cette d\u00e9faite de l&rsquo;aller n&rsquo;\u00e9tait finalement pas un accident de parcours : elle traduisait bien les difficult\u00e9s nantaises dans cette comp\u00e9tition.<\/p>\n<p style=\"text-align: justify;\">Et ce fut encore le cas ce soir. Comme souvent en Ligue des Champions, les Neptunes ont \u00e9t\u00e9 accrocheuses, volontaires. Une belle activit\u00e9 en attaque, une excellente <strong>Jessica Robinson<\/strong>, une combativit\u00e9 devenue marque de fabrique, mais ce n&rsquo;est pas encore assez pour ce niveau de comp\u00e9tition. Trois sets serr\u00e9s, mais une d\u00e9faite au final s\u00e8che, <strong>25-21, 25-22, 25-20<\/strong>. Jamais Nantes n&rsquo;aura r\u00e9ussi \u00e0 stopper la star <strong>Taylor Bannister<\/strong> (15 points), et l&rsquo;\u00e9limination est d\u00e9sormais certaine, la possibilit\u00e9 de reversement en CEV Cup \u00e9tant officiellement \u00e9vanouie. Dommage, mais sans doute capital pour la saison de cette \u00e9quipe, qui reste parmi les favorites au titre national.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 &#8211; Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d&rsquo;\u00e9limination.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":544725,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[32415,16878,38959,28388,29824],"class_list":["post-544692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-actu","tag-breve","tag-levallois-paris-saint-cloud-volley","tag-ligue-des-champions-feminine-de-volleyball","tag-neptunes-de-nantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d&#039;\u00e9limination.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d&#039;\u00e9limination.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-08T19:22:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T21:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\",\"datePublished\":\"2025-01-08T19:22:38+00:00\",\"dateModified\":\"2025-01-08T21:21:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Levallois Paris Saint-Cloud Volley\",\"Ligue des Champions f\u00e9minine de volleyball\",\"Neptunes de Nantes\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/\",\"name\":\"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png\",\"datePublished\":\"2025-01-08T19:22:38+00:00\",\"dateModified\":\"2025-01-08T21:21:11+00:00\",\"description\":\"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\\\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d'\u00e9limination.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png\",\"width\":1200,\"height\":674,\"caption\":\"Volley Ligue des Champions (F) D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et NantesVolley Ligue des Champions (F) D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes","description":"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d'\u00e9limination.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/","og_locale":"fr_FR","og_type":"article","og_title":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes","og_description":"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d'\u00e9limination.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-01-08T19:22:38+00:00","article_modified_time":"2025-01-08T21:21:11+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes","datePublished":"2025-01-08T19:22:38+00:00","dateModified":"2025-01-08T21:21:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png","keywords":["actu","br\u00e8ve","Levallois Paris Saint-Cloud Volley","Ligue des Champions f\u00e9minine de volleyball","Neptunes de Nantes"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/","url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/","name":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png","datePublished":"2025-01-08T19:22:38+00:00","dateModified":"2025-01-08T21:21:11+00:00","description":"LIGUE DES CHAMPIONS FEMMES DE VOLLEYBALL 2024\/2025 - Encore une d\u00e9faite pour Levallois Paris Saint-Cloud et Nantes, mais cette fois synonyme d'\u00e9limination.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Volley-Ligue-des-Champions-F-Defaite-et-elimination-pour-Levallois-Paris-Saint-Cloud-et-Nantes.png","width":1200,"height":674,"caption":"Volley Ligue des Champions (F) D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et NantesVolley Ligue des Champions (F) D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-f-defaite-et-elimination-pour-levallois-paris-saint-cloud-et-nantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volley Ligue des Champions (F) : D\u00e9faite et \u00e9limination pour Levallois Paris Saint-Cloud et Nantes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=544692"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544692\/revisions"}],"predecessor-version":[{"id":544752,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/544692\/revisions\/544752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/544725"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=544692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=544692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=544692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}