{"id":545610,"date":"2025-01-11T20:24:22","date_gmt":"2025-01-11T19:24:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=545610&#038;preview=true&#038;preview_id=545610"},"modified":"2025-01-11T21:00:21","modified_gmt":"2025-01-11T20:00:21","slug":"champions-cup-j3-le-stade-francais-renverse-northampton","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/","title":{"rendered":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>CHAMPIONS CUP 2024-2025 &#8211; Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s&rsquo;imposer 45-35 avec le bonus offensif. Une victoire importante pour les Soldats Roses apr\u00e8s deux d\u00e9faites cons\u00e9cutives en Top 14.<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-resultats-et-classement-rugby-champions-cup-2024-2025\/\">Calendrier, r\u00e9sultats et classement Rugby Champions Cup 2024-2025<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le match d\u00e9bute calmement avec des erreurs et des fautes des deux c\u00f4t\u00e9s. <strong>Northampton<\/strong> va commencer \u00e0 prendre le contr\u00f4le du ballon et cela va s\u2019av\u00e9rer dangereux pour les Stadistes. En six minutes, les Anglais vont inscrire trois essais. Le premier \u00e0 la 12<sup>\u00e8me<\/sup> minute, sur une touche parisienne contr\u00e9e. Le jeu va vite vers l\u2019ext\u00e9rieur et apr\u00e8s plusieurs phases <strong>Lockett<\/strong> termine sous les poteaux. Quatre minutes apr\u00e8s, les <strong>Saints<\/strong> continuent leur jeu rapide dans les espaces. <strong>Henry<\/strong> <strong>Pollock<\/strong> termine une longue action en bout de ligne. Le jeune anglais va s\u2019offrir un doubl\u00e9 deux minutes apr\u00e8s. D\u00e8s l\u2019engagement, <strong>Northampton<\/strong> retourne dans le camp adverse au pied. Suite \u00e0 la r\u00e9ception, <strong>Pollock<\/strong> arrache le ballon et va aplatir le ballon sous les poteaux. <strong>21-0<\/strong> pour les <em>Jimmies<\/em> apr\u00e8s 20 minutes de jeu.<\/p>\n<p style=\"text-align: justify;\">Le <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-francais-2025-arrivees-departs-et-prolongations\/\"><strong>Stade Fran\u00e7ais<\/strong><\/a> r\u00e9agit quelques minutes apr\u00e8s. Pour leur premi\u00e8re possession dans les 22 m\u00e8tres, le jeu est amen\u00e9 sur <strong>Ezeala<\/strong> \u00e0 gauche qui va gagner des m\u00e8tres. Apr\u00e8s plusieurs phases de jeu, <strong>Dakuwaqa<\/strong> est trouv\u00e9 de l\u2019autre c\u00f4t\u00e9 et fait parler sa vitesse pour aplatir en bout de ligne (<strong>5-21, 24\u2019<\/strong>). Dans ses 15 derni\u00e8res minutes de cette premi\u00e8re p\u00e9riode, le Stade Fran\u00e7ais montre un bien meilleur visage. Sur une possession de <strong>Northampton<\/strong>, <strong>Van Der Mescht<\/strong> contre le coup de pied de <strong>Hutchinson <\/strong>et n&rsquo;a plus\u00a0qu\u2019\u00e0 aplatir sous les poteaux (<strong>12-21, 30\u2019<\/strong>). Les <em>Soldats Roses<\/em> jouent et mettent la pression sur la d\u00e9fense anglaise qui va finir par craquer trois minutes apr\u00e8s la sir\u00e8ne. En encha\u00eenant les temps de jeu, les <strong>Anglais<\/strong> conc\u00e8dent \u00e9norm\u00e9ment de fautes et vont permettre aux Parisiens d\u2019avancer sur penaltouche. Apr\u00e8s une touche aux 5 m\u00e8tres, <strong>Tanga<\/strong> conclut un ballon port\u00e9 (<strong>19-21, 43\u2019<\/strong>).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le contre et la course de Juan ven der Mescht! <a href=\"https:\/\/t.co\/z1DRf766Ma\">pic.twitter.com\/z1DRf766Ma<\/a><\/p>\n<p>\u2014 Investec Champions Cup France (@ChampionsCup_FR) <a href=\"https:\/\/twitter.com\/ChampionsCup_FR\/status\/1878141843520569627?ref_src=twsrc%5Etfw\">January 11, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>Une seconde mi-temps parfaite, Macalou important<\/strong><\/h2>\n<p style=\"text-align: justify;\">En d\u00e9but de seconde p\u00e9riode, <strong>Northampton<\/strong> se remet \u00e0 jouer et ils vont concr\u00e9tiser ce temps fort. Apr\u00e8s plusieurs phases de jeu, <strong>Pollock<\/strong> sert <strong>Henry Walker<\/strong> qui passe sous les d\u00e9fenseurs parisiens pour aplatir (<strong>19-28, 45\u2019<\/strong>). Le <strong>Stade Fran\u00e7ais<\/strong> r\u00e9agit de nouveau et retrouve son niveau de fin de premi\u00e8re p\u00e9riode. Cela va commencer avec un <strong>essai de p\u00e9nalit\u00e9<\/strong> accord\u00e9 aux Stadistes. Sur un ballon port\u00e9 aux 5 m\u00e8tres, <strong>Mitchell<\/strong> vient sur le c\u00f4t\u00e9 et \u00e9croule le maul. De plus, le demi de m\u00eal\u00e9e \u00e9cope d\u2019un <strong>carton jaune<\/strong> (<strong>26-28, 47\u2019<\/strong>). Cet essai parisien permet \u00e9galement d\u2019acqu\u00e9rir le point de bonus offensif.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le Stade Fran\u00e7ais Paris recolle au score! <a href=\"https:\/\/t.co\/RcezBtw8Az\">pic.twitter.com\/RcezBtw8Az<\/a><\/p>\n<p>\u2014 Investec Champions Cup France (@ChampionsCup_FR) <a href=\"https:\/\/twitter.com\/ChampionsCup_FR\/status\/1878150434583371829?ref_src=twsrc%5Etfw\">January 11, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Le <strong>Stade Fran\u00e7ais<\/strong> continue \u00e0 poss\u00e9der le ballon et va bien l\u2019utiliser. Sur un ballon port\u00e9 dynamique, <strong>Weber<\/strong> attaque le c\u00f4t\u00e9 ferm\u00e9. Le jeu est \u00e9cart\u00e9 jusqu\u2019\u00e0 <strong>Delbouis<\/strong> qui joue le deux contre un avec <strong>Ezeala<\/strong>. Les Parisiens prennent l\u2019avantage pour la premi\u00e8re fois du match (<strong>31-28, 52\u2019<\/strong>). Et le 6<sup>\u00e8me<\/sup> essai parisien ne va pas tarder, apr\u00e8s un tr\u00e8s gros travail de <strong>Macalou<\/strong>, <strong>Tanga<\/strong> s\u2019offre un doubl\u00e9 et r\u00e9pond \u00e0 <strong>Pollock<\/strong> (<strong>38-28, 58\u2019<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Les Parisiens vont continuer \u00e0 poss\u00e9der le ballon et vont g\u00e9rer cette fin de match. \u00c0 la 69<sup>\u00e8me<\/sup> minute, <strong>Northampton<\/strong> est sanctionn\u00e9 d\u2019un carton jaune pour un plaquage dangereux. Sur la touche qui suit, <strong>Paul Gabrillagues<\/strong> va inscrire un <strong>7<sup>\u00e8me<\/sup> essai<\/strong>. Deux minutes avant la fin, <strong>Langdon<\/strong> inscrit un dernier essai pour <strong>Northampton<\/strong>, insuffisant. Le <strong>Stade Fran\u00e7ais<\/strong> remporte son premier match en Champions Cup et remonte \u00e0 la 4<sup>\u00e8me<\/sup> place de son groupe en attendant le match de <strong>Castres<\/strong> ce soir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Stade Fran\u00e7ais renverse Northampton<\/p>\n","protected":false},"author":110,"featured_media":545657,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47051,9129],"tags":[32415,16878,12939,3076],"class_list":["post-545610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champions-cup","category-rugby-a-xv","tag-actu","tag-breve","tag-northampton","tag-stade-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton<\/title>\n<meta name=\"description\" content=\"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s&#039;imposer 45-35.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s&#039;imposer 45-35.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-11T19:24:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-11T20:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Malo Clement\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\"},\"author\":{\"name\":\"Malo Clement\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\"},\"headline\":\"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton\",\"datePublished\":\"2025-01-11T19:24:22+00:00\",\"dateModified\":\"2025-01-11T20:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\"},\"wordCount\":697,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Northampton\",\"Stade Fran\u00e7ais\"],\"articleSection\":[\"Champions Cup\",\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\",\"name\":\"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png\",\"datePublished\":\"2025-01-11T19:24:22+00:00\",\"dateModified\":\"2025-01-11T20:00:21+00:00\",\"description\":\"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s'imposer 45-35.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png\",\"width\":1200,\"height\":674,\"caption\":\"Champions Cup (J3) Le Stade Fran\u00e7ais renverse Northampton\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\",\"name\":\"Malo Clement\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"caption\":\"Malo Clement\"},\"description\":\"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton","description":"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s'imposer 45-35.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/","og_locale":"fr_FR","og_type":"article","og_title":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton","og_description":"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s'imposer 45-35.","og_url":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-01-11T19:24:22+00:00","article_modified_time":"2025-01-11T20:00:21+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png","type":"image\/png"}],"author":"Malo Clement","twitter_card":"summary_large_image","twitter_title":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/"},"author":{"name":"Malo Clement","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce"},"headline":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton","datePublished":"2025-01-11T19:24:22+00:00","dateModified":"2025-01-11T20:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/"},"wordCount":697,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png","keywords":["actu","br\u00e8ve","Northampton","Stade Fran\u00e7ais"],"articleSection":["Champions Cup","Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/","url":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/","name":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png","datePublished":"2025-01-11T19:24:22+00:00","dateModified":"2025-01-11T20:00:21+00:00","description":"CHAMPIONS CUP 2024-2025 - Apr\u00e8s 20 premi\u00e8res minutes catastrophiques (0-21), le Stade Fran\u00e7ais a renvers\u00e9 Northampton pour s'imposer 45-35.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Champions-Cup-J3-Le-Stade-Francais-renverse-Northampton.png","width":1200,"height":674,"caption":"Champions Cup (J3) Le Stade Fran\u00e7ais renverse Northampton"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-j3-le-stade-francais-renverse-northampton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Champions Cup (J3) : Le Stade Fran\u00e7ais renverse Northampton"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce","name":"Malo Clement","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","caption":"Malo Clement"},"description":"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.","url":"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/545610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=545610"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/545610\/revisions"}],"predecessor-version":[{"id":545669,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/545610\/revisions\/545669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/545657"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=545610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=545610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=545610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}