{"id":547813,"date":"2025-01-18T22:18:43","date_gmt":"2025-01-18T21:18:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=547813&#038;preview=true&#038;preview_id=547813"},"modified":"2025-01-18T22:32:28","modified_gmt":"2025-01-18T21:32:28","slug":"basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/","title":{"rendered":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>BASKET COUPE DE FRANCE F\u00c9MININE &#8211; Les quarts de finale ont d\u00e9livr\u00e9 leur verdict ce samedi soir. Finalistes sortants, Bourges et Basket Landes restent dans la course suite \u00e0 leurs succ\u00e8s \u00e9triqu\u00e9s face \u00e0 Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL. Tarbes et les Flammes Carolo compl\u00e8tent le dernier carr\u00e9 de la comp\u00e9tition.<\/em><\/h4>\n<p style=\"text-align: justify;\">Parmi les quatre rencontres au programme des quarts de finale de la <strong>Coupe de France<\/strong>, deux matchs attiraient particuli\u00e8rement l&rsquo;attention : Bourges &#8211; Villeneuve d&rsquo;Ascq et ASVEL &#8211; Basket Landes. Deux v\u00e9ritables finales avant l&rsquo;heure entre les quatre cadors nationaux. Ces chocs au sommet ont d&rsquo;ailleurs tenu toutes leurs promesses en offrant des parties ind\u00e9cises.<\/p>\n<h2 style=\"text-align: justify;\">Les finalistes sortants Bourges et Basket Landes frappent fort<\/h2>\n<p style=\"text-align: justify;\">\u00c0 <strong>Bourges<\/strong>, les locales sont parvenues \u00e0 s&rsquo;imposer dans une ambiance de folie face aux championnes de France en titre. Dans une partie o\u00f9 l&rsquo;adresse ext\u00e9rieure a \u00e9t\u00e9 inexistante (5\/40 en cumul\u00e9), <strong>Kariata Diaby<\/strong> a fait souffrir les Tango sous le cercle (17 points, 9 rebonds), mais elle sera la seule \u00e0 v\u00e9ritablement r\u00e9gler la mire. Sans briller offensivement, Bourges est parvenu \u00e0 tenir le choc, et \u00e0 frapper le dernier pour d\u00e9crocher un succ\u00e8s sur un score \u00e9triqu\u00e9 58-56. <strong>Villeneuve d&rsquo;Ascq<\/strong> va donc devoir se concentrer uniquement sur le championnat en cette fin de saison, tandis que les Berruy\u00e8res sont toujours en lice pour faire la passe de deux.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 de <strong>Lyon-Villeurbanne<\/strong>, l&rsquo;issue s&rsquo;est \u00e9galement d\u00e9cid\u00e9e dans les derni\u00e8res secondes. Lyonnaises et Landaises ne se sont pas l\u00e2ch\u00e9es d&rsquo;un pouce, offrant un combat au sommet, dans lequel <strong>Juste Jocyte<\/strong> (22 points, 5 rebonds) et <strong>Luisa Geisesolder<\/strong> (20 points, 9 rebonds) ont excell\u00e9. \u00c0 l&rsquo;issue d&rsquo;un final haletant, les Lyonnaises vont avoir une quantit\u00e9 astronomique de cartouches afin de renverser la vapeur. Mais avec seulement deux lancers de <strong>Dominique Malonga<\/strong> dans les deux derni\u00e8res minutes, elles vont finir par buter sur des Landaises courageuses en d\u00e9fense (74-72). Finaliste l&rsquo;an dernier, <strong>Basket Landes<\/strong> reste dans la course.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83e\udd75 Le Prado a vibr\u00e9 ce soir, mais c&rsquo;est fait, on est en demi-finale !<\/p>\n<p>L&rsquo;aventure en Coupe de France continue ! \ud83d\ude0e<a href=\"https:\/\/twitter.com\/hashtag\/Fiert%C3%A9Tango?src=hash&amp;ref_src=twsrc%5Etfw\">#Fiert\u00e9Tango<\/a> <a href=\"https:\/\/t.co\/Z84rTuPdin\">pic.twitter.com\/Z84rTuPdin<\/a><\/p>\n<p>\u2014 Tango Bourges Basket (@BourgesBasket) <a href=\"https:\/\/twitter.com\/BourgesBasket\/status\/1880723620747768073?ref_src=twsrc%5Etfw\">January 18, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Tarbes et les Flammes Carolo dans le dernier carr\u00e9<\/h2>\n<p style=\"text-align: justify;\">Dans les deux autres affiches de la soir\u00e9e, les sc\u00e9narios ont aussi \u00e9t\u00e9 diff\u00e9rents. Humili\u00e9 \u00e0 domicile par <strong>Charnay<\/strong> en octobre dernier, <strong>Tarbes<\/strong> avait \u00e0 c\u0153ur de prendre sa revanche face \u00e0 l&rsquo;une des belles surprises de la saison. En mission, les filles de <strong>Fran\u00e7ois Gomez<\/strong> ont fait la course en t\u00eate tout au long du match, et ont fini par asphyxier leurs adversaires dans le troisi\u00e8me quart. Port\u00e9 par la prestation compl\u00e8te de <strong>Nancy Fora<\/strong> (19 points, 8 rebonds, 5 interceptions), le TGB a pris des airs de TGV pour finalement l&#8217;emporter en toute logique, 79-60.<\/p>\n<p style=\"text-align: justify;\">Les <strong>Flammes Carolo<\/strong> semblaient de leur c\u00f4t\u00e9 avoir pris le m\u00eame chemin sur le parquet de <strong>Landerneau<\/strong>. Face aux Bretonnes, le surprenant 2e de Boulang\u00e8re Wonderligue avait pourtant fait le n\u00e9cessaire en imposant sa mainmise sur la partie durant trois quart-temps. Mais la machine s&rsquo;est ensuite enray\u00e9e, offrant aux locales la possibilit\u00e9 de revenir, et de mener dans le money-time. Finalement, un 4-0 bien senti permettra d&rsquo;assurer l&rsquo;essentiel (75-72), avec notamment 23 points pour <strong>Sara Chevaugeon<\/strong>. Les Carolos poursuivent donc leur petit bonhomme de chemin en coupe, dans la continuit\u00e9 de leur excellente tenue en championnat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BASKET COUPE DE FRANCE F\u00c9MININE &#8211; Les quarts de finale ont d\u00e9livr\u00e9 leur verdict ce samedi soir. Finalistes sortants, Bourges et Basket Landes restent dans la course suite \u00e0 leurs succ\u00e8s \u00e9triqu\u00e9s face \u00e0 Villeneuve d&rsquo;Ascq et l&rsquo;ASVEL. Tarbes et les Flammes Carolo compl\u00e8tent le dernier carr\u00e9 de la comp\u00e9tition.<\/p>\n","protected":false},"author":55,"featured_media":547852,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2305],"tags":[7864,13487,16878,28729,27778,3416],"class_list":["post-547813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-asvel","tag-basket-landes","tag-breve","tag-flammes-carolo","tag-tarbes","tag-villeneuve-dascq"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale<\/title>\n<meta name=\"description\" content=\"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\" \/>\n<meta property=\"og:description\" content=\"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-18T21:18:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-18T21:32:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\",\"datePublished\":\"2025-01-18T21:18:43+00:00\",\"dateModified\":\"2025-01-18T21:32:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\"},\"wordCount\":609,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png\",\"keywords\":[\"ASVEL\",\"Basket Landes\",\"br\u00e8ve\",\"Flammes Carolo\",\"Tarbes\",\"Villeneuve d'Ascq\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\",\"name\":\"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png\",\"datePublished\":\"2025-01-18T21:18:43+00:00\",\"dateModified\":\"2025-01-18T21:32:28+00:00\",\"description\":\"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png\",\"width\":1200,\"height\":674,\"caption\":\"Basket Coupe de France f\u00e9minine : Bourge et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale","description":"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale","og_description":"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.","og_url":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-01-18T21:18:43+00:00","article_modified_time":"2025-01-18T21:32:28+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale","datePublished":"2025-01-18T21:18:43+00:00","dateModified":"2025-01-18T21:32:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/"},"wordCount":609,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png","keywords":["ASVEL","Basket Landes","br\u00e8ve","Flammes Carolo","Tarbes","Villeneuve d'Ascq"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/","url":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/","name":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png","datePublished":"2025-01-18T21:18:43+00:00","dateModified":"2025-01-18T21:32:28+00:00","description":"BASKET COUPE DE FRANCE F\u00c9MININE - Finalistes sortants, Bourges et Basket Landes se sont qualifi\u00e9s en demi-finales.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Basket-Coupe-de-France-feminine-Bourges-et-Basket-Landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale.png","width":1200,"height":674,"caption":"Basket Coupe de France f\u00e9minine : Bourge et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-feminine-bourges-et-basket-landes-frappent-un-grand-coup-le-resume-des-quarts-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Basket Coupe de France f\u00e9minine : Bourges et Basket Landes frappent un grand coup, le r\u00e9sum\u00e9 des quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/547813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=547813"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/547813\/revisions"}],"predecessor-version":[{"id":547861,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/547813\/revisions\/547861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/547852"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=547813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=547813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=547813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}