{"id":548421,"date":"2025-01-20T18:43:24","date_gmt":"2025-01-20T17:43:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=548421&#038;preview=true&#038;preview_id=548421"},"modified":"2025-01-20T18:43:24","modified_gmt":"2025-01-20T17:43:24","slug":"transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/","title":{"rendered":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">ASM Clermont : Alexandre Fischer va rempiler<\/h2>\n<p style=\"text-align: justify;\"><strong>Alexandre Fischer<\/strong> sera toujours un joueur de l&rsquo;<strong>ASM Clermont<\/strong> la saison prochaine. Si l&rsquo;on en croit le <em>Midi Olympique<\/em>, le troisi\u00e8me ligne de 27 ans va signer un nouveau bail de deux saisons en Auvergne. En grande forme ces derni\u00e8res semaines, <strong>Fischer<\/strong> a disput\u00e9 quinze rencontres cette saison, dont neuf dans la peau d\u2019un titulaire, \u00e0 chaque fois avec un rendement impressionnant.<\/p>\n<p style=\"text-align: justify;\">Pour rappel, celui qui a \u00e9t\u00e9 form\u00e9, en partie, \u00e0 <strong>Clermont<\/strong>, o\u00f9 il est arriv\u00e9 en 2013, \u00e9tait annonc\u00e9 proche de l&rsquo;<strong>UBB<\/strong>, il y a plusieurs semaines. Mais les dirigeants clermontois ne l&rsquo;entendaient pas de cette oreille, d\u00e9non\u00e7ant l&rsquo;ann\u00e9e en option dans son contrat actuel. Une d\u00e9marche qui a ensuite facilit\u00e9 les n\u00e9gociations en vue d&rsquo;une prolongation de contrat chez les <em>Jaunards.<\/em> Avec r\u00e9ussite, donc.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Clermont aura vraiment tout fait pour conserver Alexandre Fischer et va r\u00e9ussir son coup. Si plusieurs clubs de Top 14 \u00e9taient \u00e0 l&rsquo;aff\u00fbt, ce sont bien les Auvergnats qui ont tir\u00e9 leur \u00e9pingle du jeu, avec un coup de poker parfait, apr\u00e8s avoir d\u00e9nonc\u00e9 l&rsquo;ann\u00e9e en option du pr\u00e9c\u00e9dent contrat. Une prolongation gagnant-gagnant, Fischer \u00e9tant en pleine bourre actuellement.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-clermont-alexandre-fischer-a-tranche-pour-son-avenir\/\">Transferts Clermont : Alexandre Fischer a tranch\u00e9 pour son avenir<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Racing 92 : Wilfried Hulleu (Grenoble) va s&rsquo;engager<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Racing 92<\/strong> pioche en<strong> Pro D2<\/strong>. Toujours selon le <em>Midi Olympique<\/em>, le club altos\u00e9quanais va s&rsquo;attacher les services de <strong>Wilfried Hulleu<\/strong> (22 ans). Celui qui \u00e9volue actuellement \u00e0 Grenoble \u00e9clabousse la Pro D2 de son talent. Auteurs de 11 essais en 18 rencontres la saison pass\u00e9e avec le club is\u00e9rois, l&rsquo;ailier aux 47 matchs professionnels poursuit sur sa lanc\u00e9e au cours de cet exercice 2024-2025, avec d\u00e9j\u00e0 neuf essais en douze apparitions sous le maillot grenoblois.<\/p>\n<p style=\"text-align: justify;\">Toutefois, pour engager l&rsquo;un des meilleurs ailiers de Pro D2, le <strong>Racing 92<\/strong> va devoir sortir le ch\u00e9quier, <strong>Hulleu<\/strong> \u00e9tant sous contrat jusqu&rsquo;en 2026 avec le <strong>FCG<\/strong>. Le joueur form\u00e9 au sein du club leader de Pro D2, viendra renforcer un poste d&rsquo;ailier qui s&rsquo;est d\u00e9garni du c\u00f4t\u00e9 des Franciliens, puisque pour rappel, <strong>Donovan Taofifenua<\/strong> (26 ans) et <strong>Henry Arundell<\/strong> (22 ans) quitteront le navire ciel et blanc en juin prochain.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Mine de rien, c&rsquo;est un joli coup de la part des Racingmen. Habitu\u00e9 \u00e0 regarder \u00e0 l&rsquo;\u00e9tranger pour le poste d&rsquo;ailier, le club francilien a cette fois flair\u00e9 le bon coup en attirant Wilfried Hulleu, joueur complet et d&rsquo;avenir.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-grenoble-wilfried-hulleu-va-signer-en-top-14\/\">Transferts Grenoble : Wilfried Hulleu va signer en Top 14<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Racing 92 bis : Clovis Le Bail dans le viseur de Toulon<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Racing 92<\/strong> va perdre un deuxi\u00e8me demi de m\u00eal\u00e9e. Alors que <strong>Nolann Le Garrec<\/strong> va rejoindre les rangs du <strong>Stade Rochelais<\/strong> la saison prochaine, <strong>Clovis Le Bail<\/strong> (29 ans) va aussi quitter les Hauts-de-Seine \u00e0 l&rsquo;issue de cette saison. Selon le <a href=\"https:\/\/www.rugbyrama.fr\/2025\/01\/20\/transfertstop-14-clovis-le-bail-sur-le-depart-du-racing-toulon-interesse-12456503.php\"><em>Midi Olympique<\/em><\/a>, l&rsquo;ancien Palois serait sur les tablettes du RC Toulon.<\/p>\n<p style=\"text-align: justify;\">Depuis son arriv\u00e9e au <strong>Racing 92<\/strong> en 2023, <strong>Le Bail<\/strong> a pris \u00e0 31 rencontres sous le maillot francilien, pour seulement douze titularisations. Cette saison, il a d\u00e9j\u00e0 disput\u00e9 12 matchs, dont trois dans la peau d&rsquo;un titulaire. Celui qui a d\u00e9but\u00e9 le rugby \u00e0 Nantes, avait effectu\u00e9 ses d\u00e9buts professionnels \u00e0 la <strong>Section Paloise<\/strong>, en 2016. Il compte 134 matchs pro \u00e0 son actif.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Cette fois, c&rsquo;est s\u00fbr, Clovis Le Bail ne prolongera pas dans les Hauts-de-Seine. Si la piste toulonnaise se concr\u00e9tisait, l&rsquo;ancien Palois retomberait plut\u00f4t bien sur ses pattes, dans un club en grande forme actuellement, mais o\u00f9 la concurrence est d\u00e9j\u00e0 forte \u00e0 son poste, avec Baptiste Serin et Ben White.<\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-racing-92-clovis-le-bail-sur-le-depart-un-cador-de-top-14-sur-le-coup\/\">Transferts Racing 92 : Clovis Le Bail sur le d\u00e9part, un cador de Top 14 sur le coup<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier<\/p>\n","protected":false},"author":4,"featured_media":540867,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-548421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T17:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\",\"datePublished\":\"2025-01-20T17:43:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\",\"name\":\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png\",\"datePublished\":\"2025-01-20T17:43:24+00:00\",\"description\":\"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier","description":"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier","og_description":"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-01-20T17:43:24+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier","datePublished":"2025-01-20T17:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/","name":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png","datePublished":"2025-01-20T17:43:24+00:00","description":"TRANSFERTS RUGBY - Alexandre Fischer (Clermont) a tranch\u00e9 pour son avenir, Wilfried Hulleu (Grenoble) va signer en Top 14, Clovis Le Bail va quitter le Racing 92 : les infos transferts de ce lundi 20 janvier 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Transferts-Clermont-Un-autre-club-de-Top-14-veut-signer-Alexandre-Fischer.png","width":1200,"height":674,"caption":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-alexandre-fischer-wilfried-hulleu-clovis-le-bail-les-infos-du-lundi-20-janvier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Alexandre Fischer, Wilfried Hulleu, Clovis Le Bail, les infos du lundi 20 janvier"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=548421"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548421\/revisions"}],"predecessor-version":[{"id":548437,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548421\/revisions\/548437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/540867"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=548421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=548421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=548421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}