{"id":548567,"date":"2025-01-21T16:33:10","date_gmt":"2025-01-21T15:33:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=548567&#038;preview=true&#038;preview_id=548567"},"modified":"2025-09-16T08:51:50","modified_gmt":"2025-09-16T06:51:50","slug":"pronostic-psg-manchester-city-cotes-analyse-et-conseil","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/","title":{"rendered":"Pronostic PSG-Manchester City : Cotes, analyse et conseil"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE DES CHAMPIONS 2024-2025 &#8211; Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-des-champions-2024-2025-psg-lille-monaco-et-brest\/\">Classement de la Ligue des Champions 2024-2025<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Pronostic PSG &#8211; Manchester City : Mercredi 22 janvier, 21h00<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Paris Saint-Germain<\/strong> n&rsquo;a plus le choix pour esp\u00e9rer rester en vie en <strong>Ligue des Champions<\/strong>. Les Parisiens doivent gagner contre <strong>Manchester<\/strong> <strong>City<\/strong> pour \u00e9viter de se retrouver dans une situation tr\u00e8s compliqu\u00e9e avant la derni\u00e8re journ\u00e9e. Les Parisiens sont sur une tr\u00e8s bonne s\u00e9rie toutes comp\u00e9titions confondues et vont donc tenter de rester sur cette dynamique, avec en plus, le retour d&rsquo;<strong>Ousmane Demb\u00e9l\u00e9<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a title=\"PSG-Manchester City : Heure, cha\u00eene TV, Cotes et Compositions\" href=\"https:\/\/dicodusport.fr\/blog\/psg-manchester-city-heure-chaine-tv-cotes-et-compositions\/\" target=\"_blank\" rel=\"noopener\">PSG-Manchester City : Heure, cha\u00eene TV, Cotes et Compositions<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Ainsi, le <strong>PSG<\/strong> va devoir montrer un autre visage que lors de ses premiers matchs dans cette comp\u00e9tition, mais le probl\u00e8me est que <strong>Manchester City<\/strong> est dans une situation similaire. Les <em>Citizens<\/em> ont un seul point de plus au classement et doivent donc \u00e9viter de rentrer bredouilles de <strong>Paris<\/strong>. Apr\u00e8s un gros trou d&rsquo;air, <strong>Manchester<\/strong> <strong>City<\/strong> va mieux et est sur une s\u00e9rie de six matchs sans d\u00e9faite.<\/p>\n<p style=\"text-align: justify;\">Vous l&rsquo;aurez compris, locaux comme visiteurs vont devoir prendre des risques dans cette rencontre. On s&rsquo;attend \u00e0 un match ouvert et on part sur <strong>les deux \u00e9quipes qui marquent<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\"><strong><span style=\"font-size: 12px; color: #ffffff;\">Mercredi 22 janvier, 21h00<\/span><\/strong><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; width: 300px; text-align: center;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Les deux \u00e9quipes vont-elles marquer ?<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 520px;\"><strong>PSG &#8211; Manchester City<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 160px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Oui<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/53152293?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#07125C;border-color:#060f4a;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#525a8d;border-radius:5px;text-shadow:none\"> 1.46<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 160px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Non<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/53152293?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#000000;border-color:#000000;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d4d4d;border-radius:5px;text-shadow:none\"> 2.50<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":548605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[75,419,3169,429,4949,910],"class_list":["post-548567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-football","tag-ligue-des-champions","tag-manchester-city","tag-paris","tag-pronostics","tag-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronostic PSG-Manchester City : Cotes, analyse et conseil - Dicodusport<\/title>\n<meta name=\"description\" content=\"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic PSG-Manchester City : Cotes, analyse et conseil\" \/>\n<meta property=\"og:description\" content=\"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T15:33:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T06:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic PSG-Manchester City : Cotes, analyse et conseil\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic PSG-Manchester City : Cotes, analyse et conseil\",\"datePublished\":\"2025-01-21T15:33:10+00:00\",\"dateModified\":\"2025-09-16T06:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png\",\"keywords\":[\"Football\",\"Ligue des champions\",\"Manchester City\",\"Paris\",\"Pronostics\",\"PSG\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\",\"name\":\"Pronostic PSG-Manchester City : Cotes, analyse et conseil - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png\",\"datePublished\":\"2025-01-21T15:33:10+00:00\",\"dateModified\":\"2025-09-16T06:51:50+00:00\",\"description\":\"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic PSG-Manchester City : Cotes, analyse et conseil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic PSG-Manchester City : Cotes, analyse et conseil - Dicodusport","description":"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic PSG-Manchester City : Cotes, analyse et conseil","og_description":"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-01-21T15:33:10+00:00","article_modified_time":"2025-09-16T06:51:50+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic PSG-Manchester City : Cotes, analyse et conseil","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic PSG-Manchester City : Cotes, analyse et conseil","datePublished":"2025-01-21T15:33:10+00:00","dateModified":"2025-09-16T06:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png","keywords":["Football","Ligue des champions","Manchester City","Paris","Pronostics","PSG"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/","name":"Pronostic PSG-Manchester City : Cotes, analyse et conseil - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png","datePublished":"2025-01-21T15:33:10+00:00","dateModified":"2025-09-16T06:51:50+00:00","description":"Le PSG accueille Manchester City lors de la 7\u00e8me journ\u00e9e de Ligue des champions. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Pronostic-PSG-Manchester-City-Cotes-analyse-et-conseil.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-manchester-city-cotes-analyse-et-conseil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic PSG-Manchester City : Cotes, analyse et conseil"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=548567"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548567\/revisions"}],"predecessor-version":[{"id":548687,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548567\/revisions\/548687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/548605"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=548567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=548567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=548567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}