{"id":548616,"date":"2025-01-21T19:33:22","date_gmt":"2025-01-21T18:33:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=548616&#038;preview=true&#038;preview_id=548616"},"modified":"2025-01-21T19:33:22","modified_gmt":"2025-01-21T18:33:22","slug":"transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/","title":{"rendered":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c&rsquo;est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">Pau : Eliott Roudil partant et courtis\u00e9<\/h2>\n<p style=\"text-align: justify;\"><strong>Eliott Roudil<\/strong> ne sera plus un joueur de la <strong>Section Paloise<\/strong> la saison prochaine. Selon le <em>Midi Olympique<\/em>, l&rsquo;ancien joueur du<strong> Stade Rochelais<\/strong> ne sera pas conserv\u00e9 par le club b\u00e9arnais \u00e0 l&rsquo;issue de cette saison. <strong>Roudil<\/strong>, 28 ans, est arriv\u00e9 \u00e0 Pau en 2020, apr\u00e8s avoir fait ses d\u00e9buts professionnels \u00e0 <strong>La Rochelle<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ainsi, le <strong>RC Vannes<\/strong> serait sur le coup pour signer le trois-quarts centre palois. Plusieurs \u00e9curies de Pro D2 sont \u00e9galement sur les rangs. Cette saison, il n\u2019a jou\u00e9 que huit matchs, dont la moiti\u00e9 en <strong>Challenge<\/strong>\u00a0<strong>Cup<\/strong>. <strong>Eliott Roudil<\/strong> va donc donner un nouvel \u00e9lan \u00e0 sa carri\u00e8re \u00e0 compter de l&rsquo;\u00e9t\u00e9 prochain.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Issue logique, tant Eliott Roudil n&rsquo;est pas le premier choix en centre de l&rsquo;attaque paloise. L&rsquo;\u00e9quipe qui parviendra \u00e0 la signer r\u00e9ussira un joli coup, tant il reste performant sur le terrain \u00e0 chacune de ses apparitions.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-pau-plusieurs-clubs-veulent-signer-eliott-roudil\/\">Transferts Pau : Plusieurs clubs veulent signer Eliott Roudil<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Pays de Galles : Un retour \u00e0 XV pour Louis Rees-Zammit ?<\/h2>\n<p style=\"text-align: justify;\">La p\u00e9pite <strong>Louis Rees-Zammit<\/strong> va-t-elle faire son retour \u00e0 XV ? Celui qui a fait le choix de se lancer dans l&rsquo;aventure NFL, il y a deux ans, semble \u00eatre \u00e0 un tournant de sa carri\u00e8re. Apr\u00e8s une exp\u00e9rience rat\u00e9e du c\u00f4t\u00e9 des <strong>Kansas Chiefs<\/strong>, alors champions en titre, l\u2019ailier gallois de 23 ans avait finalement rejoint les <strong>Jacksonville Jaguars<\/strong>. Si son contrat a pris fin en ce d\u00e9but d&rsquo;ann\u00e9e 2025, il pourrait prolonger l&rsquo;aventure en Floride, les <strong>Jaguars<\/strong> lui ayant propos\u00e9 une prolongation, selon le\u00a0<em>Daily Mail<\/em>\u00a0et le\u00a0<em>Mirror US<\/em>.<\/p>\n<p style=\"text-align: justify;\">Toutefois, la presse britannique affirme que le joueur serait en pleine r\u00e9flexion quant \u00e0 son avenir. Un retour au rugby \u00e0 XV n&rsquo;est pas \u00e0 exclure. Le Gallois, qui a fait les beaux joueurs du<em> XV du Poireau<\/em>, reviendra-t-il au pays ? Pour l&rsquo;instant, rien n&rsquo;est moins s\u00fbr. <strong>Rees-Zammit<\/strong> devrait prochainement s&rsquo;exprimer sur son avenir.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>En cas de retour \u00e0 XV, Louis Rees-Zammit pourrait bien animer le march\u00e9 des transferts ces prochaines semaines. Si un retour au Pays de Galles serait logique en vue d&rsquo;une s\u00e9lection avec le XV du Poireau, on ne peut rien \u00e9carter, l&rsquo;ailier \u00e9lectrique ayant d\u00e9j\u00e0 montr\u00e9 qu&rsquo;il \u00e9tait impr\u00e9visible.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-louis-rees-zammit-pays-de-galles-vers-un-retour-au-rugby-a-xv\/\">Transferts : Louis Rees-Zammit (Pays de Galles) vers un retour au rugby \u00e0 XV ?<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Pau bis : Ignacio Calles s&rsquo;engage avec Bayonne<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est officiel. Le pilier gauche international argentin <strong>Ignacio Calles<\/strong> (29 ans), arriv\u00e9 \u00e0 <strong>Pau<\/strong> il y a huit saisons, s&rsquo;est engag\u00e9 pour trois ans avec l&rsquo;<strong>Aviron Bayonnais<\/strong>, \u00e0 compter de l&rsquo;\u00e9t\u00e9 prochain. <strong>Calles<\/strong>, pr\u00e8s de 100 matchs avec le club b\u00e9arnais, compte huit s\u00e9lections avec les Pumas.<\/p>\n<p style=\"text-align: justify;\">\u00c0 <strong>Bayonne<\/strong>, <strong>Ignacio Calles<\/strong> retrouvera plusieurs de ses compatriotes, puisque Mateo Carreras, Facundo Bosch, Lucas Paulos et Rodrigo Bruni \u00e9voluent d\u00e9j\u00e0 au sein du club basque.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Bayonne poursuit son recrutement cibl\u00e9 et de qualit\u00e9 en vue des prochaines saisons. On ne peut qu&rsquo;applaudir l&rsquo;intelligence du board bayonnais, en vue de jouer les premiers r\u00f4les dans les ann\u00e9es \u00e0 venir.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier<\/p>\n","protected":false},"author":4,"featured_media":546223,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-548616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c&#039;est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c&#039;est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T18:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\",\"datePublished\":\"2025-01-21T18:33:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/\"},\"wordCount\":579,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/\",\"name\":\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png\",\"datePublished\":\"2025-01-21T18:33:22+00:00\",\"description\":\"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c'est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier","description":"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c'est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier","og_description":"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c'est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-01-21T18:33:22+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier","datePublished":"2025-01-21T18:33:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/"},"wordCount":579,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/","name":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png","datePublished":"2025-01-21T18:33:22+00:00","description":"TRANSFERTS RUGBY - Eliott Roudil (Pau) a le choix pour son avenir, Louis Rees-Zammit (Pays de Galles) pourrait animer le march\u00e9, c'est officiel pour Ignacio Calles (Pau) : les infos transferts de ce mardi 21 janvier 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-Ignacio-Calles-devrait-quitter-Pau-pour-un-autre-club-de-Top-14.png","width":1200,"height":674,"caption":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-eliott-roudil-louis-rees-zammit-ignacio-calles-les-infos-du-mardi-21-janvier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Eliott Roudil, Louis Rees-Zammit, Ignacio Calles, les infos du mardi 21 janvier"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=548616"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548616\/revisions"}],"predecessor-version":[{"id":548631,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/548616\/revisions\/548631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/546223"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=548616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=548616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=548616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}