{"id":552541,"date":"2025-02-03T07:38:30","date_gmt":"2025-02-03T06:38:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=552541&#038;preview=true&#038;preview_id=552541"},"modified":"2025-02-03T08:20:23","modified_gmt":"2025-02-03T07:20:23","slug":"transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/","title":{"rendered":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TRANSFERTS RUGBY &#8211; Selon nos confr\u00e8res du Midi Olympique, l&rsquo;ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).<\/em><\/h4>\n<p style=\"text-align: justify;\">L&rsquo;<strong>ASM<\/strong> <strong>Clermont<\/strong> fait partie des \u00e9quipes les plus actives sur le march\u00e9 des transferts, mais avec seulement deux recrues act\u00e9es pour le moment. <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-lasm-clermont-signe-harry-plummer-sur-le-long-terme\/\"><strong>Harry<\/strong> <strong>Plummer<\/strong><\/a> (27 ans, Blues) sera le nouvel ouvreur des <strong>Jaunards<\/strong> alors que <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-pio-muarua-devrait-signer-en-top-14\/\"><strong>Pio<\/strong> <strong>Muarua<\/strong><\/a> (29 ans, Grenoble) va d\u00e9barquer pour remplacer <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-peceli-yato-va-quitter-clermont-pour-un-autre-club-de-top-14\/\"><strong>Peceli<\/strong> <strong>Yato<\/strong><\/a> (32 ans) qui s&rsquo;est engag\u00e9 avec l&rsquo;<strong>USAP<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-racing-92-stuart-lancaster-sur-le-depart-un-favori-pour-le-remplacer\/\">Transferts Racing 92 : Stuart Lancaster sur le d\u00e9part, un favori pour le remplacer<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Salmaan Moerat pist\u00e9 par Clermont<\/h2>\n<p style=\"text-align: justify;\">Toujours dans le paquet d&rsquo;avants, l&rsquo;ASM Clermont serait en qu\u00eate d&rsquo;un deuxi\u00e8me ligne, et aurait coch\u00e9 le nom du Sud-Africain <strong>Salmaan<\/strong> <strong>Moerat<\/strong>. Le colosse des Springboks \u00e9tait dans le viseur de l&rsquo;<strong>Aviron<\/strong> <strong>Bayonnais,<\/strong> mais la piste semble s&rsquo;\u00eatre refroidie. Les <strong>Jaunards<\/strong> se sont eux positionn\u00e9s et tentent donc de r\u00e9aliser un tr\u00e8s gros coup.<\/p>\n<p style=\"text-align: justify;\">Capitaine de l&rsquo;Afrique du Sud l&rsquo;\u00e9t\u00e9 dernier, <strong>Salmaan<\/strong> <strong>Moerat<\/strong> a fait toute sa carri\u00e8re en club avec les <strong>Stormers<\/strong>. Si son d\u00e9part en fin de saison semble en bonne voie, Clermont a de la concurrence sur ce dossier, puisque les Anglais de Sale sont aussi sur le coup.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 ce sujet<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-santiago-chocobares-hugo-reus-racing-92-les-infos-transferts-du-jeudi-30-janvier\/\" class=\"vlp-link\" title=\"Transferts Rugby : Santiago Chocobares, Hugo Reus, Racing 92, les infos transferts du jeudi 30 janvier\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-La-Rochelle-Hugo-Reus-pourrait-signer-chez-un-cador-de-Top-14.png\" class=\"attachment-800x445 size-800x445\" alt=\"Transferts Rugby : Santiago Chocobares, Hugo Reus, Racing 92, les infos transferts du jeudi 30 janvier\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-La-Rochelle-Hugo-Reus-pourrait-signer-chez-un-cador-de-Top-14.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-La-Rochelle-Hugo-Reus-pourrait-signer-chez-un-cador-de-Top-14-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-La-Rochelle-Hugo-Reus-pourrait-signer-chez-un-cador-de-Top-14-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/01\/Transferts-La-Rochelle-Hugo-Reus-pourrait-signer-chez-un-cador-de-Top-14-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts Rugby : Santiago Chocobares, Hugo Reus, Racing 92, les infos transferts du jeudi 30 janvier<\/div><div class=\"vlp-block-1 vlp-link-summary\">Santiago Chocobares, Hugo Reus, Racing 92, les infos transferts du jeudi 30 janvier<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Selon nos confr\u00e8res du Midi Olympique, l&rsquo;ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).<\/p>\n","protected":false},"author":1,"featured_media":552543,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47050],"tags":[32415,16878,110,111,29105],"class_list":["post-552541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-actu","tag-breve","tag-rugby-a-xv","tag-top-14","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l&#039;ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l&#039;ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T06:38:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T07:20:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat\",\"datePublished\":\"2025-02-03T06:38:30+00:00\",\"dateModified\":\"2025-02-03T07:20:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Rugby \u00e0 XV\",\"Top 14\",\"Transferts rugby\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\",\"name\":\"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png\",\"datePublished\":\"2025-02-03T06:38:30+00:00\",\"dateModified\":\"2025-02-03T07:20:23+00:00\",\"description\":\"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l'ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat","description":"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l'ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat","og_description":"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l'ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-03T06:38:30+00:00","article_modified_time":"2025-02-03T07:20:23+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat","datePublished":"2025-02-03T06:38:30+00:00","dateModified":"2025-02-03T07:20:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png","keywords":["actu","br\u00e8ve","Rugby \u00e0 XV","Top 14","Transferts rugby"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/","name":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png","datePublished":"2025-02-03T06:38:30+00:00","dateModified":"2025-02-03T07:20:23+00:00","description":"TRANSFERTS RUGBY - Selon nos confr\u00e8res du Midi Olympique, l'ASM Clermont serait aussi sur le coup pour recruter Salmaan Moerat (26 ans).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Un-2eme-club-de-Top-14-veut-signer-Salmaan-Moerat.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-un-2eme-club-de-top-14-veut-signer-salmaan-moerat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Un 2\u00e8me club de Top 14 veut signer Salmaan Moerat"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/552541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=552541"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/552541\/revisions"}],"predecessor-version":[{"id":552551,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/552541\/revisions\/552551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/552543"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=552541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=552541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=552541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}