{"id":554446,"date":"2025-02-10T17:50:24","date_gmt":"2025-02-10T16:50:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=554446&#038;preview=true&#038;preview_id=554446"},"modified":"2025-02-10T17:50:24","modified_gmt":"2025-02-10T16:50:24","slug":"edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/","title":{"rendered":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>\u00c9TOILE DE BESS\u00c8GES 2025 &#8211; Apr\u00e8s les failles organisationnelles constat\u00e9es sur la course gardoise cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2025-classement-general\/\">\u00c9toile de Bess\u00e8ges 2025 \u2013 Classement g\u00e9n\u00e9ral<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jeudi 6 f\u00e9vrier, sur les routes du Gard. Les coureurs entament le dernier tron\u00e7on de la <a href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2025-classement-2eme-etape\/\">2\u00e8me \u00e9tape de l&rsquo;\u00c9toile de Bess\u00e8ges<\/a>. \u00c0 quelques 15 km de l&rsquo;arriv\u00e9e situ\u00e9e \u00e0 Marguerittes, stupeur au sein du peloton quand une voiture arrivant \u00e0 contresens fonce droit sur eux, provoquant indirectement une chute massive. <strong>Maxim Van Gils<\/strong> abandonne, <strong>Jordi Meeus<\/strong> et <strong>Ryan Gibbons<\/strong> tombent lourdement. Le pire est \u00e9vit\u00e9, mais certaines voix s&rsquo;\u00e9l\u00e8vent d\u00e9j\u00e0 pour d\u00e9noncer une grossi\u00e8re faute de l&rsquo;organisation qui touche \u00e0 la s\u00e9curit\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">R\u00e9cidive le lendemain<\/h2>\n<p style=\"text-align: justify;\">Malheureusement, l&rsquo;incident se reproduit le lendemain en d\u00e9but d&rsquo;\u00e9tape sous une pluie battante. Cette fois-ci, le peloton met pied \u00e0 terre et proteste vivement. Pour huit \u00e9quipes, c&rsquo;en est trop, et on ne repartira pas. <a href=\"https:\/\/dicodusport.fr\/blog\/red-bull-bora-hansgrohe-bilan-2024-objectifs-pour-2025-et-effectif\/\"><strong>Red Bull-Bora-Hansgrohe<\/strong><\/a>, <strong>EF Education-EasyPost<\/strong> ou encore <a href=\"https:\/\/dicodusport.fr\/blog\/decathlon-ag2r-la-mondiale-bilan-2024-objectifs-pour-2025-et-effectif\/\"><strong>Decathlon AG2R La Mondiale<\/strong><\/a> font partie des \u00e9quipes restant \u00e0 quai. Ainsi, un peloton d&rsquo;une soixantaine de coureurs seulement repart \u00e0 l&rsquo;abordage, soit la moiti\u00e9 de la startlist qui disparait.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Rien ne va sur l\u2019\u00c9toile de Bess\u00e8ges ! Une voiture est \u00e0 nouveau apparue sur le circuit, les coureurs ont protest\u00e9, des \u00e9quipes ne souhaitent pas repartir, le peloton s\u2019est arr\u00eat\u00e9 tr\u00e8s longuement. Explications avec <a href=\"https:\/\/twitter.com\/ClaireBricogne?ref_src=twsrc%5Etfw\">@ClaireBricogne<\/a>.<a href=\"https:\/\/twitter.com\/hashtag\/lequipeVELO?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeVELO<\/a> <a href=\"https:\/\/t.co\/y368F8XmUT\">pic.twitter.com\/y368F8XmUT<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1887850729735442817?ref_src=twsrc%5Etfw\">February 7, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">En outre, pour ne rien arranger, de multiples \u00e9tapes sont modifi\u00e9es tout au long de l&rsquo;\u00e9dition, via notamment des raccourcissements. Une v\u00e9ritable balle dans le pied que se tirent les organisateurs alors que la course proposait un plateau fort all\u00e9chant et commen\u00e7ait \u00e0 trouver sa place comme course de pr\u00e9paration dans le calendrier de la saison cycliste.<\/p>\n<h2 style=\"text-align: justify;\">Mais alors, qui incriminer ?<\/h2>\n<p style=\"text-align: justify;\">Pourtant, au sein du peloton, les avis divergent. Quand <strong>Dries De Bondt<\/strong> ou <strong>Oier Lazkano<\/strong>\u00a0montent au cr\u00e9neau pour d\u00e9noncer des failles s\u00e9curitaires inacceptables, certains comme <strong>Arnaud De Lie<\/strong> d\u00e9douanent en partie l&rsquo;organisation de ses responsabilit\u00e9s. <em>\u00ab Sans les courses, on ne peut pas exercer notre m\u00e9tier \u00bb<\/em> reconnait-il prudemment, ajoutant que le comportement des usagers est tout autant \u00e0 mettre en cause. Il convient aussi largement de la difficult\u00e9 dor\u00e9navant pour les organisateurs de tout s\u00e9curiser, du moindre dos d&rsquo;\u00e2ne aux ronds-points dangereux, le tout avec un manque de moyens parfois consid\u00e9rable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Arnaud De Lie \ud83c\udde7\ud83c\uddea : \u201cSi \u00e7a ne repartait pas, l&rsquo;Etoile de Bess\u00e8ges, c\u2019\u00e9tait fini pour la vie. Il y a eu le c\u00f4t\u00e9 sentimental car je consid\u00e8re que c\u2019est une course historique\u201d. \ud83d\ude4f<br \/>\n&gt; <a href=\"https:\/\/t.co\/FsEMe6S0il\">https:\/\/t.co\/FsEMe6S0il<\/a><\/p>\n<p>\ud83d\udcf8 Xavier Pereyron \/ DirectVelo <a href=\"https:\/\/t.co\/zsHitSCZCV\">pic.twitter.com\/zsHitSCZCV<\/a><\/p>\n<p>\u2014 DirectVelo (@directvelo) <a href=\"https:\/\/twitter.com\/directvelo\/status\/1888121037281218875?ref_src=twsrc%5Etfw\">February 8, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">N\u00e9anmoins, il est difficile de ne pas sortir le carton rouge pour les \u00e9v\u00e9nements de cette semaine. Oui, cette voiture n&rsquo;aurait jamais d\u00fb passer dans le secteur au moment o\u00f9 120 bonhommes d\u00e9boulent \u00e0 50 km\/h en pleine pr\u00e9paration d&rsquo;un sprint. Aussi, la d\u00e9cision de certaines \u00e9quipes de se retirer para\u00eet tout \u00e0 fait compr\u00e9hensible. Pourquoi risquer des dommages collat\u00e9raux et pourquoi risquer de perdre son leader pour la saison ? Envoyer un signal fort en quittant la course est une option comme une autre. Tout comme repartir pour sauver la course ! Quitte \u00e0 se retrouver avec un peloton d\u00e9cim\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Au-del\u00e0 du <em>Bessegesgate<\/em>, des enjeux consid\u00e9rables pour l&rsquo;avenir<\/h2>\n<p style=\"text-align: justify;\">Une chose est s\u00fbre : cet \u00e9pisode gardois pourrait laisser des traces. Bien au-del\u00e0 du risque de la disparition pure et simple de l&rsquo;<strong>\u00c9toile de Bess\u00e8ges<\/strong>, d\u00e9j\u00e0 dramatique en soi, c&rsquo;est toute la survie des petites courses hors circuit WorldTour et Pro qui est mise en jeu ici. Pourtant, l&rsquo;int\u00e9r\u00eat de ces courses est multiple, m\u00eame pour les \u00e9quipes calibr\u00e9es pour le WorldTour. Premi\u00e8rement, elles servent souvent de courses de pr\u00e9paration fort utiles (\u00e0 l&rsquo;image de Burgos, du Tour de l&rsquo;Ain, du Tour de Slov\u00e9nie etc). Ensuite, elles permettent de voir d&rsquo;autres coureurs briller issus de divisions inf\u00e9rieures ou m\u00eame de structures D\u00e9veloppement des grosses structures. L&rsquo;occasion donc de d\u00e9couvrir le haut niveau en douceur. Enfin et surtout, ce sont essentiellement ces courses qui font vivre les petites \u00e9quipes continentales.<\/p>\n<p style=\"text-align: justify;\">Car ne nous le cachons pas : le cyclisme marche clairement par pyramide. Un syst\u00e8me fragile certes, mais qui a fait ses preuves. Aussi, la disparition des petites courses faute de moyens pour assurer la s\u00e9curit\u00e9 ou m\u00eame simplement pour organiser l&rsquo;\u00e9preuve serait un drame absolu pour l&rsquo;\u00e9quilibre du syst\u00e8me actuel. Toute id\u00e9e de ligue ferm\u00e9e avec une poign\u00e9e de courses prestigieuses et une vingtaine d&rsquo;\u00e9quipes concern\u00e9es doit faire l&rsquo;objet d&rsquo;une contestation unanime de la part de nous tous, du monde amateur aux suiveurs en passant par les acteurs et actrices du m\u00e9tier. Mais apr\u00e8s tout, peut-\u00eatre que l&rsquo;UCI, qui d\u00e9fend \u00e0 demi-mot cette id\u00e9e, souhaite une refonte compl\u00e8te du syst\u00e8me, sonnant ainsi le glas \u00e0 la fois de nombres d&rsquo;\u00e9quipes et de la majorit\u00e9 des courses du calendrier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\u00a0<\/p>\n","protected":false},"author":92,"featured_media":554619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[3119,16878,3645,24,2831],"class_list":["post-554446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-actualite-cyclisme","tag-breve","tag-etoile-de-besseges","tag-sport","tag-uci"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?<\/title>\n<meta name=\"description\" content=\"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\" \/>\n<meta property=\"og:description\" content=\"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T16:50:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Olivier Dobiezynski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/Olivier_Matros\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\"},\"author\":{\"name\":\"Olivier Dobiezynski\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc\"},\"headline\":\"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\",\"datePublished\":\"2025-02-10T16:50:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\"},\"wordCount\":922,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png\",\"keywords\":[\"Actualit\u00e9 Cyclisme\",\"br\u00e8ve\",\"Etoile de Bess\u00e8ges\",\"sport\",\"UCI\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\",\"name\":\"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png\",\"datePublished\":\"2025-02-10T16:50:24+00:00\",\"description\":\"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png\",\"width\":1200,\"height\":674,\"caption\":\"Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc\",\"name\":\"Olivier Dobiezynski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"caption\":\"Olivier Dobiezynski\"},\"description\":\"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/x.com\/Olivier_Matros\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/olivier-gh\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?","description":"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?","og_description":"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-10T16:50:24+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png","type":"image\/png"}],"author":"Olivier Dobiezynski","twitter_card":"summary_large_image","twitter_title":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?","twitter_creator":"@https:\/\/x.com\/Olivier_Matros","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/"},"author":{"name":"Olivier Dobiezynski","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc"},"headline":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?","datePublished":"2025-02-10T16:50:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/"},"wordCount":922,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png","keywords":["Actualit\u00e9 Cyclisme","br\u00e8ve","Etoile de Bess\u00e8ges","sport","UCI"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/","url":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/","name":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png","datePublished":"2025-02-10T16:50:24+00:00","description":"ETOILE DE BESSEGES 2025 - Apr\u00e8s les failles constat\u00e9es sur la course cette semaine, il est temps d\u00e9sormais de faire un \u00e9tat des lieux des enjeux et des r\u00e9percussions de cette affaire sur le monde du cyclisme.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Y-aura-t-il-un-avant-et-un-apres-Etoile-de-Besseges-2025-.png","width":1200,"height":674,"caption":"Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/edito-y-aura-t-il-un-avant-et-un-apres-etoile-de-besseges-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9dito : Y aura-t-il un avant et un apr\u00e8s \u00c9toile de Bess\u00e8ges 2025 ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc","name":"Olivier Dobiezynski","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","caption":"Olivier Dobiezynski"},"description":"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/Olivier_Matros"],"url":"https:\/\/dicodusport.fr\/blog\/author\/olivier-gh\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/554446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=554446"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/554446\/revisions"}],"predecessor-version":[{"id":554620,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/554446\/revisions\/554620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/554619"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=554446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=554446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=554446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}