{"id":555754,"date":"2025-02-15T10:22:56","date_gmt":"2025-02-15T09:22:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=555754&#038;preview=true&#038;preview_id=555754"},"modified":"2025-02-15T21:38:04","modified_gmt":"2025-02-15T20:38:04","slug":"foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/","title":{"rendered":"FOJE d&rsquo;hiver 2025 : Le relais mixte en short-track s&#8217;empare de l&rsquo;argent"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>FOJE D&rsquo;HIVER 2025 &#8211; Le quatuor compos\u00e9 d&rsquo;<strong>Isra Gharsallaoui<\/strong>, <strong>Lisa Victoria Ngo Mouaha<\/strong>, <strong>Elio Calanca <\/strong>et <strong>Nathan Muller a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 pour les Bleus en s&#8217;emparant de l&rsquo;argent en relais mixte sur 2000m.<\/strong><\/em><\/h4>\n<p style=\"text-align: justify;\">Solidement amarr\u00e9e en t\u00eate du classement des m\u00e9dailles de ces <strong>FOJE d&rsquo;hiver<\/strong>, la France fait la n\u00e9cessaire en ce samedi matin pour s\u00e9curiser sa place. Le <strong>short-track<\/strong> a permis de garder le rythme. Plus t\u00f4t dans la matin\u00e9e, <a href=\"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-lisa-victoria-ngo-mouaha-short-track-en-argent-sur-1000m\/\"><strong>Lisa Victoria Ngo Mouaha<\/strong> a ouvert le compteur de la journ\u00e9e<\/a> sur le 1000m en d\u00e9crochant de l&rsquo;argent. Dans la lanc\u00e9e, la finale du relais mixte par \u00e9quipes sur 2000m offrait une nouvelle possibilit\u00e9 puisque les Bleus devaient batailler avec trois autres \u00e9quipes.<\/p>\n<h2 style=\"text-align: justify;\">Et de cinq pour le short-track fran\u00e7ais !<\/h2>\n<p style=\"text-align: justify;\">Ainsi, le quatuor compos\u00e9 d&rsquo;<strong>Isra Gharsallaoui<\/strong>, <strong>Lisa Victoria Ngo Mouaha<\/strong>, <strong>Elio Calanca <\/strong>et <strong>Nathan Muller<\/strong> n&rsquo;a pas trembl\u00e9 pour s\u00e9curiser une nouvelle breloque. Il aura m\u00eame lutt\u00e9 pour la victoire finale jusqu&rsquo;au bout, mais c&rsquo;est finalement la <strong>Hongrie<\/strong> qui s&rsquo;est offert le titre, avec une avance infime de 44 milli\u00e8mes au moment de couper la ligne. \u00c0 plus de cinq secondes, la Turquie compl\u00e8te le podium. Cela permet au short-track fran\u00e7ais de glaner une cinqui\u00e8me m\u00e9daille, dont trois pour la seule <strong>Lisa Victoria Ngo Mouaha.<\/strong> Cette derni\u00e8re ayant \u00e9galement pris de l&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-lisa-victoria-ngo-mouaha-short-track-en-or-sur-1-500m-elio-calanca-3eme\/\">or sur le 1500m<\/a> en d\u00e9but de semaine. Un bilan convaincant, dans la lign\u00e9e des FOJE d&rsquo;Hiver prolifiques du clan tricolore.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddeb\ud83c\uddf7 Festival Olympique de la Jeunesse Europ\u00e9enne de Bakuriani 2025<\/p>\n<p>\ud83e\udd48 L\u2019argent pour conclure ce FOJE du c\u00f4t\u00e9 du short track ! Isra Gharsallaoui, Lisa Victoria Ngo Mouaha, Elio Calanca et Nathan Muller terminent 2e de la finale de relais mixte \ud83d\udca5<a href=\"https:\/\/twitter.com\/hashtag\/FOJE2025?src=hash&amp;ref_src=twsrc%5Etfw\">#FOJE2025<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/AllezLesBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesBleus<\/a> <a href=\"https:\/\/t.co\/NH8xY22Hm9\">pic.twitter.com\/NH8xY22Hm9<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/1890692473078358085?ref_src=twsrc%5Etfw\">February 15, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOJE D&rsquo;HIVER 2025 &#8211; Le quatuor compos\u00e9 d&rsquo;Isra Gharsallaoui, Lisa Victoria Ngo Mouaha, Elio Calanca et Nathan Muller a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 pour les Bleus en s&#8217;emparant de l&rsquo;argent en relais mixte sur 2000m.<\/p>\n","protected":false},"author":55,"featured_media":556109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2313],"tags":[16878,2646],"class_list":["post-555754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports-dhiver","tag-breve","tag-short-track"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FOJE d&#039;hiver 2025 : Le relais mixte en short-track s&#039;empare de l&#039;argent<\/title>\n<meta name=\"description\" content=\"FOJE D&#039;HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l&#039;argent en relais mixte sur 2000m.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FOJE d&#039;hiver 2025 : Le relais mixte en short-track s&#039;empare de l&#039;argent\" \/>\n<meta property=\"og:description\" content=\"FOJE D&#039;HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l&#039;argent en relais mixte sur 2000m.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-15T09:22:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-15T20:38:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"FOJE d&#039;hiver 2025 : Le relais mixte en short-track s&#039;empare de l&#039;argent\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"FOJE d&rsquo;hiver 2025 : Le relais mixte en short-track s&#8217;empare de l&rsquo;argent\",\"datePublished\":\"2025-02-15T09:22:56+00:00\",\"dateModified\":\"2025-02-15T20:38:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/\"},\"wordCount\":334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png\",\"keywords\":[\"br\u00e8ve\",\"short track\"],\"articleSection\":[\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/\",\"name\":\"FOJE d'hiver 2025 : Le relais mixte en short-track s'empare de l'argent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png\",\"datePublished\":\"2025-02-15T09:22:56+00:00\",\"dateModified\":\"2025-02-15T20:38:04+00:00\",\"description\":\"FOJE D'HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l'argent en relais mixte sur 2000m.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png\",\"width\":1200,\"height\":674,\"caption\":\"FOJE d'hiver 2025 Le relais mixte en short-track s'empare de l'argent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FOJE d&#8217;hiver 2025 : Le relais mixte en short-track s&#8217;empare de l&#8217;argent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FOJE d'hiver 2025 : Le relais mixte en short-track s'empare de l'argent","description":"FOJE D'HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l'argent en relais mixte sur 2000m.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/","og_locale":"fr_FR","og_type":"article","og_title":"FOJE d'hiver 2025 : Le relais mixte en short-track s'empare de l'argent","og_description":"FOJE D'HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l'argent en relais mixte sur 2000m.","og_url":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-15T09:22:56+00:00","article_modified_time":"2025-02-15T20:38:04+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"FOJE d'hiver 2025 : Le relais mixte en short-track s'empare de l'argent","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"FOJE d&rsquo;hiver 2025 : Le relais mixte en short-track s&#8217;empare de l&rsquo;argent","datePublished":"2025-02-15T09:22:56+00:00","dateModified":"2025-02-15T20:38:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/"},"wordCount":334,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png","keywords":["br\u00e8ve","short track"],"articleSection":["Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/","url":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/","name":"FOJE d'hiver 2025 : Le relais mixte en short-track s'empare de l'argent","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png","datePublished":"2025-02-15T09:22:56+00:00","dateModified":"2025-02-15T20:38:04+00:00","description":"FOJE D'HIVER 2025 - Le relais mixte tricolore a boucl\u00e9 les \u00e9preuves de short-track en beaut\u00e9 avec de l'argent en relais mixte sur 2000m.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/FOJE-dhiver-2025-Le-relais-mixte-en-short-track-sempare-de-largent-1.png","width":1200,"height":674,"caption":"FOJE d'hiver 2025 Le relais mixte en short-track s'empare de l'argent"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/foje-dhiver-2025-le-relais-mixte-en-short-track-sempare-de-largent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"FOJE d&#8217;hiver 2025 : Le relais mixte en short-track s&#8217;empare de l&#8217;argent"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/555754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=555754"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/555754\/revisions"}],"predecessor-version":[{"id":555797,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/555754\/revisions\/555797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/556109"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=555754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=555754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=555754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}