{"id":556754,"date":"2025-02-18T09:40:59","date_gmt":"2025-02-18T08:40:59","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=556754&#038;preview=true&#038;preview_id=556754"},"modified":"2025-02-18T10:24:03","modified_gmt":"2025-02-18T09:24:03","slug":"transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/","title":{"rendered":"Transferts : Fotu Lokotui sur le d\u00e9part d&rsquo;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison. Pour le remplacer, le SUA aurait trouv\u00e9 son bonheur en d\u00e9bauchant un autre joueur tongien.<\/em><\/h4>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/\">Toute l&rsquo;actualit\u00e9 du rugby<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La 3\u00e8me ligne d&rsquo;<strong>Agen<\/strong> va conna\u00eetre un jeu des chaises musicales version Tonga. Au club depuis 2021,<strong> Fotu Lokotui<\/strong> va en effet quitter le SUA en fin de saison apr\u00e8s quatre ann\u00e9es de bons et loyaux services. Indispensable durant ses trois premi\u00e8res saisons, il a vu son temps de jeu diminuer depuis le d\u00e9but de l&rsquo;exercice en cours. \u00c0 bient\u00f4t 33 ans, il va donc se mettre en qu\u00eate d&rsquo;un nouveau d\u00e9fi.<\/p>\n<h2 style=\"text-align: justify;\">Taniela Matakaiongo pour remplacer son compatriote \u00e0 Agen ?<\/h2>\n<p style=\"text-align: justify;\">Afin de le remplacer, les dirigeants agenais ont d\u00e9j\u00e0 trouv\u00e9 chaussure \u00e0 leur pied en misant sur un gar\u00e7on \u00e9voluant au niveau inf\u00e9rieur, en Nationale. Selon <em>Rugbyrama<\/em>, <strong>Taniela Matakaiongo<\/strong> serait l&rsquo;heureux \u00e9lu. Cet autre Tongien de 28 ans \u00e9volue depuis un peu plus d&rsquo;un an et demi \u00e0 <strong>Chambery<\/strong>, o\u00f9 il s&rsquo;est impos\u00e9 comme l&rsquo;une des forces majeures de la 3\u00e8me division nationale. Il devrait donc s&rsquo;engager avec le club pour les deux prochaines saisons, avec une troisi\u00e8me suppl\u00e9mentaire en option.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\">Classement Pro D2 2024-2025<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Cela devrait lui offrir l&rsquo;opportunit\u00e9 de d\u00e9couvrir la <strong>Pro D2<\/strong>, si la SUA parvient \u00e0 se maintenir. 11\u00e8me avec 40 points, le club ne compte que deux petites unit\u00e9s d&rsquo;avance sur le barragiste, Aurillac, et va donc devoir encore cravacher.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Selon nos informations, le SU Agen a d\u00e9cid\u00e9 de se s\u00e9parer de son troisi\u00e8me ligne centre tongien, Fotu Lokotui, \u00e0 l\u2019issue de la saison. Il sera remplac\u00e9 par l\u2019un de ses compatriotes, qui arrive de Chamb\u00e9ry : Taniela Matakaiongo.<a href=\"https:\/\/t.co\/MEFDwrCGac\">https:\/\/t.co\/MEFDwrCGac<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1891753521139028230?ref_src=twsrc%5Etfw\">February 18, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison. Pour le remplacer, le SUA a trouv\u00e9 son bonheur en d\u00e9bauchant un autre joueur tongien.<\/p>\n","protected":false},"author":55,"featured_media":556758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[32415,2339,16878,28226,1839,13,110,29105],"class_list":["post-556754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-actu","tag-agen","tag-breve","tag-mercato-rugby","tag-pro-d2","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Fotu Lokotui sur le d\u00e9part d&#039;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Fotu Lokotui sur le d\u00e9part d&#039;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T08:40:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T09:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Fotu Lokotui sur le d\u00e9part d&#039;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Transferts : Fotu Lokotui sur le d\u00e9part d&rsquo;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\",\"datePublished\":\"2025-02-18T08:40:59+00:00\",\"dateModified\":\"2025-02-18T09:24:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png\",\"keywords\":[\"actu\",\"Agen\",\"br\u00e8ve\",\"Mercato Rugby\",\"Pro D2\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\",\"name\":\"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png\",\"datePublished\":\"2025-02-18T08:40:59+00:00\",\"dateModified\":\"2025-02-18T09:24:03+00:00\",\"description\":\"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Fotu Lokotui sur le d\u00e9part d&#8217;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9","description":"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9","og_description":"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-18T08:40:59+00:00","article_modified_time":"2025-02-18T09:24:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Transferts : Fotu Lokotui sur le d\u00e9part d&rsquo;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9","datePublished":"2025-02-18T08:40:59+00:00","dateModified":"2025-02-18T09:24:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png","keywords":["actu","Agen","br\u00e8ve","Mercato Rugby","Pro D2","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/","name":"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png","datePublished":"2025-02-18T08:40:59+00:00","dateModified":"2025-02-18T09:24:03+00:00","description":"TRANSFERTS RUGBY - Une page va se tourner \u00e0 Agen puisque Fotu Lokotui va quitter le Lot-et-Garonne en fin de saison.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Fotu-Lokotui-sur-le-depart-dAgen-un-remplacant-deja-piste.png","width":1200,"height":674,"caption":"Transferts : Fotu Lokotui sur le d\u00e9part d'Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-fotu-lokotui-sur-le-depart-dagen-un-remplacant-deja-piste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Fotu Lokotui sur le d\u00e9part d&#8217;Agen, un rempla\u00e7ant d\u00e9j\u00e0 pist\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/556754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=556754"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/556754\/revisions"}],"predecessor-version":[{"id":556769,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/556754\/revisions\/556769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/556758"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=556754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=556754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=556754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}