{"id":557432,"date":"2025-02-20T17:38:29","date_gmt":"2025-02-20T16:38:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=557432&#038;preview=true&#038;preview_id=557432"},"modified":"2025-02-20T17:42:40","modified_gmt":"2025-02-20T16:42:40","slug":"auxerre-marseille-heure-chaine-tv-cotes-et-compositions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/","title":{"rendered":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" target=\"_blank\" rel=\"noopener\">LIGUE 1 2024-2025<\/a> &#8211; <\/em><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a title=\"Classement Ligue 1 2024-2025\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2024-2025\/\" rel=\"\"><strong>Le classement de la Ligue 1<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Auxerre est douzi\u00e8me de Ligue 1, mais n&rsquo;a plus gagn\u00e9 depuis plusieurs mois. Les <strong>Auxerrois<\/strong> enchainent les matchs nuls et les d\u00e9faites ces derni\u00e8res semaines, puisque leur derni\u00e8re victoire remonte \u00e0 fin novembre face \u00e0 Angers sur le score de 1 \u00e0 0. La semaine pass\u00e9e, <strong>Auxerre<\/strong> a obtenu un bon match nul sur la pelouse de <strong>Brest<\/strong>, 2 partout.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/\">L&rsquo;actualit\u00e9 du football<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, l&rsquo;<strong>Olympique de Marseille<\/strong> encha\u00eene les victoires apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e 2025 un peu plus compliqu\u00e9. Les <strong>Olympiens<\/strong> ont remport\u00e9 leurs trois derniers matchs, face \u00e0 l&rsquo;<strong>Olympique Lyonnais<\/strong>, <strong>Angers<\/strong> et <strong>Saint-\u00c9tienne<\/strong>. Toujours dauphin du <strong>PSG<\/strong>, <strong>Marseille<\/strong> a fait le break sur le troisi\u00e8me, Nice, avec pas moins de six points d&rsquo;avance.<\/p>\n<p style=\"text-align: justify;\">Au match aller, <strong>Auxerre<\/strong> avait cr\u00e9\u00e9 la sensation avec une victoire 3 buts \u00e0 1 au <strong>V\u00e9lodrome<\/strong>. Chez les bookmakers, l&rsquo;<strong>Olympique de Marseille<\/strong> est largement favori pour cette rencontre.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le programme TV d&rsquo;Auxerre-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">Samedi 22 f\u00e9vrier 2025<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur beIN SPORTS 1<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 21h05.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions d&rsquo;Auxerre-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">La composition d&rsquo;Auxerre<\/h3>\n<p style=\"text-align: justify;\">\u00c0 venir&#8230;<\/p>\n<h3 style=\"text-align: justify;\">La composition de Marseille<\/h3>\n<p style=\"text-align: justify;\">\u00c0 venir&#8230;<\/p>\n<h2 style=\"text-align: justify;\">Les cotes d&rsquo;Auxerre-Marseille<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Samedi 22 f\u00e9vrier, 21h05<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Auxerre<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955753?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 5.60<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955753?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 4.30<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/50955753?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.56<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2024-2025 &#8211; \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?<\/p>\n","protected":false},"author":1,"featured_media":557435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,2301,47045],"tags":[5776,16878,17213,44284,75,21768,1554,446,8799],"class_list":["post-557432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-football","category-ligue-1","tag-auxerre","tag-breve","tag-chaine","tag-chaine-tv","tag-football","tag-horaire","tag-ligue-1","tag-marseille","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T16:38:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T16:42:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions\",\"datePublished\":\"2025-02-20T16:38:29+00:00\",\"dateModified\":\"2025-02-20T16:42:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"keywords\":[\"Auxerre\",\"br\u00e8ve\",\"Cha\u00eene\",\"Cha\u00eene TV\",\"Football\",\"Horaire\",\"Ligue 1\",\"Marseille\",\"Programme TV\"],\"articleSection\":[\"Cha\u00eene TV\",\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\",\"name\":\"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"datePublished\":\"2025-02-20T16:38:29+00:00\",\"dateModified\":\"2025-02-20T16:42:40+00:00\",\"description\":\"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions","description":"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/","og_locale":"fr_FR","og_type":"article","og_title":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions","og_description":"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?","og_url":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-20T16:38:29+00:00","article_modified_time":"2025-02-20T16:42:40+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions","datePublished":"2025-02-20T16:38:29+00:00","dateModified":"2025-02-20T16:42:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png","keywords":["Auxerre","br\u00e8ve","Cha\u00eene","Cha\u00eene TV","Football","Horaire","Ligue 1","Marseille","Programme TV"],"articleSection":["Cha\u00eene TV","Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/","url":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/","name":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png","datePublished":"2025-02-20T16:38:29+00:00","dateModified":"2025-02-20T16:42:40+00:00","description":"LIGUE 1 2024-2025 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Auxerre et Marseille, dans le cadre de la 23\u00e8me journ\u00e9e de Ligue 1 ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Auxerre-Marseille-Heure-Chaine-TV-Cotes-et-Compositions.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/auxerre-marseille-heure-chaine-tv-cotes-et-compositions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Auxerre-Marseille : Heure, Cha\u00eene TV, Cotes et Compositions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=557432"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557432\/revisions"}],"predecessor-version":[{"id":557440,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557432\/revisions\/557440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/557435"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=557432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=557432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=557432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}