{"id":557620,"date":"2025-02-21T13:42:14","date_gmt":"2025-02-21T12:42:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=557620&#038;preview=true&#038;preview_id=557620"},"modified":"2025-02-21T13:42:36","modified_gmt":"2025-02-21T12:42:36","slug":"ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/","title":{"rendered":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE EUROPA 2024\/2025 &#8211; Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.<\/em><\/h4>\n<p style=\"text-align: justify;\">Le tirage au sort des <strong>8\u00e8mes de finale de la Ligue Europa 2024-2025<\/strong> s&rsquo;est d\u00e9roul\u00e9 ce vendredi 21 f\u00e9vrier. Un club fran\u00e7ais est en lice \u00e0 ce stade de la comp\u00e9tition : l&rsquo;<strong>Olympique Lyonnais<\/strong>. Retrouvez l&rsquo;ensemble des affiches des <strong>8\u00e8mes de finale<\/strong>.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">L\u2019<b>OL<\/b> affrontera le <b>Steaua Bucarest<\/b>. Le club roumain s\u2019est d\u00e9fait du PAOK Salonique en s\u2019imposant 2-1 \u00e0 l\u2019aller et 2-0 au retour. Il a surtout \u00e9vit\u00e9 l&rsquo;<b>Ajax Amsterdam<\/b> qui devra affronter l\u2019<strong>Eintracht Franckfurt<\/strong>. De belles affiches sont \u00e9galement \u00e0 venir avec un <b>Real Sociedad-Manchester United<\/b> ainsi qu\u2019un <b>AS Roma-Athletic Bilbao<\/b>.<\/p>\n<h2 style=\"text-align: justify;\">8\u00e8mes de finale Ligue Europa 2024-2025 &#8211; Tirage au sort et affiches<\/h2>\n<p style=\"text-align: justify;\">Les 8\u00e8mes de finale se joueront les 6 mars (aller) et les 13 mars (retour).<\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 100%;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 320px\" colspan=\"3\"><strong>8\u00c8MES DE FINALE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddff VIKTORIA PLZEN<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H1)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 LAZIO ROME<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf4 BOD\u00d8\/GLIMT<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H2)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\uddf7 OLYMPIACOS<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf1 AJAX AMSTERDAM<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H3)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde9\ud83c\uddea EINTRACHT FRANCFORT<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf1 AZ ALKMAAR<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H4)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3761\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png\" alt=\"\" width=\"17\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-390x205.png 390w\" sizes=\"auto, (max-width: 17px) 100vw, 17px\" \/> TOTTENHAM<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 AS ROMA<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H5)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 ATHLETIC BILBAO<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf9\ud83c\uddf7 FENERBAH\u00c7E<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H6)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8797 \" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse.png\" alt=\"\" width=\"17\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse.png 1000w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-390x205.png 390w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-800x445.png 800w\" sizes=\"auto, (max-width: 17px) 100vw, 17px\" \/> GLASGOW RANGERS<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf7\ud83c\uddf4 FCSB<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H7)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 LYON<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 REAL SOCIEDAD<\/strong><\/span><\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 280px\">(H8)<\/td>\n<td style=\"text-align: center;vertical-align: middle;width: 33%\"><span style=\"font-size: 0.9em\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3761\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png\" alt=\"\" width=\"17\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-390x205.png 390w\" sizes=\"auto, (max-width: 17px) 100vw, 17px\" \/> MANCHESTER UNITED<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/\"><strong>L&rsquo;actualit\u00e9 du football<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tirage au sort et affiches des 8\u00e8mes de finale de la Ligue Europa<\/p>\n","protected":false},"author":80,"featured_media":557631,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[32415,16878,75,4437,449,1146],"class_list":["post-557620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-actu","tag-breve","tag-football","tag-ligue-europa","tag-lyon","tag-olympique-lyonnais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale<\/title>\n<meta name=\"description\" content=\"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T12:42:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T12:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale\",\"datePublished\":\"2025-02-21T12:42:14+00:00\",\"dateModified\":\"2025-02-21T12:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\"},\"wordCount\":209,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Football\",\"Ligue Europa\",\"Lyon\",\"Olympique lyonnais\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\",\"name\":\"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png\",\"datePublished\":\"2025-02-21T12:42:14+00:00\",\"dateModified\":\"2025-02-21T12:42:36+00:00\",\"description\":\"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue Europa Tirage au sort et affiches des 8\u00e8mes de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\/\/killiantanguy.wixsite.com\/monsite\",\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\",\"https:\/\/www.instagram.com\/sport.killiantanguy\/\",\"https:\/\/www.linkedin.com\/in\/killiantanguy\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy\",\"https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale","description":"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale","og_description":"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2025-02-21T12:42:14+00:00","article_modified_time":"2025-02-21T12:42:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale","datePublished":"2025-02-21T12:42:14+00:00","dateModified":"2025-02-21T12:42:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/"},"wordCount":209,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png","keywords":["actu","br\u00e8ve","Football","Ligue Europa","Lyon","Olympique lyonnais"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/","name":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png","datePublished":"2025-02-21T12:42:14+00:00","dateModified":"2025-02-21T12:42:36+00:00","description":"Retrouvez le tirage au sort complet ainsi que les affiches des 8\u00e8mes de finale de la Ligue Europa 2024-2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Ligue-Europa-Tirage-au-sort-et-affiches-des-8emes-de-finale.png","width":1200,"height":674,"caption":"Ligue Europa Tirage au sort et affiches des 8\u00e8mes de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-tirage-au-sort-et-affiches-des-8emes-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue Europa : Tirage au sort et affiches des 8\u00e8mes de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=557620"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557620\/revisions"}],"predecessor-version":[{"id":557661,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/557620\/revisions\/557661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/557631"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=557620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=557620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=557620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}