{"id":558573,"date":"2025-02-23T15:32:58","date_gmt":"2025-02-23T14:32:58","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=558573&#038;preview=true&#038;preview_id=558573"},"modified":"2025-02-23T19:06:36","modified_gmt":"2025-02-23T18:06:36","slug":"top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/","title":{"rendered":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TOP 16 EUROP\u00c9EN 2025 &#8211; Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic. Le Fran\u00e7ais n\u2019aura laiss\u00e9 que 2 manches dans ce chemin jusqu\u2019au titre et met fin \u00e0 28 ans d\u2019attente pour le tennis de table tricolore dans la comp\u00e9tition.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis-de-table\/\">Toute l&rsquo;actualit\u00e9 du tennis de table<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir veng\u00e9 son fr\u00e8re <a href=\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-resiste-a-franziska-et-poursuit-sa-route-en-finale\/\">au tour pr\u00e9c\u00e9dent<\/a>, <strong>Alexis Lebrun<\/strong> avait d\u00e9j\u00e0 marqu\u00e9 de son empreinte la comp\u00e9tition, devenant le 1<sup>er<\/sup> Fran\u00e7ais \u00e0 atteindre la finale du Top 16 depuis <strong>Jean-Philippe Gatien<\/strong> en 1997. Et comme son pr\u00e9d\u00e9cesseur, il voulait d\u00e9crocher le plus beau des m\u00e9taux. Pour cela, il fallait faire tomber le triple tenant du titre, le Slov\u00e8ne Darko Jorgic. Rien que \u00e7a. Mais \u00e0 l&rsquo;image de son tournoi, <strong>Alexis Lebrun<\/strong> n&rsquo;a rien l\u00e2ch\u00e9, ou presque, pour monter sur la plus haute marche.<\/p>\n<h2 style=\"text-align: justify;\">1 partout, balle au centre<\/h2>\n<p style=\"text-align: justify;\">On sent la tension en d\u00e9but de matchs avec quelques impr\u00e9cisions de part et d\u2019autre. Le score se tient \u00e0 4-4 avant une belle d\u00e9fense tricolore qui attrape le bout de la table. De la r\u00e9ussite, Alexis Lebrun continue d\u2019en avoir et est le premier \u00e0 faire le break, prenant m\u00eame un peu d\u2019air (8-4). Malgr\u00e9 un l\u00e9ger retour au combat de Jorgic, le champion d\u2019Europe s\u2019empare du 1<sup>er<\/sup> set 11-8 gr\u00e2ce \u00e0 une nouvelle gifle en coup droit.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Alexis Lebrun prend la premi\u00e8re manche !<\/p>\n<p>Le Fran\u00e7ais semble au dessus pour le moment<\/p>\n<p>Suivez le match ici &gt; <a href=\"https:\/\/t.co\/4aKX3vuX6w\">https:\/\/t.co\/4aKX3vuX6w<\/a> <a href=\"https:\/\/t.co\/4kkdyM7lC2\">pic.twitter.com\/4kkdyM7lC2<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1893665575483691392?ref_src=twsrc%5Etfw\">February 23, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Sur sa lanc\u00e9e, Alexis \u00e9touffe le Slov\u00e8ne, rapidement men\u00e9 5-1 dans l\u2019acte II. \u00c0 d\u00e9faut d\u2019aller chercher ses points, Jorgic reste en vie notamment gr\u00e2ce aux fautes du Fran\u00e7ais, qui continue n\u00e9anmoins de faire course en t\u00eate pour s\u2019offrir 2 balles de 2<sup>\u00e8me<\/sup> manche. Instant choisi par le triple tenant du titre pour en mettre un peu plus dans ses frappes et inscrire 4 points de rang, renversant ainsi le set dans sa poche.<\/p>\n<h2 style=\"text-align: justify;\">Alexis Lebrun sur la plus haute marche<\/h2>\n<p style=\"text-align: justify;\">1-1, le match est d\u00e9finitivement lanc\u00e9, les \u00e9changes s\u2019intensifient. Surfant sur un revers performant, le Slov\u00e8ne s\u2019\u00e9chappe 7-3. Mais il n\u2019avait sans doute pas suivi la remontada du Fran\u00e7ais en quarts de finale. Car le Fran\u00e7ais a une nouvelle fois renvers\u00e9 la manche. 5 points cons\u00e9cutifs et une gifle crois\u00e9e en coup droit pour conclure, le voil\u00e0 plus qu\u2019\u00e0 1 manche de l\u2019histoire.<\/p>\n<p style=\"text-align: justify;\">Appliqu\u00e9, globalement dominateur dans cette finale malgr\u00e9 ce petit passage \u00e0 vide, Alexis Lebrun fait voyager son rival. Droite, gauche, le Slov\u00e8ne va malgr\u00e9 tout esp\u00e9rer jusqu\u2019au bout apr\u00e8s avoir sauv\u00e9 deux balles de match. Mais la 3<sup>\u00e8me<\/sup> est la bonne pour Alexis (11-8, 11-5, 9-11, 12-10). Il peut monter sur la table, il remporte pour la 1<sup>\u00e8re<\/sup> fois de sa carri\u00e8re le Top 16 europ\u00e9en, <a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-tennis-de-table-2024-alexis-lebrun-sacre-champion-deurope-en-simple\/\">quelques mois apr\u00e8s son titre continental<\/a>. Histoire de marquer un peu plus le coup, il met fin \u00e0 une disette de 28 ans dans la comp\u00e9tition pour le ping tricolore. Chapeau\u00a0!<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">ALEXIS LEBRUN REMPORTE LE TOP 16 EUROP\u00c9EN !<\/p>\n<p>Vainqueur face au triple tenant du titre Darko Jorgic, il devient le premier Fran\u00e7ais \u00e0 remporter ce tournoi depuis Jean-Philippe Gatien, en 1997 ! <a href=\"https:\/\/twitter.com\/hashtag\/lequipeTTABLE?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeTTABLE<\/a> <a href=\"https:\/\/t.co\/L8iaeIQIgp\">pic.twitter.com\/L8iaeIQIgp<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1893670898542006352?ref_src=twsrc%5Etfw\">February 23, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 16 EUROP\u00c9EN 2025 &#8211; Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic. Le Fran\u00e7ais n\u2019aura laiss\u00e9 que 2 manches dans ce chemin jusqu\u2019au titre et met fin \u00e0 28 ans d\u2019attente pour le tennis de table tricolore dans la comp\u00e9tition.<\/p>\n","protected":false},"author":18,"featured_media":558740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9663],"tags":[32415,22533,16878,27448,24,19375],"class_list":["post-558573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis-de-table","tag-actu","tag-alexis-lebrun","tag-breve","tag-ping-francais","tag-sport","tag-top-16-europeen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien<\/title>\n<meta name=\"description\" content=\"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s&#039;offrir le titre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\" \/>\n<meta property=\"og:description\" content=\"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s&#039;offrir le titre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-23T14:32:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-23T18:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\",\"datePublished\":\"2025-02-23T14:32:58+00:00\",\"dateModified\":\"2025-02-23T18:06:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\"},\"wordCount\":595,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png\",\"keywords\":[\"actu\",\"Alexis Lebrun\",\"br\u00e8ve\",\"ping fran\u00e7ais\",\"sport\",\"Top 16 europ\u00e9en\"],\"articleSection\":[\"Tennis de table\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\",\"name\":\"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png\",\"datePublished\":\"2025-02-23T14:32:58+00:00\",\"dateModified\":\"2025-02-23T18:06:36+00:00\",\"description\":\"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s'offrir le titre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Top 16 europ\u00e9en Tennis de table Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien","description":"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s'offrir le titre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien","og_description":"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s'offrir le titre.","og_url":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2025-02-23T14:32:58+00:00","article_modified_time":"2025-02-23T18:06:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien","datePublished":"2025-02-23T14:32:58+00:00","dateModified":"2025-02-23T18:06:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/"},"wordCount":595,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png","keywords":["actu","Alexis Lebrun","br\u00e8ve","ping fran\u00e7ais","sport","Top 16 europ\u00e9en"],"articleSection":["Tennis de table"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/","url":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/","name":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png","datePublished":"2025-02-23T14:32:58+00:00","dateModified":"2025-02-23T18:06:36+00:00","description":"TOP 16 EUROP\u00c9EN 2025 - Alexis Lebrun a parfaitement termin\u00e9 le travail contre Darko Jorgic pour s'offrir le titre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Top-16-europeen-Tennis-de-table-Alexis-Lebrun-domine-Jorgic-et-succede-a-Jean-Philippe-Gatien-1.png","width":1200,"height":674,"caption":"Top 16 europ\u00e9en Tennis de table Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-16-europeen-tennis-de-table-alexis-lebrun-domine-jorgic-et-succede-a-jean-philippe-gatien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 16 europ\u00e9en Tennis de table : Alexis Lebrun domine Jorgic et succ\u00e8de \u00e0 Jean-Philippe Gatien"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=558573"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558573\/revisions"}],"predecessor-version":[{"id":558610,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558573\/revisions\/558610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/558740"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=558573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=558573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=558573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}