{"id":558816,"date":"2025-02-24T10:05:28","date_gmt":"2025-02-24T09:05:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=558816&#038;preview=true&#038;preview_id=558816"},"modified":"2025-02-24T10:12:17","modified_gmt":"2025-02-24T09:12:17","slug":"transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/","title":{"rendered":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TRANSFERTS RUGBY &#8211; Selon le <a href=\"https:\/\/www.rugbyrama.fr\/2025\/02\/22\/transfertstop-14-exclu-midol-libere-par-castres-cet-ete-yann-peysson-signe-en-faveur-de-brive-12529645.php\" target=\"_blank\" rel=\"noopener\">Midi Olympique<\/a>, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s&rsquo;engager avec Brive.<\/em><\/h4>\n<p style=\"text-align: justify;\">Le <strong>Castres<\/strong> <strong>Olympique<\/strong> fait partie des \u00e9quipes discr\u00e8tes pour le moment sur le march\u00e9 des transferts, puisque les Tarnais ont privil\u00e9gi\u00e9 la continuit\u00e9 avec de nombreuses prolongations de contrat. Les Castrais ont aussi recrut\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-oyonnax-teddy-durand-va-signer-en-top-14\/\"><strong>Teddy Durand<\/strong><\/a> (25 ans) pour remplacer <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-castres-gaetan-barlot-a-choisi-son-prochain-club\/\"><strong>Ga\u00ebtan Barlot<\/strong><\/a> (28 ans), mais aussi <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-valence-romans-adam-vargas-devrait-signer-en-top-14\/\"><strong>Adam<\/strong> <strong>Vargas<\/strong><\/a> (24 ans) pour densifier leur ligne de trois-quarts.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-francais-raffaele-costa-storti-va-signer-en-pro-d2\/\" target=\"_blank\" rel=\"noopener\">Transferts Stade Fran\u00e7ais : Raffaele Costa Storti va signer en Pro D2<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Yann Peysson \u00e0 Brive<\/h2>\n<p style=\"text-align: justify;\">Dans le paquet d&rsquo;avants, le CO a s\u00e9curis\u00e9 plusieurs joueurs sur le long terme, et notamment en troisi\u00e8me ligne avec les prolongations de <strong>Simon<\/strong> <strong>Meka<\/strong> (25 ans), <strong>Mathieu<\/strong> <strong>Babillot<\/strong> (31 ans) et <strong>Abraham<\/strong> <strong>Papali&rsquo;i<\/strong> (32 ans). <strong>Yann<\/strong> <strong>Peysson<\/strong> \u00e9tait lui sous contrat jusqu&rsquo;en juin 2026 mais, en manque de temps de jeu, il a obtenu une lib\u00e9ration anticip\u00e9e aupr\u00e8s de ses dirigeants.<\/p>\n<p style=\"text-align: justify;\">S&rsquo;il va bien terminer la saison avec le <strong>Castres Olympique<\/strong>, il devrait \u00e9voluer en <strong>Pro<\/strong> <strong>D2<\/strong> la saison prochaine. Selon nos confr\u00e8res du Midol, il va s&rsquo;engager pour trois saisons avec le <strong>CA<\/strong> <strong>Brive<\/strong>. Alors qu&rsquo;il n&rsquo;a disput\u00e9 que quatre matchs cette saison, il esp\u00e8re retrouver plus de temps de jeu durant la prochaine.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-2025-arrivees-departs-et-prolongations\/\" class=\"vlp-link\" title=\"Transferts Stade Toulousain 2025 : Recrues, d\u00e9parts et prolongations\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-La-Rochelle-Teddy-Thomas-signe-finalement-avec-un-cador-du-Top-14.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-La-Rochelle-Teddy-Thomas-signe-finalement-avec-un-cador-du-Top-14.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-La-Rochelle-Teddy-Thomas-signe-finalement-avec-un-cador-du-Top-14-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-La-Rochelle-Teddy-Thomas-signe-finalement-avec-un-cador-du-Top-14-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/Transferts-La-Rochelle-Teddy-Thomas-signe-finalement-avec-un-cador-du-Top-14-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts Stade Toulousain 2025 : Recrues, d\u00e9parts et prolongations<\/div><div class=\"vlp-block-1 vlp-link-summary\">Arriv\u00e9es, d\u00e9parts et prolongations au Stade Toulousain<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s&rsquo;engager avec Brive.<\/p>\n","protected":false},"author":1,"featured_media":558819,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,13,110,29105],"class_list":["post-558816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Yann Peysson va quitter Castres pour signer en Pro D2<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s&#039;engager avec Brive.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s&#039;engager avec Brive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-24T09:05:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T09:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2\",\"datePublished\":\"2025-02-24T09:05:28+00:00\",\"dateModified\":\"2025-02-24T09:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\",\"name\":\"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png\",\"datePublished\":\"2025-02-24T09:05:28+00:00\",\"dateModified\":\"2025-02-24T09:12:17+00:00\",\"description\":\"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s'engager avec Brive.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2","description":"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s'engager avec Brive.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2","og_description":"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s'engager avec Brive.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-24T09:05:28+00:00","article_modified_time":"2025-02-24T09:12:17+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2","datePublished":"2025-02-24T09:05:28+00:00","dateModified":"2025-02-24T09:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png","keywords":["actu","br\u00e8ve","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/","name":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png","datePublished":"2025-02-24T09:05:28+00:00","dateModified":"2025-02-24T09:12:17+00:00","description":"TRANSFERTS RUGBY - Selon le Midi Olympique, Yann Peysson (24 ans) va quitter le Castres Olympique cet \u00e9t\u00e9 pour s'engager avec Brive.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Yann-Peysson-va-quitter-Castres-pour-signer-en-Pro-D2.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-yann-peysson-va-quitter-castres-pour-signer-en-pro-d2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Yann Peysson va quitter Castres pour signer en Pro D2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=558816"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558816\/revisions"}],"predecessor-version":[{"id":558821,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558816\/revisions\/558821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/558819"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=558816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=558816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=558816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}