{"id":558955,"date":"2025-02-26T14:26:19","date_gmt":"2025-02-26T13:26:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=558955&#038;preview=true&#038;preview_id=558955"},"modified":"2025-03-02T18:17:00","modified_gmt":"2025-03-02T17:17:00","slug":"stade-briochin-psg-heure-chaine-tv-cotes-et-compositions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/","title":{"rendered":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>COUPE DE FRANCE &#8211; \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre Saint-Brieuc et le PSG, dans le cadre des quarts de finale de Coupe de France ?<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-de-football-le-tirage-au-sort-des-quarts-de-finale\/\"><strong>Le tirage au sort des quarts de finale de la Coupe de France<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le<b> Stade Briochin <\/b>est en milieu de tableau de son groupe de <strong>National<\/strong> <strong>2,<\/strong> et reste sur une belle victoire face \u00e0 <strong>Granville<\/strong>, 6 \u00e0 2. Avant cela, le club de <strong>Saint-Brieuc<\/strong> avait encha\u00een\u00e9 deux d\u00e9faites face \u00e0 la <strong>Roche-sur-Yon<\/strong> et les <strong>Herbiers<\/strong>. En <strong>Coupe de France<\/strong>, le <strong>Stade<\/strong> <strong>Briochin<\/strong> a notamment \u00e9limin\u00e9 <strong>Nice<\/strong>, <strong>Annecy<\/strong> et <strong>Le<\/strong> <strong>Havre<\/strong> pour acc\u00e9der aux quarts de finale.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/\"><strong>L&rsquo;actualit\u00e9 du football<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Qui va arr\u00eater le <strong>Paris Saint-Germain<\/strong> ? Les joueurs de <strong>Luis<\/strong> <strong>Enrique<\/strong> ont remport\u00e9 17 de leurs 18 derniers matchs. Seul le Stade Brestois a r\u00e9ussi \u00e0 faire un nul face aux <strong>Parisiens<\/strong> ces derni\u00e8res semaines. Le week-end pass\u00e9, le <strong>PSG<\/strong> est venu \u00e0 bout de l&rsquo;Olympique Lyonnais sur le score de 3 buts \u00e0 2 avec notamment un doubl\u00e9 d&rsquo;<strong>Achraf<\/strong> <strong>Hakimi<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Les deux \u00e9quipes ne se sont jamais affront\u00e9es, et ce sera donc une grande premi\u00e8re ce mercredi soir. Chez les bookmakers, le <strong>PSG<\/strong> est largement favori pour cette rencontre de Coupe de France.<\/p>\n<h2 style=\"text-align: justify;\">Coupe de France : Le programme TV de Stade Briochin-PSG<\/h2>\n<h3 style=\"text-align: justify;\">Mercredi 26 f\u00e9vrier 2025<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur France 3 <\/b>&amp;<b> beIN SPORTS 1<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 21h10.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions de Stade Briochin-PSG<\/h2>\n<h3 style=\"text-align: justify;\">La composition de Stade Briochin<\/h3>\n<p style=\"text-align: justify;\">L&rsquo;Hostis &#8211; Le Marer, Angoua, Kerbrat, Boudin, Diakit\u00e9 &#8211; Beghin, Yob\u00e9, Zakharyan &#8211; Janno, Konan<\/p>\n<h3 style=\"text-align: justify;\">La composition du PSG<\/h3>\n<p style=\"text-align: justify;\">Safonov &#8211; Beraldo, Marquinhos, Pacho, Hernandez &#8211; Mayulu, Neves, Ruiz &#8211; Dou\u00e9, Ramos, Kvaratskhelia<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Stade Briochin-PSG<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Mercredi 26 f\u00e9vrier, 21h10<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Stade Briochin<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/57886915?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#101339;border-color:#0d102e;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#585a75;border-radius:5px;text-shadow:none\"> 21<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/57886915?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#101339;border-color:#0d102e;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#585a75;border-radius:5px;text-shadow:none\"> 9.50<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>PSG<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/57886915?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#101339;border-color:#0d102e;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#585a75;border-radius:5px;text-shadow:none\"> 1.10<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DE FRANCE &#8211; \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?<\/p>\n","protected":false},"author":1,"featured_media":558979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,2301],"tags":[16878,17213,2870,75,21768,8799,910],"class_list":["post-558955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-football","tag-breve","tag-chaine","tag-coupe-de-france","tag-football","tag-horaire","tag-programme-tv","tag-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions<\/title>\n<meta name=\"description\" content=\"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions\" \/>\n<meta property=\"og:description\" content=\"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-26T13:26:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T17:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions\",\"datePublished\":\"2025-02-26T13:26:19+00:00\",\"dateModified\":\"2025-03-02T17:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\"},\"wordCount\":388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"keywords\":[\"br\u00e8ve\",\"Cha\u00eene\",\"Coupe de France\",\"Football\",\"Horaire\",\"Programme TV\",\"PSG\"],\"articleSection\":[\"Cha\u00eene TV\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\",\"name\":\"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"datePublished\":\"2025-02-26T13:26:19+00:00\",\"dateModified\":\"2025-03-02T17:17:00+00:00\",\"description\":\"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions","description":"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/","og_locale":"fr_FR","og_type":"article","og_title":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions","og_description":"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?","og_url":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-26T13:26:19+00:00","article_modified_time":"2025-03-02T17:17:00+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions","datePublished":"2025-02-26T13:26:19+00:00","dateModified":"2025-03-02T17:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/"},"wordCount":388,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png","keywords":["br\u00e8ve","Cha\u00eene","Coupe de France","Football","Horaire","Programme TV","PSG"],"articleSection":["Cha\u00eene TV","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/","url":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/","name":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png","datePublished":"2025-02-26T13:26:19+00:00","dateModified":"2025-03-02T17:17:00+00:00","description":"COUPE DE FRANCE - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match entre le Stade Briochin et le PSG, dans le cadre des quarts de finale de Coupe de France ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Stade-Briochin-PSG-Heure-Chaine-TV-Cotes-et-Compositions.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/stade-briochin-psg-heure-chaine-tv-cotes-et-compositions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Saint-Brieuc PSG : Heure, Cha\u00eene TV, Cotes et Compositions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=558955"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558955\/revisions"}],"predecessor-version":[{"id":560762,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/558955\/revisions\/560762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/558979"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=558955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=558955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=558955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}