{"id":560012,"date":"2025-02-28T23:03:00","date_gmt":"2025-02-28T22:03:00","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=560012&#038;preview=true&#038;preview_id=560012"},"modified":"2025-02-28T23:39:35","modified_gmt":"2025-02-28T22:39:35","slug":"pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/","title":{"rendered":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong><em>PRO D2 2024-2025 &#8211; Biarritz est revenu de l&rsquo;enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble a d\u00e9roul\u00e9 \u00e0 domicile. Le BOPB \u00e9tait men\u00e9 de 19 points \u00e0 la pause dans l&rsquo;Ain, avant de r\u00e9aliser 20 derni\u00e8res minutes monumentales (36-29). Grenoble a encore inscrit une valise d&rsquo;essais et est plus que jamais leader (45-14).<\/em><\/strong><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2024-2025\/\">Classement Pro D2 2024-2025<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Le choc du jour : Grenoble \u00e9tait trop fort pour B\u00e9ziers<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;\u00e9tait le choc de la soir\u00e9e, entre deux des \u00e9quipes les plus s\u00e9duisantes de cette Pro D2. On attendait du beau spectacle entre Grenoble et B\u00e9ziers. Cela s&rsquo;est transform\u00e9 en massacre Alpestre d\u00e8s le premier acte. Grenoble est d\u00e9cid\u00e9ment une machine \u00e0 broyer ses adversaires.<\/p>\n<p style=\"text-align: justify;\">D\u00e8s le premier acte, un impitoyable 31-0. Avec cinq essais inscrits et aucun points encaiss\u00e9s. \u00c0 peine le premier quart d&rsquo;heure pass\u00e9, que le ton \u00e9tait donn\u00e9. Trois essais pour les Grenoblois. D&rsquo;abord un doubl\u00e9 de<strong> Wilfried Hulleu,<\/strong> qui inscrit alors ses 13 et 14e essais de la saison, rejoignant alors un certain <strong>Gabin Lorre,<\/strong> qui, en face, n&rsquo;a jamais eu de munitions. Puis un troisi\u00e8me essai du talonneur <strong>Bastien Soury,<\/strong> pour mener 17-0. La machine \u00e0 concasser ne s&rsquo;est pas arr\u00eat\u00e9e l\u00e0. Avec deux essais de <strong>Gerswin Mouton<\/strong> (25e) et <strong>Johannes Jonker<\/strong> (33e). Les Biterrois tenteront de r\u00e9agir en fin de premier acte, mais il n&rsquo;y avait rien \u00e0 faire dans ce premier acte. Avec deux situations d&rsquo;essais qui ne vont pas aller au bout.<\/p>\n<p style=\"text-align: justify;\">Le second acte sera un peu plus fade que le premier. Grenoble a assur\u00e9 dans le premier acte. Le point noir de cette soir\u00e9e sera ce carton rouge pour<strong> Brandon Nansen<\/strong> (43e), rattrap\u00e9 par la vid\u00e9o. Il y aura un moment de flottement. <strong>Antoine Payrastre<\/strong> profite de la double sup\u00e9riorit\u00e9 pour passer en force et sonner la r\u00e9volte des visiteurs (31-7, 46e). Mais m\u00eame \u00e0 14, m\u00eame un peu bouscul\u00e9, cette \u00e9quipe de Grenoble est trop forte. Et <strong>Bastien Soury<\/strong> s&rsquo;offre \u00e0 son tour son doubl\u00e9 (38-7, 53e). Afin de r\u00e9primer toute r\u00e9volte. Et si <strong>Harry Glynn<\/strong> inscrit un essai (38-14, 72e),<strong> Barnab\u00e9 Couilloud<\/strong> frappe imm\u00e9diatement, pour r\u00e9tablir l&rsquo;\u00e9quilibre (45-14, 75e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Trasnformation r\u00e9ussie !<br \/>\n\ud83d\udd34\ud83d\udd35 FCG 45 &#8211; 14 B\u00e9ziers \ud83d\udd34\ud83d\udd35<a href=\"https:\/\/twitter.com\/hashtag\/FCGASBH?src=hash&amp;ref_src=twsrc%5Etfw\">#FCGASBH<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/AllezFCG?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezFCG<\/a> <a href=\"https:\/\/t.co\/hpOiumpr6T\">pic.twitter.com\/hpOiumpr6T<\/a><\/p>\n<p>\u2014 FC Grenoble Rugby #AllezFCG (@FCGrugby) <a href=\"https:\/\/twitter.com\/FCGrugby\/status\/1895593274087469365?ref_src=twsrc%5Etfw\">February 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le gagnant du jour : Biarritz a tout renvers\u00e9<\/h2>\n<p style=\"text-align: justify;\">Au bord du gouffre en championnat, avec sept d\u00e9faites cons\u00e9cutives et au bord du gouffre dans un match dans lequel ils ont \u00e9t\u00e9 men\u00e9s de plus de 15 points sur la pelouse d&rsquo;Oyonnax, Biarritz a totalement ressuscit\u00e9. Pour renverser des Aindinois qui ont pris une tornade dans les 20 derni\u00e8res minutes. Comme si tout ne marchait pas s&rsquo;\u00e9tait mis \u00e0 marcher tout d&rsquo;un coup. Avec des essais de <strong>Thomas Dologaray<\/strong> (59e), <strong>Fran\u00e7ois Vergnaud<\/strong> (63e), avant que le coup de gr\u00e2ce ne vienne du jeune Basque de 18 ans <strong>Anoa Laurent<\/strong>. Comme un symbole, c&rsquo;est un minot du BOPB qui offre la victoire \u00e0 son \u00e9quipe. Un succ\u00e8s en d\u00e9placement qui \u00e9tait tellement inesp\u00e9r\u00e9 \u00e0 la mi-temps (26-7).<\/p>\n<p style=\"text-align: justify;\">Oyonnax a donc encaiss\u00e9 un 29-3 dans le second acte. Pire encore, c&rsquo;est une d\u00e9faite \u00e0 0 point \u00e0 domicile. Qui les mets \u00e0 12 points de retard sur le Top 6 occup\u00e9 par le SA XV (lire plus bas). Surtout, la zone rouge se rapproche de nouveau pour les Oyomens. Qui n&rsquo;ont plus que cinq points d&rsquo;avance sur Valence-Romans. Et sont rejoints par leur adversaire du soir, qui se donne un \u00e9norme bol d&rsquo;air au meilleur moment. Dans un match et dans un lieu qu&rsquo;on aurait pu penser hostile pour eux.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83e\udd73 \ud835\udde9\ud835\udddc\ud835\uddd6\ud835\udde7\ud835\udde2\ud835\udddc\ud835\udde5\ud835\uddd8 avec \ud835\udde0\ud835\uddf6\ud835\uddfb\ud835\uddf1\ud835\ude02\ud835\uddff\ud835\uddff\ud835\ude06 \ud835\udde3\ud835\uddff\ud835\uddfc\ud835\uddfa\ud835\uddfc\ud835\ude01\ud835\uddf6\ud835\uddfc\ud835\uddfb<\/p>\n<p>Celle-l\u00e0 : elle fait un bien fou ! Bravo \u00e0 nos Rouge &amp; Blanc ! \ud83e\udd29<br \/>\nM\u00eame envie vendredi prochain contre Dax \ud83d\udc4a<a href=\"https:\/\/twitter.com\/hashtag\/OYOBO?src=hash&amp;ref_src=twsrc%5Etfw\">#OYOBO<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/BOPB?src=hash&amp;ref_src=twsrc%5Etfw\">#BOPB<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/AupaBO?src=hash&amp;ref_src=twsrc%5Etfw\">#AupaBO<\/a> | 2\ufe0f\u20e39\ufe0f\u20e3-3\ufe0f\u20e36\ufe0f\u20e3 <a href=\"https:\/\/t.co\/DLiGVnujIN\">pic.twitter.com\/DLiGVnujIN<\/a><\/p>\n<p>\u2014 BOPBweb (@BOPBweb) <a href=\"https:\/\/twitter.com\/BOPBweb\/status\/1895569802485547248?ref_src=twsrc%5Etfw\">February 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le perdant du jour : Dax s&rsquo;effrite \u00e0 domicile<\/h2>\n<p style=\"text-align: justify;\">Dax avait b\u00e2ti son incroyable saison 2023-2024 sur une \u00e9norme solidit\u00e9 \u00e0 domicile. D\u00e9sormais, les Dacquois souffrent de plus en plus chez eux. Avec une troisi\u00e8me d\u00e9faite en douze matchs ce vendredi soir. Cueillis par une \u00e9quipe de Nevers qui encha\u00eene l\u00e0 une seconde victoire de rang. La troisi\u00e8me en d\u00e9placement pour les Nivernais, qui ont fait le plus dur dans un match tendu (19-17). Un petit score, mais quatre essais tout de m\u00eame, deux de chaque c\u00f4t\u00e9.<strong> Simon Tarel<\/strong> (34e) et <strong>Chris Gabriel<\/strong> (66e) qui ont \u00e9t\u00e9 en terre promise pour les visiteurs qui ont inscrit deux p\u00e9nalit\u00e9s de plus que son adversaire. Qui contrebalance les deux transformations de Dax.<\/p>\n<p style=\"text-align: justify;\">Avec ce succ\u00e8s, Nevers, longtemps en grande difficult\u00e9 dans cette Pro D2, se projette, pour la premi\u00e8re fois de la saison, dans la bonne moiti\u00e9 de ce championnat, \u00e0 la 8e place. Certes \u00e0 9 points de la 6e place, mais avec sept points d&rsquo;avance sur le barragiste. Et double Dax, qui va commencer, pour la premi\u00e8re fois de la saison, \u00e0 regarder vers le bas. Ils n&rsquo;ont plus que six points d&rsquo;avance sur Valence-Romans. Ce championnat est spectaculaire et les autres r\u00e9sultats nous le montrent.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Avec une grosse d\u00e9fense de nos jaunets, c\u2019est une troisi\u00e8me victoire \u00e0 l\u2019ext\u00e9rieur de la saison au compteur ! \ud83d\udd25<\/p>\n<p>Bravo messieurs \ud83d\udc99 <a href=\"https:\/\/t.co\/N9KTTYgTbT\">pic.twitter.com\/N9KTTYgTbT<\/a><\/p>\n<p>\u2014 USON NEVERS RUGBY (@usonneversrugby) <a href=\"https:\/\/twitter.com\/usonneversrugby\/status\/1895590697153290429?ref_src=twsrc%5Etfw\">February 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les autres r\u00e9sultats<\/h2>\n<p style=\"text-align: justify;\">Dans le premier match de ce vendredi, <strong>Colomiers<\/strong> a longtemps \u00e9t\u00e9 derri\u00e8re<strong> Brive<\/strong>. Mais les Colum\u00e9rins, \u00e0 domicile, arrache un court, mais pr\u00e9cieux succ\u00e8s contre les Corr\u00e9ziens (20-19), dans un match tr\u00e8s accroch\u00e9. Et continuent de lorgner vers le haut de tableau. Mais glissent d&rsquo;une place, sortent du Top 6. Car, quelques minutes plus tard, <strong>Soyaux-Angoul\u00eame<\/strong> a remport\u00e9 un succ\u00e8s bonifi\u00e9 \u00e0 Chanzy contre <strong>Aurillac (40-20), <\/strong>dans un match \u00e0 8 essais. Et reviennent, eux aussi, \u00e0 57 points. Mais ont la diff\u00e9rence particuli\u00e8re \u00e0 leur avantage par rapport \u00e0 Colomiers. Incroyables Angoumoisins qui s&rsquo;accrochent au Top 6. Alors qu&rsquo;Aurillac profite de mauvais r\u00e9sultats, pour rester hors de la place de barragiste \u00e0 la 14e place. Brive recule, \u00e0 l&rsquo;issue de la 22e journ\u00e9e, de la 2e \u00e0 la 3e place.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udd1a \ud835\ude41\ud835\ude5e\ud835\ude63 \ud835\ude59\ud835\ude5a \ud835\ude62\ud835\ude56\ud835\ude69\ud835\ude58\ud835\ude5d \ud835\ude56\u0300 \ud835\ude3e\ud835\ude5d\ud835\ude56\ud835\ude63\ud835\ude6f\ud835\ude6e<br \/>\nUn match s\u00e9rieux de nos violets qui s\u2019imposent avec le bonus offensif face \u00e0 Aurillac ! \ud83e\udee1<br \/>\nMerci \u00e0 tous pour votre soutien ! \ud83e\udd70<br \/>\n<a href=\"https:\/\/twitter.com\/hashtag\/PROD2?src=hash&amp;ref_src=twsrc%5Etfw\">#PROD2<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/SAXVSACA?src=hash&amp;ref_src=twsrc%5Etfw\">#SAXVSACA<\/a> <a href=\"https:\/\/t.co\/x9upb5MJmS\">pic.twitter.com\/x9upb5MJmS<\/a><\/p>\n<p>\u2014 SA XV Charente Rugby (@SAXV_Charente) <a href=\"https:\/\/twitter.com\/SAXV_Charente\/status\/1895570006811029727?ref_src=twsrc%5Etfw\">February 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Bouscul\u00e9 par une \u00e9quipe de <strong>Nice<\/strong> qui a encore envie d&rsquo;exister dans cette Pro D2, <strong>Mont-de-Marsan<\/strong> s&rsquo;en est sorti \u00e0 domicile et frappe un joli coup dans la lutte pour le maintien. Avec une victoire <strong>26-22<\/strong>. Un ouf de soulagement et un bol d&rsquo;air au classement. Avec sept points d&rsquo;avance sur le barragiste Valence-Romans. Alors que Nice se rapproche encore plus de la Nationale. Dans le match de la peur, Agen a souffert \u00e0 domicile contre Valence-Romans. Mais ce sont bien les Agenais qui font la bonne op\u00e9ration, en l&#8217;emportant de trois points (26-23). Agen prend trois points d&rsquo;avance sur son adversaire, qui redevient barragiste. N\u00e9anmoins, les Dr\u00f4mois ne repartent pas les mains vides et confirment qu&rsquo;ils sont dans le coup dans ce championnat.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udc73\ud835\udc82 \ud835\udc97\ud835\udc8a\ud835\udc84\ud835\udc95\ud835\udc90\ud835\udc8a\ud835\udc93\ud835\udc86 ! \ud83d\udd25 Nos joueurs ont tout donn\u00e9 pour s\u2019imposer au terme d\u2019un match intense. Merci pour votre soutien \ud83d\udc99\ud83e\udd0d <a href=\"https:\/\/t.co\/GzlOgH7m9k\">pic.twitter.com\/GzlOgH7m9k<\/a><\/p>\n<p>\u2014 Agen Rugby &#8211; SUA LG (@agen_rugby) <a href=\"https:\/\/twitter.com\/agen_rugby\/status\/1895569924988526866?ref_src=twsrc%5Etfw\">February 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2024-2025 &#8211; Biarritz est revenu de l&rsquo;enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble a d\u00e9roul\u00e9 \u00e0 domicile.<\/p>\n","protected":false},"author":83,"featured_media":560045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[32415,16878,1839],"class_list":["post-560012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-actu","tag-breve","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir<\/title>\n<meta name=\"description\" content=\"PRO D2 2024-2025 - Biarritz est revenu de l&#039;enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2024-2025 - Biarritz est revenu de l&#039;enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T22:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T22:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\",\"datePublished\":\"2025-02-28T22:03:00+00:00\",\"dateModified\":\"2025-02-28T22:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/\"},\"wordCount\":1262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/\",\"name\":\"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png\",\"datePublished\":\"2025-02-28T22:03:00+00:00\",\"dateModified\":\"2025-02-28T22:39:35+00:00\",\"description\":\"PRO D2 2024-2025 - Biarritz est revenu de l'enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png\",\"width\":1200,\"height\":674,\"caption\":\"Pro D2 (J21) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/etienne-goursaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir","description":"PRO D2 2024-2025 - Biarritz est revenu de l'enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir","og_description":"PRO D2 2024-2025 - Biarritz est revenu de l'enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.","og_url":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-02-28T22:03:00+00:00","article_modified_time":"2025-02-28T22:39:35+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir","datePublished":"2025-02-28T22:03:00+00:00","dateModified":"2025-02-28T22:39:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/"},"wordCount":1262,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png","keywords":["actu","br\u00e8ve","Pro D2"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/","url":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/","name":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png","datePublished":"2025-02-28T22:03:00+00:00","dateModified":"2025-02-28T22:39:35+00:00","description":"PRO D2 2024-2025 - Biarritz est revenu de l'enfer pour d\u00e9crocher \u00e0 Oyonnax son premier succ\u00e8s en 2025, alors que Grenoble \u00e0 d\u00e9roul\u00e9 \u00e0 domicile.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Pro-D2-J21-Biarritz-renversant-Grenoble-ecrasant-le-resume-du-vendredi-soir.png","width":1200,"height":674,"caption":"Pro D2 (J21) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j21-biarritz-renversant-grenoble-ecrasant-le-resume-du-vendredi-soir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pro D2 (J22) : Biarritz renversant, Grenoble \u00e9crasant, le r\u00e9sum\u00e9 du vendredi soir"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=560012"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560012\/revisions"}],"predecessor-version":[{"id":560070,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560012\/revisions\/560070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/560045"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=560012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=560012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=560012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}