{"id":56007,"date":"2020-01-02T08:52:35","date_gmt":"2020-01-02T07:52:35","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=56007&#038;preview=true&#038;preview_id=56007"},"modified":"2021-10-18T17:01:26","modified_gmt":"2021-10-18T15:01:26","slug":"calendrier-xv-de-france-2020","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/","title":{"rendered":"Le calendrier du XV de France en 2020"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>C&rsquo;est une ann\u00e9e 2020 copieuse qui attend le <a href=\"https:\/\/www.ffr.fr\/actualites\/xv-de-france\" target=\"_blank\" rel=\"noopener noreferrer\">XV de France<\/a> du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.<br \/>\n<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Dimanche 2 f\u00e9vrier, 16h<\/h2>\n<p style=\"text-align: justify;\"><strong>6 Nations :<\/strong> France &#8211; Angleterre au Stade de France<\/p>\n<h2 style=\"text-align: justify;\">Samedi 8 f\u00e9vrier, 16h<\/h2>\n<p style=\"text-align: justify;\"><strong>6 Nations :<\/strong> France &#8211; Italie au Stade de France<\/p>\n<h2 style=\"text-align: justify;\">Samedi 22 f\u00e9vrier, 17h45<\/h2>\n<p style=\"text-align: justify;\"><strong>6 Nations :<\/strong> Pays de Galles &#8211; France au Principality Stadium, Cardiff<\/p>\n<h2 style=\"text-align: justify;\">Dimanche 8 mars, 16h<\/h2>\n<p style=\"text-align: justify;\"><strong>6 Nations :<\/strong> \u00c9cosse &#8211; France \u00e0 Murrayfield, \u00c9dimbourg<\/p>\n<h2 style=\"text-align: justify;\">Samedi 14 mars, 21h<\/h2>\n<p style=\"text-align: justify;\"><strong>6 Nations :<\/strong> France &#8211; Irlande au Stade de France <strong>REPORT\u00c9<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Samedi 4 juillet<\/h2>\n<p style=\"text-align: justify;\"><strong>Tourn\u00e9e d&rsquo;\u00e9t\u00e9 :<\/strong> Argentine &#8211; France<\/p>\n<h2 style=\"text-align: justify;\">Samedi 11 juillet<\/h2>\n<p style=\"text-align: justify;\"><strong>Tourn\u00e9e d&rsquo;\u00e9t\u00e9 :<\/strong> Argentine &#8211; France<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Samedi 7 novembre<\/h2>\n<p style=\"text-align: justify;\"><strong>Tourn\u00e9e d&rsquo;automne :<\/strong> France &#8211; G\u00e9orgie au Stade Geoffroy Guichard, Saint-\u00c9tienne<\/p>\n<h2 style=\"text-align: justify;\">Samedi 14 novembre<\/h2>\n<p style=\"text-align: justify;\"><strong>Tourn\u00e9e d&rsquo;automne :<\/strong> France &#8211; Australie au Stade de France<\/p>\n<h2 style=\"text-align: justify;\">Samedi 21 novembre<\/h2>\n<p style=\"text-align: justify;\"><strong>Tourn\u00e9e d&rsquo;automne :<\/strong> France &#8211; Afrique du Sud au Stade de France<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.<\/p>\n","protected":false},"author":4,"featured_media":56022,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,19951],"tags":[13,1638],"class_list":["post-56007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-rugby","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le calendrier du XV de France en 2020<\/title>\n<meta name=\"description\" content=\"C&#039;est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le calendrier du XV de France en 2020\" \/>\n<meta property=\"og:description\" content=\"C&#039;est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-02T07:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T15:01:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le calendrier du XV de France en 2020\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Le calendrier du XV de France en 2020\",\"datePublished\":\"2020-01-02T07:52:35+00:00\",\"dateModified\":\"2021-10-18T15:01:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\"},\"wordCount\":154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png\",\"keywords\":[\"Rugby\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\",\"name\":\"Le calendrier du XV de France en 2020\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png\",\"datePublished\":\"2020-01-02T07:52:35+00:00\",\"dateModified\":\"2021-10-18T15:01:26+00:00\",\"description\":\"C'est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png\",\"width\":800,\"height\":445,\"caption\":\"Le calendrier du XV de France en 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le calendrier du XV de France en 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le calendrier du XV de France en 2020","description":"C'est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Le calendrier du XV de France en 2020","og_description":"C'est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.","og_url":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-01-02T07:52:35+00:00","article_modified_time":"2021-10-18T15:01:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Le calendrier du XV de France en 2020","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Le calendrier du XV de France en 2020","datePublished":"2020-01-02T07:52:35+00:00","dateModified":"2021-10-18T15:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/"},"wordCount":154,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png","keywords":["Rugby","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/","url":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/","name":"Le calendrier du XV de France en 2020","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png","datePublished":"2020-01-02T07:52:35+00:00","dateModified":"2021-10-18T15:01:26+00:00","description":"C'est une ann\u00e9e 2020 copieuse qui attend le XV de France du nouveau s\u00e9lectionneur, Fabien Galthi\u00e9. Le calendrier complet des Bleus.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/01\/Le-calendrier-du-XV-de-France-en-2020.png","width":800,"height":445,"caption":"Le calendrier du XV de France en 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/calendrier-xv-de-france-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le calendrier du XV de France en 2020"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/56007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=56007"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/56007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/56022"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=56007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=56007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=56007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}