{"id":560956,"date":"2025-03-04T12:39:04","date_gmt":"2025-03-04T11:39:04","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=560956&#038;preview=true&#038;preview_id=560956"},"modified":"2025-09-16T08:51:46","modified_gmt":"2025-09-16T06:51:46","slug":"dortmund-lille-heure-chaine-tv-compositions-et-cotes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/","title":{"rendered":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE DES CHAMPIONS<b> &#8211; <\/b><\/em><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes<\/em><em>.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-ligue-des-champions-le-tableau-complet\/https:\/\/dicodusport.fr\/blog\/phase-finale-ligue-des-champions-le-tableau-complet\/\" target=\"_blank\" rel=\"noopener\">Phase finale Ligue des Champions : Le tableau complet<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Dortmund a d\u00fb passer par les barrages pour se qualifier en huiti\u00e8me de finale de la <strong>Ligue des Champions<\/strong>. Les <strong>Allemands<\/strong> sont venus \u00e0 bout du <strong>Sporting<\/strong> gr\u00e2ce \u00e0 une large victoire au Portugal. En championnat, le <strong>Borussia<\/strong> <strong>Dortmund<\/strong> vit une saison bien plus compliqu\u00e9e, et est seulement dixi\u00e8me apr\u00e8s 24 journ\u00e9es, avec 35 points au compteur.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/\"><strong>L&rsquo;actualit\u00e9 du football<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Lille<\/strong> s&rsquo;est de son c\u00f4t\u00e9 qualifi\u00e9 directement pour les huiti\u00e8mes de finale, et n&rsquo;a donc pas eu \u00e0 encha\u00eener les matchs au mois de f\u00e9vrier. Les <strong>Lillois<\/strong> restent n\u00e9anmoins sur une large d\u00e9faite face au <strong>Paris Saint-Germain<\/strong> le week-end dernier. Le <strong>LOSC<\/strong> est cinqui\u00e8me de Ligue 1, toujours en course pour une qualification en <strong>Ligue<\/strong> <strong>des<\/strong> <strong>Champions<\/strong> la saison prochaine.<\/p>\n<p style=\"text-align: justify;\">En 2022, les deux \u00e9quipes se sont affront\u00e9es deux fois pour deux matchs nuls. Chez les bookmakers, <strong>Dortmund<\/strong> est favori pour cette rencontre de <strong>Ligue<\/strong> <strong>des<\/strong> <strong>Champions<\/strong> face \u00e0 <strong>Lille<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Ligue des Champions : Le programme TV de Dortmund-Lille<\/h2>\n<h3 style=\"text-align: justify;\">Mardi 4 mars 2024<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur Canal+ Foot<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 21h00.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions probables de Dortmund-Lille<\/h2>\n<h3 style=\"text-align: justify;\">La composition de Dortmund<\/h3>\n<p style=\"text-align: justify;\">Kobel &#8211;\u00a0Couto, Can, Schlotterbeck, Benseba\u00efni &#8211; Sabitzer, Gross &#8211; Adeyemi, Brandt, Gittens &#8211;\u00a0Guirassy<\/p>\n<h3 style=\"text-align: justify;\">La composition de Lille<\/h3>\n<p style=\"text-align: justify;\">Chevalier &#8211; Meunier, Diakit\u00e9, Alexsandro, Gudmundsson &#8211;\u00a0Andr\u00e9, Bouaddi &#8211;\u00a0Haraldsson, Angel Gomes, Bakker &#8211;\u00a0David<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Dortmund-Lille<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Mardi 4 mars, 21h00<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Dortmund<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/58261985?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.66<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/58261985?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 4.00<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Lille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/58261985?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 5.10<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS &#8211; \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/p>\n","protected":false},"author":1,"featured_media":560974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[16878,17213,4085,75,21768,419,451,2391,8799],"class_list":["post-560956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-breve","tag-chaine","tag-dortmund","tag-football","tag-horaire","tag-ligue-des-champions","tag-lille","tag-losc","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-04T11:39:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T06:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes\",\"datePublished\":\"2025-03-04T11:39:04+00:00\",\"dateModified\":\"2025-09-16T06:51:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png\",\"keywords\":[\"br\u00e8ve\",\"Cha\u00eene\",\"Dortmund\",\"Football\",\"Horaire\",\"Ligue des champions\",\"Lille\",\"LOSC\",\"Programme TV\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\",\"name\":\"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png\",\"datePublished\":\"2025-03-04T11:39:04+00:00\",\"dateModified\":\"2025-09-16T06:51:46+00:00\",\"description\":\"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes","description":"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/","og_locale":"fr_FR","og_type":"article","og_title":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes","og_description":"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-03-04T11:39:04+00:00","article_modified_time":"2025-09-16T06:51:46+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes","datePublished":"2025-03-04T11:39:04+00:00","dateModified":"2025-09-16T06:51:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png","keywords":["br\u00e8ve","Cha\u00eene","Dortmund","Football","Horaire","Ligue des champions","Lille","LOSC","Programme TV"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/","url":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/","name":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png","datePublished":"2025-03-04T11:39:04+00:00","dateModified":"2025-09-16T06:51:46+00:00","description":"LIGUE DES CHAMPIONS - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des Champions entre Dortmund et Lille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Dortmund-Lille-Heure-Chaine-TV-Compositions-et-Cotes.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dortmund-lille-heure-chaine-tv-compositions-et-cotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dortmund-Lille : Compositions, Heure, Cha\u00eene TV et Cotes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=560956"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560956\/revisions"}],"predecessor-version":[{"id":561099,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/560956\/revisions\/561099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/560974"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=560956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=560956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=560956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}