{"id":563297,"date":"2025-03-12T00:06:26","date_gmt":"2025-03-11T23:06:26","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=563297&#038;preview=true&#038;preview_id=563297"},"modified":"2025-09-16T07:59:33","modified_gmt":"2025-09-16T05:59:33","slug":"video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/","title":{"rendered":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em><b>LIGUE DES CHAMPIONS 2024-2025 &#8211; Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/b><\/em><\/h4>\n<p style=\"text-align: justify;\">Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-liverpool-realise-un-braquage-a-langlaise-face-au-psg\/\">la victoire 1 \u00e0 0 de Liverpool<\/a> au <strong>Parc<\/strong> <strong>des<\/strong> <strong>Princes<\/strong>, le <strong>Paris Saint-Germain<\/strong> doit faire un exploit \u00e0 <strong>Anfield<\/strong> pour esp\u00e9rer rejoindre les quarts de finale de la <strong>Ligue<\/strong> <strong>des<\/strong> <strong>Champions<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a title=\"Phase finale Ligue des Champions : Le tableau complet\" href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-ligue-des-champions-le-tableau-complet\/\" rel=\"\">Phase finale Ligue des Champions : Le tableau complet<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Ligue des champions : Le r\u00e9sum\u00e9 vid\u00e9o de Liverpool &#8211; PSG<\/h2>\n<p><span class=\"hGPjZcKEJ5OCJdzlgrbH1vFmRRThfVojsYnpuCD5L4o7SrADnlL3dA96iz02iQgOYv4xf8sPBZBQ\"><iframe loading=\"lazy\" title=\"Le r\u00e9sum\u00e9 de Liverpool \/ PSG - Ligue des champions 2024-25 (1\/8e de finale retour)\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/a6MsxYJWE1c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.<\/p>\n","protected":false},"author":1,"featured_media":563300,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[16878,75,419,3120,910,4605],"class_list":["post-563297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-breve","tag-football","tag-ligue-des-champions","tag-liverpool","tag-psg","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions<\/title>\n<meta name=\"description\" content=\"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions\" \/>\n<meta property=\"og:description\" content=\"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T23:06:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T05:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions\",\"datePublished\":\"2025-03-11T23:06:26+00:00\",\"dateModified\":\"2025-09-16T05:59:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\"},\"wordCount\":103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue des champions\",\"Liverpool\",\"PSG\",\"vid\u00e9o\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\",\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png\",\"datePublished\":\"2025-03-11T23:06:26+00:00\",\"dateModified\":\"2025-09-16T05:59:33+00:00\",\"description\":\"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions","description":"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions","og_description":"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","og_url":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-03-11T23:06:26+00:00","article_modified_time":"2025-09-16T05:59:33+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions","datePublished":"2025-03-11T23:06:26+00:00","dateModified":"2025-09-16T05:59:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/"},"wordCount":103,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png","keywords":["br\u00e8ve","Football","Ligue des champions","Liverpool","PSG","vid\u00e9o"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/","url":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/","name":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png","datePublished":"2025-03-11T23:06:26+00:00","dateModified":"2025-09-16T05:59:33+00:00","description":"Ce mardi, Liverpool recevait le PSG en 8\u00e8me de finale retour de Ligue des champions. Voici le r\u00e9sum\u00e9 vid\u00e9o du match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Video-Resume-Liverpool-PSG-8eme-de-finale-retour-de-Ligue-des-champions.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/video-resume-liverpool-psg-8eme-de-finale-retour-de-ligue-des-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] R\u00e9sum\u00e9 Liverpool-PSG, 8\u00e8me de finale retour de Ligue des champions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=563297"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563297\/revisions"}],"predecessor-version":[{"id":563322,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563297\/revisions\/563322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/563300"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=563297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=563297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=563297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}