{"id":563646,"date":"2025-03-13T14:09:19","date_gmt":"2025-03-13T13:09:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=563646&#038;preview=true&#038;preview_id=563646"},"modified":"2025-03-13T14:35:26","modified_gmt":"2025-03-13T13:35:26","slug":"equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/","title":{"rendered":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>FOOTBALL &#8211; \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des 24 joueurs s\u00e9lectionn\u00e9s. Kylian Mbapp\u00e9 est bien de retour en bleu apr\u00e8s ses deux derni\u00e8res absences.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Une liste avec des certitudes et une nouveaut\u00e9. <a href=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-didier-deschamps-quittera-son-poste-de-selectionneur-en-2026\/\"><b>Didier Deschamps<\/b><\/a> a annonc\u00e9 ce 13 mars la liste des joueurs s\u00e9lectionn\u00e9s pour la double confrontation en quart de finale de la <strong>Ligue des Nations<\/strong>, face \u00e0 la Croatie (20 et 23 mars). Absent lors des deux derniers rassemblements, <b>Kylian Mbapp\u00e9<\/b> est bien de retour avec l\u2019<a href=\"https:\/\/dicodusport.fr\/blog\/edito-passion-pour-equipe-de-france-de-foot-cherche-nouveau-souffle\/\">\u00e9quipe de France<\/a>. <em>\u00ab\u00a0Il sera capitaine\u00a0\u00bb<\/em>, a d\u00e9clar\u00e9 Didier Deschamps lors de la conf\u00e9rence de presse. Petit nouveau chez les Bleus, <b>D\u00e9sir\u00e9 Dou\u00e9<\/b> a convaincu le s\u00e9lectionneur des Bleus apr\u00e8s ses belles performances avec le Paris Saint-Germain. Il conna\u00eet donc sa premi\u00e8re liste avec l&rsquo;\u00e9quipe de France, \u00e0 19 ans. Vingt-quatre joueurs donc, avec une l\u00e9g\u00e8re incertitude autour de <b>Marcus Thuram<\/b>, touch\u00e9 \u00e0 la cheville, et l\u2019envie de voir <strong>D\u00e9sir\u00e9 Dou\u00e9<\/strong>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><b>N\u2019Golo Kant\u00e9<\/b>, touch\u00e9 au niveau musculaire, est lui absent. Pas encore \u00e0 100%, <strong>Warren Za\u00efre-Emery<\/strong> est convoqu\u00e9.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/comment-le-cas-kylian-mbappe-peut-etre-un-bouleversement-dans-le-football\/\">Comment le cas Kylian Mbapp\u00e9 peut \u00eatre un bouleversement dans le football<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">La liste de Didier Deschamps<\/h2>\n<p style=\"text-align: justify;\"><strong>Gardiens<\/strong> : Lucas Chevalier, Mike Maignan, Brice Samba.<\/p>\n<p style=\"text-align: justify;\"><strong>D\u00e9fenseurs<\/strong> : Jonathan Clauss, Lucas Digne, Th\u00e9o Hernandez, Ibrahima Konat\u00e9, Jules Kound\u00e9, Benjamin Pavard, William Saliba, Dayot Upamecano.<\/p>\n<p style=\"text-align: justify;\"><strong>Milieux de terrain<\/strong> : Eduardo Camavinga, Matt\u00e9o Guendouzi, Manu Kon\u00e9, Adrien Rabiot, Aur\u00e9lien Tchouam\u00e9ni, Warren Za\u00efre-Emery.<\/p>\n<p style=\"text-align: justify;\"><strong>Attaquants<\/strong> : Bradley Barcola, Ousmane Demb\u00e9l\u00e9, Desir\u00e9 Dou\u00e9, Randal Kolo Muani, Kylian Mbapp\u00e9, Michael Olise, Marcus Thuram.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DHI_sxFNzCJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/DHI_sxFNzCJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Equipe de France de Football (@equipedefrance)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La liste des Bleus pour affronter la Croatie<\/p>\n","protected":false},"author":88,"featured_media":563706,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[32415,16878,4318,18243,75,2236],"class_list":["post-563646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-actu","tag-breve","tag-didier-deschamps","tag-equipe-de-france-foot","tag-football","tag-kylian-mbappe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9quipe de France : La liste des Bleus pour affronter la Croatie<\/title>\n<meta name=\"description\" content=\"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T13:09:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T13:35:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paul Lalevee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\"},\"author\":{\"name\":\"Paul Lalevee\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\"},\"headline\":\"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie\",\"datePublished\":\"2025-03-13T13:09:19+00:00\",\"dateModified\":\"2025-03-13T13:35:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Didier Deschamps\",\"\u00c9quipe de france foot\",\"Football\",\"Kylian Mbapp\u00e9\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\",\"name\":\"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png\",\"datePublished\":\"2025-03-13T13:09:19+00:00\",\"dateModified\":\"2025-03-13T13:35:26+00:00\",\"description\":\"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png\",\"width\":1200,\"height\":674,\"caption\":\"\u00c9quipe de France La liste des Bleus pour affronter la Croatie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\",\"name\":\"Paul Lalevee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"caption\":\"Paul Lalevee\"},\"description\":\"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie","description":"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie","og_description":"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.","og_url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-03-13T13:09:19+00:00","article_modified_time":"2025-03-13T13:35:26+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png","type":"image\/png"}],"author":"Paul Lalevee","twitter_card":"summary_large_image","twitter_title":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/"},"author":{"name":"Paul Lalevee","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd"},"headline":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie","datePublished":"2025-03-13T13:09:19+00:00","dateModified":"2025-03-13T13:35:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png","keywords":["actu","br\u00e8ve","Didier Deschamps","\u00c9quipe de france foot","Football","Kylian Mbapp\u00e9"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/","url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/","name":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png","datePublished":"2025-03-13T13:09:19+00:00","dateModified":"2025-03-13T13:35:26+00:00","description":"FOOTBALL - \u00c0 une semaine de la double confrontation face \u00e0 la Croatie (20 et 23 mars), Didier Deschamps a annonc\u00e9 le nom des s\u00e9lectionn\u00e9s.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Equipe-de-France-La-liste-des-Bleus-pour-affronter-la-Croatie.png","width":1200,"height":674,"caption":"\u00c9quipe de France La liste des Bleus pour affronter la Croatie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-la-liste-des-bleus-pour-affronter-la-croatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipe de France : La liste des Bleus pour affronter la Croatie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd","name":"Paul Lalevee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","caption":"Paul Lalevee"},"description":"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.","url":"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=563646"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563646\/revisions"}],"predecessor-version":[{"id":563728,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/563646\/revisions\/563728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/563706"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=563646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=563646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=563646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}