{"id":564334,"date":"2025-03-15T17:08:48","date_gmt":"2025-03-15T16:08:48","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=564334&#038;preview=true&#038;preview_id=564334"},"modified":"2025-03-15T18:07:30","modified_gmt":"2025-03-15T17:07:30","slug":"tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/","title":{"rendered":"Tirreno-Adriatico 2025 &#8211; Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TIRRENO-ADRIATICO 2025 &#8211; Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s&rsquo;est d\u00e9roul\u00e9e ce samedi 15 mars 2025, entre Cartoceto et Frontignano (162,6 km).<span class=\"red fw400\"><span style=\"font-size: 0.9em;\"><br \/>\n<\/span><\/span><\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tirreno-adriatico-2025\/\">Classement g\u00e9n\u00e9ral Tirreno-Adriatico 2025<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Tirreno-Adriatico 2025 <\/strong>poursuit sa route ce <strong>samedi 15 mars<\/strong>. La <strong>6\u00e8me \u00e9tape<\/strong>, l&rsquo;avant-derni\u00e8re de cette <em>Course des Deux Mers<\/em>, est l\u2019\u00e9tape reine avec une arriv\u00e9e en mont\u00e9e au sommet de <strong>Frontignano<\/strong>, une ascension longue 7,6 km \u00e0 7,9 %. Cette journ\u00e9e va donc dessiner le classement g\u00e9n\u00e9ral de l&rsquo;\u00e9preuve italienne. <strong>Retrouvez le classement et les r\u00e9sultats du jour<\/strong>.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-parcours-detaille-et-profil-des-etapes\/\">Tirreno-Adriatico 2025 : Parcours d\u00e9taill\u00e9 et profil des \u00e9tapes<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Classement 6\u00e8me \u00e9tape &#8211; Tirreno-Adriatico 2025<\/h2>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 JUAN AYUSO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES &#8211; XRG<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">4h14m02s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 THOMAS PIDCOCK<\/strong><br \/>\n<span style=\"font-size: 0.8em\">Q36.5 PRO CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 13s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa JAI HINDLEY<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL &#8211; BORA &#8211; HANSGROHE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 13s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 MIKEL LANDA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SOUDAL QUICK-STEP<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 15s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9<\/strong><\/span> ANTONIO TIBERI<\/strong><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">BAHRAIN VICTORIOUS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 20s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\udde6 DEREK GEE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ISRAEL &#8211; PREMIER TECH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 20s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf2\ud83c\uddfd ISAAC DEL TORO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES &#8211; XRG<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 36s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddea BEN HEALY<\/strong><br \/>\n<span style=\"font-size: 0.8em\">EF EDUCATION &#8211; EASYPOST<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 42s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf4 TOBIAS HALLAND JOHANNESSEN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UNO-X MOBILITY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 45s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 LORENZO FORTUNATO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">XDS ASTANA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 50s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 PELLO BILBAO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BAHRAIN &#8211; VICTORIOUS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 50s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 DAVID DE LA CRUZ<\/strong><br \/>\n<span style=\"font-size: 0.8em\">Q36.5 PRO CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 50s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 FILIPPO GANNA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">INEOS GRENADIERS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 50s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 SIMON YATES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM VISMA | LEASE A BIKE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 50s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 VALENTIN PARET-PEINTRE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SOUDAL QUICK-STEP<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m08s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">\ud83c\uddee\ud83c\uddf9<\/strong> MATTIA CATTANEO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SOUDAL &#8211; QUICK STEP<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m14s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 ALESSANDRO PINARELLO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">VF GROUP &#8211; BARDIANI CSF &#8211; FAIZAN\u00c8<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m14s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 DAVIDE PIGANZOLI<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM POLTI VISITMALTA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m14s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 GIULIO CICCONE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">LIDL &#8211; TREK<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m14s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 ADAM YATES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES &#8211; XRG<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 1m14s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/tirreno-adriatico\/2025\/stage-6\"><strong>Le classement complet de la 6\u00e8me \u00e9tape<\/strong><\/a><strong><br \/>\n<\/strong><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-uci-par-equipes-2023-2025\/\" class=\"vlp-link\" title=\"Classement UCI par \u00e9quipes 2023-2025\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025.png\" class=\"attachment-800x445 size-800x445\" alt=\"Classement UCI par \u00e9quipes 2023-2025\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Classement UCI par \u00e9quipes 2023-2025<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez le classement UCI par \u00e9quipes sur la p\u00e9riode 2023-2025<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s&rsquo;est d\u00e9roul\u00e9e ce samedi 15 mars 2025.<\/p>\n","protected":false},"author":4,"featured_media":564336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,7435],"class_list":["post-564334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-tirreno-adriatico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s&#039;est d\u00e9roul\u00e9e ce samedi 15 mars 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s&#039;est d\u00e9roul\u00e9e ce samedi 15 mars 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T16:08:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-15T17:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tirreno-Adriatico 2025 &#8211; Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\",\"datePublished\":\"2025-03-15T16:08:48+00:00\",\"dateModified\":\"2025-03-15T17:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png\",\"keywords\":[\"br\u00e8ve\",\"Tirreno-Adriatico\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\",\"name\":\"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png\",\"datePublished\":\"2025-03-15T16:08:48+00:00\",\"dateModified\":\"2025-03-15T17:07:30+00:00\",\"description\":\"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s'est d\u00e9roul\u00e9e ce samedi 15 mars 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png\",\"width\":1200,\"height\":674,\"caption\":\"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tirreno-Adriatico 2025 &#8211; Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape","description":"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s'est d\u00e9roul\u00e9e ce samedi 15 mars 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape","og_description":"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s'est d\u00e9roul\u00e9e ce samedi 15 mars 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-03-15T16:08:48+00:00","article_modified_time":"2025-03-15T17:07:30+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tirreno-Adriatico 2025 &#8211; Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape","datePublished":"2025-03-15T16:08:48+00:00","dateModified":"2025-03-15T17:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png","keywords":["br\u00e8ve","Tirreno-Adriatico"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/","name":"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png","datePublished":"2025-03-15T16:08:48+00:00","dateModified":"2025-03-15T17:07:30+00:00","description":"Retrouvez le classement et les r\u00e9sultats de la 6\u00e8me \u00e9tape de Tirreno-Adriatico 2025, qui s'est d\u00e9roul\u00e9e ce samedi 15 mars 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tirreno-Adriatico-2025-Classement-et-Resultats-de-la-6eme-etape.png","width":1200,"height":674,"caption":"Tirreno-Adriatico 2025 - Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tirreno-adriatico-2025-classement-et-resultats-de-la-6eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tirreno-Adriatico 2025 &#8211; Classement et R\u00e9sultats de la 6\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/564334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=564334"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/564334\/revisions"}],"predecessor-version":[{"id":564590,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/564334\/revisions\/564590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/564336"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=564334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=564334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=564334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}