{"id":565395,"date":"2025-03-22T16:50:39","date_gmt":"2025-03-22T15:50:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=565395&#038;preview=true&#038;preview_id=565395"},"modified":"2025-07-09T18:32:26","modified_gmt":"2025-07-09T16:32:26","slug":"biathlon-finales-oslo-2025-programme-complet-et-horaires","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/","title":{"rendered":"Biathlon Finales Oslo 2025 : Programme complet et horaires"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape<\/em><em> de la Coupe du monde de biathlon 2024-2025, qui se d\u00e9roule \u00e0 Oslo-Holmenkollen (Norv\u00e8ge)<\/em><em>, du vendredi 21 au dimanche 23 mars 2025.<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-coupe-du-monde-2024-2025-le-calendrier-complet\/\">Coupe du monde Biathlon 2024-2025 \u2013 Le calendrier complet<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong>Coupe du monde de biathlon 2024-2025<\/strong> s&rsquo;ach\u00e8ve du vendredi 21 au dimanche 23 mars 2025, avec <strong>les finales d&rsquo;Oslo-Holmenkollen<\/strong>, en Norv\u00e8ge. Le programme est royal pour cette ultime \u00e9tape de la Coupe du monde, avec les <strong>sprints<\/strong> vendredi, les <strong>poursuites<\/strong> samedi avant les <strong>mass starts<\/strong> en feu d&rsquo;artifice ce dimanche. Retraite des fr\u00e8res Boe oblige, l&rsquo;<strong>IBU<\/strong> a d\u00e9cid\u00e9 d&rsquo;inverser les courses dimanche, avec la mass start messieurs en guise de derni\u00e8re \u00e9preuve de la saison.<\/p>\n<p style=\"text-align: justify;\">Outre certains petits globes, les classements g\u00e9n\u00e9raux sont \u00e9galement en jeu du c\u00f4t\u00e9 d&rsquo;<strong>Oslo<\/strong>. \u00c0 l&rsquo;issue de <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-pokljuka-2025-resultats-et-classements\/\">l&rsquo;\u00e9tape de <strong>Pokljuka<\/strong><\/a> (Slov\u00e9nie), <strong>Lou Jeanmonnot<\/strong> est revenue \u00e0 20 longueurs de <strong>Franziska Preuss<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-pokljuka-2025-lou-jeanmonnot-triomphe-sur-la-mass-start-et-met-la-pression-sur-franziska-preuss\/\">la Fran\u00e7aise ayant remport\u00e9 la mass start slov\u00e8ne<\/a>. Chez les hommes, le forfait de <strong>Johannes Boe<\/strong> pour la mass start de Pokljuka, a permis \u00e0 <strong>Sturla Laegreid<\/strong> de faire un petit break sur son compatriote, avec une avance de 104 points.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-la-selection-francaise\/\">Biathlon Finales Oslo 2025 : La s\u00e9lection fran\u00e7aise<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Biathlon Coupe du monde Oslo 2025 &#8211; Programme et horaires des courses<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Les courses seront retransmises en direct sur La cha\u00eene L&rsquo;\u00c9quipe et Eurosport.<\/strong><\/em><\/span><\/p>\n<h3 style=\"text-align: justify;\">Vendredi 21 mars<\/h3>\n<p style=\"text-align: justify;\"><strong>13H30 : <\/strong>Sprint hommes &#8211; <a title=\"Biathlon Finales Oslo 2025 : Johannes Boe remporte le sprint, la Norv\u00e8ge signe un quintupl\u00e9\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-johannes-boe-remporte-le-sprint-la-norvege-signe-un-quintuple\/\" rel=\"\"><em><strong>R\u00e9sum\u00e9<\/strong><\/em><\/a> &#8211; <a title=\"Biathlon Finales Oslo \u2013 Classement et r\u00e9sultats Sprint hommes\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-sprint-hommes\/\" rel=\"\"><em><strong>Classement<\/strong><\/em><\/a><br \/>\n<strong>16H15 :<\/strong> Sprint femmes &#8211; <a title=\"Biathlon Finales Oslo 2025 : Franziska Preuss s\u2019impose de justesse face \u00e0 Lou Jeanmonnot sur le sprint\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-franziska-preuss-simpose-de-justesse-face-a-lou-jeanmonnot-sur-le-sprint\/\" rel=\"\"><em><strong>R\u00e9sum\u00e9<\/strong><\/em><\/a> &#8211; <a title=\"Biathlon Finales Oslo \u2013 Classement et r\u00e9sultats Sprint femmes\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-sprint-femmes\/\" rel=\"\"><em><strong>Classement<\/strong><\/em><\/a><\/p>\n<h3 style=\"text-align: justify;\">Samedi 22 mars<\/h3>\n<p style=\"text-align: justify;\"><strong>13H45 :<\/strong> Poursuite hommes &#8211; <a title=\"Biathlon Oslo-Holmenkollen 2025 : Quentin Fillon Maillet 3\u00e8me de la poursuite, Sturla Laegreid s\u2019impose et s\u2019assure du gros globe\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-oslo-holmenkollen-2025-quentin-fillon-maillet-3eme-de-la-poursuite-sturla-laegreid-simpose-et-sassure-du-gros-globe\/\" rel=\"\"><em><strong>R\u00e9sum\u00e9<\/strong><\/em><\/a> &#8211; <a title=\"Biathlon Finales Oslo \u2013 Classement et r\u00e9sultats Poursuite hommes\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-poursuite-hommes\/\" rel=\"\"><em><strong>Classement<\/strong><\/em><\/a><br \/>\n<strong>15H50 :<\/strong> Poursuite femmes &#8211; <a title=\"Biathlon Finales Oslo 2025 : Lou Jeanmonnot s\u2019impose sur la poursuite et prend la t\u00eate du g\u00e9n\u00e9ral !\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-lou-jeanmonnot-simpose-sur-la-poursuite-et-prend-la-tete-du-general\/\" rel=\"\"><em><strong>R\u00e9sum\u00e9<\/strong><\/em><\/a> &#8211; <a title=\"Biathlon Finales Oslo \u2013 Classement et r\u00e9sultats Poursuite femmes\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-poursuite-femmes\/\" rel=\"\"><em><strong>Classement<\/strong><\/em><\/a><\/p>\n<h3 style=\"text-align: justify;\">Dimanche 23 mars<\/h3>\n<p style=\"text-align: justify;\"><strong>13H15 :<\/strong> Mass start femmes &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-cruelle-3eme-place-pour-lou-jeanmonnot-franziska-preuss-remporte-le-gros-globe-de-cristal\/\"><b><i>R\u00e9sum\u00e9 <\/i><\/b><\/a>&#8211;<a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-mass-start-femmes\/\"><b><i> Classement<\/i><\/b><\/a><br \/>\n<strong>15H45 :<\/strong> Mass start hommes &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-eric-perrot-deuxieme-de-la-mass-start-derriere-sebastian-samuelsson-clap-de-fin-pour-les-freres-boe\/\"><b><i>R\u00e9sum\u00e9<\/i><\/b><\/a><b><i> <\/i><\/b>&#8211;<b><i> <\/i><\/b><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-classement-et-resultats-mass-start-hommes\/\"><b><i>Classement<\/i><\/b><\/a><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 ce sujet<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-classement-general-femmes-coupe-du-monde-2024-2025\/\"><strong>Biathlon \u2013 Classement g\u00e9n\u00e9ral femmes Coupe du monde 2024-2025<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-classement-general-hommes-coupe-du-monde-2024-2025\/\">Biathlon \u2013 Classement g\u00e9n\u00e9ral hommes Coupe du monde 2024-2025<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).<\/p>\n","protected":false},"author":4,"featured_media":566818,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47040],"tags":[2427,22316,30329,16878],"class_list":["post-565395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-biathlon","tag-biathlon","tag-biathlon-oslo","tag-biathlon-oslo-holmenkollen","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biathlon Finales Oslo 2025 : Programme complet et horaires<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biathlon Finales Oslo 2025 : Programme complet et horaires\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-22T15:50:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T16:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Biathlon Finales Oslo 2025 : Programme complet et horaires\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Biathlon Finales Oslo 2025 : Programme complet et horaires\",\"datePublished\":\"2025-03-22T15:50:39+00:00\",\"dateModified\":\"2025-07-09T16:32:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png\",\"keywords\":[\"Biathlon\",\"biathlon oslo\",\"Biathlon Oslo-Holmenkollen\",\"br\u00e8ve\"],\"articleSection\":[\"Coupe du monde de biathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\",\"name\":\"Biathlon Finales Oslo 2025 : Programme complet et horaires\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png\",\"datePublished\":\"2025-03-22T15:50:39+00:00\",\"dateModified\":\"2025-07-09T16:32:26+00:00\",\"description\":\"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png\",\"width\":1200,\"height\":674,\"caption\":\"Biathlon Finales Oslo Cruelle 3\u00e8me place pour Lou Jeanmonnot, Franziska Preuss remporte le gros globe de cristal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biathlon Finales Oslo 2025 : Programme complet et horaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biathlon Finales Oslo 2025 : Programme complet et horaires","description":"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Biathlon Finales Oslo 2025 : Programme complet et horaires","og_description":"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).","og_url":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-03-22T15:50:39+00:00","article_modified_time":"2025-07-09T16:32:26+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Biathlon Finales Oslo 2025 : Programme complet et horaires","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Biathlon Finales Oslo 2025 : Programme complet et horaires","datePublished":"2025-03-22T15:50:39+00:00","dateModified":"2025-07-09T16:32:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png","keywords":["Biathlon","biathlon oslo","Biathlon Oslo-Holmenkollen","br\u00e8ve"],"articleSection":["Coupe du monde de biathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/","url":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/","name":"Biathlon Finales Oslo 2025 : Programme complet et horaires","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png","datePublished":"2025-03-22T15:50:39+00:00","dateModified":"2025-07-09T16:32:26+00:00","description":"D\u00e9couvrez le programme complet et les horaires de la 9\u00e8me et derni\u00e8re \u00e9tape de la Coupe du monde de biathlon, qui se d\u00e9roule \u00e0 Oslo (Norv\u00e8ge).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Biathlon-Finales-Oslo-Cruelle-3eme-place-pour-Lou-Jeanmonnot-Franziska-Preuss-remporte-le-gros-globe-de-cristal.png","width":1200,"height":674,"caption":"Biathlon Finales Oslo Cruelle 3\u00e8me place pour Lou Jeanmonnot, Franziska Preuss remporte le gros globe de cristal"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-finales-oslo-2025-programme-complet-et-horaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Biathlon Finales Oslo 2025 : Programme complet et horaires"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/565395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=565395"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/565395\/revisions"}],"predecessor-version":[{"id":566915,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/565395\/revisions\/566915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/566818"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=565395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=565395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=565395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}