{"id":567625,"date":"2025-03-26T15:07:55","date_gmt":"2025-03-26T14:07:55","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=567625&#038;preview=true&#038;preview_id=567625"},"modified":"2025-03-26T15:07:55","modified_gmt":"2025-03-26T14:07:55","slug":"tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/","title":{"rendered":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>MONDIAUX TENNIS DE TABLE 2025 &#8211; \u00c0 moins de deux mois du coup d&rsquo;envoi des championnats du monde de Busan, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs pour d\u00e9fendre les couleurs tricolores en Cor\u00e9e du Sud. Avec \u00e9videmment les fr\u00e8res Lebrun en fers de lance.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis-de-table\/\">Toute l&rsquo;actualit\u00e9 du tennis de table<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Depuis l&rsquo;av\u00e8nement d&rsquo;Alexis et F\u00e9lix Lebrun, le tennis de table fran\u00e7ais a pris l&rsquo;habitude de briller sur les plus grands terrains. Ce fut le cas aux Jeux Olympiques, mais \u00e9galement lors des derniers<strong> championnats du monde<\/strong>, o\u00f9 les deux \u00e9quipes \u00e9taient parvenues \u00e0 d\u00e9crocher une m\u00e9daille (argent pour les hommes, bronze pour les femmes).<\/p>\n<h2>Les fr\u00e8res Lebrun en chefs de file d&rsquo;une belle s\u00e9lection<\/h2>\n<p style=\"text-align: justify;\">Un an plus tard, les Bleus essaieront de faire au moins aussi bien \u00e0 <strong>Busan<\/strong> (Cor\u00e9e du Sud), du <strong>17 au 25 mai prochain<\/strong>. Pour cela, la F\u00e9d\u00e9ration Fran\u00e7aise de Tennis de Table compte s&rsquo;appuyer sur 12 \u00e9l\u00e9ments : sept hommes et cinq femmes. La s\u00e9lection masculine sera naturellement port\u00e9e par <strong>Alexis Lebrun<\/strong> et <strong>F\u00e9lix Lebrun<\/strong>, qui ont \u00e0 eux deux permis \u00e0 la discipline de retrouver la lumi\u00e8re dans l&rsquo;hexagone. Naturellement, ils repr\u00e9senteront les meilleurs espoirs tricolores dans les tableaux individuels.<\/p>\n<p style=\"text-align: justify;\">Leur partenaire habituel en \u00e9quipe, <strong>Simon Gauzy<\/strong>, sera \u00e9galement de la partie, tout comme <strong>Thibault Poret<\/strong><strong>\u00a0<\/strong>et <strong>Lilian Bardet<\/strong>. \u00c0 noter qu&rsquo;<strong>Esteban Dorr <\/strong>et<strong> Florian Bourrassaud <\/strong>prendront eux part uniquement au tournoi de double. La f\u00e9d\u00e9ration a pr\u00e9cis\u00e9 \u00e0 ce sujet, dans son communiqu\u00e9, que les autres \u00e9quipes seront d\u00e9voil\u00e9es ult\u00e9rieurement.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 de la s\u00e9lection f\u00e9minine, pas de surprise \u00e9galement puisque les habituelles cheffes de file que sont <strong>Prithika Pavade, Jia Nan Yuan<\/strong> et <strong>Charlotte Lutz<\/strong> seront de la partie, tout comme <strong>Audrey Zarif<\/strong>, et la toute jeune prodige <strong>L\u00e9ana Hochart<\/strong> (16 ans).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La s\u00e9lection pour les Championnats du monde individuels \ud83c\udfc6<\/p>\n<p>\ud83d\udcce Suite au comit\u00e9 de s\u00e9lection du 24 mars 2025, d\u00e9couvrez les joueurs et joueuses tricolores pour les championnats du monde individuels \u27a1\ufe0f <a href=\"https:\/\/t.co\/4Duf7FG9wj\">https:\/\/t.co\/4Duf7FG9wj<\/a><a href=\"https:\/\/twitter.com\/hashtag\/TeamFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#TeamFrance<\/a> \ud83c\uddeb\ud83c\uddf7 <a href=\"https:\/\/t.co\/67gbCtEQVM\">pic.twitter.com\/67gbCtEQVM<\/a><\/p>\n<p>\u2014 F\u00e9d\u00e9ration Fran\u00e7aise de Tennis de Table (@ffttofficiel) <a href=\"https:\/\/twitter.com\/ffttofficiel\/status\/1904892894579662903?ref_src=twsrc%5Etfw\">March 26, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>La s\u00e9lection tricolore pour les Mondiaux 2025 de tennis de table<\/h3>\n<p><strong><em>Hommes :<\/em><\/strong> Lilian BARDET \/ Florian BOURRASSAUD <em>(double)<\/em> \/ Esteban DORR <em>(double)<\/em> \/ Simon GAUZY \/ Alexis LEBRUN \/ F\u00e9lix LEBRUN \/ Thibault PORET<\/p>\n<p><strong><em>Femmes :<\/em> <\/strong>L\u00e9ana HOCHART \/ Charlotte LUTZ \/ Prithika PAVADE \/ Jia Nan YUAN \/ Audrey ZARIF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONDIAUX TENNIS DE TABLE 2025 &#8211; \u00c0 moins de deux mois du coup d&rsquo;envoi des championnats du monde de Busan, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs pour d\u00e9fendre les couleurs tricolores en Cor\u00e9e du Sud, avec \u00e9videmment les fr\u00e8res Lebrun en fers de lance.<\/p>\n","protected":false},"author":55,"featured_media":567626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9663],"tags":[32415,22533,16878,24337,27448],"class_list":["post-567625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis-de-table","tag-actu","tag-alexis-lebrun","tag-breve","tag-felix-lebrun","tag-ping-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025<\/title>\n<meta name=\"description\" content=\"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l&#039;\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\" \/>\n<meta property=\"og:description\" content=\"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l&#039;\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T14:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\",\"datePublished\":\"2025-03-26T14:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png\",\"keywords\":[\"actu\",\"Alexis Lebrun\",\"br\u00e8ve\",\"F\u00e9lix Lebrun\",\"ping fran\u00e7ais\"],\"articleSection\":[\"Tennis de table\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\",\"name\":\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png\",\"datePublished\":\"2025-03-26T14:07:55+00:00\",\"description\":\"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l'\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png\",\"width\":1200,\"height\":674,\"caption\":\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025","description":"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l'\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025","og_description":"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l'\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.","og_url":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-03-26T14:07:55+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025","datePublished":"2025-03-26T14:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png","keywords":["actu","Alexis Lebrun","br\u00e8ve","F\u00e9lix Lebrun","ping fran\u00e7ais"],"articleSection":["Tennis de table"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/","url":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/","name":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png","datePublished":"2025-03-26T14:07:55+00:00","description":"MONDIAUX TENNIS DE TABLE 2025 - \u00c0 moins de deux mois de l'\u00e9ch\u00e9ance, la FFTT a communiqu\u00e9 ce mercredi une liste de 12 joueurs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Tennis-de-table-La-selection-francaise-pour-les-Mondiaux-2025.png","width":1200,"height":674,"caption":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tennis-de-table-la-selection-francaise-pour-les-mondiaux-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tennis de table : La s\u00e9lection fran\u00e7aise pour les Mondiaux 2025"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/567625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=567625"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/567625\/revisions"}],"predecessor-version":[{"id":567631,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/567625\/revisions\/567631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/567626"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=567625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=567625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=567625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}