{"id":569537,"date":"2025-04-03T20:56:10","date_gmt":"2025-04-03T18:56:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=569537&#038;preview=true&#038;preview_id=569537"},"modified":"2025-04-03T21:01:16","modified_gmt":"2025-04-03T19:01:16","slug":"euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/","title":{"rendered":"EuroLigue (J33) : Le Panathina\u00efkos d&rsquo;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>EUROLIGUE 2024\/25 &#8211; L&rsquo;AS Monaco a connu un coup d&rsquo;arr\u00eat \u00e0 domicile ce jeudi soir, s&rsquo;inclinant face au Panathina\u00efkos, 88-76. Malgr\u00e9 une entame catastrophique, la Roca Team a rebondi pour rester dans le coup. Mais face \u00e0 un Kendrick Nunn absolument intenable (37 points), les Mon\u00e9gasques ont d\u00fb rendre les armes. Une victoire sera donc n\u00e9cessaire \u00e0 Lyon la semaine prochaine pour s\u00e9curiser un Top 4, synonyme d&rsquo;avantage du terrain en quarts de finale.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/basket-ball\/euroligue-2024-2025\/\">Toute l&rsquo;actualit\u00e9 de l&rsquo;EuroLigue<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La place dans le Top 6 \u00e9tant quasiment garantie, l&rsquo;<strong>AS Monaco<\/strong> pouvait regarder plus haut dans le classement en cette fin de saison r\u00e9guli\u00e8re d&rsquo;<strong>EuroLigue<\/strong>. Port\u00e9e par une s\u00e9rie de trois victoires cons\u00e9cutives, la Roca Team \u00e9tait en confiance au moment d&rsquo;affronter le <strong>Panathina\u00efkos<\/strong> dans un match crucial. Les deux \u00e9quipes disposant du m\u00eame bilan, le vainqueur de ce duel allait se retrouver seul 3\u00e8me avant l&rsquo;ultime journ\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\">La d\u00e9fense de Monaco absente, le Panathina\u00efkos se r\u00e9gale<\/h2>\n<p style=\"text-align: justify;\">Cela n&rsquo;a pas emp\u00each\u00e9 le spectacle d&rsquo;\u00eatre au rendez-vous d&#8217;embl\u00e9e. L&rsquo;adresse est au rendez-vous, et la Roca Team peut s&rsquo;appuyer sur l&rsquo;entame de match tonitruante de <strong>Daniel Theis<\/strong>, qui encha\u00eene cinq points et un contre dans les deux premi\u00e8res minutes ! Plus globalement, l&rsquo;offensive mon\u00e9gasque montre une belle alternance. En revanche, la Roca Team souffre d\u00e9fensivement, notamment face \u00e0 l&rsquo;impact int\u00e9rieur de <strong>Wenyen Gabriel<\/strong>. Progressivement, cette derni\u00e8re va m\u00eame litt\u00e9ralement prendre l&rsquo;eau face aux transitions rapides et assassines des Grecs. Chaque ballon perdu ou repli trop mou est imm\u00e9diatement puni par la bande \u00e0 <strong>Kendrick Nunn<\/strong>, qui encha\u00eene les paniers faciles comme les petits pains. Preuve de cette insolente r\u00e9ussite, le Pana cumule un impressionnant<strong> 13\/15 au tir<\/strong> \u00e0 l&rsquo;issue d&rsquo;un premier quart prolifique. Le r\u00e9cital sera boucl\u00e9 avec maestria par un buzzer beater \u00e0 trois points de Nunn (21-32) !<\/p>\n<p style=\"text-align: justify;\">\u00c0 l&rsquo;instar d&rsquo;un Mam Jaiteh qui vendange plusieurs paniers sous le cercle, la Roca Team a totalement perdu le fil. Incapable de r\u00e9aliser le moindre stop, elle continue au contraire \u00e0 se noyer face \u00e0 un rouleau compresseur grec qui avance tel un m\u00e9tronome, s\u00fbr de sa force. Dans ce naufrage, seul <strong>Jaron Blossomgame<\/strong> s&rsquo;illustre par son intensit\u00e9, mais l&rsquo;ailier am\u00e9ricain est bien esseul\u00e9. L&rsquo;\u00e9cart se creuse inlassablement, et le ph\u00e9nom\u00e8ne <strong>Kendrick Nunn<\/strong> se charge de porter l&rsquo;\u00e9cart jusqu&rsquo;\u00e0 +17 gr\u00e2ce \u00e0 ses 18 points dans le premier acte. Malgr\u00e9 tout, la Roca Team va limiter la casse en profitant d&rsquo;une drastique baisse d&rsquo;adresse adverse en fin de p\u00e9riode. Cette derni\u00e8re s&rsquo;en sort m\u00eame bien \u00e9tant seulement rel\u00e9gu\u00e9e \u00e0 8 points suite \u00e0 un buzzer beater d&rsquo;<strong>\u00c9lie Okobo<\/strong> pour boucler un 11-2 bienvenu (41-49).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"tr\">Kendrick Nunn ilk \u00e7eyre\u011fi \u00fc\u00e7l\u00fck ile sonland\u0131r\u0131yor!<a href=\"https:\/\/twitter.com\/hashtag\/EveryGameMatters?src=hash&amp;ref_src=twsrc%5Etfw\">#EveryGameMatters<\/a> <a href=\"https:\/\/t.co\/7rTnzKE7UO\">pic.twitter.com\/7rTnzKE7UO<\/a><\/p>\n<p>\u2014 Turkish Airlines EuroLeague T\u00fcrkiye (@EuroLeagueTUR) <a href=\"https:\/\/twitter.com\/EuroLeagueTUR\/status\/1907847081110163832?ref_src=twsrc%5Etfw\">April 3, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;insoluble probl\u00e9matique Kendrick Nunn<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, ce renversement de situation improbable se poursuit. Monaco a retrouv\u00e9 de l&rsquo;impact en d\u00e9fense et cadenasse totalement des Grecs la t\u00eate \u00e0 l&rsquo;envers. Totalement aphones, ces derniers vont devoir patienter cinq longues minutes pour enfin retrouver le chemin du cercle alors que la Roca Team est revenu \u00e0 une unit\u00e9 (48-49). Mais avec deux shoots lunaires, <strong>Kendrick Nunn<\/strong> r\u00e9veille son \u00e9quipe. Dans la foul\u00e9e, l&rsquo;Am\u00e9ricain offre un alley-oop \u00e0<strong> Omer Yurtseven<\/strong> avant d&rsquo;envoyer un <em>floater<\/em> pour valider un terrible 11-0 (48-60). Comme si cela ne suffisait pas, il va coller son 30\u00e8me point du match au buzzer du 3\u00e8me quart pour remettre sur orbite le Pana (53-65).<\/p>\n<p style=\"text-align: justify;\">L&rsquo;ASM retrouve du scoring en d\u00e9but de dernier quart, avec notamment un beau shoot ext\u00e9rieur de <strong>Matthew Strazel<\/strong>. Seulement, cela n&rsquo;est pas accompagn\u00e9 des stops n\u00e9cessaires pour r\u00e9duire la marque. Et lorsque l&rsquo;espoir rena\u00eet, c&rsquo;est au tour de <strong>Kostas Sloukas<\/strong> de se signaler avec un deux plus un pour annihiler les efforts produits jusqu&rsquo;alors (64-74). Alors que tout le monde s&rsquo;endormait suite \u00e0 une longue s\u00e9quence hach\u00e9e par les arbitrages vid\u00e9o, une fl\u00e8che d&rsquo;<strong>\u00c9lie Okobo<\/strong> ranime l&rsquo;assembl\u00e9e, et le souffle chaud de l&rsquo;ASM se fait sentir sur la nuque des Grecs (69-74).<\/p>\n<p style=\"text-align: justify;\">H\u00e9las, <strong>Kendrick Nunn<\/strong> (37 points, 5 passes) avait des allures de Michael Jordan ce soir. Discret tout le quatri\u00e8me quart, il va se charger d&rsquo;enfiler un panier assassin \u00e0 l&rsquo;angle z\u00e9ro pour remettre les Mon\u00e9gasques \u00e0 +9 (69-78). Cette fois, la Roca Team ne s&rsquo;en rel\u00e8vera pas. Logiquement, <strong>le Panathina\u00efkos s&rsquo;impose 88-76<\/strong> et s\u00e9curise sa place sur le podium. De son c\u00f4t\u00e9, l&rsquo;AS Monaco reste provisoirement 4\u00e8me, mais doit absolument s&rsquo;imposer sur le parquet de l&rsquo;ASVEL lors de la derni\u00e8re journ\u00e9e pour pr\u00e9server son Top 4.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">When every option is off the table, you create your own! \ud83e\uddd1\u200d\ud83c\udfa8<a href=\"https:\/\/twitter.com\/nunnbetter_?ref_src=twsrc%5Etfw\">@nunnbetter_<\/a> drills a ridiculously tough three as the shot clock runs out\u2014AND ONE! \ud83d\udca5 Talk about making something out of nothing!\u23f3 <a href=\"https:\/\/t.co\/TukRHNiwoW\">pic.twitter.com\/TukRHNiwoW<\/a><\/p>\n<p>\u2014 SKWEEK (@skweektv) <a href=\"https:\/\/twitter.com\/skweektv\/status\/1907861065435852976?ref_src=twsrc%5Etfw\">April 3, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2024\/25 &#8211; L&rsquo;AS Monaco a connu un coup d&rsquo;arr\u00eat \u00e0 domicile ce jeudi soir, s&rsquo;inclinant face au Panathina\u00efkos, 88-76. Malgr\u00e9 une entame catastrophique, la Roca Team a rebondi pour rester dans le coup. Mais face \u00e0 un Kendrick Nunn absolument intenable (37 points), les Mon\u00e9gasques ont d\u00fb rendre les armes. Une victoire sera donc n\u00e9cessaire \u00e0 Lyon la semaine prochaine pour s\u00e9curiser un Top 4, synonyme d&rsquo;avantage du terrain en quarts de finale.<\/p>\n","protected":false},"author":55,"featured_media":569573,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47001],"tags":[16232,16878,1678,8989],"class_list":["post-569537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-as-monaco-basket","tag-breve","tag-monaco","tag-panathinaikos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EuroLigue (J33) : Le Panathina\u00efkos d&#039;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2024\/25 - L&#039;AS Monaco s&#039;est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d&#039;un Kendrick Nunn intenable (37 points), 88-76.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue (J33) : Le Panathina\u00efkos d&#039;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2024\/25 - L&#039;AS Monaco s&#039;est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d&#039;un Kendrick Nunn intenable (37 points), 88-76.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-03T18:56:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T19:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue (J33) : Le Panathina\u00efkos d&#039;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"EuroLigue (J33) : Le Panathina\u00efkos d&rsquo;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\",\"datePublished\":\"2025-04-03T18:56:10+00:00\",\"dateModified\":\"2025-04-03T19:01:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/\"},\"wordCount\":893,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png\",\"keywords\":[\"as monaco basket\",\"br\u00e8ve\",\"Monaco\",\"Panathina\u00efkos\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/\",\"name\":\"EuroLigue (J33) : Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png\",\"datePublished\":\"2025-04-03T18:56:10+00:00\",\"dateModified\":\"2025-04-03T19:01:16+00:00\",\"description\":\"EUROLIGUE 2024\\\/25 - L'AS Monaco s'est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d'un Kendrick Nunn intenable (37 points), 88-76.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png\",\"width\":1200,\"height\":674,\"caption\":\"EuroLigue (J33) Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue (J33) : Le Panathina\u00efkos d&rsquo;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue (J33) : Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco","description":"EUROLIGUE 2024\/25 - L'AS Monaco s'est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d'un Kendrick Nunn intenable (37 points), 88-76.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue (J33) : Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco","og_description":"EUROLIGUE 2024\/25 - L'AS Monaco s'est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d'un Kendrick Nunn intenable (37 points), 88-76.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-04-03T18:56:10+00:00","article_modified_time":"2025-04-03T19:01:16+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"EuroLigue (J33) : Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"EuroLigue (J33) : Le Panathina\u00efkos d&rsquo;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco","datePublished":"2025-04-03T18:56:10+00:00","dateModified":"2025-04-03T19:01:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/"},"wordCount":893,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png","keywords":["as monaco basket","br\u00e8ve","Monaco","Panathina\u00efkos"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/","name":"EuroLigue (J33) : Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png","datePublished":"2025-04-03T18:56:10+00:00","dateModified":"2025-04-03T19:01:16+00:00","description":"EUROLIGUE 2024\/25 - L'AS Monaco s'est inclin\u00e9e \u00e0 domicile face au Panathina\u00efkos d'un Kendrick Nunn intenable (37 points), 88-76.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J33-Le-Panathinaikos-dun-Kendrick-Nunn-brillant-stoppe-la-serie-de-Monaco-1.png","width":1200,"height":674,"caption":"EuroLigue (J33) Le Panathina\u00efkos d'un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j33-le-panathinaikos-dun-kendrick-nunn-brillant-stoppe-la-serie-de-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue (J33) : Le Panathina\u00efkos d&rsquo;un Kendrick Nunn brillant stoppe la s\u00e9rie de Monaco"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/569537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=569537"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/569537\/revisions"}],"predecessor-version":[{"id":569576,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/569537\/revisions\/569576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/569573"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=569537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=569537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=569537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}