{"id":570904,"date":"2025-04-09T14:00:57","date_gmt":"2025-04-09T12:00:57","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=570904&#038;preview=true&#038;preview_id=570904"},"modified":"2025-04-09T14:21:49","modified_gmt":"2025-04-09T12:21:49","slug":"augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/","title":{"rendered":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \u00ab\u00a0Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\u00a0\u00bb"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>T\u00c9L\u00c9MARK \u2013 Troisi\u00e8me de la derni\u00e8re Coupe du monde, m\u00e9daill\u00e9e d\u2019argent aux Mondiaux S\u00e9niors, triple m\u00e9daill\u00e9e d\u2019or aux Mondiaux Juniors\u2026 Dire que la saison d\u2019Augustine Carliez a \u00e9t\u00e9 couronn\u00e9e de r\u00e9ussite serait un euph\u00e9misme. Du haut de ses 20 ans, l\u2019Ann\u00e9cienne a franchi un nouveau cap dans sa progression lin\u00e9aire pour devenir une r\u00e9elle menace sur le circuit. Quelques jours apr\u00e8s ses exploits \u00e0 Bardonecchia, la t\u00e9l\u00e9markeuse tricolore s\u2019est livr\u00e9e en longueur sur son brillant hiver pour Dicodusport.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-dhiver\/telemark\/\">Toute l&rsquo;actualit\u00e9 du t\u00e9l\u00e9mark<\/a><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><em>Dicodusport :<\/em> La semaine derni\u00e8re, tu as sign\u00e9 une performance historique aux Mondiaux Juniors en r\u00e9alisant le tripl\u00e9 (Un exploit seulement r\u00e9alis\u00e9 par Johanna Holzmann et Kaja Bjornstad Konow par le pass\u00e9). Comment as-tu v\u00e9cu cette semaine folle ?<\/h3>\n<p style=\"text-align: justify;\"><em>Augustine Carliez :<\/em> Je suis arriv\u00e9e tr\u00e8s fatigu\u00e9e de la saison autant \u00e9motionnellement que physiquement. On venait de faire les finales de Coupe du monde o\u00f9 j\u2019avais l\u2019ambition de remporter le globe. Je n\u2019ai pas r\u00e9ussi donc j\u2019ai d\u00fb faire face \u00e0 un \u00ab \u00e9chec \u00bb, m\u00eame si j\u2019ai pris la 2\u00e8me place au g\u00e9n\u00e9ral. J\u2019en suis satisfaite maintenant, mais sur le moment, c&rsquo;\u00e9tait dur \u00e0 accepter vu que je ne suis pas pass\u00e9e loin. Je suis arriv\u00e9e aux Mondiaux juniors en \u00e9tant la grande favorite puisque sur les courses d\u2019avant, j\u2019\u00e9tais largement la meilleure de la cat\u00e9gorie. En raison de la fatigue, la semaine n\u2019a pas \u00e9t\u00e9 facile. <strong>Physiquement, j&rsquo;\u00e9tais cuite, donc je n\u2019ai pas trouv\u00e9 mes meilleures sensations<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Heureusement, <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-juniors-de-telemark-2025-augustine-carliez-mene-un-incroyable-triple-tricolore-sur-la-classic\/\">on commen\u00e7ait par la Classic<\/a>, qui est ma discipline de c\u0153ur, et celle o\u00f9 je performe le plus. Je savais que j\u2019avais un peu de marge sans \u00eatre \u00e0 100 %. Je n\u2019ai pas produit du grand ski, et il n\u2019y a pas eu un \u00e9norme \u00e9cart, mais \u00e7a a suffi ! <strong>J\u2019\u00e9tais contente d\u2019avoir cette premi\u00e8re m\u00e9daille, mais je me suis rendue compte que \u00e7a n\u2019allait pas \u00eatre simple sur les deux autres disciplines<\/strong>. <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-juniors-de-telemark-2025-augustine-carliez-decroche-un-titre-historique-sur-le-sprint-zian-peccoux-en-argent\/\">Le sprint a \u00e9t\u00e9 tr\u00e8s difficile<\/a>. Je termine 3\u00e8me de la premi\u00e8re manche apr\u00e8s avoir gagn\u00e9 une place suite aux p\u00e9nalit\u00e9s. Il fallait donc que j\u2019augmente mon niveau de ski sur la seconde. J\u2019ai serr\u00e9 les dents pour aller chercher mes derni\u00e8res ressources. J\u2019arrive finalement en t\u00eate, mais la deuxi\u00e8me \u00e9tait tr\u00e8s proche donc j\u2019ai eu un peu de chance.<\/p>\n<p style=\"text-align: justify;\">Enfin, <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-juniors-de-telemark-2025-augustine-carliez-realise-le-triple-dore-en-remportant-le-sprint-parallele\/\">sur la parall\u00e8le<\/a>, on savait que c\u2019\u00e9tait la derni\u00e8re de la saison donc il fallait tout mettre. Je passe les tours avec difficult\u00e9, sans \u00eatre dominante. Et au final, je r\u00e9alise une derni\u00e8re belle manche contre L\u00e9a Lathion, qui \u00e9tait \u00e9galement pr\u00e9tendante au titre, pour gagner difficilement cette 3\u00e8me m\u00e9daille d\u2019or. <strong>Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !<\/strong><\/p>\n<div id=\"attachment_570907\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-570907\" class=\"size-full wp-image-570907\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-avec-ses-3-medailles-dor-a-Bardonecchia.jpg\" alt=\"Augustine Carliez avec ses 3 m\u00e9dailles d'or, \u00e0 Bardonecchia\" width=\"590\" height=\"788\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-avec-ses-3-medailles-dor-a-Bardonecchia.jpg 590w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-avec-ses-3-medailles-dor-a-Bardonecchia-225x300.jpg 225w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><p id=\"caption-attachment-570907\" class=\"wp-caption-text\">Augustine Carliez avec ses 3 m\u00e9dailles d&rsquo;or, \u00e0 Bardonecchia (Cr\u00e9dit : FIS T\u00e9l\u00e9mark)<\/p><\/div>\n<h3 style=\"text-align: justify;\">Deux semaines plus t\u00f4t, tu avais d\u00e9j\u00e0 frapp\u00e9 un grand coup aux Mondiaux en obtenant ta premi\u00e8re m\u00e9daille en Senior (argent) sur le sprint. Quel bilan tires-tu de cette semaine aux Contamines-Montjoie\u00a0?<\/h3>\n<p style=\"text-align: justify;\">C\u2019\u00e9tait assez exceptionnel\u00a0! Mes proches sont venus me voir sur le stade des Contamines qu\u2019on conna\u00eet tr\u00e8s bien pour s\u2019y entra\u00eener avec l\u2019\u00c9quipe de France. C\u2019est aussi la station de notre entra\u00eeneur (Antoine Bouvier). <strong>J\u2019\u00e9tais vraiment en forme<\/strong>, et pr\u00eate \u00e0 essayer d\u2019aller chercher un titre. Je savais que j\u2019en avais les moyens suite \u00e0 mes deux victoires en Coupe du monde. Mais le faire aux championnats du monde, sur une course d\u2019un jour, c\u2019est autre chose.<\/p>\n<p style=\"text-align: justify;\">En sprint, je n\u2019\u00e9tais pas ultra-favorite, mais j\u2019ai ski\u00e9 \u00e0 fond pour ne pas avoir de regrets. J\u2019ai fini 2\u00e8me sur la premi\u00e8re manche, donc j\u2019\u00e9tais tr\u00e8s contente, mais il fallait ensuite confirmer. \u00c7a m\u2019a stress\u00e9 avant le d\u00e9part de la seconde manche puisque je ne m\u2019\u00e9tais jamais retrouv\u00e9 dans une telle position sur des championnats du monde. Finalement, je passe la ligne d\u2019arriv\u00e9e avec juste le regret d\u2019avoir conc\u00e9d\u00e9 une p\u00e9nalit\u00e9 au saut. J\u2019ai eu peur que \u00e7a me co\u00fbte la m\u00e9daille. L\u2019attente a \u00e9t\u00e9 tr\u00e8s longue puisque les r\u00e9sultats officiels ont mis 45 minutes \u00e0 tomber ! Mais au final, <strong>cette premi\u00e8re m\u00e9daille chez les grands a \u00e9t\u00e9 tr\u00e8s intense \u00e9motionnellement<\/strong>, et \u00e7a concr\u00e9tise pas mal de choses.<\/p>\n<p style=\"text-align: justify;\">En revanche, <strong>il y a de la d\u00e9ception sur la Classic<\/strong>, car j\u2019esp\u00e9rais beaucoup sur cette discipline, mais je suis tomb\u00e9e sur un saut un peu trop gros, que je ne suis pas parvenue \u00e0 g\u00e9rer. Malgr\u00e9 tout, je tire un bilan positif de ces Mondiaux avec cette m\u00e9daille d\u2019argent.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-telemark-2025-noe-claye-augustine-carliez-et-yoann-rostolan-se-hissent-sur-le-podium-du-sprint\/\" class=\"vlp-link\" title=\"Mondiaux de T\u00e9l\u00e9mark 2025\u00a0: No\u00e9 Claye, Augustine Carliez et Yoann Rostolan se hissent sur le podium du sprint\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Mondiaux-de-Telemark-2025-Noe-Claye-Augustine-Carliez-et-Yoann-Rostolan-se-hissent-sur-le-podium-du-sprint-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mondiaux de T\u00e9l\u00e9mark 2025\u00a0 No\u00e9 Claye, Augustine Carliez et Yoann Rostolan se hissent sur le podium du sprint\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Mondiaux-de-Telemark-2025-Noe-Claye-Augustine-Carliez-et-Yoann-Rostolan-se-hissent-sur-le-podium-du-sprint-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Mondiaux-de-Telemark-2025-Noe-Claye-Augustine-Carliez-et-Yoann-Rostolan-se-hissent-sur-le-podium-du-sprint-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Mondiaux-de-Telemark-2025-Noe-Claye-Augustine-Carliez-et-Yoann-Rostolan-se-hissent-sur-le-podium-du-sprint-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/03\/Mondiaux-de-Telemark-2025-Noe-Claye-Augustine-Carliez-et-Yoann-Rostolan-se-hissent-sur-le-podium-du-sprint-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mondiaux de T\u00e9l\u00e9mark 2025\u00a0: No\u00e9 Claye, Augustine Carliez et Yoann Rostolan se hissent sur le podium du sprint<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS DU MONDE DE T\u00c9L\u00c9MARK 2025 - L'\u00c9quipe de France a d\u00e9croch\u00e9 ses trois premi\u00e8res m\u00e9dailles sur les sprints disput\u00e9s ce mercredi aux Contamines-Montjoie ! Dans le tableau masculin, No\u00e9 Claye (argent) et Yoann Rostolan (bronze) ont tous deux pris place sur le podium, tandis qu'Augustine Carliez a rafl\u00e9 l'argent chez les femmes.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h3 style=\"text-align: justify;\">Cheffe de file de l\u2019\u00c9quipe de France f\u00e9minine, Argeline Tan-Bouquet avait <a href=\"https:\/\/www.ledauphine.com\/skichrono\/2025\/03\/24\/c-est-un-manque-de-respect-le-coup-de-gueule-d-argeline-tan-bouquet\">pouss\u00e9 un coup de gueule<\/a> sur la participation de Johanna Holzmann, (l\u2019Allemande a effectu\u00e9 son retour sur la discipline uniquement pour les Mondiaux, trois ans apr\u00e8s sa transition en skicross) cette derni\u00e8re ayant en prime rafl\u00e9 tous les titres. Quel est ton sentiment \u00e0 ce sujet\u00a0?<\/h3>\n<p style=\"text-align: justify;\">Je ne suis pas de cet avis, <strong>je ne consid\u00e8re pas avoir \u00e9t\u00e9 priv\u00e9e d\u2019une m\u00e9daille d\u2019or<\/strong>. Au contraire, elle a le droit de s\u2019inscrire aux Mondiaux. Elle est sans doute arriv\u00e9e avec plus d\u2019\u00e9nergie vu qu\u2019elle n\u2019a pas fait les comp\u00e9titions d\u2019avant. Cependant, je consid\u00e8re qu\u2019<strong>elle m\u00e9rite ce titre<\/strong>, et que nous, les athl\u00e8tes \u00e9voluant sur le circuit, devons le prendre comme une remise en question. Se dire qu\u2019on a encore de la marge pour arriver \u00e0 son niveau. Elle a vraiment domin\u00e9 et je suis admirative de \u00e7a. Sa pr\u00e9paration physique a \u00e9t\u00e9 faite \u00e0 100 % et il faut s\u2019inspirer de \u00e7a. C\u2019\u00e9tait \u00e0 nous d\u2019\u00eatre meilleures.<\/p>\n<h3 style=\"text-align: justify;\">En Coupe du monde, tu es parvenue \u00e0 te hisser sur le podium du classement g\u00e9n\u00e9ral derri\u00e8re Jasmin Taylor et Argeline Tan-Bouquet. Est-ce que tu t\u2019attendais \u00e0 te retrouver en si bonne position au d\u00e9but de l\u2019hiver\u00a0?<\/h3>\n<p style=\"text-align: justify;\">En d\u00e9but d\u2019hiver, <strong>je m\u2019\u00e9tais fix\u00e9e des objectifs plus ambitieux que les pr\u00e9c\u00e9dentes ann\u00e9es<\/strong>. C\u2019\u00e9tait ma cinqui\u00e8me saison de t\u00e9l\u00e9mark, la quatri\u00e8me en \u00c9quipe de France, et je souhaitais <strong>enlever cette \u00e9tiquette de grand espoir du circuit<\/strong>, dans le but d\u2019aller chercher quelque chose de grand. En discutant avec l\u2019entra\u00eeneur, je me suis dit que mes objectifs \u00e9taient peut-\u00eatre trop \u00e9lev\u00e9s, mais je voulais sortir de ma zone de confort. Il s\u2019agissait soit d\u2019obtenir un globe, soit de finir dans le Top 3 du classement g\u00e9n\u00e9ral. L\u2019objectif est donc rempli !<\/p>\n<p style=\"text-align: justify;\">La saison s\u2019est vraiment bien pass\u00e9e, m\u00eame si j\u2019ai un peu p\u00each\u00e9 \u00e0 la fin. Au fur et \u00e0 mesure de l\u2019hiver, j\u2019ai cru \u00e0 ce globe. J\u2019ai appr\u00e9ci\u00e9 mes victoires, mais toujours avec cet objectif dans un coin de la t\u00eate, et une ambition \u00e9lev\u00e9e. Finalement, <strong>ma saison est r\u00e9ussie, m\u00eame si j\u2019ai l\u2019impression d\u2019\u00eatre pass\u00e9e \u00e0 c\u00f4t\u00e9 de ce globe en Coupe du monde, et d\u2019une m\u00e9daille d\u2019or aux Mondiaux<\/strong>. Avec un peu de recul, je vais \u00eatre tr\u00e8s satisfaite, et je suis contente de m\u2019\u00eatre fix\u00e9 des objectifs ambitieux qui ont \u00e9t\u00e9 accomplis.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">VICTOIRE \u00c0 LA MAISON ! \ud83c\uddeb\ud83c\uddf7<br \/>\nAugustine Carliez remporte la Classic telemark de Pra Loup !<br \/>\nDe bon augure pour les mondiaux qui approchent \u00e0 domicile dans la station <a href=\"https:\/\/twitter.com\/les_contamines?ref_src=twsrc%5Etfw\">@les_contamines<\/a> . \ud83d\udcaa<\/p>\n<p>De nombreux Bleus sur la bo\u00eete Classic :<br \/>\n\u2fe2 Charly Petex<br \/>\n\u2fe3 Laly Chaucheprat &amp; Yoann Rostolan<\/p>\n<p>\ud83d\udcf8\u2026 <a href=\"https:\/\/t.co\/lI83qaDdCu\">pic.twitter.com\/lI83qaDdCu<\/a><\/p>\n<p>\u2014 FFS &#8211; F\u00e9d\u00e9ration Fran\u00e7aise de Ski (@FedFranceSki) <a href=\"https:\/\/twitter.com\/FedFranceSki\/status\/1899794207000195230?ref_src=twsrc%5Etfw\">March 12, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">Un petit globe de cristal, ou m\u00eame le gros globe, se rapprochent au fil des hivers. Selon toi, quels sont les aspects que tu dois travailler pour pouvoir y pr\u00e9tendre\u00a0?<\/h3>\n<p style=\"text-align: justify;\"><strong>Physiquement, j\u2019ai encore quelques points \u00e0 am\u00e9liorer<\/strong>. Sur certaines courses, j\u2019ai eu du mal \u00e0 me mettre dedans d\u00e8s le d\u00e9part. C\u2019est pour \u00e7a que la Classic me correspond bien, il me faut un peu de temps et quelques portes pour rentrer dans mon plan de ski. <strong>Sur le plan mental, certains aspects sont \u00e9galement \u00e0 travailler.<\/strong> J\u2019avais une pr\u00e9paratrice en d\u00e9but de saison. Malheureusement, je n\u2019ai pas pu aller au bout avec, mais j\u2019ai continu\u00e9 \u00e0 mettre en place les cl\u00e9s qu\u2019elle m\u2019avait donn\u00e9es.<\/p>\n<p style=\"text-align: justify;\">Je suis plut\u00f4t jeune par rapport aux autres cadors du circuit et j\u2019ai encore <strong>un d\u00e9ficit d\u2019exp\u00e9rience \u00e0 combler<\/strong>. Sinon, il faut \u00e9galement continuer \u00e0 s\u2019entra\u00eener techniquement et physiquement. Cet hiver, j\u2019ai mis en place une bonne routine de r\u00e9cup\u00e9ration que je n\u2019avais pas auparavant. Je suis aussi suivie par un masseur et un centre de r\u00e9cup\u00e9ration, ce qui m\u2019a permis d\u2019optimiser le tout. Mais je peux encore faire mieux vu que la fin de saison a \u00e9t\u00e9 difficile. Il y a encore du travail !<\/p>\n<h3 style=\"text-align: justify;\">En parall\u00e8le \u00e0 ta carri\u00e8re sportive, tu m\u00e8nes des \u00e9tudes en odontologie (chirurgie dentaire). Comment parviens-tu \u00e0 g\u00e9rer cette double casquette, notamment en pleine saison ?<\/h3>\n<p style=\"text-align: justify;\">J\u2019ai v\u00e9cu une vie d\u2019\u00e9tudiante plut\u00f4t classique sur les mois de septembre, octobre et novembre, m\u00eame si on a eu quelques stages sur les skis, environ un par mois. C\u2019est d\u00e9j\u00e0 pas mal, mais c\u2019est plut\u00f4t l\u00e9ger par rapport \u00e0 l\u2019hiver o\u00f9 j\u2019y ai moins mis les pieds. La facult\u00e9 me permet d\u2019avoir des am\u00e9nagements pour rattraper les cours et les travaux pratiques. J\u2019avais le droit de changer de groupe, de rattraper en amont. L\u00e0, j&rsquo;ai encore une mati\u00e8re que je vais rattraper cette semaine.<\/p>\n<p style=\"text-align: justify;\"><strong>La facult\u00e9 a jou\u00e9 le jeu du double projet et m\u2019a fait confiance avec ces am\u00e9nagements<\/strong>. J\u2019ai deux gros mois de cours th\u00e9oriques \u00e0 rattraper, donc je serai beaucoup plus pr\u00e9sente sur Lyon pour combler ce retard avant les examens de mi-mai. On est en p\u00e9riode de repos sportif, donc je vais pouvoir me mettre \u00e0 100 % dans les cours. Je suis sur une deuxi\u00e8me ann\u00e9e plut\u00f4t l\u00e9g\u00e8re, contrairement \u00e0 la premi\u00e8re, que j\u2019ai effectu\u00e9 \u00e0 l\u2019Universit\u00e9 Grenoble Alpes, et qui \u00e9tait d\u00e9doubl\u00e9e sur deux ans.<\/p>\n<p>\u00a0<iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FUnivLyon1%2Fposts%2Fpfbid02SKKnhKHHExo79JScKXu8mgkTG1Gh1eBmXUqbqJ1SRHi15qrLFz4iBDwjzkNvyw3Ql&amp;show_text=false&amp;width=500\" width=\"500\" height=\"498\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3 style=\"text-align: justify;\">Comme de nombreux membres de l\u2019\u00c9quipe de France, tu as effectu\u00e9 la transition de l\u2019alpin au t\u00e9l\u00e9mark il y a plusieurs ann\u00e9es. Pourquoi avoir fait le choix de te lancer \u00e0 100\u00a0% dans cette discipline\u00a0?<\/h3>\n<p style=\"text-align: justify;\">Effectivement, j\u2019ai fait <strong>beaucoup de ski alpin, jusqu\u2019\u00e0 environ 15 ans<\/strong>. Puis, au fur et \u00e0 mesure des s\u00e9lections, je pense \u00eatre arriv\u00e9e \u00e0 mon meilleur niveau et je ne faisais pas partie des dix meilleures fran\u00e7aises. Du coup, j\u2019ai voulu trouver un nouveau challenge. Ma m\u00e8re fait du t\u00e9l\u00e9mark depuis toujours donc j\u2019avais essay\u00e9 d\u00e9j\u00e0 quelques fois. Je me suis orient\u00e9e l\u00e0-dessus en sachant que toutes les bases physiques et techniques de l\u2019alpin m\u2019ont facilit\u00e9 cette transition. Les deux disciplines sont assez proches. Il y a tout de m\u00eame des contraintes en plus, notamment la fente, mais aussi le ski de fond et le saut que j\u2019ai d\u00fb travailler.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/laly-chaucheprat-telemark-on-manque-de-visibilite-alors-que-cest-un-sport-tres-televisuel\/\">Laly Chaucheprat (T\u00e9l\u00e9mark) : \u00ab On manque de visibilit\u00e9 alors que c\u2019est un sport tr\u00e8s t\u00e9l\u00e9visuel \u00bb<\/a><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Tu auras seulement 26 ans lorsque les Jeux Olympiques se d\u00e9rouleront dans les Alpes. Est-ce que l\u2019espoir d\u2019y participer est d\u00e9j\u00e0 dans ton esprit\u00a0?<\/h3>\n<p style=\"text-align: justify;\">Je l\u2019ai dans un coin de ma t\u00eate\u00a0! Cinq ans, c\u2019est \u00e0 la fois long et rapide. On esp\u00e8re que \u00e7a deviendra un sport olympique avant d\u2019y \u00eatre. On sait qu\u2019il y a des chances et tout le monde fait en sorte que \u00e7a se concr\u00e9tise. <strong>Si \u00e7a y rentre, le r\u00eave ultime sera bien s\u00fbr de participer<\/strong>. Je suis encore assez jeune donc je me vois encore continuer jusque-l\u00e0. J\u2019y pense sans trop y penser, mais c\u2019est s\u00fbr que \u00e7a fait r\u00eaver\u00a0!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00c9L\u00c9MARK \u2013 3\u00e8me de la derni\u00e8re Coupe du monde, m\u00e9daill\u00e9e d\u2019argent aux Mondiaux S\u00e9niors, triple m\u00e9daill\u00e9e d\u2019or aux Mondiaux Juniors\u2026 Dire que la saison d\u2019Augustine Carliez a \u00e9t\u00e9 couronn\u00e9e de r\u00e9ussite serait un euph\u00e9misme. Quelques jours apr\u00e8s ses derniers exploits \u00e0 Bardonecchia, la t\u00e9l\u00e9markeuse tricolore s\u2019est livr\u00e9e en longueur sur son brillant hiver pour Dicodusport.<\/p>\n","protected":false},"author":55,"featured_media":570978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[45756],"tags":[30242,16878,45038,24,675],"class_list":["post-570904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-telemark","tag-augustine-carliez","tag-breve","tag-championnats-du-monde-telemark","tag-sport","tag-telemark"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: &quot;Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !&quot;<\/title>\n<meta name=\"description\" content=\"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: &quot;Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !&quot;\" \/>\n<meta property=\"og:description\" content=\"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T12:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T12:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: &quot;Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \u00ab\u00a0Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\u00a0\u00bb\",\"datePublished\":\"2025-04-09T12:00:57+00:00\",\"dateModified\":\"2025-04-09T12:21:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\"},\"wordCount\":2278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png\",\"keywords\":[\"Augustine Carliez\",\"br\u00e8ve\",\"championnats du monde t\u00e9l\u00e9mark\",\"sport\",\"T\u00e9l\u00e9mark\"],\"articleSection\":[\"T\u00e9l\u00e9mark\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\",\"name\":\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \\\"Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png\",\"datePublished\":\"2025-04-09T12:00:57+00:00\",\"dateModified\":\"2025-04-09T12:21:49+00:00\",\"description\":\"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png\",\"width\":1200,\"height\":674,\"caption\":\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0 Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \u00ab\u00a0Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \"Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\"","description":"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/","og_locale":"fr_FR","og_type":"article","og_title":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \"Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\"","og_description":"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.","og_url":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-04-09T12:00:57+00:00","article_modified_time":"2025-04-09T12:21:49+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \"Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\"","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \u00ab\u00a0Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\u00a0\u00bb","datePublished":"2025-04-09T12:00:57+00:00","dateModified":"2025-04-09T12:21:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/"},"wordCount":2278,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png","keywords":["Augustine Carliez","br\u00e8ve","championnats du monde t\u00e9l\u00e9mark","sport","T\u00e9l\u00e9mark"],"articleSection":["T\u00e9l\u00e9mark"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/","url":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/","name":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \"Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png","datePublished":"2025-04-09T12:00:57+00:00","dateModified":"2025-04-09T12:21:49+00:00","description":"T\u00c9L\u00c9MARK \u2013 Dans la foul\u00e9e de son tripl\u00e9 dor\u00e9 aux Mondiaux juniors, Augustine Carliez est revenue en longueur sur son excellente saison.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Augustine-Carliez-Telemark-Je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note-.png","width":1200,"height":674,"caption":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0 Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/augustine-carliez-telemark-je-suis-soulagee-de-sortir-de-cette-saison-sur-une-bonne-note\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Augustine Carliez (T\u00e9l\u00e9mark)\u00a0: \u00ab\u00a0Je suis soulag\u00e9e de sortir de cette saison sur une bonne note !\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/570904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=570904"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/570904\/revisions"}],"predecessor-version":[{"id":570979,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/570904\/revisions\/570979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/570978"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=570904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=570904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=570904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}