{"id":571042,"date":"2025-04-09T19:47:06","date_gmt":"2025-04-09T17:47:06","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=571042&#038;preview=true&#038;preview_id=571042"},"modified":"2025-04-09T19:47:06","modified_gmt":"2025-04-09T17:47:06","slug":"transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/","title":{"rendered":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">FC Grenoble : Raffaele Costa Storti (Stade Fran\u00e7ais) s&rsquo;engage<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est officiel. Selon <a href=\"https:\/\/www.ledauphine.com\/sport\/2025\/04\/09\/fcg-un-accord-trouve-pour-l-international-portugais-du-stade-francais-raffaele-costa-storti\"><em>Le Dauphin\u00e9<\/em><\/a>, <strong>Raffaele Costa Storti<\/strong> \u00e9voluera \u00e0 <strong>Grenoble<\/strong> d\u00e8s l&rsquo;\u00e9t\u00e9 prochain. Le trois-quarts portugais de 24 ans, encore sous contrat au <strong>Stade Fran\u00e7ais<\/strong> la saison prochaine, est \u00e0 la recherche de temps de jeu. Avec seulement 13 matchs au compteur cette saison (un essai inscrit), le retour de <strong>Costa Storti<\/strong> \u00e0 <strong>Paris<\/strong> ne s&rsquo;est pas pass\u00e9 comme pr\u00e9vu, apr\u00e8s un pr\u00eat de grande qualit\u00e9 \u00e0 <strong>B\u00e9ziers<\/strong>.<\/p>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 annonc\u00e9 proche d&rsquo;un transfert \u00e0 <strong>Castres<\/strong> (avec effet imm\u00e9diat) il y a quelques semaines, l&rsquo;international portugais a finalement trouv\u00e9 une porte de sortie, en signant \u00e0 <strong>Grenoble<\/strong>, club des plus ambitieux, largement en t\u00eate de la Pro D2, o\u00f9 il devrait encha\u00eener les rencontres.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>: <\/strong>Sacr\u00e9e prise de la part du FC Grenoble ! Malgr\u00e9 sa saison bien d\u00e9licate au Stade Fran\u00e7ais, il reste un serial marqueur hors pair. Si le club is\u00e9rois parvient \u00e0 monter en Top 14, gare aux d\u00e9fenses adverses !<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-raffaele-costa-storti-va-quitter-le-stade-francais-pour-signer-en-pro-d2\/\">Transferts : Raffaele Costa Storti va quitter le Stade Fran\u00e7ais pour signer en Pro D2<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Stade Rochelais : \u00c7a coince pour Tommaso Menoncello<\/h2>\n<p style=\"text-align: justify;\"><strong>Tommaso Menoncello<\/strong> \u00e0 La Rochelle, une affaire qui a pris du plomb dans l&rsquo;aile. Selon nos confr\u00e8res d&rsquo;<a href=\"https:\/\/actu.fr\/nouvelle-aquitaine\/la-rochelle_17300\/transferts-le-dossier-menoncello-en-stand-by-a-la-rochelle-pourquoi-ca-bloque_62488341.html\"><em>Actu Rugby<\/em><\/a>, le trois-quarts de 22 ans, qui \u00e9volue au <strong>Benetton Tr\u00e9vise<\/strong>, est loin d&rsquo;avoir sign\u00e9 au <strong>Stade Rochelais<\/strong>, alors que son transfert semblait en bonne voie ces derniers jours. En cause, la mauvaise passe des <em>Maritimes<\/em>, seulement 10\u00e8mes au classement de Top 14 et \u00e9limin\u00e9s de la Champions Cup au stade des 8\u00e8mes de finale.<\/p>\n<p style=\"text-align: justify;\">Cons\u00e9quence, le recrutement du crack italien, capable de jouer aux deux postes de centre, est mis sur pause, face \u00e0 l&rsquo;incertitude d&rsquo;une qualification (ou non) en <strong>Champions Cup<\/strong> la saison prochaine, les <em>Jaune et Noir<\/em> pointant \u00e0 trois points de la 8\u00e8me place. Pour rappel, le <strong>RC Toulon<\/strong> est aussi \u00e0 l&rsquo;aff\u00fbt sur le dossier <strong>Menoncello<\/strong>, ce dernier \u00e9tant encore sous contrat une saison \u00e0 <strong>Tr\u00e9vise<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> Les premiers effets de la mauvaise forme du Stade Rochelais. Parmi les clubs les plus attractifs de France (et d&rsquo;Europe), La Rochelle pourrait conna\u00eetre un revers de taille sur le march\u00e9 des transferts. Si Menoncello choisit un autre club, car les Jaune et Noir ne parviennent pas \u00e0 se qualifier en Champions Cup, ce serait un v\u00e9ritable coup dur.<\/em><\/p>\n<h2 style=\"text-align: justify;\">Stade Ni\u00e7ois : Vague de d\u00e9parts \u00e0 Nice<\/h2>\n<p style=\"text-align: justify;\">Onze, c&rsquo;est le nombre de d\u00e9parts annonc\u00e9s par le <strong>Stade Ni\u00e7ois<\/strong> ce mercredi. Devant d&rsquo;abord, six joueurs vont quitter le C\u00f4te d&rsquo;Azur. Les piliers <strong>K\u00e9vin Yam\u00e9ogo<\/strong> (28 ans), <strong>Tom Ross<\/strong> (27 ans), <strong>Julien Beaufils<\/strong> (26 ans) et <strong>Fabio Gonzalez<\/strong> (25 ans) s&rsquo;en vont. M\u00eame chose pour le deuxi\u00e8me ligne <strong>Adrien Vigne<\/strong> (26 ans), ainsi que le troisi\u00e8me ligne <strong>Joris Simon<\/strong> (29 ans).<\/p>\n<p style=\"text-align: justify;\">\u00c0 la charni\u00e8re, deux demis de m\u00eal\u00e9e font leur valise : <strong>Thibault Dufau<\/strong> (30 ans) et <strong>Corentin Penc&rsquo;hoat<\/strong> (24 ans). L&rsquo;ouvreur <strong>Mathis Viard<\/strong> (28 ans) plie \u00e9galement bagages. Enfin, chez les trois-quarts, deux d\u00e9parts sont \u00e0 signaler : le centre <strong>Alban Conduch\u00e9<\/strong> (28 ans) et l&rsquo;ailier <strong>Christiaan Erasmus<\/strong> (29 ans).<\/p>\n<p style=\"text-align: justify;\">Pour rappel, le <strong>Stade Ni\u00e7ois<\/strong> a r\u00e9alis\u00e9 un recrutement XXL, avec des noms ronflants comme <strong>Hayden Thompson-Stringer<\/strong>, <strong>Josh Tyrell<\/strong>, <strong>Uzair Cassiem<\/strong>, <strong>Guillaume Rouet<\/strong>, <strong>Owen Williams<\/strong> ou <strong>Waisea Nayacalevu<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> Sans surprise, au regard du recrutement pl\u00e9thorique pour une \u00e9quipe qui \u00e9voluera en Nationale la saison prochaine, Nice fait le m\u00e9nage. Un changement de dimension, humainement parlant, sur le terrain, synonyme d&rsquo;avenir radieux ? En attendant, les Ni\u00e7ois vont devoir manger leur pain noir en troisi\u00e8me division.<\/em><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril<\/p>\n","protected":false},"author":4,"featured_media":557968,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-571042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T17:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\",\"datePublished\":\"2025-04-09T17:47:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\"},\"wordCount\":672,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\",\"name\":\"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png\",\"datePublished\":\"2025-04-09T17:47:06+00:00\",\"description\":\"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby : Raffaele Costa Storti, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril","description":"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril","og_description":"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-04-09T17:47:06+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril","datePublished":"2025-04-09T17:47:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/"},"wordCount":672,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/","name":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png","datePublished":"2025-04-09T17:47:06+00:00","description":"TRANSFERTS RUGBY - Raffaele Costa Storti (Stade Fran\u00e7ais) signe en Pro D2, \u00e7a coince pour Tommaso Menoncello au Stade Rochelais, le Stade Ni\u00e7ois annonce une vague de d\u00e9parts : les infos transferts du mercredi 9 avril.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Transferts-Stade-Francais-Raffaele-Costa-Storti-va-signer-en-Pro-D2.png","width":1200,"height":674,"caption":"Transferts Rugby : Raffaele Costa Storti, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-raffaele-costa-storti-tommaso-menoncello-stade-nicois-les-infos-transferts-du-mercredi-9-avril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Raffaele Costa Storti, Tommaso Menoncello, Stade Ni\u00e7ois, les infos transferts du mercredi 9 avril"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=571042"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571042\/revisions"}],"predecessor-version":[{"id":571113,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571042\/revisions\/571113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/557968"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=571042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=571042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=571042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}