{"id":571093,"date":"2025-04-09T22:56:33","date_gmt":"2025-04-09T20:56:33","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=571093&#038;preview=true&#038;preview_id=571093"},"modified":"2025-09-16T07:59:24","modified_gmt":"2025-09-16T05:59:24","slug":"ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/","title":{"rendered":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>LIGUE DES CHAMPIONS 2024-2025 &#8211; Dominateur sans r\u00e9ellement briller, le PSG a assur\u00e9 l\u2019essentiel. Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer (3-1) lors de ce quart de finale aller. C\u2019est Khvicha Kvaratskhelia qui a remis les siens sur les rails, avant que D\u00e9sir\u00e9 Dou\u00e9 et Nuno Mendes ne scellent la victoire. Un succ\u00e8s important pour les hommes de Luis Enrique, qui prennent ainsi une pr\u00e9cieuse avance avant le match retour en Angleterre.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-ligue-des-champions-le-tableau-complet\/\">Phase finale Ligue des Champions : Le tableau complet<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Dernier repr\u00e9sentant tricolore en Ligue des champions, le <strong>Paris Saint-Germain<\/strong> recevait ce soir le club anglais d\u2019<strong>Aston Villa<\/strong> au Parc des Princes, \u00e0 l\u2019occasion du quart de finale aller. L\u2019objectif \u00e9tait clair pour les Parisiens : s\u2019imposer devant leur public, avec autorit\u00e9, afin de prendre une option sur la qualification avant le match retour pr\u00e9vu la semaine prochaine \u00e0 <strong>Villa Park<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Un PSG dominateur face \u00e0 un mur anglais<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"228\" data-end=\"803\">Les 30 premi\u00e8res minutes donnent le ton : le <strong>PSG<\/strong> monopolise le ballon avec plus de 85 % de possession. En face, <strong>Aston Villa<\/strong> campe dans ses 30 m\u00e8tres, repli\u00e9 en double rideau d\u00e9fensif avec pour seul objectif de verrouiller les espaces. Sans v\u00e9ritable num\u00e9ro 9, <strong>Gon\u00e7alo Ramos<\/strong> une nouvelle fois laiss\u00e9 sur le banc, les <strong>Parisiens<\/strong> peinent \u00e0 se montrer dangereux dans la surface adverse. Les rares tentatives proviennent de frappes lointaines sign\u00e9es <strong>Vitinha<\/strong>, <strong>Jo\u00e3o Neves<\/strong> ou encore<strong> Achraf Hakimi<\/strong>, mais elles s\u2019envolent ou sont ais\u00e9ment capt\u00e9es par <strong>Emiliano Martinez<\/strong>, vigilant.<\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"805\" data-end=\"986\">C\u00f4t\u00e9 anglais, les tentatives offensives restent timides. Les quelques contres tent\u00e9s par les <strong>Villans<\/strong> sont rapidement \u00e9touff\u00e9s par un contre-pressing parisien toujours aussi efficace.<\/p>\n<h2 style=\"text-align: justify;\" data-start=\"805\" data-end=\"986\">Morgan Rogers climatise le Parc des Princes<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"212\" data-end=\"713\">Mais alors que la domination parisienne s\u2019enlisait dans une st\u00e9rilit\u00e9 grandissante, marqu\u00e9e par quelques impr\u00e9cisions techniques \u00e0 l\u2019image d\u2019un d\u00e9calage compl\u00e8tement manqu\u00e9 de <strong>Demb\u00e9l\u00e9<\/strong> pour <strong>Hakimi<\/strong>, <strong>Aston Villa<\/strong> va frapper l\u00e0 o\u00f9 \u00e7a fait mal. Sur une perte de balle de <strong>Nuno Mendes<\/strong> plein axe, le rus\u00e9 <strong>John McGinn<\/strong> intercepte et lance imm\u00e9diatement la transition.<\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"212\" data-end=\"713\">Le milieu \u00e9cossais renverse le jeu vers <strong>Marcus Rashford<\/strong>, qui contr\u00f4le, fixe <strong>Beraldo<\/strong>, puis sert intelligemment <strong>Youri Tielemans<\/strong> dans la profondeur. Le Belge centre en premi\u00e8re intention au sol, et <strong>Morgan Rogers<\/strong> surgit au second poteau pour pousser le ballon dans un but d\u00e9sert\u00e9. Impuissant, <strong>Donnarumma<\/strong> ne peut que constater les d\u00e9g\u00e2ts. \u00c0 l\u2019image de sa c\u00e9l\u00e9bration glaciale, l\u2019attaquant anglais vient de faire chuter la temp\u00e9rature sur la capitale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le Prince William peut exulter !<\/p>\n<p>Aston Villa m\u00e8ne 1-0 gr\u00e2ce \u00e0 Morgan Rogers. \ud83e\udd76<a href=\"https:\/\/twitter.com\/hashtag\/PARAVL?src=hash&amp;ref_src=twsrc%5Etfw\">#PARAVL<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/qP1HgoWCUv\">pic.twitter.com\/qP1HgoWCUv<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1910055219284660477?ref_src=twsrc%5Etfw\">April 9, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" data-start=\"212\" data-end=\"713\">Cinq minutes plus tard, le PSG remet les pendules \u00e0 l\u2019heure<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"184\" data-end=\"806\">La r\u00e9ponse parisienne ne se fait pas attendre. Moins de cinq minutes apr\u00e8s l\u2019ouverture du score, <strong>D\u00e9sir\u00e9 Dou\u00e9<\/strong> allume la premi\u00e8re m\u00e8che : une frappe puissante des 20 m\u00e8tres, repouss\u00e9e en deux temps par <strong>Emiliano Martinez<\/strong>. L\u2019action se poursuit, et quelques instants plus tard, le jeune milieu parisien r\u00e9cup\u00e8re \u00e0 nouveau le ballon c\u00f4t\u00e9 gauche. Il repique l\u00e9g\u00e8rement sur son pied droit, d\u00e9clenche une frappe enroul\u00e9e, et trouve la lucarne avec l\u2019aide de la barre transversale. <strong>Martinez<\/strong>, fig\u00e9 sur sa ligne, ne peut qu\u2019aller chercher le ballon au fond de ses filets, au plus grand bonheur des 70 millions de Fran\u00e7ais. Explosion de joie au Parc.<\/p>\n<ul style=\"text-align: justify;\">\n<li data-start=\"184\" data-end=\"806\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/video-resume-psg-aston-villa-quart-de-finale-aller-de-ligue-des-champions\/\">[Vid\u00e9o] R\u00e9sum\u00e9 PSG-Aston Villa, quart de finale aller de Ligue des champions<\/a><\/strong><\/li>\n<\/ul>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"808\" data-end=\"1037\">Un but somptueux qui permet au PSG de revenir \u00e0 1-1, juste avant la pause. Un score prometteur, mais qui appelle les <strong>Parisiens<\/strong> \u00e0 davantage de prise de risques en seconde p\u00e9riode pour enfin faire c\u00e9der le bloc compact des Villans.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">QUEL CHEF-D&rsquo;\u0152UVRE DE D\u00c9SIR\u00c9 DOU\u00c9 \ud83e\udd2f<\/p>\n<p>Le PSG \u00e9galise seulement 3min apr\u00e8s l&rsquo;ouverture du score d&rsquo;Aston Villa !<a href=\"https:\/\/twitter.com\/hashtag\/PARAVL?src=hash&amp;ref_src=twsrc%5Etfw\">#PARAVL<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/dbBE6T06H3\">pic.twitter.com\/dbBE6T06H3<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1910057206189301848?ref_src=twsrc%5Etfw\">April 9, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" data-start=\"808\" data-end=\"1037\">Kvaratskhelia embrase la capitale<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"218\" data-end=\"562\">Le <strong>PSG<\/strong> a bien saisi la le\u00e7on : pour faire craquer le verrou anglais, il faut acc\u00e9l\u00e9rer le rythme. Et d\u00e8s le retour des vestiaires, les <strong>Parisiens<\/strong> mettent les gaz. Apr\u00e8s un superbe encha\u00eenement en une touche entre <strong>Demb\u00e9l\u00e9<\/strong>, <strong>Hakimi<\/strong> et <strong>Fabi\u00e1n Ruiz<\/strong>, le ballon atterrit dans les pieds de <strong>Kvaratskhelia<\/strong>, \u00e0 une quarantaine de m\u00e8tres du but, c\u00f4t\u00e9 gauche. Le G\u00e9orgien remonte le terrain balle au pied, fixe <strong>Axel Disasi<\/strong>, tout juste entr\u00e9 en jeu, et le fait litt\u00e9ralement danser. Un crochet d\u00e9vastateur, puis une frappe pied gauche surpuissante, qui vient se loger sous la barre. <strong>Emiliano Martinez<\/strong> ne peut rien faire. Le Parc explose, <strong>Paris<\/strong> passe devant, 2-1.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LE BIJOU DE KVARATSKHELIA PERMET \u00c0 PARIS DE PRENDRE L&rsquo;AVANTAGE ! \ud83e\udd2f<\/p>\n<p>Magnifique crochet sur Disasi, accompagn\u00e9 d&rsquo;une frappe splendide en lucarne !<a href=\"https:\/\/twitter.com\/hashtag\/PARAVL?src=hash&amp;ref_src=twsrc%5Etfw\">#PARAVL<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/yOx8supB2L\">pic.twitter.com\/yOx8supB2L<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1910064252041244877?ref_src=twsrc%5Etfw\">April 9, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"864\" data-end=\"1118\">Les hommes de <strong>Luis Enrique<\/strong> ne s\u2019arr\u00eatent pas l\u00e0. Dop\u00e9s par cette entame tonitruante de seconde p\u00e9riode, ils encha\u00eenent les mouvements rapides, les permutations, les combinaisons. Les intentions sont claires : breaker au plus vite pour se mettre \u00e0 l\u2019abri.<\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"864\" data-end=\"1118\">Apr\u00e8s un temps fort du <strong>PSG<\/strong>, le rythme retombe progressivement. Les minutes d\u00e9filent avec une nette possession parisienne, mais sans v\u00e9ritable occasion franche \u00e0 signaler. Seul un but refus\u00e9 \u00e0 <strong>Achraf Hakimi<\/strong>, logiquement annul\u00e9 pour une position de hors-jeu flagrante, vient bri\u00e8vement animer une seconde p\u00e9riode globalement ma\u00eetris\u00e9e par les <strong>Parisiens<\/strong>. Le contre-pressing du <strong>PSG<\/strong> reste redoutablement efficace, \u00e9touffant toute tentative de relance c\u00f4t\u00e9 anglais. Les <strong>Villans<\/strong>, totalement accul\u00e9s, peinent \u00e0 franchir la ligne m\u00e9diane et subissent l\u2019intensit\u00e9 impos\u00e9e par les joueurs de la capitale.<\/p>\n<h2 style=\"text-align: justify;\" data-start=\"864\" data-end=\"1118\">Nuno Mendes assomme Aston Villa dans le temps additionnel<\/h2>\n<p style=\"text-align: justify;\" data-start=\"864\" data-end=\"1118\"><strong data-start=\"142\" data-end=\"253\">Le break viendra dans le temps additionnel, au terme d&rsquo;une action parfaitement exploit\u00e9e par les Parisiens.<\/strong> Alors qu\u2019<strong>Aston Villa<\/strong> tente un dernier pressing, trop haut et mal coordonn\u00e9, les espaces s\u2019ouvrent dans leur dos. <strong>Ousmane<\/strong> <strong>Demb\u00e9l\u00e9<\/strong> en profite imm\u00e9diatement et lance <strong>Nuno Mendes<\/strong> dans la profondeur. Le lat\u00e9ral portugais, plein de lucidit\u00e9, \u00e9limine son vis-\u00e0-vis d\u2019un crochet avant d\u2019ajuster un tir puissant du pied droit qui termine sa course en pleine lucarne. <strong>3-1<\/strong> score final, un but aussi superbe que crucial dans la course \u00e0 la qualification.<\/p>\n<p style=\"text-align: justify;\" data-start=\"864\" data-end=\"1118\">Rendez-vous dans une semaine \u00e0 Birmingham pour le match retour, o\u00f9 le <strong>PSG<\/strong> devra confirmer cette avance acquise au Parc. Avec ce succ\u00e8s 3-1, les <strong>Parisiens<\/strong> prennent une belle option sur les demi-finales, mais restent conscients que rien n\u2019est encore jou\u00e9 face \u00e0 une \u00e9quipe d\u2019<strong>Aston Villa<\/strong> capable de r\u00e9agir devant son public.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-affiches-et-dates-des-quarts-de-finale\/\">Ligue des Champions : Affiches et dates des quarts de finale<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS 2024-2025 &#8211; Dominateur sans r\u00e9ellement briller, le PSG a assur\u00e9 l\u2019essentiel. Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer (3-1) lors de ce quart de finale aller. C\u2019est Khvicha Kvaratskhelia qui a remis les siens sur les rails, avant que D\u00e9sir\u00e9 Dou\u00e9 et Nuno Mendes ne scellent la victoire. Un succ\u00e8s important pour les hommes de Luis Enrique, qui prennent ainsi une pr\u00e9cieuse avance avant le match retour en Angleterre.<\/p>\n","protected":false},"author":111,"featured_media":571163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[16878,75,910,24],"class_list":["post-571093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-breve","tag-football","tag-psg","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T20:56:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T05:59:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\",\"datePublished\":\"2025-04-09T20:56:33+00:00\",\"dateModified\":\"2025-09-16T05:59:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\"},\"wordCount\":1174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"PSG\",\"sport\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\",\"name\":\"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png\",\"datePublished\":\"2025-04-09T20:56:33+00:00\",\"dateModified\":\"2025-09-16T05:59:24+00:00\",\"description\":\"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue des Champions Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9","description":"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9","og_description":"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-04-09T20:56:33+00:00","article_modified_time":"2025-09-16T05:59:24+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9","datePublished":"2025-04-09T20:56:33+00:00","dateModified":"2025-09-16T05:59:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/"},"wordCount":1174,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png","keywords":["br\u00e8ve","Football","PSG","sport"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/","name":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png","datePublished":"2025-04-09T20:56:33+00:00","dateModified":"2025-09-16T05:59:24+00:00","description":"LIGUE DES CHAMPIONS 2024-2025 - Men\u00e9s 0-1 contre le cours du jeu, les Parisiens ont su renverser la situation pour s\u2019imposer lors de ce quart de finale aller.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ligue-des-Champions-Paris-fait-le-job-contre-Aston-Villa-et-se-rapproche-du-dernier-carre.png","width":1200,"height":674,"caption":"Ligue des Champions Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-paris-fait-le-job-contre-aston-villa-et-se-rapproche-du-dernier-carre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue des Champions : Paris fait le job contre Aston Villa et se rapproche du dernier carr\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=571093"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571093\/revisions"}],"predecessor-version":[{"id":571169,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571093\/revisions\/571169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/571163"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=571093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=571093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=571093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}