{"id":571184,"date":"2025-04-11T14:17:17","date_gmt":"2025-04-11T12:17:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=571184&#038;preview=true&#038;preview_id=571184"},"modified":"2025-04-11T14:18:40","modified_gmt":"2025-04-11T12:18:40","slug":"ospreys-lyon-compositions-chaine-tv-et-heure","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/","title":{"rendered":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/em><\/h4>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/challenge-cup-2024-2025-tableau-complet-de-la-phase-finale\/\">Phase finale Challenge Cup : Le tableau complet<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le quart de finale de la Challenge Cup 2024\/2025 opposant les <strong>Ospreys<\/strong> au <strong>Lyon OU<\/strong> aura lieu ce samedi 12 avril, \u00e0 18h30, au Swansea.com Stadium.<\/p>\n<h2 style=\"text-align: justify;\">Pas facile pour Lyon<\/h2>\n<p style=\"text-align: justify;\"><strong>Lyon<\/strong> conna\u00eet jusqu&rsquo;ici une ann\u00e9e 2025 assez r\u00e9ussie. Dix matchs, 7 victoires, et les Lyonnais se sont replac\u00e9s en Top 14, \u00e9tant d\u00e9sormais parfaitement install\u00e9s dans la lutte pour le Top 6. En Challenge Cup, apr\u00e8s une phase de poule ma\u00eetris\u00e9e et une deuxi\u00e8me place, le LOU a parfaitement n\u00e9goci\u00e9 son 8\u00e8me de finale en \u00e9cartant sans coup f\u00e9rir les <strong>Sharks<\/strong>, tenants du titre, le weekend dernier dans son stade.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/challenge-cup-8emes-de-finale-le-lou-ne-fait-quune-bouchee-des-sharks\/\" class=\"vlp-link\" title=\"Challenge Cup (8\u00e8mes de finale) : Le LOU ne fait qu&#039;une bouch\u00e9e des Sharks\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Challenge-Cup-8emes-de-finale-Le-LOU-ne-fait-quune-bouchee-des-Sharks.png\" class=\"attachment-800x445 size-800x445\" alt=\"Challenge Cup (8\u00e8mes de finale) : Le LOU ne fait qu&#039;une bouch\u00e9e des Sharks\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Challenge-Cup-8emes-de-finale-Le-LOU-ne-fait-quune-bouchee-des-Sharks.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Challenge-Cup-8emes-de-finale-Le-LOU-ne-fait-quune-bouchee-des-Sharks-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Challenge-Cup-8emes-de-finale-Le-LOU-ne-fait-quune-bouchee-des-Sharks-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Challenge-Cup-8emes-de-finale-Le-LOU-ne-fait-quune-bouchee-des-Sharks-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Challenge Cup (8\u00e8mes de finale) : Le LOU ne fait qu'une bouch\u00e9e des Sharks<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONS CUP 2024-2025 - Le LOU a valid\u00e9 sa qualification en quarts de finale suite \u00e0 son succ\u00e8s autoritaire face aux Sharks, 34-21. Les Lyonnais se sont rendus la soir\u00e9e facile en \u00e9crasant la premi\u00e8re p\u00e9riode, avant de d\u00e9fendre le plomb pour an\u00e9antir des Sud-africains brouillons.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">Les <strong>Ospreys<\/strong>, de leur c\u00f4t\u00e9, \u00e9voluent en United Rugby Championship. Mais si leur saison n&rsquo;est pas \u00e0 jeter, ils sont en ballotage d\u00e9favorable pour une place dans le Top 8 de leur Championnat. Ils pourraient donc reporter leurs ambitions sur la Challenge Cup, et encore plus apr\u00e8s leur succ\u00e8s du weekend dernier sur les Scarlets. N\u00e9anmoins, les Gallois sont en tr\u00e8s bonne forme, et n&rsquo;ont perdu que deux de leurs dix derniers matchs toutes comp\u00e9titions confondues.<\/p>\n<p style=\"text-align: justify;\">Si les Lyonnais ont remport\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/challenge-cup-lyon-remporte-son-premier-trophee-europeen\/\"><strong>cette comp\u00e9tition en 2022<\/strong><\/a>, ils ne seront pas n\u00e9cessairement les favoris ce samedi soir. Cette saison, seuls les <strong>Bulls<\/strong> et le <strong>Leinster<\/strong> sont venus s&rsquo;imposer \u00e0 Swansea. Les <strong>Ospreys<\/strong> entendent bien faire respecter l&rsquo;avantage du terrain et faire un pas de plus vers une premi\u00e8re finale europ\u00e9enne dans leur histoire. On ne compte que deux confrontations directes, lors de la phase de poule de la Challenge Cup 2016-2017, toutes deux remport\u00e9es par les <strong>Ospreys<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Ospreys &#8211; Lyon : \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match ?<\/h2>\n<p style=\"text-align: justify;\">Match \u00e0 suivre ce <strong>samedi 12 avril 2025 \u00e0 18h30<\/strong>, sur <b>beIN Sports Max 7<\/b>.<\/p>\n<h2 style=\"text-align: justify;\">Les compositions de\u00a0Ospreys &#8211; Lyon<\/h2>\n<h3 style=\"text-align: justify;\">La composition des Ospreys<\/h3>\n<p style=\"text-align: justify;\"><strong>Le XV de d\u00e9part<\/strong> :\u00a0 Thomas, Lake, Botha &#8211; Davies, Beard &#8211; Morgan (c), Tipuric, Morris &#8211; Hardy, Edwards &#8211; Giles, Williams, Boshoff, Kasende &#8211; Walsh<\/p>\n<p style=\"text-align: justify;\"><strong>Rempla\u00e7ants<\/strong> : McGuigan, Phillips, Warren, Fender, Morse, Morgan-Williams, Williams, Hopkins<\/p>\n<h3 style=\"text-align: justify;\">La composition de Lyon<\/h3>\n<p style=\"text-align: justify;\"><strong>Le XV de d\u00e9part :<\/strong> De Benedittis &#8211; Matavesi &#8211; Kaabeche \/ Lambey &#8211; Roussel \/ Blanc-Mappaz &#8211; Shvangiradze &#8211; Gouzou \/ Cassang &#8211; Berdeu \/ Dumortier &#8211; Millet &#8211; Maraku &#8211; Rattez \/ Tchaptchet<\/p>\n<p style=\"text-align: justify;\"><strong>Rempla\u00e7ants<\/strong> : Marchand &#8211; Taofifenua &#8211; Simutoga &#8211; Guillard &#8211; William &#8211; Cretin &#8211; Couilloud &#8211; Parisien<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de\u00a0Ospreys &#8211; Lyon<\/h2>\n<table style=\"width: 800px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\" colspan=\"3\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 12 avril 2025,18h30<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 14px;\"><b>Ospreys<br \/>\n<\/b><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#000;border-color:#000000;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d4d4d;border-radius:5px;text-shadow:none\"> NC<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#000;border-color:#000000;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d4d4d;border-radius:5px;text-shadow:none\"> NC<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><b>Lyon<\/b><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#000;border-color:#000000;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d4d4d;border-radius:5px;text-shadow:none\"> NC<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/p>\n","protected":false},"author":59,"featured_media":571185,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,9129],"tags":[16878,4299,26512,5709],"class_list":["post-571184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-rugby-a-xv","tag-breve","tag-challenge-cup","tag-lyon-ou","tag-ospreys"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure<\/title>\n<meta name=\"description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure\" \/>\n<meta property=\"og:description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-11T12:17:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T12:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure\",\"datePublished\":\"2025-04-11T12:17:17+00:00\",\"dateModified\":\"2025-04-11T12:18:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\"},\"wordCount\":636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png\",\"keywords\":[\"br\u00e8ve\",\"Challenge cup\",\"Lyon OU\",\"Ospreys\"],\"articleSection\":[\"Cha\u00eene TV\",\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\",\"name\":\"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png\",\"datePublished\":\"2025-04-11T12:17:17+00:00\",\"dateModified\":\"2025-04-11T12:18:40+00:00\",\"description\":\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png\",\"width\":1200,\"height\":674,\"caption\":\"Ospreys-Lyon Compositions, Cha\u00eene TV et Heure\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/","og_locale":"fr_FR","og_type":"article","og_title":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure","og_description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-04-11T12:17:17+00:00","article_modified_time":"2025-04-11T12:18:40+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure","datePublished":"2025-04-11T12:17:17+00:00","dateModified":"2025-04-11T12:18:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png","keywords":["br\u00e8ve","Challenge cup","Lyon OU","Ospreys"],"articleSection":["Cha\u00eene TV","Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/","url":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/","name":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png","datePublished":"2025-04-11T12:17:17+00:00","dateModified":"2025-04-11T12:18:40+00:00","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le quart de finale de Challenge Cup entre les Ospreys et Lyon ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Ospreys-Lyon-Compositions-Chaine-TV-et-Heure.png","width":1200,"height":674,"caption":"Ospreys-Lyon Compositions, Cha\u00eene TV et Heure"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ospreys-lyon-compositions-chaine-tv-et-heure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ospreys-Lyon : Compositions, Cha\u00eene TV et Heure"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=571184"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571184\/revisions"}],"predecessor-version":[{"id":571537,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571184\/revisions\/571537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/571185"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=571184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=571184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=571184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}