{"id":571370,"date":"2025-04-10T22:44:30","date_gmt":"2025-04-10T20:44:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=571370&#038;preview=true&#038;preview_id=571370"},"modified":"2025-04-10T22:52:39","modified_gmt":"2025-04-10T20:52:39","slug":"euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/","title":{"rendered":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux. Solides en d\u00e9fense malgr\u00e9 quelques passages \u00e0 vide offensifs, les Parisiens s\u2019imposent facilement face \u00e0 l\u2019Alba Berlin (72-63) et concluent leur campagne d\u2019EuroLigue sur une belle note. Place aux Play-in.<\/em><\/h4>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"194\" data-end=\"580\">10\u00e8me au classement avant cette derni\u00e8re journ\u00e9e d\u2019EuroLigue, le club parisien a d\u00e9j\u00e0 valid\u00e9 son ticket pour les play-in. Mais les ambitions sont plus hautes : accrocher une place dans le Top 6, synonyme de qualification directe pour les quarts de finale. Un sc\u00e9nario encore possible, mais sem\u00e9 d\u2019emb\u00fbches. Pour y parvenir, il fallait d\u2019abord que <strong>Paris<\/strong> s\u2019impose ce soir devant son public. Ensuite, plusieurs r\u00e9sultats devaient tourner en sa faveur : des d\u00e9faites du <strong>Bayern Munich<\/strong> (7\u00e8me), de l\u2019<strong>\u00c9toile Rouge de Belgrade<\/strong> (9\u00e8me), de <strong>Barcelone<\/strong> (8\u00e8me) et de l\u2019<strong>Efes Istanbul<\/strong> (5\u00e8me), ainsi qu\u2019une victoire du <strong>Real Madrid<\/strong> (6\u00e8me). Une combinaison complexe, mais pas impossible. Et dans ce genre de soir\u00e9e, tout peut arriver.<\/p>\n<h2 style=\"text-align: justify;\" data-start=\"194\" data-end=\"580\">Un d\u00e9but tranquille, puis Paris acc\u00e9l\u00e8re<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"231\" data-end=\"465\">Si l\u2019entame de match est plut\u00f4t calme, les <strong>Parisiens<\/strong> d\u00e9cident de prendre les choses en main en fin de premier quart-temps. Un run de 13-4 leur permet de creuser un premier \u00e9cart significatif et de virer en t\u00eate avec 8 points d\u2019avance. Mais cette avance n\u2019est pas seulement le fruit d\u2019une attaque efficace : elle repose aussi sur une grosse intensit\u00e9 d\u00e9fensive. <strong>Paris<\/strong> force une attaque <strong>berlinoise<\/strong> d\u00e9j\u00e0 en difficult\u00e9 \u00e0 se contenter d\u2019un maigre 35,7 % de r\u00e9ussite au tir dans ce premier acte. Une pression constante qui emp\u00eache l\u2019<strong>Alba Berlin<\/strong> de trouver son rythme.<\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"797\" data-end=\"1039\">Le deuxi\u00e8me quart repart sur les m\u00eames bases. Le <strong>Paris Basketball<\/strong> continue d\u2019imposer sa cadence et fait rapidement grimper l\u2019\u00e9cart \u00e0 +15. <strong>Mikael Jantunen<\/strong> se distingue avec un excellent d\u00e9but de match : 13 points \u00e0 la pause. Les <strong>Parisiens<\/strong> se r\u00e9galent, \u00e0 l\u2019image de plusieurs actions de grande classe sign\u00e9es <strong>TJ Shorts<\/strong>, v\u00e9ritable dynamiteur du jeu parisien encore ce soir. Seul petit b\u00e9mol dans cette premi\u00e8re mi-temps : un nombre trop \u00e9lev\u00e9 de fautes d\u2019\u00e9quipe dans le deuxi\u00e8me quart, qui permet aux <strong>Berlinois<\/strong> d&rsquo;\u00e9viter de compl\u00e8tement couler gr\u00e2ce \u00e0 quelques passages sur la ligne.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le festival de TJ pour Micke !!<\/p>\n<p>QT2 &#8211; 2\u201912<a href=\"https:\/\/twitter.com\/ParisBasketball?ref_src=twsrc%5Etfw\">@ParisBasketball<\/a> 39<a href=\"https:\/\/twitter.com\/albaberlin?ref_src=twsrc%5Etfw\">@albaberlin<\/a> 27 <a href=\"https:\/\/t.co\/W7kPoJwHVC\">pic.twitter.com\/W7kPoJwHVC<\/a><\/p>\n<p>\u2014 Paris Basketball (@ParisBasketball) <a href=\"https:\/\/twitter.com\/ParisBasketball\/status\/1910414969981854081?ref_src=twsrc%5Etfw\">April 10, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"1379\" data-end=\"1521\">\u00c0 la mi-temps, <strong>Paris<\/strong> m\u00e8ne logiquement 46-31 et fait le boulot. Reste \u00e0 d\u00e9rouler en deuxi\u00e8me p\u00e9riode pour offrir un beau cadeau au public de l&rsquo;Adidas Arena.<\/p>\n<h2 style=\"text-align: justify;\" data-start=\"1379\" data-end=\"1521\">Paris verrouille, Berlin \u00e9touffe<\/h2>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"192\" data-end=\"506\">Le retour des vestiaires se fait sur un faux rythme. Beaucoup de d\u00e9chet offensif des deux c\u00f4t\u00e9s et les filets ne tremblent que rarement : seulement 5 petits points inscrits au total apr\u00e8s 4 minutes 30. <strong>Paris<\/strong> peine \u00e0 retrouver l\u2019adresse de la premi\u00e8re mi-temps, mais compense par une d\u00e9fense toujours aussi solide. \u00c0 l\u2019image de <strong>Mikael Jantunen<\/strong>, impeccable des deux c\u00f4t\u00e9s du terrain. Le Finlandais r\u00e9gale le public avec un contre autoritaire sur <strong>Yanni Wetzell<\/strong>, symbole de l\u2019engagement d\u00e9fensif des Parisiens dans ce troisi\u00e8me acte hach\u00e9, mais ma\u00eetris\u00e9.<\/p>\n<p style=\"text-align: justify;\" data-start=\"192\" data-end=\"506\">Le troisi\u00e8me quart-temps se referme sur un score de 60-39 en faveur des <strong>Parisiens<\/strong>. Une p\u00e9riode pauvre en points, seulement 22 inscrits au total, mais riche en intensit\u00e9 d\u00e9fensive. Malgr\u00e9 un certain rel\u00e2chement offensif, les hommes de <strong>Tiago Splitter<\/strong> gardent la main sur le match et semblent se diriger sereinement vers une victoire pr\u00e9cieuse.<\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"420\" data-end=\"713\">Le dernier quart-temps reste dans la lign\u00e9e du pr\u00e9c\u00e9dent, marqu\u00e9 par des attaques en berne des deux c\u00f4t\u00e9s. Seul vrai coup d\u2019\u00e9clat offensif : les deux tirs prim\u00e9s cons\u00e9cutifs de <strong>Nadir Hifi<\/strong>, qui s\u2019est offert une belle soir\u00e9e avec 15 points, \u00e9galant <strong>Jantunen<\/strong> au rang de meilleur scoreur du match. Un petit flottement en fin de rencontre aurait pu relancer l\u2019<strong>Alba Berlin<\/strong>, revenu \u00e0 neuf longueurs, mais les <strong>Parisiens<\/strong> ont su g\u00e9rer pour s\u2019imposer sans r\u00e9elle frayeur.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"in\">NADIR AGAIN !<\/p>\n<p>QT4 &#8211; 5\u201931<a href=\"https:\/\/twitter.com\/ParisBasketball?ref_src=twsrc%5Etfw\">@ParisBasketball<\/a> 70<a href=\"https:\/\/twitter.com\/albaberlin?ref_src=twsrc%5Etfw\">@albaberlin<\/a> 47 <a href=\"https:\/\/t.co\/u9kTuaiaEf\">pic.twitter.com\/u9kTuaiaEf<\/a><\/p>\n<p>\u2014 Paris Basketball (@ParisBasketball) <a href=\"https:\/\/twitter.com\/ParisBasketball\/status\/1910428104008622473?ref_src=twsrc%5Etfw\">April 10, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"\" style=\"text-align: justify;\" data-start=\"883\" data-end=\"1181\">Mission accomplie pour <strong>Paris<\/strong>, qui remporte cette ultime journ\u00e9e d\u2019<strong>EuroLeague<\/strong>. Reste \u00e0 savoir si cela suffira pour accrocher le Top 6 : verdict demain, avec les derniers r\u00e9sultats \u00e0 surveiller de pr\u00e8s. Ce soir, le <strong>Bayern Munich<\/strong> s\u2019est inclin\u00e9, tandis que le Real Madrid a domin\u00e9 le Partizan Belgrade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.<\/p>\n","protected":false},"author":111,"featured_media":571428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[16878,18992,42210],"class_list":["post-571370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-breve","tag-paris-basketball","tag-paris-basketball-euroligue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T20:44:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T20:52:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9\",\"datePublished\":\"2025-04-10T20:44:30+00:00\",\"dateModified\":\"2025-04-10T20:52:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\"},\"wordCount\":775,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png\",\"keywords\":[\"br\u00e8ve\",\"Paris Basketball\",\"Paris Basketball Euroligue\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\",\"name\":\"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png\",\"datePublished\":\"2025-04-10T20:44:30+00:00\",\"dateModified\":\"2025-04-10T20:52:39+00:00\",\"description\":\"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png\",\"width\":1200,\"height\":674,\"caption\":\"EuroLigue (J34) Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa campagne en beaut\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9","description":"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9","og_description":"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-04-10T20:44:30+00:00","article_modified_time":"2025-04-10T20:52:39+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9","datePublished":"2025-04-10T20:44:30+00:00","dateModified":"2025-04-10T20:52:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/"},"wordCount":775,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png","keywords":["br\u00e8ve","Paris Basketball","Paris Basketball Euroligue"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/","name":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png","datePublished":"2025-04-10T20:44:30+00:00","dateModified":"2025-04-10T20:52:39+00:00","description":"EUROLIGUE 2024\/25 \u2013 EUROLIGUE 2024\/25 \u2013 Apr\u00e8s avoir rapidement creus\u00e9 l\u2019\u00e9cart, le Paris Basketball a su g\u00e9rer son avance avec s\u00e9rieux.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/EuroLigue-J34-Facile-vainqueur-de-lAlba-Berlin-le-Paris-Basketball-conclut-sa-campagne-en-beaute.png","width":1200,"height":674,"caption":"EuroLigue (J34) Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa campagne en beaut\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j34-facile-vainqueur-de-lalba-berlin-le-paris-basketball-conclut-sa-saison-reguliere-en-beaute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue (J34) : Facile vainqueur de l\u2019Alba Berlin, le Paris Basketball conclut sa saison r\u00e9guli\u00e8re en beaut\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=571370"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571370\/revisions"}],"predecessor-version":[{"id":571437,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/571370\/revisions\/571437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/571428"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=571370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=571370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=571370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}