{"id":573173,"date":"2025-04-18T16:17:50","date_gmt":"2025-04-18T14:17:50","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=573173&#038;preview=true&#038;preview_id=573173"},"modified":"2025-04-18T16:33:04","modified_gmt":"2025-04-18T14:33:04","slug":"classic-grand-besancon-doubs-2025-classement-et-resultats","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/","title":{"rendered":"Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement et r\u00e9sultats"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France, qui se d\u00e9roule ce vendredi 18 avril entre Besan\u00e7on et Montfaucon (166 km).<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2025\/\">L\u2019actualit\u00e9 du cyclisme sur route<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong>Classic Grand Besan\u00e7on Doubs 2025<\/strong> se d\u00e9roule ce <strong>vendredi 18 avril<\/strong>, marquant la cinqui\u00e8me \u00e9dition de cette course fran\u00e7aise class\u00e9e UCI Europe Tour 1.1. Organis\u00e9e par l&rsquo;association <strong>Jura Cyclisme<\/strong> et le <strong>Team Organisation Marchaux<\/strong>, cette \u00e9preuve s&rsquo;inscrit dans un triptyque avec le <strong>Tour du Jura<\/strong> et le <strong>Tour du Doubs<\/strong>, offrant trois jours de comp\u00e9tition sur des parcours de moyenne montagne.<\/p>\n<p style=\"text-align: justify;\"><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\"><a href=\"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-parcours-profil-et-favoris\/\">Le parcours de la Classic Grand Besan\u00e7on Doubs<\/a>, exigeant, est ponctu\u00e9 de plusieurs ascensions, culminant avec l&rsquo;arriv\u00e9e au sommet du <strong>Belv\u00e9d\u00e8re de Montfaucon<\/strong>.<\/span> <span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Cette mont\u00e9e finale (3,9 km \u00e0 8,9 %), avec ses pentes raides, devrait \u00eatre d\u00e9cisive pour la victoire. Parmi les favoris du jour, on retrouve <strong>Guillaume Martin<\/strong> (Groupama-FDJ), <strong>Jordan Jegat<\/strong> (TotalEnergies) et <strong>Cl\u00e9ment Berthet<\/strong> (Decathlon AG2R La Mondiale).<\/span><\/p>\n<p style=\"text-align: justify;\">Arriv\u00e9e de la course pr\u00e9vue sur les coups de 15h50. Retrouvez <strong>les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025<\/strong> ci-dessous.<\/p>\n<h2 style=\"text-align: justify;\">Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement de la course<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement officiel mis \u00e0 jour \u00e0 l&rsquo;issue de la course.<\/em><\/strong><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 GUILLAUME MARTIN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">GROUPAMA-FDJ<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">4h07m28s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 JOSE MANUEL DIAZ<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BURGOS BURPELLET BH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 6s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 CL\u00c9MENT BERTHET<\/strong><br \/>\n<span style=\"font-size: 0.8em\">DECATHLON AG2R LA MONDIALE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 8s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 JORDAN JEGAT<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM TOTALENERGIES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 13s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 ADRIEN MAIRE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UNIBET TIETEMA ROCKETS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 20s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea SYLVAIN MONIQUET<\/strong><br \/>\n<span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 20s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 IV\u00c1N COBO<\/strong><\/span><br \/>\n<span style=\"font-size: 0.8em\">EQUIPO KERN PHARMA<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 20s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 CL\u00c9MENT BRAZ AFONSO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">GROUPAMA &#8211; FDJ<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 21s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 CRISTI\u00c1N RODR\u00cdGUEZ<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ARK\u00c9A &#8211; B&amp;B HOTELS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 21s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 NICOLAS BREUILLARD<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ST MICHEL &#8211; PREFERENCE HOME &#8211; AUBER93<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 21s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 IKER MINTEGI<\/strong><br \/>\n<span style=\"font-size: 0.8em\">EUSKALTEL &#8211; EUSKADI<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 23s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde9\ud83c\uddea EMANUEL BUCHMANN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 23s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde9\ud83c\uddea ANTON SCHIFFER<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BIKE AID<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 23s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa SEBASTIAN BERWICK<\/strong><br \/>\n<span style=\"font-size: 0.8em\">CAJA RURAL &#8211; SEGUROS RGA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 36s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 R\u00c9MI CAPRON<\/strong><br \/>\n<span style=\"font-size: 0.8em\">VAN RYSEL ROUBAIX<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 45s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea FLORIS DE TIER<\/strong><br \/>\n<span style=\"font-size: 0.8em\">WAGNER BAZIN WB<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 45s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 JON AGIRRE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">EUSKALTEL &#8211; EUSKADI<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 47s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 AXEL MARIAULT<\/strong><br \/>\n<span style=\"font-size: 0.8em\">CIC &#8211; U &#8211; NANTES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 47s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 YA\u00cbL JOALLAND<\/strong><br \/>\n<span style=\"font-size: 0.8em\">CIC &#8211; U &#8211; NANTES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 47s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 JES\u00daS HERRADA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 47s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/classic-grand-besancon-doubs\/2025\/result\"><strong>Le classement complet de la Classic Grand Besan\u00e7on Doubs 2025<\/strong><\/a><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-uci-par-equipes-2023-2025\/\" class=\"vlp-link\" title=\"Classement UCI par \u00e9quipes 2023-2025\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025.png\" class=\"attachment-800x445 size-800x445\" alt=\"Classement UCI par \u00e9quipes 2023-2025\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Classement-UCI-par-equipes-2023-2025-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Classement UCI par \u00e9quipes 2023-2025<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez le classement UCI par \u00e9quipes sur la p\u00e9riode 2023-2025<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.<\/p>\n","protected":false},"author":4,"featured_media":573176,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46994],"tags":[16878,18995],"class_list":["post-573173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-classic-grand-besancon-doubs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats<\/title>\n<meta name=\"description\" content=\"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T14:17:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T14:33:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement et r\u00e9sultats\",\"datePublished\":\"2025-04-18T14:17:50+00:00\",\"dateModified\":\"2025-04-18T14:33:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/\"},\"wordCount\":451,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png\",\"keywords\":[\"br\u00e8ve\",\"Classic Grand Besan\u00e7on Doubs\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/\",\"name\":\"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png\",\"datePublished\":\"2025-04-18T14:17:50+00:00\",\"dateModified\":\"2025-04-18T14:33:04+00:00\",\"description\":\"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png\",\"width\":1200,\"height\":674,\"caption\":\"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/classic-grand-besancon-doubs-2025-classement-et-resultats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement et r\u00e9sultats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats","description":"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/","og_locale":"fr_FR","og_type":"article","og_title":"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats","og_description":"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.","og_url":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-04-18T14:17:50+00:00","article_modified_time":"2025-04-18T14:33:04+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement et r\u00e9sultats","datePublished":"2025-04-18T14:17:50+00:00","dateModified":"2025-04-18T14:33:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/"},"wordCount":451,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png","keywords":["br\u00e8ve","Classic Grand Besan\u00e7on Doubs"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/","url":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/","name":"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png","datePublished":"2025-04-18T14:17:50+00:00","dateModified":"2025-04-18T14:33:04+00:00","description":"Retrouvez le classement et les r\u00e9sultats complets de la Classic Grand Besan\u00e7on Doubs 2025, sixi\u00e8me manche de la Coupe de France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Classic-Grand-Besancon-Doubs-2025-Classement-et-resultats.png","width":1200,"height":674,"caption":"Classic Grand Besan\u00e7on Doubs 2025 - Classement et r\u00e9sultats"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/classic-grand-besancon-doubs-2025-classement-et-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Classic Grand Besan\u00e7on Doubs 2025 &#8211; Classement et r\u00e9sultats"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=573173"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573173\/revisions"}],"predecessor-version":[{"id":573230,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573173\/revisions\/573230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/573176"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=573173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=573173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=573173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}