{"id":573373,"date":"2025-04-19T16:18:35","date_gmt":"2025-04-19T14:18:35","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=573373&#038;preview=true&#038;preview_id=573373"},"modified":"2025-04-19T16:41:14","modified_gmt":"2025-04-19T14:41:14","slug":"xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/","title":{"rendered":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&rsquo;Italie"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>TOURNOI DES 6 NATIONS F\u00c9MININ 2025 &#8211; D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/6-nations-feminin-2025-j4-dans-la-douleur-les-bleues-simposent-en-italie\/\">la p\u00e9nible victoire en Italie (21-34)<\/a>.<\/em><\/h4>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/xv-de-france\/\">L&rsquo;actualit\u00e9 du XV de France<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les avants<\/h2>\n<p style=\"text-align: justify;\"><strong>Yllana Brosseau &#8211; 5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Une grosse perc\u00e9e (6e) et quelques ballons int\u00e9ressants.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a \u00e9t\u00e9 moins mobile qu&rsquo;\u00e0 son habitude et a souffert sur les regroupements.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Pilier de mobilit\u00e9, elle a \u00e9t\u00e9 bien moins en vue. M\u00eame si ses quelques ballons ont \u00e9t\u00e9 probants. Remplac\u00e9e par <strong>Ambre Mwayembe (52e)<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Manon Bigot &#8211; 4,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: D\u00e9fensivement, elle a fait son match et ne s&rsquo;est pas d\u00e9rob\u00e9e. Avec 16 plaquages r\u00e9ussis \u00e0 sa sortie, dans le haut du panier fran\u00e7ais.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: En revanche, il y eu de l&rsquo;indiscipline dans cette partie. Elle conc\u00e8de deux fautes. P\u00e9nalis\u00e9e pour \u00eatre entr\u00e9e sur le c\u00f4t\u00e9 d&rsquo;un regroupement (23e) et pour avoir jou\u00e9 un ballon au sol (38e). Une touche perdue (49e). Offensivement, elle a \u00e9t\u00e9 moins saignante qu&rsquo;\u00e0 son habitude.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Celle qui \u00e9tait une des satisfactions de ce tournoi est un peu pass\u00e9e \u00e0 c\u00f4t\u00e9 de sa rencontre ce samedi en Italie. Elle a sembl\u00e9 avoir moins de jus que sur les autres matchs qu&rsquo;elle a disput\u00e9. Remplac\u00e9e par <strong>Elisa Riffonneau (52e)<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Assia Khalfaoui &#8211; 5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Quelques courses int\u00e9ressantes dans le premier acte. Une grosse perc\u00e9e (6e) et quelques actes d\u00e9fensifs int\u00e9ressants.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: P\u00e9nalis\u00e9e pour un plaquage haut (44e), elle a parfois (comme toutes les avants) subi le rythme de ses homologues italiennes.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Un match assez neutre, parfois int\u00e9ressante dans ses courses, mais domin\u00e9e dans les collisions. Remplac\u00e9e par <strong>Clara Joyeux (52e)<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a title=\"Tournoi des 6 Nations f\u00e9minin 2025 : Calendrier, classement et r\u00e9sultats\" href=\"https:\/\/dicodusport.fr\/blog\/tournoi-des-6-nations-feminin-2025-calendrier-classement-et-resultats\/\" rel=\"\">Tournoi des 6 Nations f\u00e9minin 2025 : Calendrier, classement et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Manae Feleu (cocap) &#8211; 5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle est impliqu\u00e9e dans les deux premiers essais des Bleues. Au relais sur le premier essai (2e). Elle d\u00e9livre une tr\u00e8s bonne passe apr\u00e8s contact, dans l&rsquo;action du 2e essai des siennes (30e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a \u00e9t\u00e9 domin\u00e9e dans la puissance face aux transalpines dans le premier acte.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Son manque de puissance est inqui\u00e9tant \u00e0 un match de jouer les Anglaises, qui vont \u00eatre redoutable. Heureusement, elle a montr\u00e9 qu&rsquo;elle pouvait \u00eatre une arme offensive. Comme souvent. Mais l&rsquo;ensemble est trop moyen aujourd&rsquo;hui. Remplac\u00e9e par <strong>Charlotte Escudero (52e)<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Madoussou Fall Raclot &#8211; 5,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle lance l&rsquo;avant-derni\u00e8re charge sur le 3e essai des Bleues (55e). Elle livre un nouveau match solide d\u00e9fensivement, avec 24 plaquages r\u00e9ussis, le meilleur total pour une joueuse, avec<strong> Teani Feleu<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle \u00e9cope d&rsquo;un carton jaune pour un plaquage haut (8e). Un carton jaune qui co\u00fbte un essai \u00e0 son \u00e9quipe (18e). Elle a \u00e9t\u00e9 domin\u00e9e dans la puissance face aux transalpines dans le premier acte.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Elle est pass\u00e9e \u00e0 c\u00f4t\u00e9 de son premier acte, avec ce carton jaune qui a redonn\u00e9 beaucoup de confiance aux italiennes. Avant de se remettre un peu la t\u00eate \u00e0 l&rsquo;endroit, \u00e0 l&rsquo;origine du troisi\u00e8me essai des siennes. Mais ce n&rsquo;\u00e9tait pas non plus une immense <strong>Madoussou Fall Raclot<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Romane M\u00e9nager &#8211; 6<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle marque le troisi\u00e8me essai des Bleues (55e), un essai qui symbolise son mieux offensif du d\u00e9but du second acte. D\u00e9fensivement, elle est \u00e9galement sortie du lot, troisi\u00e8me joueuse ayant le plus plaqu\u00e9 \u00e0 sa sortie. Avec 22 plaquages r\u00e9ussis en 71 minutes.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: P\u00e9nalis\u00e9e pour \u00eatre pass\u00e9e dans le camp italien sur une touche (39e) et pour un ballon tenu au sol proche de la ligne d&rsquo;essai italienne (52e). Elle a \u00e9t\u00e9 domin\u00e9e dans la puissance face aux transalpines dans le premier acte.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Elle a mis une grosse demi-heure pour rentrer dans son match, avant d&rsquo;inverser la tendance. Son troisi\u00e8me essai sera forc\u00e9ment retenu, car il permet aux siennes de faire basculer la partie. Comme sa d\u00e9fense. Une mont\u00e9e en puissance int\u00e9ressante pour la suite. Remplac\u00e9e par <strong>Axelle Berthoumieu (72e)<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/SixNationsRugby?src=hash&amp;ref_src=twsrc%5Etfw\">#SixNationsRugby<\/a> | \ud83c\uddee\ud83c\uddf9\u26a1\ufe0f\ud83c\uddeb\ud83c\uddf7 Romane M\u00e9nager ram\u00e8ne les Bleues \u00e0 hauteur des Italiennes \ud83d\udc4a <a href=\"https:\/\/twitter.com\/hashtag\/ITAFRA?src=hash&amp;ref_src=twsrc%5Etfw\">#ITAFRA<\/a><\/p>\n<p>\ud83d\udcfa Suivez le direct : <a href=\"https:\/\/t.co\/TEEAIJgGcu\">https:\/\/t.co\/TEEAIJgGcu<\/a> <a href=\"https:\/\/t.co\/3vdmDtiRKb\">pic.twitter.com\/3vdmDtiRKb<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1913584682890862880?ref_src=twsrc%5Etfw\">April 19, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e9raphine Okemba &#8211; 6<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: D\u00e9fensivement, elle a encore une fois tenu son rang. Elle d\u00e9fend bien derri\u00e8re sa ligne, sur une \u00e9ni\u00e8me situation dangereuse des avants italiennes (33e). Elle termine son match \u00e0 20 plaquages, le 3e total pour une joueuse \u00e0 ce moment de la partie. Offensivement, elle r\u00e9cup\u00e8re une p\u00e9nalit\u00e9 (42e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a \u00e9t\u00e9 domin\u00e9e dans la puissance face aux transalpines dans le premier acte, en souffrance dans les mauls et, il faut le dire, globalement domin\u00e9e dans les collisions, qu&rsquo;elles soient offensives ou d\u00e9fensives.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Un match plein de s\u00e9rieux et m\u00eame de courage d&rsquo;un point de vue d\u00e9fensif. Elle ne s&rsquo;est pas d\u00e9rob\u00e9e. Maintenant, on peut aussi avoir une pointe d&rsquo;inqui\u00e9tude sur ce manque de puissance, alors que l&rsquo;Angleterre se profile. Remplac\u00e9e par <strong>L\u00e9a Champon (62e)<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Teani Feleu &#8211; 6,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: D\u00e9fensivement, elle a \u00e9t\u00e9 pr\u00e9cieuse. Joueuse qui a le plus plaqu\u00e9 dans le match avec <strong>Madoussou Fall Raclot <\/strong>(24), elle d\u00e9passait les 20 plaquages r\u00e9ussis apr\u00e8s l&rsquo;heure de jeu (62e) et symbolise aussi la domination italienne. Une grosse d\u00e9fense derri\u00e8re sa ligne d&rsquo;essai, pour emp\u00eacher un essai transalpin (36e et 46e). On peut aussi noter un ballon gratt\u00e9 tr\u00e8s pr\u00e9cieux (63e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Malgr\u00e9 une grosse abn\u00e9gation, elle a \u00e9t\u00e9 domin\u00e9e dans la puissance, dans chacun de ses duels dans le premier acte, comme pour toutes ses co\u00e9quipi\u00e8res.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref : <\/strong>: D&rsquo;abord domin\u00e9e physiquement, elle a su ne jamais se d\u00e9rober, jamais l\u00e2cher, m\u00eame si elle a \u00e9t\u00e9 en souffrance dans le premier acte. Elle a ensuite sorti la t\u00eate de l&rsquo;eau. Toujours aussi impressionnant dans son volume.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/2\/#charniereettroisquarts\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Les notes de la charni\u00e8re et des trois-quarts<\/span><\/a>\n<p style=\"text-align: justify;\"><!--nextpage--><\/p>\n<h4 style=\"text-align: justify;\"><a id=\"charniereettroisquarts\"><\/a><strong><em>T<\/em><\/strong><em>OURNOI DES 6 NATIONS F\u00c9MININ 2025 &#8211; <\/em><em>D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/6-nations-feminin-2025-j4-dans-la-douleur-les-bleues-simposent-en-italie\/\">la p\u00e9nible victoire en Italie (21-34)<\/a>.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">La charni\u00e8re<\/h2>\n<p style=\"text-align: justify;\"><strong>Pauline Bourdon Sansus &#8211; 5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Passeuse d\u00e9cisive pour Morgane Bourgeois, sur le deuxi\u00e8me essai des Bleues (30e). On peut noter cette volont\u00e9 de mettre un peu de folie, mais aussi sa capacit\u00e9 \u00e0 temporiser quand il le faut. Globalement, elle a bien jou\u00e9 les rares ballons eu dans le premier acte.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a subi la pression sur certaines situations. Et quelques ballons offensifs qui auraient pu \u00eatre mieux exploit\u00e9s en d\u00e9but de second acte. On peut noter une touche directe, qui a remis de la pression sur son \u00e9quipe (34e). Elle a \u00e9t\u00e9 p\u00e9nalis\u00e9e pour avoir tenu le ballon au sol dans ses 22 m (35e).<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Pas aid\u00e9e par ses avants, dans le dur, elle a subi la pression. Mais n&rsquo;a pas toujours su calmer le jeu, redonnant plusieurs fois de la pression \u00e0 ses co\u00e9quipi\u00e8res. Mais dans l&rsquo;utilisation du ballon, elle a parfois su \u00eatre pr\u00e9cieuse. Remplac\u00e9e par <strong>Alexandra Chambon (60e)<\/strong>. Qui marque le cinqui\u00e8me essai des Bleues.<\/p>\n<p style=\"text-align: justify;\"><strong>Carla Arbez &#8211; 4<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + :\u00a0<\/strong>RAS.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Au pied, elle a \u00e9t\u00e9 beaucoup moins probante que sur ses derni\u00e8res sorties. On peut noter une touche directe (15e). C&rsquo;est toujours compliqu\u00e9e dans la transformation du jeu, ballon en mains.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Un match globalement tr\u00e8s compliqu\u00e9 pour l&rsquo;ouvreuse fran\u00e7aise, dans un contexte o\u00f9 les siennes n&rsquo;ont longtemps pas eu le ballon. Remplac\u00e9e par <strong>Lina Queyroi (66e)<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Les arri\u00e8res<\/h2>\n<p style=\"text-align: justify;\"><strong>\u00c9milie Boulard &#8211; 5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle a tent\u00e9 quelques perc\u00e9es et a su garder les ballons et ne pas se faire p\u00e9naliser.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle manque encore de tranchant sur certaines courses.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Dans cette domination italienne qui a dur\u00e9 pr\u00e8s d&rsquo;une heure, c&rsquo;est forc\u00e9ment un match frustrant pour une aili\u00e8re. Elle a n\u00e9anmoins souffert de la comparaison avec sa co\u00e9quipi\u00e8re <strong>Joanna Grisez<\/strong>. On n&rsquo;a pas encore retrouv\u00e9 la \u00c9milie Boulard de ses d\u00e9buts.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabrielle Vernier &#8211; 6,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Offensivement, elle a \u00e9t\u00e9 une arme pr\u00e9cieuse. Sa perc\u00e9e a mis les siennes dans l&rsquo;avanc\u00e9e, sur le premier essai des Bleues (2e). Elle r\u00e9cup\u00e8re une p\u00e9nalit\u00e9 dans les 22 m\u00e8tres italiens, en grattant un ballon. Et est impliqu\u00e9e sur l&rsquo;action qui suit et qui am\u00e8ne le 3e essai (55e). Deux ballons gratt\u00e9s \u00e9galement.<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: P\u00e9nalis\u00e9e pour un passage \u00e0 vide (6e)<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Son retour a fait beaucoup de bien \u00e0 ses co\u00e9quipi\u00e8res. Elle a su \u00eatre tranchante dans ses courses et bien au-del\u00e0 des actions des deux essais. Mais aussi perturber les italiennes sur d&rsquo;autres s\u00e9quences en r\u00e9cup\u00e9rant des munitions. Peut-\u00eatre la meilleure fran\u00e7aise cet apr\u00e8s-midi. M\u00eame si elle ne marque pas.<\/p>\n<p style=\"text-align: justify;\"><strong>Marine M\u00e9nager (cocap) &#8211; 5,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle marque l&rsquo;essai qui scelle la victoire des Bleues et qui offre le bonus \u00e0 son \u00e9quipe (78e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a longtemps \u00e9t\u00e9 tr\u00e8s discr\u00e8te d\u00e9fensivement, avec peu de munitions. Il a fallu attendre l&rsquo;heure de jeu pour la voir effectuer une charge.<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Son match \u00e9tait plus que moyen, mais elle a su s&rsquo;arracher jusqu&rsquo;au bout pour aller chercher un point de bonus offensif. Un essai loin d&rsquo;\u00eatre fait et qui est symbole d&rsquo;une abn\u00e9gation int\u00e9ressante. Mais il faudra faire mieux.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/SixNationsRugby?src=hash&amp;ref_src=twsrc%5Etfw\">#SixNationsRugby<\/a> | \ud83c\uddee\ud83c\uddf9\u26a1\ufe0f\ud83c\uddeb\ud83c\uddf7 L&rsquo;essai LIB\u00c9RATEUR sign\u00e9 Marine M\u00e9nager ! Les Bleues m\u00e8nent 29-21 \ud83d\ude2e\u200d\ud83d\udca8 <a href=\"https:\/\/twitter.com\/hashtag\/ITAFRA?src=hash&amp;ref_src=twsrc%5Etfw\">#ITAFRA<\/a><\/p>\n<p>\ud83d\udcfa Suivez le direct : <a href=\"https:\/\/t.co\/TEEAIJgGcu\">https:\/\/t.co\/TEEAIJgGcu<\/a> <a href=\"https:\/\/t.co\/pYotUnHquc\">pic.twitter.com\/pYotUnHquc<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1913592740819972491?ref_src=twsrc%5Etfw\">April 19, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Joanna Grisez &#8211; 6<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle marque le premier essai des Bleues (2e). Son d\u00e9marrage sur l&rsquo;aile droite est \u00e0 l&rsquo;origine du deuxi\u00e8me essai (30e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: P\u00e9nalis\u00e9 pour un plaquage haut (66e).<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Avec peu elle a su faire bien. Peu servie, elle est directement impliqu\u00e9e sur un essai et indirectement sur un second. Une donn\u00e9e qui peut \u00eatre int\u00e9ressante dans un match contre l&rsquo;Angleterre, o\u00f9 les Bleues risquent d&rsquo;\u00eatre une nouvelle fois priv\u00e9e de ballon.<\/p>\n<p style=\"text-align: justify;\"><strong>Morgane Bourgeois &#8211; 4,5<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Le + <\/strong>: Elle marque le deuxi\u00e8me essai des Bleues (30e).<\/p>\n<p style=\"text-align: justify;\"><strong>Le &#8211; <\/strong>: Elle a \u00e9t\u00e9 moins en r\u00e9ussite \u00e0 la botte, avec trois \u00e9checs, dont deux en bonne position, alors que les Bleues n&rsquo;avaient qu&rsquo;un point d&rsquo;avance (71e et 74e). Une mauvaise passe (12e).<\/p>\n<p style=\"text-align: justify;\"><strong>En bref<\/strong> : Pour la premi\u00e8re fois du tournoi, elle n&rsquo;a pas \u00e9t\u00e9 en r\u00e9ussite \u00e0 la botte. Au fond de nous, on peut se dire qu&rsquo;il valait mieux aujourd&rsquo;hui que contre l&rsquo;Angleterre. Son essai sauve un peu son match assez compliqu\u00e9.<\/p>\n<h3 style=\"text-align: justify;\">La note de Romain Huet <strong>&#8211; 5<\/strong><\/h3>\n<p style=\"text-align: justify;\">Comme sur les matchs pr\u00e9c\u00e9dents, il a su insuffler du renouveau en d\u00e9but de seconde p\u00e9riode. N\u00e9anmoins, le s\u00e9lectionneur fran\u00e7ais peine \u00e0 trouver des solutions pour palier les mauvais premier acte de ses joueuses. Le projet de jeu peine \u00e9galement \u00e0 se d\u00e9velopper.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Revenir aux avants<\/span><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Vernier, Teani Feleu, Romane Menager, les notes des Bleues face \u00e0 l&rsquo;Italie<\/p>\n","protected":false},"author":83,"featured_media":573456,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47048,19951],"tags":[16878,6649,24,1638,3643],"class_list":["post-573373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-tournoi-des-6-nations","category-xv-de-france","tag-breve","tag-notes-xv-de-france","tag-sport","tag-xv-de-france","tag-xv-de-france-feminin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&#039;Italie<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&#039;Italie\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-19T14:18:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-19T14:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&#039;Italie\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&rsquo;Italie\",\"datePublished\":\"2025-04-19T14:18:35+00:00\",\"dateModified\":\"2025-04-19T14:41:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\"},\"wordCount\":1969,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png\",\"keywords\":[\"br\u00e8ve\",\"Notes XV de France\",\"sport\",\"XV de France\",\"XV de France f\u00e9minin\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Tournoi des 6 Nations\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\",\"name\":\"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l'Italie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png\",\"datePublished\":\"2025-04-19T14:18:35+00:00\",\"dateModified\":\"2025-04-19T14:41:14+00:00\",\"description\":\"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png\",\"width\":1200,\"height\":674,\"caption\":\"XV de France f\u00e9minin Vernier, Teani Feleu, Romane Menager, les notes des Bleues face \u00e0 l'Italie\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l'Italie","description":"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/","next":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l'Italie","og_description":"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-04-19T14:18:35+00:00","article_modified_time":"2025-04-19T14:41:14+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l'Italie","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l&rsquo;Italie","datePublished":"2025-04-19T14:18:35+00:00","dateModified":"2025-04-19T14:41:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/"},"wordCount":1969,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png","keywords":["br\u00e8ve","Notes XV de France","sport","XV de France","XV de France f\u00e9minin"],"articleSection":["Rugby \u00e0 XV","Tournoi des 6 Nations","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/","name":"XV de France f\u00e9minin : Vernier, Teani Feleu, Romane M\u00e9nager, les notes des Bleues face \u00e0 l'Italie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png","datePublished":"2025-04-19T14:18:35+00:00","dateModified":"2025-04-19T14:41:14+00:00","description":"D\u00e9couvrez les notes du XV de France f\u00e9minin apr\u00e8s la p\u00e9nible victoire en Italie (21-34).","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-feminin-vernier-teani-feleu-romane-menager-les-notes-des-bleues-face-italie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/XV-de-France-feminin-Vernier-Teani-Feleu-Romane-Menager-les-notes-des-Bleues-face-a-lItalie.png","width":1200,"height":674,"caption":"XV de France f\u00e9minin Vernier, Teani Feleu, Romane Menager, les notes des Bleues face \u00e0 l'Italie"},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=573373"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573373\/revisions"}],"predecessor-version":[{"id":573471,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/573373\/revisions\/573471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/573456"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=573373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=573373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=573373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}