{"id":574844,"date":"2025-05-19T09:00:01","date_gmt":"2025-05-19T07:00:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=574844&#038;preview=true&#038;preview_id=574844"},"modified":"2025-05-20T12:07:58","modified_gmt":"2025-05-20T10:07:58","slug":"championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/","title":{"rendered":"Championnats d&rsquo;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>GYMNASTIQUE &#8211; Les Championnats d&rsquo;Europe de gymnastique artistique se d\u00e9roulent du 26 au 31 mai \u00e0 Leipzig. Voici la s\u00e9lection fran\u00e7aise.<\/em><\/h4>\n<p align=\"justify\">Le mois dernier, la F\u00e9d\u00e9ration Fran\u00e7aise de Gymnastique a d\u00e9voil\u00e9 la s\u00e9lection fran\u00e7aise pour les <strong>Championnats d&rsquo;Europe de gymnastique artistique<\/strong>. Beaucoup de jeunes qui vont connaitre leur premier grand championnat chez les seniors. Cette ann\u00e9e, pas de dates diff\u00e9rentes entre les femmes et les hommes.<\/p>\n<h2 align=\"justify\">S\u00e9lection masculine<\/h2>\n<p align=\"justify\">L\u00e9o Saladino, Anthony Mansard, Justin Labro, Romain Cavallaro, Loris Frasca (\u00e9quipe)<\/p>\n<p align=\"justify\">Samir A\u00eft Sa\u00efd (individuel &#8211; anneaux)<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-championnats-deurope-de-gymnastique-artistique-2025\/\" target=\"_blank\" rel=\"noopener\">Programme et r\u00e9sultats Championnats d&rsquo;Europe de gymnastique artistique f\u00e9minine 2025<\/a><\/strong><\/li>\n<\/ul>\n<h2 align=\"justify\">S\u00e9lection f\u00e9minine<\/h2>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des femmes, si deux cadres sont bien pr\u00e9sentes, on voit \u00e9galement un renouveau dans l&rsquo;\u00e9quipe. Pas de M\u00e9lanie De Jesus Dos Santos. Coline Devillard, op\u00e9r\u00e9e au tibia fin 2024, ne concourra pas cette saison. L&rsquo;ancienne capitaine Marine Boyer qui s&rsquo;essaye au saut \u00e0 la perche n&rsquo;a pas officialis\u00e9 sa d\u00e9cision de poursuivre ou pas la gymnastique.<\/p>\n<p style=\"text-align: justify;\">Lorette Charpy, Morgane Osyssek-Reimer, Ming Gherardi van Eijken, Romane Hamelin, Djenna Laroui<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[GAM &#8211; Championnats d&rsquo;Europe] \ud83d\udccdLeipzig (GER)<br \/>\nD\u00e9couvrez les gymnastes tricolores qui repr\u00e9senteront la France \ud83c\uddeb\ud83c\uddf7 \u00e0 Leipzig du 26 au 31 mai !<\/p>\n<p>En savoir plus \u27a1\ufe0f <a href=\"https:\/\/t.co\/p5yiTxTyR9\">https:\/\/t.co\/p5yiTxTyR9<\/a> <a href=\"https:\/\/t.co\/9iYYw2Hjn4\">pic.twitter.com\/9iYYw2Hjn4<\/a><\/p>\n<p>\u2014 F\u00e9d\u00e9ration Fran\u00e7aise de Gymnastique (@ffgymnastique) <a href=\"https:\/\/twitter.com\/ffgymnastique\/status\/1915057457736429798?ref_src=twsrc%5Etfw\">April 23, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GYMNASTIQUE &#8211; Les Championnats d&rsquo;Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.<\/p>\n","protected":false},"author":12,"featured_media":578390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10429],"tags":[16878,6976],"class_list":["post-574844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gymnastique","tag-breve","tag-gymnastique-artistique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Championnats d&#039;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise<\/title>\n<meta name=\"description\" content=\"GYMNASTIQUE - Les Championnats d&#039;Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats d&#039;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise\" \/>\n<meta property=\"og:description\" content=\"GYMNASTIQUE - Les Championnats d&#039;Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T07:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T10:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Championnats d&#039;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Championnats d&rsquo;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise\",\"datePublished\":\"2025-05-19T07:00:01+00:00\",\"dateModified\":\"2025-05-20T10:07:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\"},\"wordCount\":250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png\",\"keywords\":[\"br\u00e8ve\",\"Gymnastique artistique\"],\"articleSection\":[\"Gymnastique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\",\"name\":\"Championnats d'Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png\",\"datePublished\":\"2025-05-19T07:00:01+00:00\",\"dateModified\":\"2025-05-20T10:07:58+00:00\",\"description\":\"GYMNASTIQUE - Les Championnats d'Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png\",\"width\":1200,\"height\":674,\"caption\":\"Championnats d'Europe de gymnastique artistique 2025 La s\u00e9lection fran\u00e7aise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats d&rsquo;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats d'Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise","description":"GYMNASTIQUE - Les Championnats d'Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats d'Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise","og_description":"GYMNASTIQUE - Les Championnats d'Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-05-19T07:00:01+00:00","article_modified_time":"2025-05-20T10:07:58+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Championnats d'Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Championnats d&rsquo;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise","datePublished":"2025-05-19T07:00:01+00:00","dateModified":"2025-05-20T10:07:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/"},"wordCount":250,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png","keywords":["br\u00e8ve","Gymnastique artistique"],"articleSection":["Gymnastique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/","name":"Championnats d'Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png","datePublished":"2025-05-19T07:00:01+00:00","dateModified":"2025-05-20T10:07:58+00:00","description":"GYMNASTIQUE - Les Championnats d'Europe de gymnastique artistique se d\u00e9roulent du 24 avril au 5 mai. Voici la s\u00e9lection fran\u00e7aise.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Championnats-dEurope-de-gymnastique-artistique-2025-La-selection-francaise.png","width":1200,"height":674,"caption":"Championnats d'Europe de gymnastique artistique 2025 La s\u00e9lection fran\u00e7aise"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-gymnastique-artistique-2025-la-selection-francaise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats d&rsquo;Europe de gymnastique artistique 2025 : La s\u00e9lection fran\u00e7aise"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/574844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=574844"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/574844\/revisions"}],"predecessor-version":[{"id":580427,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/574844\/revisions\/580427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/578390"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=574844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=574844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=574844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}