{"id":575662,"date":"2025-04-30T19:00:48","date_gmt":"2025-04-30T17:00:48","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=575662&#038;preview=true&#038;preview_id=575662"},"modified":"2025-04-30T19:00:48","modified_gmt":"2025-04-30T17:00:48","slug":"transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/","title":{"rendered":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril"},"content":{"rendered":"<h4 style=\"text-align: justify;\" align=\"justify\"><em>TRANSFERTS RUGBY &#8211; Mouvements d&rsquo;envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d&rsquo;un ouvreur, Lyon s&rsquo;attelle \u00e0 prolonger ses cadres : <\/em><em>les infos transferts du mercredi 30 avril.<\/em><\/h4>\n<h2 style=\"text-align: justify;\">Agen : chaises musicales confirm\u00e9es et retour de Reggiardo<\/h2>\n<p style=\"text-align: justify;\">La saison du SU Agen ne restera pas dans les annales. Principalement parce qu&rsquo;il n&rsquo;est toujours pas officiellement certain de son maintien en Pro D2 \u00e0 deux journ\u00e9es de la fin, m\u00eame s&rsquo;il a son destin en mains. Malgr\u00e9 tout, ce club historique du rugby fran\u00e7ais est bien loin de pouvoir jouer les premiers r\u00f4les et pourquoi pas viser un retour en Top 14, alors les dirigeants ont des choix \u00e0 faire.<\/p>\n<p style=\"text-align: justify;\">Selon <a href=\"https:\/\/www.rugbyrama.fr\/2025\/04\/30\/transferts-pro-d2-exclu-midol-mauricio-reggiardo-bientot-nomme-thomas-leger-quitte-le-su-agen-12668546.php\"><strong>Midi Olympique<\/strong><\/a>, ils en ont fait un premier. Ancien coach du SUA, <strong>Mauricio Reggiardo<\/strong> va effectuer son retour. L&rsquo;Argentin est actuellement manager g\u00e9n\u00e9ral \u00e0 Provence Rugby, et reviendra \u00e0 Agen en tant que directeur sportif, lui qui a entra\u00een\u00e9 le SUA entre 2016 et 2019, soit pendant la derni\u00e8re p\u00e9riode du club en Top 14. Ce qui entra\u00eenera m\u00e9caniquement le d\u00e9part de l&rsquo;actuel d\u00e9tenteur du poste, <strong>Thomas L\u00e9ger<\/strong>. Mais rien n&rsquo;est fini en termes de mouvement, l&rsquo;organigramme \u00e9tant parti pour un profond lifting.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:\u00a0<\/strong>renouer avec un ex, une strat\u00e9gie qui fera toujours parler. Mais en tant que manager g\u00e9n\u00e9ral d&rsquo;un club qui pourrait bien monter en Top 14 \u00e0 la fin de la saison, nul doute que Reggiardo a beaucoup \u00e0 apporter \u00e0 un club qu&rsquo;il conna\u00eet bien.\u00a0<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-agen-mauricio-reggiardo-billy-searle-ca-bouge-au-sua\/\">Transferts Agen : Mauricio Reggiardo, Billy Searle, \u00e7a bouge au SUA<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Bayonne : qui sera le rempla\u00e7ant de Camille Lopez ?<\/h2>\n<p style=\"text-align: justify;\">La surprise a \u00e9t\u00e9 importante quand <strong>Camille Lopez<\/strong> a annonc\u00e9 sa retraite en fin de saison. L&rsquo;ancien international va basculer dans l&rsquo;encadrement, mais sans nul doute laisser un vide au poste d&rsquo;ouvreur \u00e0 Bayonne. Avec <strong>Joris Segonds<\/strong>, on pourrait croire que l&rsquo;Aviron est arm\u00e9, mais dans le rugby moderne, sur les postes cl\u00e9s, deux joueurs de haut niveau sont indispensables.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-aviron-bayonnais-2025-arrivees-departs-et-prolongations\/\">Transferts Bayonne 2025 : Recrues, d\u00e9parts et prolongations<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les Basques se sont d&rsquo;abord pench\u00e9s sur le dossier <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-2-clubs-de-top-14-veulent-duncan-weir-ecosse\/\"><strong>Duncan Weir<\/strong><\/a>, mais plus de nouvelles de l&rsquo;\u00c9cossais, qui \u00e9tait de toute fa\u00e7on courtis\u00e9. Ainsi, deux noms sont apparus : <strong>Gareth Anscombe<\/strong> et <strong>Tommaso Allan<\/strong>. Le premier est le favori, puisqu&rsquo;en fin de contrat, et semble la piste ayant le plus de chances d&rsquo;aboutir. Le deuxi\u00e8me, engag\u00e9 avec Perpignan, sera sans doute difficile \u00e0 d\u00e9baucher sans engager d&rsquo;indemnit\u00e9s&#8230; \u00e0 moins que l&rsquo;USAP ne se maintienne pas en Top 14. <strong>Luka Matkava<\/strong>, actuellement joker m\u00e9dical \u00e0 Castres, est \u00e9galement une possibilit\u00e9, mais tout devrait se d\u00e9canter prochainement.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> les noms avanc\u00e9s sont de qualit\u00e9, mais il est s\u00fbr qu&rsquo;un Gareth Anscombe serait une recrue du plus bel effet pour un Aviron Bayonnais qui ne cache plus sa volont\u00e9 de grandir. Un \u00e9tat de fait \u00e9vident quand on voit son recrutement.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-bayonne-piste-2-ouvreurs-internationaux\/\">Transferts : Bayonne piste 2 ouvreurs internationaux<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Lyon : prolongations en cascades \u00e0 venir<\/h2>\n<p style=\"text-align: justify;\">Moribond en d\u00e9but de saison, le <strong>LOU<\/strong> a s\u00e9rieusement r\u00e9agi. Une belle s\u00e9rie de victoires, et les Lyonnais sont en course pour les barrages, en plus d&rsquo;\u00eatre qualifi\u00e9s pour les demi-finales de la Challenge Cup. Une info loin d&rsquo;\u00eatre anodine, puisque le vainqueur de la comp\u00e9tition assure sa place en Champions Cup la saison suivante. Engag\u00e9 donc sur tous les tableaux, Lyon a besoin d&rsquo;un effectif profond et de qualit\u00e9.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/challenge-cup-2024-2025-tableau-complet-de-la-phase-finale\/\">Challenge Cup 2024-2025 : Tableau complet de la phase finale<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Selon <a href=\"https:\/\/www.lequipe.fr\/Rugby\/Actualites\/Prolongation-en-vue-pour-tchaptchet-william-et-parisien-a-lyon\/1558145\"><strong>L&rsquo;\u00c9quipe<\/strong><\/a>, le club rhodanien s&rsquo;attache \u00e0 conserver cette densit\u00e9. <strong>Alexandre Tchaptchet<\/strong> sera sans doute le premier \u00e0 parapher un nouveau contrat, jusqu&rsquo;en 2028, apr\u00e8s s&rsquo;\u00eatre impos\u00e9 \u00e0 l&rsquo;arri\u00e8re du XV de d\u00e9part. <strong>Th\u00e9o William<\/strong> et <strong>Alfred Parisien<\/strong>, eux, devraient suivre, eux qui sont de solides membres de la rotation lyonnaise. Pierre apr\u00e8s pierre, le LOU dessine les contours de son effectif pour les saisons \u00e0 venir.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis de Dicodusport<\/strong> <strong>:<\/strong> Lyon n&rsquo;a pas toujours brill\u00e9 par sa stabilit\u00e9 ces derni\u00e8res saisons, il est donc appr\u00e9ciable de voir que ces derni\u00e8res semaines, le LOU fait le choix de la continuit\u00e9.\u00a0<\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-lou-2025-arrivees-departs-et-prolongations\/\">Transferts LOU 2025 : Recrues, d\u00e9parts et prolongations<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril<\/p>\n","protected":false},"author":59,"featured_media":575679,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-575662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Mouvements d&#039;envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d&#039;un ouvreur, Lyon s&#039;attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Mouvements d&#039;envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d&#039;un ouvreur, Lyon s&#039;attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T17:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\",\"datePublished\":\"2025-04-30T17:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\"},\"wordCount\":739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\",\"name\":\"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png\",\"datePublished\":\"2025-04-30T17:00:48+00:00\",\"description\":\"TRANSFERTS RUGBY - Mouvements d'envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d'un ouvreur, Lyon s'attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril","description":"TRANSFERTS RUGBY - Mouvements d'envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d'un ouvreur, Lyon s'attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril","og_description":"TRANSFERTS RUGBY - Mouvements d'envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d'un ouvreur, Lyon s'attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-04-30T17:00:48+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril","datePublished":"2025-04-30T17:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/"},"wordCount":739,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/","name":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png","datePublished":"2025-04-30T17:00:48+00:00","description":"TRANSFERTS RUGBY - Mouvements d'envergure confirm\u00e9s \u00e0 Agen, Bayonne toujours en qu\u00eate d'un ouvreur, Lyon s'attelle \u00e0 prolonger ses cadres : les infos transferts du mercredi 30 avril.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Transferts-Rugby-Mauricio-Reggiardo-Bayonne-LOU-les-infos-du-mercredi-30-avril.png","width":1200,"height":674,"caption":"Transferts Rugby Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-mauricio-reggiardo-bayonne-lou-les-infos-du-mercredi-30-avril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Mauricio Reggiardo, Bayonne, LOU, les infos du mercredi 30 avril"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/575662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=575662"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/575662\/revisions"}],"predecessor-version":[{"id":575684,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/575662\/revisions\/575684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/575679"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=575662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=575662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=575662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}