{"id":576012,"date":"2025-05-02T18:19:20","date_gmt":"2025-05-02T16:19:20","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=576012&#038;preview=true&#038;preview_id=576012"},"modified":"2025-05-02T18:30:58","modified_gmt":"2025-05-02T16:30:58","slug":"squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/","title":{"rendered":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&rsquo;Europe !"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><em>CHAMPIONNATS D&rsquo;EUROPE PAR \u00c9QUIPES DE SQUASH 2025 &#8211; Sans trembler, les Bleus ont assum\u00e9 leur statut contre les Suisses, et d\u00e9fieront de nouveau l&rsquo;Angleterre en finale demain.\u00a0<\/em><\/h4>\n<p style=\"text-align: justify;\">Comme \u00e0 chaque \u00e9dition depuis 2000, l&rsquo;\u00e9quipe de France masculine de squash \u00e9tait au rendez-vous des demi-finales des Championnats d&rsquo;Europe par \u00e9quipes. Mais avant de penser \u00e0 un \u00e9ni\u00e8me remake du grand classique contre l&rsquo;Angleterre, il fallait n\u00e9gocier une demi-finale pi\u00e9geuse. La Suisse, troisi\u00e8me des deux derni\u00e8res \u00e9ditions, \u00e9tait en effet un adversaire qu&rsquo;il fallait traiter avec la plus grande attention.<\/p>\n<h2 style=\"text-align: justify;\">Net et (presque) sans bavures<\/h2>\n<p style=\"text-align: justify;\">Un point de vue soulign\u00e9 par le premier match de <strong>Gr\u00e9goire Marche<\/strong> contre<strong> Nicolas Mueller<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/squash-victor-crouin-battu-en-finale-des-championnats-deurope\/\"><strong>champion d&rsquo;Europe 2022<\/strong><\/a>, mais en recul ces derniers temps. Le Suisse a n\u00e9anmoins d\u00e9marr\u00e9 tambour battant, remportant le premier jeu en produisant un squash de grande qualit\u00e9, mais la machine s&rsquo;est enray\u00e9e en fin de deuxi\u00e8me. N\u00e9anmoins, le Fran\u00e7ais, sup\u00e9rieur dans le petit jeu, a d\u00fb rester concentr\u00e9 jusqu&rsquo;au bout pour contenir un baroud d&rsquo;honneur vain et s&rsquo;imposer en quatre jeux. Sa joie en fin de rencontre traduisait clairement la valeur de sa performance.<\/p>\n<p style=\"text-align: justify;\">Place ensuite au duel des n\u00b01 entre <strong>Victor Crouin<\/strong> et <strong>Dimitri Steinmann<\/strong>. Un match qui faisait transparaitre une r\u00e9elle tension, puisqu&rsquo;il pouvait d\u00e9cider de la suite de la rencontre. Appliqu\u00e9, mais surtout ma\u00eetre du jeu dans le money time, le Fran\u00e7ais a parfaitement g\u00e9r\u00e9 sa rencontre. Une victoire nette et sans bavure en trois jeux, qui mettait <strong>Baptiste Masotti<\/strong> sur une voie royale, avec seulement deux jeux \u00e0 gagner contre<strong> Yannick Wilhelmi<\/strong> pour ent\u00e9riner le succ\u00e8s. Ce sera chose faite malgr\u00e9 une toute petite tremblote en fin de partie. Demain, 14h00, les Bleus d\u00e9fieront de nouveau l&rsquo;Angleterre, en esp\u00e9rant cette fois le titre !<\/p>\n<h2 style=\"text-align: justify;\">R\u00e9sultats<\/h2>\n<p style=\"text-align: justify;\"><strong>France 3-0 Suisse<\/strong><\/p>\n<p style=\"text-align: justify;\">Gr\u00e9goire Marche 5-11, 11-8, 11-6, 11-8 Nicolas Mueller<\/p>\n<p style=\"text-align: justify;\">Victor Crouin 11-9, 11-8, 11-9 Dimitri Steinmann<\/p>\n<p style=\"text-align: justify;\">Baptiste Masotti 11-7, 11-7 Yannick Wilhelmi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE PAR \u00c9QUIPES DE SQUASH 2025 &#8211; Sans trembler, les Bleus ont assum\u00e9 leur statut contre les Suisses, et d\u00e9fieront de nouveau l&rsquo;Angleterre en finale demain.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":576073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9608],"tags":[16878,24081],"class_list":["post-576012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-squash","tag-breve","tag-squash-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&#039;Europe !<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l&#039;Angleterre en finale demain.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&#039;Europe !\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l&#039;Angleterre en finale demain.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-02T16:19:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T16:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&#039;Europe !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&rsquo;Europe !\",\"datePublished\":\"2025-05-02T16:19:20+00:00\",\"dateModified\":\"2025-05-02T16:30:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png\",\"keywords\":[\"br\u00e8ve\",\"Squash fran\u00e7ais\"],\"articleSection\":[\"Squash\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\",\"name\":\"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png\",\"datePublished\":\"2025-05-02T16:19:20+00:00\",\"dateModified\":\"2025-05-02T16:30:58+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l'Angleterre en finale demain.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png\",\"width\":1200,\"height\":674,\"caption\":\"Squash Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&rsquo;Europe !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !","description":"CHAMPIONNATS D'EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l'Angleterre en finale demain.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/","og_locale":"fr_FR","og_type":"article","og_title":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !","og_description":"CHAMPIONNATS D'EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l'Angleterre en finale demain.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-05-02T16:19:20+00:00","article_modified_time":"2025-05-02T16:30:58+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&rsquo;Europe !","datePublished":"2025-05-02T16:19:20+00:00","dateModified":"2025-05-02T16:30:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png","keywords":["br\u00e8ve","Squash fran\u00e7ais"],"articleSection":["Squash"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/","url":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/","name":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png","datePublished":"2025-05-02T16:19:20+00:00","dateModified":"2025-05-02T16:30:58+00:00","description":"CHAMPIONNATS D'EUROPE PAR \u00c9QUIPES DE SQUASH 2025 - Les Bleus ont domin\u00e9 les Suisses, et d\u00e9fieront de nouveau l'Angleterre en finale demain.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Squash-Les-Bleus-dominent-les-Suisses-et-retournent-en-finale-des-Championnats-dEurope-.png","width":1200,"height":674,"caption":"Squash Les Bleus dominent les Suisses et retournent en finale des Championnats d'Europe !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/squash-les-bleus-dominent-les-suisses-et-retournent-en-finale-des-championnats-deurope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Squash : Les Bleus dominent les Suisses et retournent en finale des Championnats d&rsquo;Europe !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/576012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=576012"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/576012\/revisions"}],"predecessor-version":[{"id":576082,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/576012\/revisions\/576082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/576073"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=576012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=576012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=576012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}