{"id":584642,"date":"2025-06-06T11:05:34","date_gmt":"2025-06-06T09:05:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=584642&#038;preview=true&#038;preview_id=584642"},"modified":"2025-06-06T13:36:27","modified_gmt":"2025-06-06T11:36:27","slug":"transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/","title":{"rendered":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS OM &#8211; Selon Rik Elfrink, l&rsquo;Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Depuis la fin de la <strong>Ligue<\/strong> <strong>1<\/strong>, <strong>Pablo<\/strong> <strong>Longoria<\/strong> et <strong>Medhi<\/strong> <strong>Benatia<\/strong> sont au four et au moulin pour renforcer l&rsquo;effectif de l&rsquo;<strong>Olympique de Marseille<\/strong>. Selon plusieurs sources, le club phoc\u00e9en serait m\u00eame en train de boucler <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-nelson-semedo-devrait-signer-a-marseille\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;arriv\u00e9e de <strong>Nelson<\/strong> <strong>Semedo<\/strong><\/a>. Apr\u00e8s plusieurs saisons \u00e0 Wolverhampton, le lat\u00e9ral droit pass\u00e9 par le Bar\u00e7a est libre de tout contrat.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-om-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato OM 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS OM - Retrouvez tous les mouvements de l'Olympique de Marseille pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Naples veut aussi Noa Lang<\/h2>\n<p style=\"text-align: justify;\">Autre poste prioritaire, celui d&rsquo;ailier gauche pour palier au d\u00e9part de <strong>Luis<\/strong> <strong>Henrique<\/strong> \u00e0 l&rsquo;<strong>Inter Milan<\/strong>. L&rsquo;<strong>OM<\/strong> a notamment pris des renseignements pour <b>Ivan Peri\u0161i\u0107<\/b>\u00a0et <strong>Igor<\/strong> <strong>Paix\u00e3o<\/strong> mais ces deux pistes semblent tomber \u00e0 l&rsquo;eau pour des raisons financi\u00e8res. <strong>Noa<\/strong> <strong>Lang<\/strong> serait finalement le mieux plac\u00e9 pour venir renforcer le couloir gauche olympien.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-passe-a-loffensive-pour-signer-nayef-aguerd\/\">Transferts OM : Marseille passe \u00e0 l\u2019offensive pour signer Nayef Aguerd<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Mais <strong>Marseille<\/strong> a de la concurrence sur ce dossier, car selon notre confr\u00e8re, <strong>Naples<\/strong> est aussi tr\u00e8s int\u00e9ress\u00e9 par le profil du joueur n\u00e9erlandais. D&rsquo;autres clubs, non connus pour le moment, sont aussi sur le coup pour tenter de l&rsquo;arracher au PSV. Le club n\u00e9erlandais demande pas moins de 30 millions d&rsquo;euros pour lib\u00e9rer <strong>Noa<\/strong> <strong>Lang<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS OM &#8211; Selon Rik Elfrink, l&rsquo;Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).<\/p>\n","protected":false},"author":1,"featured_media":584645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301,47045],"tags":[16878,75,1889,39821],"class_list":["post-584642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-football","tag-om","tag-transferts-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang<\/title>\n<meta name=\"description\" content=\"TRANSFERTS OM - Selon Rik Elfrink, l&#039;Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS OM - Selon Rik Elfrink, l&#039;Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-06T09:05:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-06T11:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang\",\"datePublished\":\"2025-06-06T09:05:34+00:00\",\"dateModified\":\"2025-06-06T11:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"OM\",\"Transferts OM\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\",\"name\":\"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png\",\"datePublished\":\"2025-06-06T09:05:34+00:00\",\"dateModified\":\"2025-06-06T11:36:27+00:00\",\"description\":\"TRANSFERTS OM - Selon Rik Elfrink, l'Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang","description":"TRANSFERTS OM - Selon Rik Elfrink, l'Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang","og_description":"TRANSFERTS OM - Selon Rik Elfrink, l'Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-06T09:05:34+00:00","article_modified_time":"2025-06-06T11:36:27+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang","datePublished":"2025-06-06T09:05:34+00:00","dateModified":"2025-06-06T11:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png","keywords":["br\u00e8ve","Football","OM","Transferts OM"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/","name":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png","datePublished":"2025-06-06T09:05:34+00:00","dateModified":"2025-06-06T11:36:27+00:00","description":"TRANSFERTS OM - Selon Rik Elfrink, l'Olympique de Marseille a de la concurrence dans la course \u00e0 la signature de Noa Lang (PSV).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-a-de-la-concurrence-pour-la-signature-de-Noa-Lang.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-a-de-la-concurrence-pour-la-signature-de-noa-lang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts OM : Marseille a de la concurrence pour la signature de Noa Lang"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/584642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=584642"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/584642\/revisions"}],"predecessor-version":[{"id":584694,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/584642\/revisions\/584694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/584645"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=584642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=584642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=584642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}