{"id":587041,"date":"2025-06-15T10:07:46","date_gmt":"2025-06-15T08:07:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=587041&#038;preview=true&#038;preview_id=587041"},"modified":"2025-06-15T10:07:46","modified_gmt":"2025-06-15T08:07:46","slug":"24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/","title":{"rendered":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>24 HEURES DU MANS 2025 &#8211; Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n&rsquo;a pas dit son dernier mot et Toyota reste en embuscade.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-2025-classement-en-direct\/\">24 Heures du Mans 2025 \u2013 Classement en direct<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Ferrari\u00a0<\/strong>m\u00e8ne les d\u00e9bats depuis la veille et c&rsquo;est toujours le cas ce dimanche matin. Apr\u00e8s 250 tours, il y avait moins de deux secondes d&rsquo;\u00e9cart entre la #51 pilot\u00e9e par\u00a0<strong>Antonio Giovinazzi<\/strong> et <strong>l&rsquo;AF Corse<\/strong> num\u00e9ro 83 de\u00a0<strong>Robert Kubica<\/strong>. Les \u00e9carts sont toujours assez similaires \u00e0 10 heures avec m\u00eame un tripl\u00e9 pour le Cheval cabr\u00e9 avec sa #50. L&rsquo;\u00e9curie italienne a donc des probl\u00e8mes de riches, puisque le Polonais s&rsquo;est un temps impatient\u00e9 derri\u00e8re la voiture de t\u00eate, avant de se faire une raison et de garder sa position.<\/p>\n<p style=\"text-align: justify;\"><strong>Cadillac<\/strong> est plus en difficult\u00e9, surtout sa #311. D&rsquo;abord rentr\u00e9e dans son box, cette voiture est repartie, mais va finalement s&rsquo;arr\u00eater en piste, avant le virage Dunlop. Les trois ex-pilotes F2 <strong>Vesti, Aitken\u00a0<\/strong>et\u00a0<strong>Drugovich\u00a0<\/strong>ont \u00e9t\u00e9 contraints \u00e0 l&rsquo;abandon apr\u00e8s 16 heures de course. Derri\u00e8re les <strong>Ferrari<\/strong>, <strong>Porsche, Toyota<\/strong> et <strong>BMW<\/strong> se suivent et attendent une br\u00e8che pour monter sur ce podium.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Unfortunately this is the end for the Cadillac #311.<br \/>\nIt still remains the two Cadillac Hertz Team JOTA in the race.<a href=\"https:\/\/twitter.com\/hashtag\/LeMans24?src=hash&amp;ref_src=twsrc%5Etfw\">#LeMans24<\/a> <a href=\"https:\/\/t.co\/7wXRE7Dfg6\">pic.twitter.com\/7wXRE7Dfg6<\/a><\/p>\n<p>\u2014 24 Hours of Le Mans (@24hoursoflemans) <a href=\"https:\/\/twitter.com\/24hoursoflemans\/status\/1934132821578174832?ref_src=twsrc%5Etfw\">June 15, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Une cat\u00e9gorie LMP2 ind\u00e9cise<\/h2>\n<p style=\"text-align: justify;\">Dans les autres cat\u00e9gories, rien n&rsquo;est fait alors qu&rsquo;il reste six heures de courses. <strong>En LMP2<\/strong>, c&rsquo;est <strong>l&rsquo;Inter Europole Comp\u00e9tition<\/strong>, avec \u00e0 son bord <strong>Tom Dillmann<\/strong>, qui m\u00e8ne avec moins de vingt secondes d&rsquo;avance sur la #48 du <strong>VDS Panis Racing<\/strong>.\u00a0<strong>La LMGT3\u00a0<\/strong>n&rsquo;a pas encore rendu son verdict avec la <strong>Manthey 1ST Phorm<\/strong> (<strong>Porsche<\/strong>) num\u00e9ro 92 en t\u00eate depuis des lustres devant la <strong>Vista AF Corse<\/strong>. Les deux voitures sont s\u00e9par\u00e9es par une minute \u00e0 ce stade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>24 HEURES DU MANS 2025 &#8211; Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n&rsquo;a pas dit son dernier mot et Toyota reste en embuscade.<\/p>\n","protected":false},"author":61,"featured_media":587065,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[16331],"tags":[5168,16878,5927],"class_list":["post-587041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-endurance","tag-24-heures-du-mans","tag-breve","tag-ferrari"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h<\/title>\n<meta name=\"description\" content=\"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n&#039;a pas dit son dernier mot et Toyota reste en embuscade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h\" \/>\n<meta property=\"og:description\" content=\"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n&#039;a pas dit son dernier mot et Toyota reste en embuscade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-15T08:07:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h\",\"datePublished\":\"2025-06-15T08:07:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png\",\"keywords\":[\"24 heures du Mans\",\"br\u00e8ve\",\"Ferrari\"],\"articleSection\":[\"Endurance\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\",\"name\":\"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png\",\"datePublished\":\"2025-06-15T08:07:46+00:00\",\"description\":\"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n'a pas dit son dernier mot et Toyota reste en embuscade.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png\",\"width\":1200,\"height\":674,\"caption\":\"24 Heures du Mans Le point sur la course ce dimanche \u00e0 10h\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h","description":"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n'a pas dit son dernier mot et Toyota reste en embuscade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/","og_locale":"fr_FR","og_type":"article","og_title":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h","og_description":"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n'a pas dit son dernier mot et Toyota reste en embuscade.","og_url":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-15T08:07:46+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h","datePublished":"2025-06-15T08:07:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png","keywords":["24 heures du Mans","br\u00e8ve","Ferrari"],"articleSection":["Endurance"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/","url":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/","name":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png","datePublished":"2025-06-15T08:07:46+00:00","description":"24 HEURES DU MANS 2025 - Ferrari domine toujours la course sarthoise avec ses trois voitures en t\u00eate. Porsche n'a pas dit son dernier mot et Toyota reste en embuscade.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/24-Heures-du-Mans-Le-point-sur-la-course-ce-dimanche-a-10h.png","width":1200,"height":674,"caption":"24 Heures du Mans Le point sur la course ce dimanche \u00e0 10h"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/24-heures-du-mans-le-point-sur-la-course-ce-dimanche-a-10h\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"24 Heures du Mans : Le point sur la course ce dimanche \u00e0 10h"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=587041"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587041\/revisions"}],"predecessor-version":[{"id":587066,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587041\/revisions\/587066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/587065"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=587041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=587041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=587041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}