{"id":587222,"date":"2025-06-15T18:21:23","date_gmt":"2025-06-15T16:21:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=587222&#038;preview=true&#038;preview_id=587222"},"modified":"2025-06-15T18:37:04","modified_gmt":"2025-06-15T16:37:04","slug":"finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/","title":{"rendered":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FINALE BETCLIC \u00c9LITE 2025 &#8211; Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l&rsquo;AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont parfaitement lanc\u00e9 cette s\u00e9rie.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-2025-tableau-calendrier-et-resultats\/\">Playoffs Betclic \u00c9lite 2025 : Tableau, calendrier et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les deux meilleures \u00e9quipes de l&rsquo;hexagone se retrouvaient ce dimanche pour lancer en fanfare la finale de <strong>Betclic \u00c9lite<\/strong>. Finaliste sortant de l&rsquo;Euroligue et tenant en titre, l&rsquo;<strong>AS Monaco<\/strong> se d\u00e9pla\u00e7ait sur le parquet de sa victime de la derni\u00e8re finale, <strong>Paris<\/strong>. Un d\u00e9placement \u00e0 l&rsquo;<strong>Adidas Arena<\/strong> qui s&rsquo;effectuait dans un contexte particulier, <strong>Mike James<\/strong> ayant \u00e9t\u00e9 \u00e0 nouveau \u00e9cart\u00e9 pour des raisons extra sportives.<\/p>\n<h2 style=\"text-align: justify;\">Paris ma\u00eetrise de bout en bout<\/h2>\n<p style=\"text-align: justify;\">Cette absence n&rsquo;a pas perturb\u00e9 la Roca Team dans un premier quart \u00e9quilibr\u00e9. En s&rsquo;appuyant sur la puissance physique d&rsquo;<strong>Alpha Diallo<\/strong> et <strong>Mam Jaiteh<\/strong>, auteurs \u00e0 eux deux de 17 points en dix minutes, cette derni\u00e8re est parvenue \u00e0 tenir le rythme de Parisiens men\u00e9s par leur doublette magique <strong>Nadir Hifi &#8211; TJ Shorts<\/strong>. Seulement, les affaires se sont cors\u00e9es dans le deuxi\u00e8me quart. En totale panne d&rsquo;adresse, les Mon\u00e9gasques ont l\u00e2ch\u00e9 du lest, se retrouvant largu\u00e9s \u00e0 11 unit\u00e9s de locaux d\u00e9termin\u00e9s (49-38).<\/p>\n<p style=\"text-align: justify;\">Domin\u00e9, le champion de France en titre souffre, mais ne l\u00e2che pas totalement prise malgr\u00e9 un \u00e9cart qui est mont\u00e9 jusqu&rsquo;\u00e0 15 unit\u00e9s. Paris n&rsquo;a pas r\u00e9ussi \u00e0 tuer le match, la faute \u00e0 une adresse ext\u00e9rieure d\u00e9faillante. Ainsi, sans faire de bruit, la Roca Team est revenue sous la barre des dix points en d\u00e9but de quatri\u00e8me quart, laissant planer sur l&rsquo;Adidas Arena la menace d&rsquo;une nouvelle remont\u00e9e folle, quelques jours apr\u00e8s le <a href=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-2025-monaco-renverse-lasvel-et-file-en-finale\/\">lunaire match 4 remport\u00e9 face \u00e0 l&rsquo;ASVEL<\/a>.<\/p>\n<p style=\"text-align: justify;\">Cependant, avant de quitter le club, <strong>TJ Shorts<\/strong> (30 points, 6 rebonds, 6 passes) compte bien partir sur un titre. \u00c0 lui seul, il va coller un 5-0 en deux actions pour refaire un break cons\u00e9quent (81-67). Puis, apr\u00e8s avoir b\u00e9n\u00e9fici\u00e9 de quelques minutes de repos, le meneur am\u00e9ricain a termin\u00e9 son chantier en continuant d&rsquo;enfiler les filoches de patron pour d\u00e9finitivement annihiler les espoirs mon\u00e9gasques. Avec ses fid\u00e8les lieutenants <strong>Tyson Ward<\/strong> (16 points) et <strong>Nadir Hifi<\/strong> (18 ponts), le leader de Paris a port\u00e9 son club \u00e0 la victoire, <strong>94-82<\/strong>. D\u00e8s mardi, les deux \u00e9quipes se retrouveront de nouveau \u00e0 l&rsquo;Adidas Arena pour le match 2.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udc51| TJ Shorts en mode patron ce soir ! \ud83c\udfc0\ud83d\udca5<br \/>\n\ud83d\udd17 Le dernier quart du match \u00e0 suivre gratuitement sur DAZN : <a href=\"https:\/\/t.co\/vRDcDnw952\">https:\/\/t.co\/vRDcDnw952<\/a><a href=\"https:\/\/twitter.com\/hashtag\/PlayoffsBetclicELITE?src=hash&amp;ref_src=twsrc%5Etfw\">#PlayoffsBetclicELITE<\/a> <a href=\"https:\/\/t.co\/bffjWyCwlF\">pic.twitter.com\/bffjWyCwlF<\/a><\/p>\n<p>\u2014 DAZN France (@DAZN_FR) <a href=\"https:\/\/twitter.com\/DAZN_FR\/status\/1934280530838606189?ref_src=twsrc%5Etfw\">June 15, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FINALE BETCLIC \u00c9LITE 2025 &#8211; Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l&rsquo;AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont lanc\u00e9 parfaitement cette s\u00e9rie.<\/p>\n","protected":false},"author":55,"featured_media":587263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2305,46998],"tags":[17909,16878,1678,429],"class_list":["post-587222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","category-betclic-elite","tag-betclic-elite","tag-breve","tag-monaco","tag-paris"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1<\/title>\n<meta name=\"description\" content=\"FINALE BETCLIC \u00c9LITE 2025 - Le Paris Basketball a remport\u00e9 le match 1 en dominant l&#039;AS Monaco \u00e0 l&#039;Adidas Arena, 94-82.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1\" \/>\n<meta property=\"og:description\" content=\"FINALE BETCLIC \u00c9LITE 2025 - Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l&#039;AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont lanc\u00e9 parfaitement cette s\u00e9rie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-15T16:21:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-15T16:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"FINALE BETCLIC \u00c9LITE 2025 - Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l&#039;AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont lanc\u00e9 parfaitement cette s\u00e9rie.\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1\",\"datePublished\":\"2025-06-15T16:21:23+00:00\",\"dateModified\":\"2025-06-15T16:37:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\"},\"wordCount\":461,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png\",\"keywords\":[\"Betclic Elite\",\"br\u00e8ve\",\"Monaco\",\"Paris\"],\"articleSection\":[\"Basket-ball\",\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\",\"name\":\"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png\",\"datePublished\":\"2025-06-15T16:21:23+00:00\",\"dateModified\":\"2025-06-15T16:37:04+00:00\",\"description\":\"FINALE BETCLIC \u00c9LITE 2025 - Le Paris Basketball a remport\u00e9 le match 1 en dominant l'AS Monaco \u00e0 l'Adidas Arena, 94-82.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1","description":"FINALE BETCLIC \u00c9LITE 2025 - Le Paris Basketball a remport\u00e9 le match 1 en dominant l'AS Monaco \u00e0 l'Adidas Arena, 94-82.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1","og_description":"FINALE BETCLIC \u00c9LITE 2025 - Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l'AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont lanc\u00e9 parfaitement cette s\u00e9rie.","og_url":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-15T16:21:23+00:00","article_modified_time":"2025-06-15T16:37:04+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_description":"FINALE BETCLIC \u00c9LITE 2025 - Paris a remport\u00e9 \u00e0 domicile le match 1 en dominant de bout en bout l'AS Monaco, 94-82. Men\u00e9s par un TJ Shorts (30 points) de gala, les Parisiens ont lanc\u00e9 parfaitement cette s\u00e9rie.","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1","datePublished":"2025-06-15T16:21:23+00:00","dateModified":"2025-06-15T16:37:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/"},"wordCount":461,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png","keywords":["Betclic Elite","br\u00e8ve","Monaco","Paris"],"articleSection":["Basket-ball","Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/","url":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/","name":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png","datePublished":"2025-06-15T16:21:23+00:00","dateModified":"2025-06-15T16:37:04+00:00","description":"FINALE BETCLIC \u00c9LITE 2025 - Le Paris Basketball a remport\u00e9 le match 1 en dominant l'AS Monaco \u00e0 l'Adidas Arena, 94-82.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Finale-Betclic-Elite-2025-TJ-Shorts-et-Paris-font-plier-Monaco-dans-le-match-1.png","width":1200,"height":674,"caption":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/finale-betclic-elite-2025-tj-shorts-et-paris-font-plier-monaco-dans-le-match-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Finale Betclic \u00c9lite 2025 : TJ Shorts et Paris font plier Monaco dans le match 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=587222"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587222\/revisions"}],"predecessor-version":[{"id":587271,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587222\/revisions\/587271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/587263"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=587222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=587222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=587222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}