{"id":587741,"date":"2025-06-17T16:11:12","date_gmt":"2025-06-17T14:11:12","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=587741&#038;preview=true&#038;preview_id=587741"},"modified":"2025-06-17T16:16:19","modified_gmt":"2025-06-17T14:16:19","slug":"transferts-om-quentin-merlin-pourrait-quitter-marseille","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/","title":{"rendered":"Transferts OM : Quentin Merlin pourrait quitter Marseille"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS OM &#8211; Selon <a href=\"https:\/\/www.laprovence.com\/article\/om\/5357575545571614\/mercato-om-quentin-merlin-un-avenir-en-question\">La Provence<\/a>, Quentin Merlin (23 ans) n&rsquo;est pas certain de rester \u00e0 Marseille la saison prochaine.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;<b>Olympique de Marseille <\/b>anime le march\u00e9 des transferts ces deniers jours avec de nombreuses pistes activ\u00e9es et d\u00e9j\u00e0 deux renforts : <strong>Angel<\/strong> <strong>Gomes<\/strong> et <strong>CJ<\/strong> <strong>Egan-Riley<\/strong>. <strong>Roberto<\/strong> <strong>De<\/strong> <strong>Zerbi<\/strong> et les dirigeants olympiens doivent aussi trancher l&rsquo;avenir de certains joueurs dans l&rsquo;effectif actuel, \u00e0 commencer par celui de <strong>Quentin<\/strong> <strong>Merlin<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-active-la-piste-eliesse-ben-seghir\/\" target=\"_blank\" rel=\"noopener\">Transferts OM : Marseille active la piste Eliesse Ben Seghir<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Quentin Merlin sur le d\u00e9part ?<\/h2>\n<p style=\"text-align: justify;\">Un temps dans les petits papiers de <strong>Bournemouth<\/strong> en <strong>Angleterre<\/strong>, <strong>Quentin<\/strong> <strong>Merlin<\/strong> ne rejoindra pas l&rsquo;\u00e9quipe de <strong>Premier<\/strong> <strong>League<\/strong>. Cette derni\u00e8re a finalement choisi de miser sur un autre joueur Fran\u00e7ais, <strong>Adrien<\/strong> <strong>Truffert<\/strong>. Le lat\u00e9ral gauche va-t-il rester \u00e0 l&rsquo;OM pour autant ? Rien n&rsquo;est moins s\u00fbr si on en croit les informations de nos confr\u00e8res.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-marseille-et-lille-foncent-sur-sikou-niakate\/\">Transferts : Marseille et Lille foncent sur Sikou Niakat\u00e9<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Roberto<\/strong> <strong>De<\/strong> <strong>Zerbi<\/strong> voudrait repasser \u00e0 une d\u00e9fense \u00e0 4 la saison prochaine et ne ferait pas confiance \u00e0 <strong>Quentin<\/strong> <strong>Merlin<\/strong> dans ce sch\u00e9ma. L&rsquo;ancien Nantais pourrait donc \u00eatre pouss\u00e9 vers la sortie alors que l&rsquo;<strong>Olympique de Marseille<\/strong> serait en qu\u00eate d&rsquo;un profil plus d\u00e9fensif \u00e0 ce poste. Si d&rsquo;autres \u00e9quipes sont \u00e0 l&rsquo;aff\u00fbt pour le recruter, les noms n&rsquo;ont pour le moment pas filtr\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"text-align: justify;\">\u00c0 ce sujet<\/span><\/strong><\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-om-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato OM 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS OM - Retrouvez tous les mouvements de l'Olympique de Marseille pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS OM &#8211; Selon La Provence, Quentin Merlin n&rsquo;est pas certain de rester \u00e0 Marseille la saison prochaine.<\/p>\n","protected":false},"author":1,"featured_media":587743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,446,41344],"class_list":["post-587741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-marseille","tag-mercatom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts OM : Quentin Merlin pourrait quitter Marseille<\/title>\n<meta name=\"description\" content=\"TRANSFERTS OM - Selon La Provence, Quentin Merlin n&#039;est pas certain de rester \u00e0 Marseille la saison prochaine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts OM : Quentin Merlin pourrait quitter Marseille\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS OM - Selon La Provence, Quentin Merlin n&#039;est pas certain de rester \u00e0 Marseille la saison prochaine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-17T14:11:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T14:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts OM : Quentin Merlin pourrait quitter Marseille\",\"datePublished\":\"2025-06-17T14:11:12+00:00\",\"dateModified\":\"2025-06-17T14:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png\",\"keywords\":[\"br\u00e8ve\",\"Marseille\",\"MercatOM\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\",\"name\":\"Transferts OM : Quentin Merlin pourrait quitter Marseille\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png\",\"datePublished\":\"2025-06-17T14:11:12+00:00\",\"dateModified\":\"2025-06-17T14:16:19+00:00\",\"description\":\"TRANSFERTS OM - Selon La Provence, Quentin Merlin n'est pas certain de rester \u00e0 Marseille la saison prochaine.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts OM : Quentin Merlin pourrait quitter Marseille\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts OM : Quentin Merlin pourrait quitter Marseille","description":"TRANSFERTS OM - Selon La Provence, Quentin Merlin n'est pas certain de rester \u00e0 Marseille la saison prochaine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts OM : Quentin Merlin pourrait quitter Marseille","og_description":"TRANSFERTS OM - Selon La Provence, Quentin Merlin n'est pas certain de rester \u00e0 Marseille la saison prochaine.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-17T14:11:12+00:00","article_modified_time":"2025-06-17T14:16:19+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts OM : Quentin Merlin pourrait quitter Marseille","datePublished":"2025-06-17T14:11:12+00:00","dateModified":"2025-06-17T14:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png","keywords":["br\u00e8ve","Marseille","MercatOM"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/","name":"Transferts OM : Quentin Merlin pourrait quitter Marseille","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png","datePublished":"2025-06-17T14:11:12+00:00","dateModified":"2025-06-17T14:16:19+00:00","description":"TRANSFERTS OM - Selon La Provence, Quentin Merlin n'est pas certain de rester \u00e0 Marseille la saison prochaine.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Avenir-incertain-a-Marseille-pour-Quentin-Merlin.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-quentin-merlin-pourrait-quitter-marseille\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts OM : Quentin Merlin pourrait quitter Marseille"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=587741"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587741\/revisions"}],"predecessor-version":[{"id":587746,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/587741\/revisions\/587746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/587743"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=587741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=587741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=587741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}