{"id":588514,"date":"2025-06-20T11:58:15","date_gmt":"2025-06-20T09:58:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=588514&#038;preview=true&#038;preview_id=588514"},"modified":"2025-06-20T12:27:40","modified_gmt":"2025-06-20T10:27:40","slug":"transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/","title":{"rendered":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS &#8211; Selon The Athletic, l&rsquo;Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Si le mercato olympien est plus calme ces derniers jours, <strong>Medhi<\/strong> <strong>Benatia<\/strong> est parti aux \u00c9tats-Unis pour le Mondial des clubs. L&rsquo;homme fort du recrutement de l&rsquo;OM devrait en profiter pour activer quelques pistes, et continuer son travail de recrutement. \u00c0 noter que la Juventus Turin est entr\u00e9 en contact avec <strong>Nayef<\/strong> <strong>Aguerd<\/strong>, aussi courtis\u00e9 par les Phoc\u00e9ens.<\/p>\n<h2 style=\"text-align: justify;\">La piste Ayden Heaven pour l&rsquo;OM<\/h2>\n<p style=\"text-align: justify;\">Toujours en qu\u00eate de renfort en d\u00e9fense centrale, l&rsquo;<strong>Olympique de Marseille<\/strong> avait coch\u00e9 un nouveau nom, celui du d\u00e9fenseur <strong>mancunien<\/strong>, <strong>Ayden<\/strong> <strong>Heaven<\/strong>. Le jeune talent, form\u00e9 \u00e0 <strong>Arsenal,<\/strong> \u00e9tait courtis\u00e9 par plusieurs clubs en Europe et notamment en Angleterre. <strong>Chelsea<\/strong> et <strong>Newcastle<\/strong> \u00e9taient sur le coup pour signer le joueur de 18 ans. La piste qui remonte \u00e0 quelques mois ne s&rsquo;est pas finalis\u00e9 puisqu&rsquo;il a d\u00e9cid\u00e9 de rejoindre Manchester United d\u00e9but f\u00e9vrier<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-bayern-munich-veut-kaoru-mitoma-marseille-aussi\/\" target=\"_blank\" rel=\"noopener\">Transferts : Le Bayern Munich veut Kaoru Mitoma, Marseille aussi ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Toujours au niveau de la d\u00e9fense centrale, l&rsquo;Olympique de Marseille veut garder <strong>Leo Balerdi<\/strong> \u00e0 tout prix, et a d\u00e9j\u00e0 refus\u00e9 des avances de la Juventus Turin. Mais selon la presse italienne, l&rsquo;AS Rome voudrait revenir \u00e0 la charge pour tenter de l&rsquo;arracher \u00e0 l&rsquo;OM. Devenu international argentin, il dispose d&rsquo;une belle cote sur le march\u00e9, mais les dirigeants phoc\u00e9ens veulent le garder pour jouer la Ligue des champions la saison prochaine.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"text-align: justify;\">\u00c0 ce sujet<\/span><\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-om-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato OM 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-OM-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato OM 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS OM - Retrouvez tous les mouvements de l'Olympique de Marseille pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS &#8211; Selon The Athletic, l&rsquo;Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0<\/p>\n","protected":false},"author":1,"featured_media":588519,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,41344,1889],"class_list":["post-588514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-mercatom","tag-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9<\/title>\n<meta name=\"description\" content=\"TRANSFERTS - Selon The Athletic, l&#039;Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS - Selon The Athletic, l&#039;Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T09:58:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T10:27:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9\",\"datePublished\":\"2025-06-20T09:58:15+00:00\",\"dateModified\":\"2025-06-20T10:27:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png\",\"keywords\":[\"br\u00e8ve\",\"MercatOM\",\"OM\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\",\"name\":\"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png\",\"datePublished\":\"2025-06-20T09:58:15+00:00\",\"dateModified\":\"2025-06-20T10:27:40+00:00\",\"description\":\"TRANSFERTS - Selon The Athletic, l'Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9","description":"TRANSFERTS - Selon The Athletic, l'Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9","og_description":"TRANSFERTS - Selon The Athletic, l'Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-20T09:58:15+00:00","article_modified_time":"2025-06-20T10:27:40+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9","datePublished":"2025-06-20T09:58:15+00:00","dateModified":"2025-06-20T10:27:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png","keywords":["br\u00e8ve","MercatOM","OM"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/","name":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png","datePublished":"2025-06-20T09:58:15+00:00","dateModified":"2025-06-20T10:27:40+00:00","description":"TRANSFERTS - Selon The Athletic, l'Olympique de Marseille suivrait de pr\u00e8s la situation du jeune Ayden Heaven (Manchester United).\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Transferts-OM-Marseille-piste-Ayden-Heaven-Leonardo-Balerdi-toujours-courtise.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-ayden-heaven-leonardo-balerdi-toujours-courtise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts OM : Marseille piste Ayden Heaven, Leonardo Balerdi toujours courtis\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/588514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=588514"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/588514\/revisions"}],"predecessor-version":[{"id":588529,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/588514\/revisions\/588529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/588519"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=588514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=588514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=588514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}