{"id":590929,"date":"2025-06-28T15:29:34","date_gmt":"2025-06-28T13:29:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=590929&#038;preview=true&#038;preview_id=590929"},"modified":"2025-06-28T15:58:39","modified_gmt":"2025-06-28T13:58:39","slug":"motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/","title":{"rendered":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>MOTO GP &#8211; GRAND PRIX DES PAYS-BAS 2025 &#8211; Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas). Alex Marquez (Gresini) et Marco Bezzecchi (Aprilia) compl\u00e9tent le podium de cette course. Malgr\u00e9 un bon d\u00e9part, Fabio Quartararo (Yamaha) \u00e9tait bien plac\u00e9 dans la lutte au Top 4 avant de chuter \u00e0 quelques tours de l&rsquo;arriv\u00e9e. Parti 12\u00e8me, Johann Zarco (LCR Honda) termine 11\u00e8me.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-horaires-programme-tv-et-resultats\/\">MotoGP Pays-Bas 2025 : Programme TV, Horaires et R\u00e9sultats<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet\u00a0<\/strong><strong>\u2013\u00a0<\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-assen-la-grille-de-depart-du-grand-prix-des-pays-bas-2025\/\"><strong>MotoGP Assen \u2013 La grille de d\u00e9part du Grand Prix des Pays-Bas 2025<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Suite \u00e0 une qualification en d\u00e9but de journ\u00e9e, <strong>Fabio<\/strong> <strong>Quartararo<\/strong> s\u2019\u00e9lan\u00e7ait pour la 4\u00e8me fois de la saison de la premi\u00e8re place en course sprint. Dans des conditions m\u00e9t\u00e9os plut\u00f4t nuageuses, <strong>Bagnaia<\/strong> et <strong>Alex<\/strong> <strong>Marquez<\/strong> partait derri\u00e8re le pilote <strong>Yamaha<\/strong>, tout comme <strong>Marc<\/strong> <strong>Marquez<\/strong>, 4\u00e8me au d\u00e9part.<\/p>\n<p style=\"text-align: justify;\">Alors que <strong>Quartararo<\/strong> a r\u00e9alis\u00e9 un bon d\u00e9part, c\u2019est derri\u00e8re lui que c\u2019est impressionnant, avec l\u2019\u00e9norme d\u00e9part de <strong>Marc<\/strong> <strong>Marquez<\/strong>. D\u00e8s le premier virage, le pilote <strong>Ducati<\/strong> se montre mena\u00e7ant sur le poleman et r\u00e9ussit \u00e0 le d\u00e9passer \u00e0 la fin du 1<sup>er<\/sup> tour. Le pilote fran\u00e7ais a rapidement perdu gros dans les trois premiers tours. Apr\u00e8s la perte de la t\u00eate de course, il se fait d\u00e9passer dans la ligne droite des stands par <strong>Alex<\/strong> <strong>Marquez<\/strong> (tour 2). Un tour apr\u00e8s, c\u2019est au tour de <strong>Bezzecchi<\/strong> de passer et de sortir <strong>Quartararo<\/strong> du podium.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Licked the stamp and sent it \ud83d\ude80<a href=\"https:\/\/twitter.com\/marcmarquez93?ref_src=twsrc%5Etfw\">@marcmarquez93<\/a> hits the front and <a href=\"https:\/\/twitter.com\/alexmarquez73?ref_src=twsrc%5Etfw\">@alexmarquez73<\/a> takes P2 \ud83d\udcc8<a href=\"https:\/\/twitter.com\/hashtag\/DutchGP?src=hash&amp;ref_src=twsrc%5Etfw\">#DutchGP<\/a> \ud83c\uddf3\ud83c\uddf1 <a href=\"https:\/\/t.co\/Jstl1UsE8D\">pic.twitter.com\/Jstl1UsE8D<\/a><\/p>\n<p>\u2014 MotoGP\u2122\ud83c\udfc1 (@MotoGP) <a href=\"https:\/\/twitter.com\/MotoGP\/status\/1938946981235175595?ref_src=twsrc%5Etfw\">June 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pendant que la bataille de t\u00eate de course, entre les fr\u00e8res <strong>Marquez<\/strong>, est isol\u00e9, <strong>Fabio<\/strong> <strong>Quartararo<\/strong> lutte en quatri\u00e8me position. D\u2019un c\u00f4t\u00e9, le pilote <strong>Yamaha<\/strong> a essay\u00e9 de revenir sur le podium et <strong>Bezzecchi<\/strong> mais dans le m\u00eame temps, il a d\u00fb faire attention au retour de <strong>Di<\/strong> <strong>Giannantonio<\/strong>. En essayant de revenir sur les trois premiers, le pilote fran\u00e7ais a chut\u00e9 \u00e0 quatre tours de l\u2019arriv\u00e9e. Au cours d\u2019une nouvelle course men\u00e9e depuis le premier tour, <strong>Marc<\/strong> <strong>Marquez<\/strong> termine victorieux de cette victoire sprint devant son fr\u00e8re <strong>Alex<\/strong>. Alors qu\u2019il avait r\u00e9alis\u00e9 un bon d\u00e9part, <strong>Johann<\/strong> <strong>Zarco<\/strong> ne gagne qu\u2019une seule place, et termine 11<sup>\u00e8me<\/sup> en dehors des points.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-gp-des-pays-bas-2025-classement-course-sprint-a-assen\/\" class=\"vlp-link\" title=\"MotoGP GP des Pays-Bas 2025 - Classement Course sprint \u00e0 Assen\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-GP-des-Pays-Bas-2025-Classement-Course-sprint-a-Assen.png\" class=\"attachment-800x445 size-800x445\" alt=\"MotoGP GP des Pays-Bas 2025 - Classement Course sprint \u00e0 Assen\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-GP-des-Pays-Bas-2025-Classement-Course-sprint-a-Assen.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-GP-des-Pays-Bas-2025-Classement-Course-sprint-a-Assen-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-GP-des-Pays-Bas-2025-Classement-Course-sprint-a-Assen-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-GP-des-Pays-Bas-2025-Classement-Course-sprint-a-Assen-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">MotoGP GP des Pays-Bas 2025 - Classement Course sprint \u00e0 Assen<\/div><div class=\"vlp-block-1 vlp-link-summary\">Retrouvez le classement complet et les r\u00e9sultats de la course sprint du Grand Prix d'Italie 2025 au Mugello, qui a eu lieu ce samedi 21 juin 2025.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-motogp-2025-le-point-sur-le-championnat-du-monde-des-pilotes\/\">MotoGP 2025 : Le classement du championnat du monde des pilotes<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).<\/p>\n","protected":false},"author":110,"featured_media":590967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47087],"tags":[16878,17577,24],"class_list":["post-590929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motogp","tag-breve","tag-grand-prix-des-pays-bas-motogp","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint<\/title>\n<meta name=\"description\" content=\"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint\" \/>\n<meta property=\"og:description\" content=\"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-28T13:29:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-28T13:58:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Malo Clement\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\"},\"author\":{\"name\":\"Malo Clement\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\"},\"headline\":\"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint\",\"datePublished\":\"2025-06-28T13:29:34+00:00\",\"dateModified\":\"2025-06-28T13:58:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\"},\"wordCount\":518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png\",\"keywords\":[\"br\u00e8ve\",\"Grand Prix des Pays-Bas MotoGP\",\"sport\"],\"articleSection\":[\"MotoGP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\",\"name\":\"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png\",\"datePublished\":\"2025-06-28T13:29:34+00:00\",\"dateModified\":\"2025-06-28T13:58:39+00:00\",\"description\":\"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png\",\"width\":1200,\"height\":674,\"caption\":\"MotoGP Pays-Bas 2025 Solide victoire de Marc Marquez en course sprint (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\",\"name\":\"Malo Clement\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"caption\":\"Malo Clement\"},\"description\":\"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint","description":"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/","og_locale":"fr_FR","og_type":"article","og_title":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint","og_description":"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).","og_url":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-06-28T13:29:34+00:00","article_modified_time":"2025-06-28T13:58:39+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png","type":"image\/png"}],"author":"Malo Clement","twitter_card":"summary_large_image","twitter_title":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/"},"author":{"name":"Malo Clement","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce"},"headline":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint","datePublished":"2025-06-28T13:29:34+00:00","dateModified":"2025-06-28T13:58:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/"},"wordCount":518,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png","keywords":["br\u00e8ve","Grand Prix des Pays-Bas MotoGP","sport"],"articleSection":["MotoGP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/","url":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/","name":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png","datePublished":"2025-06-28T13:29:34+00:00","dateModified":"2025-06-28T13:58:39+00:00","description":"Dans une course plut\u00f4t calme malgr\u00e9 un d\u00e9part agit\u00e9, Marc Marquez (Ducati) remporte sa 9\u00e8me course sprint cette saison, \u00e0 Assen (Pays-Bas).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/MotoGP-Pays-Bas-2025-Solide-victoire-de-Marc-Marquez-en-course-sprint-1.png","width":1200,"height":674,"caption":"MotoGP Pays-Bas 2025 Solide victoire de Marc Marquez en course sprint (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2025-solide-victoire-de-marc-marquez-en-course-sprint\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MotoGP Pays-Bas 2025 : Solide victoire de Marc Marquez en course sprint"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce","name":"Malo Clement","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","caption":"Malo Clement"},"description":"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.","url":"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/590929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=590929"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/590929\/revisions"}],"predecessor-version":[{"id":590961,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/590929\/revisions\/590961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/590967"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=590929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=590929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=590929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}