{"id":595325,"date":"2025-08-03T15:16:29","date_gmt":"2025-08-03T13:16:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=595325&#038;preview=true&#038;preview_id=595325"},"modified":"2025-08-03T15:16:12","modified_gmt":"2025-08-03T13:16:12","slug":"tableau-des-medailles-championnats-du-monde-natation-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/","title":{"rendered":"Tableau des m\u00e9dailles Championnats du monde Natation 2025"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.<\/i><\/b><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-des-championnats-du-monde-de-natation-2025\/\">Programme et r\u00e9sultats des Championnats du monde de natation 2025<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>tableau des m\u00e9dailles des Championnats du monde de natation 2025<\/strong>, organis\u00e9s \u00e0 Singapour, refl\u00e8te les performances des nations engag\u00e9es dans les six grandes disciplines au programme : <strong>natation en bassin<\/strong>, <strong>natation en eau libre<\/strong>, <strong>plongeon<\/strong>, <strong>plongeon de haut vol<\/strong>, <strong>natation artistique<\/strong> et <strong>water-polo<\/strong>. Avec 77 titres mondiaux en jeu et la participation de pr\u00e8s de 200 pays, cette \u00e9dition historique en Asie du Sud-Est met en lumi\u00e8re les meilleurs nageurs et nageuses du monde entier.<\/p>\n<p style=\"text-align: justify;\">Le <strong>classement des m\u00e9dailles, actualis\u00e9 apr\u00e8s chaque journ\u00e9e de comp\u00e9tition<\/strong>, permet de suivre les nations les plus titr\u00e9es et d\u2019identifier les pays \u00e9mergents dans les disciplines aquatiques. La domination traditionnelle de certaines nations comme les \u00c9tats-Unis, la Chine ou l\u2019Australie est parfois bouscul\u00e9e par des surprises, notamment dans les \u00e9preuves mixtes ou les sports artistiques. Un suivi incontournable pour ne rien manquer des temps forts de la natation mondiale en 2025.<\/p>\n<h2 style=\"text-align: justify;\">Tableau des m\u00e9dailles des Championnats du monde de Natation 2025<\/h2>\n<form><a id=\"choix\"><\/a><select spellcheck=\"false\" name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\" data-lt-tmp-id=\"lt-557350\" data-gramm=\"false\"><option value=\"#choix\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong><a id=\"tableau\"><\/a>Tableau des m\u00e9dailles final (77\/77).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\uddf3 CHINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>15<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">36<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>13<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">27<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 \u00c9TATS-UNIS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>9<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">11<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">11<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">31<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" data-wp-editing=\"1\" \/> ATHL\u00c8TES NEUTRES B<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>6<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">18<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>6<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">10<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">10<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udde6 CANADA<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">11<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">19<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf9\ud83c\uddf3 TUNISIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddef\ud83c\uddf5 JAPON<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf2\ud83c\uddfd MEXIQUE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddff\ud83c\udde6 AFRIQUE DU SUD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf1 PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\uddf7 GR\u00c8CE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 AUTRICHE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf1\ud83c\uddf9 LITUANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">21.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udded SUISSE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">22.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES A<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">23.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde7\ud83c\uddea BELGIQUE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">23.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddf5 COR\u00c9E DU NORD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">25.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf1 POLOGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">25.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">27.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddf7 COR\u00c9E DU SUD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">27.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddec KIRGHIZSTAN<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">27.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf2\ud83c\udde8 MONACO<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natation\"><\/a>Tableau des m\u00e9dailles de la natation sportive<\/h2>\n<form><select spellcheck=\"false\" name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\" data-lt-tmp-id=\"lt-568657\" data-gramm=\"false\"><option value=\"#natation\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (42\/42).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 \u00c9TATS-UNIS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>9<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">11<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">29<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>8<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udde6 CANADA<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES B<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\uddf3 CHINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">14<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf9\ud83c\uddf3 TUNISIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddff\ud83c\udde6 AFRIQUE DU SUD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf1 PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf1\ud83c\uddf9 LITUANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddef\ud83c\uddf5 JAPON<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udded SUISSE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde7\ud83c\uddea BELGIQUE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf1 POLOGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES A<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddf7 COR\u00c9E DU SUD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddec KIRGHIZSTAN<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natationartistique\"><\/a>Tableau des m\u00e9dailles de la natation artistique<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#natationartistique\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (11\/11).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\uddf3 CHINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES B<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 AUTRICHE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES A<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddef\ud83c\uddf5 JAPON<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf2\ud83c\uddfd MEXIQUE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natationeaulibre\"><\/a>Tableau des m\u00e9dailles de la natation en eau libre<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#natationeaulibre\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (7\/7).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddef\ud83c\uddf5 JAPON<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf2\ud83c\udde8 MONACO<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"plongeon\"><\/a>Tableau des m\u00e9dailles du plongeon<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#plongeon\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (13\/13).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\uddf3 CHINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>9<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">16<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf2\ud83c\uddfd MEXIQUE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.worldaquatics.com\/resources\/v2.12.26\/i\/elements\/flags\/nab.png\" alt=\"NAB\" width=\"14\" height=\"14\" \/> ATHL\u00c8TES NEUTRES B<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf0\ud83c\uddf5 COR\u00c9E DU NORD<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 \u00c9TATS-UNIS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddef\ud83c\uddf5 JAPON<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"plongeonhautvol\"><\/a>Tableau des m\u00e9dailles du plongeon de haut vol<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#plongeonhautvol\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/7\/#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (2\/2).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 \u00c9TATS-UNIS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udde6 CANADA<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"waterpolo\"><\/a>Tableau des m\u00e9dailles du water-polo<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#plongeonhautvol\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#tableau\">Championnats du monde de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><option value=\"#waterpolo\">Water-polo<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau des m\u00e9dailles final (2\/2).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\uddf7 GR\u00c8CE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.<\/p>\n","protected":false},"author":4,"featured_media":595347,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"0","footnotes":""},"categories":[2306],"tags":[16878,22970,37583],"class_list":["post-595325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natation","tag-breve","tag-championnats-du-monde-de-natation","tag-championnats-du-monde-natation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tableau des m\u00e9dailles Championnats du monde Natation 2025<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tableau des m\u00e9dailles Championnats du monde Natation 2025\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T13:16:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tableau des m\u00e9dailles Championnats du monde Natation 2025\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tableau des m\u00e9dailles Championnats du monde Natation 2025\",\"datePublished\":\"2025-08-03T13:16:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\"},\"wordCount\":697,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png\",\"keywords\":[\"br\u00e8ve\",\"championnats du monde de natation\",\"Championnats du monde natation\"],\"articleSection\":[\"Natation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\",\"name\":\"Tableau des m\u00e9dailles Championnats du monde Natation 2025\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png\",\"datePublished\":\"2025-08-03T13:16:29+00:00\",\"description\":\"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png\",\"width\":1200,\"height\":674,\"caption\":\"Tableau des m\u00e9dailles Championnats du monde Natation 2025\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tableau des m\u00e9dailles Championnats du monde Natation 2025","description":"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/","next":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"Tableau des m\u00e9dailles Championnats du monde Natation 2025","og_description":"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.","og_url":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-08-03T13:16:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tableau des m\u00e9dailles Championnats du monde Natation 2025","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tableau des m\u00e9dailles Championnats du monde Natation 2025","datePublished":"2025-08-03T13:16:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/"},"wordCount":697,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png","keywords":["br\u00e8ve","championnats du monde de natation","Championnats du monde natation"],"articleSection":["Natation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/","url":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/","name":"Tableau des m\u00e9dailles Championnats du monde Natation 2025","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png","datePublished":"2025-08-03T13:16:29+00:00","description":"D\u00e9couvrez le tableau des m\u00e9dailles des championnats du monde de natation 2025, qui se disputent du vendredi 11 juillet au dimanche 3 ao\u00fbt 2025 \u00e0 Singapour.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-championnats-du-monde-natation-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Tableau-des-medailles-Championnats-du-monde-Natation-2025.png","width":1200,"height":674,"caption":"Tableau des m\u00e9dailles Championnats du monde Natation 2025"},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/595325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=595325"}],"version-history":[{"count":7,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/595325\/revisions"}],"predecessor-version":[{"id":600146,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/595325\/revisions\/600146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/595347"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=595325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=595325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=595325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}