{"id":596155,"date":"2025-07-18T16:18:02","date_gmt":"2025-07-18T14:18:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=596155&#038;preview=true&#038;preview_id=596155"},"modified":"2025-07-18T16:22:06","modified_gmt":"2025-07-18T14:22:06","slug":"transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/","title":{"rendered":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS &#8211; Selon <a href=\"https:\/\/www.footmercato.net\/a5490110514985918252-le-stade-rennais-pense-a-pierre-lees-melou\">Foot Mercato<\/a>, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-lyon-jordan-veretout-tout-proche-de-quitter-lol\/\">Transferts Lyon : Jordan Veretout tout proche de quitter l\u2019OL<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>Stade<\/strong> <strong>Rennais<\/strong> a \u00e9t\u00e9 plut\u00f4t discret sur le march\u00e9 des transferts pour le moment. Plusieurs retours de pr\u00eat, et l&rsquo;arriv\u00e9e d\u00e9finitive de <strong>Lilian<\/strong> <strong>Brassier,<\/strong> mais pas d&rsquo;autres recrues pour le moment. Ces derni\u00e8res heures, les <strong>Bretons<\/strong> sont pass\u00e9s \u00e0 l&rsquo;offensive pour le milieu offensif de <strong>Genk<\/strong>, <strong>Zakaria<\/strong> <strong>El<\/strong> <strong>Ouahdi<\/strong> avec une premi\u00e8re offre.<\/p>\n<h2 style=\"text-align: justify;\">Pierre Lees-Melou vis\u00e9 par Rennes<\/h2>\n<p style=\"text-align: justify;\">Et ce ne serait pas la seule piste pour le <strong>Stade<\/strong> <strong>Rennais,<\/strong> selon nos confr\u00e8res. D\u00e9j\u00e0 convoit\u00e9 il y a quelques mois, <strong>Pierre Lees-Melou<\/strong> a toujours la cote. Le milieu de terrain r\u00e9cup\u00e9rateur du <strong>Stade<\/strong> <strong>Brestois<\/strong> sort d&rsquo;une saison moins aboutie, et ne serait pas contre un nouveau challenge.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-monaco-situation-incertaine-pour-eliesse-ben-seghir-et-maghnes-akliouche\/\">Transferts Monaco : Situation incertaine pour Eliesse Ben Seghir et Maghnes Akliouche<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>Stade<\/strong> <strong>Rennais<\/strong> voudrait le recruter, mais pour pouvoir y parvenir, le club doit vendre au m\u00eame poste. <strong>Jordan<\/strong> <strong>James, Glen<\/strong> <strong>Kamara<\/strong> ou <strong>Baptiste<\/strong> <strong>Santamaria<\/strong> doivent donc s&rsquo;en aller pour faire de la place \u00e0 <strong>Pierre Lees-Melou<\/strong>. Il est \u00e9valu\u00e9 \u00e0 6 millions d&rsquo;euros par le site <a href=\"https:\/\/www.transfermarkt.fr\/\">Transfermarkt<\/a>.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"text-align: justify;\">\u00c0 ce sujet<\/span><\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-brest-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato Brest 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Brest-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato Brest 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Brest-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Brest-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Brest-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Brest-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato Brest 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS BREST - Retrouvez tous les mouvements du Stade Brestois 29 pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS &#8211; Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.<\/p>\n","protected":false},"author":1,"featured_media":596165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,14093],"class_list":["post-596155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-mercato-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Brest : Rennes sur la piste de Pierre Lees-Melou<\/title>\n<meta name=\"description\" content=\"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T14:18:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T14:22:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou\",\"datePublished\":\"2025-07-18T14:18:02+00:00\",\"dateModified\":\"2025-07-18T14:22:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png\",\"keywords\":[\"br\u00e8ve\",\"Mercato football\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\",\"name\":\"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png\",\"datePublished\":\"2025-07-18T14:18:02+00:00\",\"dateModified\":\"2025-07-18T14:22:06+00:00\",\"description\":\"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou","description":"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou","og_description":"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-07-18T14:18:02+00:00","article_modified_time":"2025-07-18T14:22:06+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou","datePublished":"2025-07-18T14:18:02+00:00","dateModified":"2025-07-18T14:22:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png","keywords":["br\u00e8ve","Mercato football"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/","name":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png","datePublished":"2025-07-18T14:18:02+00:00","dateModified":"2025-07-18T14:22:06+00:00","description":"TRANSFERTS - Selon Foot Mercato, le Stade Rennais pense \u00e0 Pierre Lees-Melou (Rennes) pour se renforcer au milieu de terrain.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-Brest-Rennes-sur-la-piste-de-Pierre-Lees-Melou.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brest-rennes-sur-la-piste-de-pierre-lees-melou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Brest : Rennes sur la piste de Pierre Lees-Melou"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/596155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=596155"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/596155\/revisions"}],"predecessor-version":[{"id":596167,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/596155\/revisions\/596167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/596165"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=596155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=596155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=596155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}