{"id":597101,"date":"2025-07-30T11:47:02","date_gmt":"2025-07-30T09:47:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=597101&#038;preview=true&#038;preview_id=597101"},"modified":"2025-07-30T11:47:12","modified_gmt":"2025-07-30T09:47:12","slug":"parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/","title":{"rendered":"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-france-femmes-2025-mis-a-jour\/\">Classement g\u00e9n\u00e9ral Tour de France Femmes 2025 mis \u00e0 jour<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Ce <strong>mercredi 30 juillet<\/strong>, le peloton du <strong>Tour de France Femmes 2025<\/strong> fera face \u00e0 la plus longue \u00e9tape du\u00a0Tour de France Femmes 2025 avec 166 kilom\u00e8tres reliant <strong>Chasseneuil-du-Poitou<\/strong> (au d\u00e9part du Futuroscope) \u00e0 <strong>Gu\u00e9ret<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Le parcours complet de la 5\u00e8me \u00e9tape du Tour de France 2025<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-france-femmes-2025-lorena-wiebes-double-la-mise-au-sprint\/\">le doubl\u00e9 de <strong>Lorena Wiebes<\/strong> \u00e0 Poitiers<\/a>, place \u00e0 une journ\u00e9e casse-pattes. La cinqui\u00e8me \u00e9tape d\u00e9butera \u00e0 13h20 depuis le <strong>Futuroscope<\/strong> \u00e0<strong> Chasseneuil-du-Poitou<\/strong>. Puis, la premi\u00e8re moiti\u00e9 de l&rsquo;\u00e9tape se d\u00e9roulera sur des routes plates puis en faux plat montant pour monter progressivement \u00e0 400 m\u00e8tres d&rsquo;altitude. Mais, les trente derniers kilom\u00e8tres de cette \u00e9tape \u00e0 travers la campagne comporteront trois ascensions class\u00e9es, cr\u00e9ant un terrain id\u00e9al pour les attaques et les \u00e9carts.<\/p>\n<p style=\"text-align: justify;\">Ce final commencera par la <strong>C\u00f4te de Chabannes (1,4 km \u00e0 5,2 %)<\/strong>, suivie de la\u00a0<strong>C\u00f4te Peyroux (3,3 km \u00e0 4,3 %)<\/strong>, o\u00f9 les premi\u00e8res cassures importantes seront attendues. Mais la bataille d\u00e9cisive devrait se d\u00e9rouler sur <strong>Le Maupuy (2,8 km \u00e0 5,4 %)<\/strong>, \u00e0 un peu moins de sept kilom\u00e8tres de l&rsquo;arriv\u00e9e. Cette derni\u00e8re ascension, dans la Creuse bois\u00e9e, est le point de d\u00e9part id\u00e9al pour les coureuses du classement g\u00e9n\u00e9ral. L&rsquo;arriv\u00e9e vers 17h30 &#8211; dans le chef-lieu de la Creuse &#8211; Gu\u00e9ret sera en l\u00e9g\u00e8re mont\u00e9e sur les 500 derniers m\u00e8tres, ce qui rendra encore plus difficile ce final \u00e9prouvant.<\/p>\n<h2 style=\"text-align: justify;\">Le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025<\/h2>\n<div id=\"attachment_598878\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-598878\" class=\"size-full wp-image-598878\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret.jpg\" alt=\"Profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret\" width=\"960\" height=\"576\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret-300x180.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret-768x461.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret-590x354.jpg 590w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025-entre-Chasseneuil-du-Poitou-et-Gueret-400x240.jpg 400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-598878\" class=\"wp-caption-text\">Profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret<\/p><\/div>\n<hr \/>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2025\/\">L\u2019actualit\u00e9 du cyclisme sur route<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).<\/p>\n","protected":false},"author":48,"featured_media":598875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46995],"tags":[32415,16878,574,11197,1262],"class_list":["post-597101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-de-france","tag-actu","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5e \u00e9tape du Tour de France Femmes 2025 : profil et parcours entre Chasseneuil-du-Poitou et Gu\u00e9ret\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T09:47:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T09:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"5e \u00e9tape du Tour de France Femmes 2025 : profil et parcours entre Chasseneuil-du-Poitou et Gu\u00e9ret\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape\",\"datePublished\":\"2025-07-30T09:47:02+00:00\",\"dateModified\":\"2025-07-30T09:47:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de France\"],\"articleSection\":[\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\",\"name\":\"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png\",\"datePublished\":\"2025-07-30T09:47:02+00:00\",\"dateModified\":\"2025-07-30T09:47:12+00:00\",\"description\":\"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png\",\"width\":1200,\"height\":674,\"caption\":\"Parcours et profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape","description":"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"5e \u00e9tape du Tour de France Femmes 2025 : profil et parcours entre Chasseneuil-du-Poitou et Gu\u00e9ret","og_description":"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).","og_url":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2025-07-30T09:47:02+00:00","article_modified_time":"2025-07-30T09:47:12+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"5e \u00e9tape du Tour de France Femmes 2025 : profil et parcours entre Chasseneuil-du-Poitou et Gu\u00e9ret","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape","datePublished":"2025-07-30T09:47:02+00:00","dateModified":"2025-07-30T09:47:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png","keywords":["actu","br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de France"],"articleSection":["Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/","url":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/","name":"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png","datePublished":"2025-07-30T09:47:02+00:00","dateModified":"2025-07-30T09:47:12+00:00","description":"Retrouvez le parcours complet et le profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025, qui se dispute ce mercredi 30 juillet 2025 entre Chasseneuil-du-Poitou et Gu\u00e9ret (165,8 km).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Parcours-et-profil-de-la-5eme-etape-du-Tour-de-France-Femmes-2025.png","width":1200,"height":674,"caption":"Parcours et profil de la 5\u00e8me \u00e9tape du Tour de France Femmes 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/parcours-et-profil-de-la-5eme-etape-du-tour-de-france-femmes-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France Femmes 2025 : Parcours et Profil de la 5\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=597101"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597101\/revisions"}],"predecessor-version":[{"id":599042,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597101\/revisions\/599042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/598875"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=597101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=597101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=597101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}